{"id":10143,"date":"2015-03-21T15:36:35","date_gmt":"2015-03-21T14:36:35","guid":{"rendered":"http:\/\/www.vindjeu.eu\/?p=10143"},"modified":"2015-03-21T15:39:02","modified_gmt":"2015-03-21T14:39:02","slug":"trains-rising-sun","status":"publish","type":"post","link":"https:\/\/www.vindjeu.eu\/prd\/2015\/03\/21\/trains-rising-sun\/","title":{"rendered":"Trains: Rising Sun"},"content":{"rendered":"<p><a href=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2015\/01\/932-trains-rs-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-10145\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2015\/01\/932-trains-rs-1.jpg\" alt=\"932 trains rs 1\" width=\"500\" height=\"500\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2015\/01\/932-trains-rs-1.jpg 500w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2015\/01\/932-trains-rs-1-150x150.jpg 150w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2015\/01\/932-trains-rs-1-300x300.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2015\/01\/932-trains-rs-1-160x160.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2015\/01\/932-trains-rs-1-245x245.jpg 245w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2015\/01\/932-trains-rs-1-340x340.jpg 340w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><strong><span style=\"color: #333399;\">SwatSh<\/span>: <span style=\"color: #800000;\">7,5 \/10<\/span><\/strong><\/p>\n<p>Trains Rising Sun est un stand alone (=variante du jeu de base ne n\u00e9cessitant pas de poss\u00e9der le jeu de base) du tr\u00e8s bon jeu de deckbuilding qu\u2019est <span style=\"color: #0000ff;\">Trains<\/span>.<\/p>\n<p>La majorit\u00e9 des nouveaut\u00e9s de cette version n\u2019est pas du tout r\u00e9volutionnaire mais permet de varier les plaisirs\u00a0: &#8211; Une nouvelle carte double face dont le recto ressemble fort aux cartes d\u2019origine et le verso propose 2 cartes pour 2 joueurs donnant un r\u00e9el plus au jeu \u00e0 2. &#8211; De nombreuses nouvelles cartes offrant des variantes aux actions d\u00e9j\u00e0 existantes.\u00a0 Je suis un peu d\u00e9\u00e7u de ces nouvelles cartes.\u00a0 Les actions propos\u00e9es sont trop proches des actions du jeu de base, par exemple\u00a0: Une carte permet de construire un rail mais rapporte aussi une pi\u00e8ce, une carte permet de d\u00e9truire 2 wastes maximum non seulement de sa main, mais aussi de sa d\u00e9fausse,&#8230;\u00a0 Rien de fondamentalement nouveau \u00e0 l\u2019exception des cartes attaque et d\u00e9fense qui fonctionnent un peu de la m\u00eame mani\u00e8re que ce type de cartes dans <a href=\"http:\/\/www.vindjeu.eu\/2009\/01\/24\/dominion\/\" target=\"_blank\">Dominion\u00a0<\/a>: les cartes attaque vont obliger les adversaires \u00e0 se d\u00e9fausser de cartes et d\u2019autres trucs moins sympas tandis que les cartes d\u00e9fense vont s\u2019en prot\u00e9ger et apporter une action moins puissante \u00e0 son tour. C\u2019est d\u2019autant plus dommage que <span style=\"color: #0000ff;\">Trains<\/span> peut \u00eatre sujet \u00e0 de la cr\u00e9ativit\u00e9\u00a0: on pourrait imaginer plus de nouveaut\u00e9s sur la carte, d\u2019autres types de rail, pouvoir transporter des marchandises ou des passagers,&#8230; et pouvoir nettoyer son deck\u00a0!\u00a0 Contrairement \u00e0 d\u2019autres jeux de deckbuilding, dans trains rising sun, on ne sait pas nettoyer son deck \u00e0 l\u2019exception des cartes Waste.\u00a0 Il est impossible de se d\u00e9faire de ses cartes les moins puissantes comme les cartes de base par exemple.\u00a0 C\u2019est d\u2019autant plus dommage qu\u2019on se retrouve avec un gros deck \u00e0 la fin du jeu qui dilue toute modification dans sa constitution.<\/p>\n<p>La plus belle id\u00e9e pour moi est les cartes objectifs.\u00a0 Au d\u00e9but de la partie on tire au hasard autant de cartes objectif qu\u2019il y a de joueurs parmi les 5 disponibles pour ce plateau. Ces cartes indiquent 2 villes qui doivent \u00eatre reli\u00e9es.\u00a0 Le premier \u00e0 relier les 2 villes avec son r\u00e9seau re\u00e7oit les PVs de la carte + un petit bonus.\u00a0 C\u2019est assez sympa car \u00e7a permet d\u2019ouvrir le jeu, de donner plus de choix (vais-je essayer de remplir cet objectif, cet autre objectif ou bien je me dirige plut\u00f4t vers les cit\u00e9s adverses\u00a0?) et d\u2019augmenter cette ambiance de course lorsque plusieurs joueurs se disputent un m\u00eame objectif&#8230;<a href=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2015\/01\/932-trains-rs-2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-large wp-image-10146\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2015\/01\/932-trains-rs-2-768x1024.jpg\" alt=\"932 trains rs 2\" width=\"720\" height=\"960\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2015\/01\/932-trains-rs-2-768x1024.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2015\/01\/932-trains-rs-2-225x300.jpg 225w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2015\/01\/932-trains-rs-2-120x160.jpg 120w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2015\/01\/932-trains-rs-2-183x245.jpg 183w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2015\/01\/932-trains-rs-2-255x340.jpg 255w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><\/a><\/p>\n<p>Cerise sur le g\u00e2teau, le jeu fourni 5 cartes objectifs par plateau existant dont ceux de la boite de base ce qui rend l\u2019utilisation de ces cartes indispensables m\u00eame pour le jeu de base.<\/p>\n<p>En conclusion, je dirais que le nombre et le type de nouveaut\u00e9s sont particuli\u00e8rement restreints et, si vous avez d\u00e9j\u00e0 le jeu de base, cette extension est dispensable sauf si vraiment vous \u00eates fans absolus et que vous voulez vous procurer la boite pour une de ces 2 raisons\u00a0: vous jouez souvent \u00e0 2 ou vous voulez absolument jouer avec ces quelques cartes objectifs.\u00a0 Pour les personnes n\u2019ayant pas le jeu de base, je conseille plut\u00f4t cette version-ci qui augmente les choix de la version de base gr\u00e2ce \u00e0 ses cartes objectifs.<\/p>\n<p style=\"text-align: center;\">_____________________________________<\/p>\n<p><strong><span style=\"color: #333399;\">Dan\u00a0<\/span>:\u00a0 <span style=\"color: #800000;\">7,75\/10<\/span><\/strong><\/p>\n<p>Jeu de deck building assez simple \u00e0 assimiler et assez agr\u00e9able \u00e0 jouer.<\/p>\n<p>Particularit\u00e9 plaisante\u00a0: le jeu consiste \u00e0 acqu\u00e9rir des cartes qui offrent de plus grandes capacit\u00e9s dont des cartes d\u2019attaque et de d\u00e9fense (comme dans tout jeu de deck building me direz-vous\u00a0\ud83d\ude09 ), des cartes qui permettent de gagner des points mais aussi et surtout des cartes qui permettent le placement de rails et de gares sur le plateau commun.<\/p>\n<p>En d\u00e9coule un peu de strat\u00e9gie.\u00a0 Petit d\u00e9faut\u00a0: la taille du deck carr\u00e9ment volumineuse en fin de partie r\u00e9duisant l\u2019int\u00e9r\u00eat de certaines cartes dont la fr\u00e9quence d\u2019apparition ne justifie pas le co\u00fbt.<\/p>\n<p style=\"text-align: center;\">________________________________________________<\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2015\/01\/932-trains-rs-3.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-10147\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2015\/01\/932-trains-rs-3-1024x768.jpg\" alt=\"932 trains rs 3\" width=\"1200\" height=\"900\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2015\/01\/932-trains-rs-3-1024x768.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2015\/01\/932-trains-rs-3-300x225.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2015\/01\/932-trains-rs-3-160x120.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2015\/01\/932-trains-rs-3-326x245.jpg 326w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2015\/01\/932-trains-rs-3-453x340.jpg 453w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/a><\/p>\n<p style=\"text-align: center;\">Chercher les diff\u00e9rences avec le plateau original \ud83d\ude42<\/p>\n<p style=\"text-align: center;\">___________________________________________________________________________<\/p>\n<p><a href=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2015\/01\/932-trains-rs-4.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-10144\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2015\/01\/932-trains-rs-4-768x1024.jpg\" alt=\"932 trains rs 4\" width=\"1200\" height=\"1600\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2015\/01\/932-trains-rs-4-768x1024.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2015\/01\/932-trains-rs-4-225x300.jpg 225w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2015\/01\/932-trains-rs-4-120x160.jpg 120w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2015\/01\/932-trains-rs-4-183x245.jpg 183w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2015\/01\/932-trains-rs-4-255x340.jpg 255w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p> Trains Rising Sun est un stand alone (=variante du jeu de base ne n\u00e9cessitant pas de poss\u00e9der le jeu de base) du tr\u00e8s bon jeu de deckbuilding qu\u2019est Trains. La majorit\u00e9 des nouveaut\u00e9s de cette version n\u2019est pas du tout r\u00e9volutionnaire mais permet de varier les&#46;&#46;&#46;<\/p>\n","protected":false},"author":3,"featured_media":10145,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[4848],"tags":[502,7],"class_list":["post-10143","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-initie","tag-dan","tag-swatsh","annee-779","auteurs-hisashi-hayashi","auteurs-steve-ellis","editeurs-alderac-entertainment-group"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/10143","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/comments?post=10143"}],"version-history":[{"count":0,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/10143\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media\/10145"}],"wp:attachment":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media?parent=10143"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/categories?post=10143"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/tags?post=10143"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}