{"id":11799,"date":"2015-10-06T11:44:49","date_gmt":"2015-10-06T09:44:49","guid":{"rendered":"http:\/\/www.vindjeu.eu\/?p=11799"},"modified":"2015-10-06T11:44:49","modified_gmt":"2015-10-06T09:44:49","slug":"the-mystery-of-dattakamo","status":"publish","type":"post","link":"https:\/\/www.vindjeu.eu\/prd\/2015\/10\/06\/the-mystery-of-dattakamo\/","title":{"rendered":"The Mystery of Dattakamo"},"content":{"rendered":"<p><a href=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2015\/10\/1125-Dattakamo-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-11801\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2015\/10\/1125-Dattakamo-1.jpg\" alt=\"1125 Dattakamo 1\" width=\"350\" height=\"350\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2015\/10\/1125-Dattakamo-1.jpg 500w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2015\/10\/1125-Dattakamo-1-150x150.jpg 150w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2015\/10\/1125-Dattakamo-1-300x300.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2015\/10\/1125-Dattakamo-1-160x160.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2015\/10\/1125-Dattakamo-1-245x245.jpg 245w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2015\/10\/1125-Dattakamo-1-340x340.jpg 340w\" sizes=\"auto, (max-width: 350px) 100vw, 350px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><strong><span style=\"color: #333399;\">SwatSh<\/span>:\u00a0<span style=\"color: #800000;\"> 7\/10<\/span><\/strong><\/p>\n<p>Jouez-vous de temps en temps avec vos enfants dans la bagnole lors de vos longs trajets vacanciers\u00a0?\u00a0 Si oui, je vous conseille bien entendu <a href=\"http:\/\/www.vindjeu.eu\/2015\/08\/09\/sur-la-route-50-jeux-pour-les-petits-voyageurs\/\" target=\"_blank\">Sur la Route<\/a>, mais aussi le simple jeu de devinette o\u00f9 l\u2019on ne peut r\u00e9pondre que par oui ou par non et o\u00f9 les autres doivent deviner ce que vous avez en t\u00eate.<\/p>\n<p>The Mystery of Dattakamo est bas\u00e9 sur ce simple jeu en ajoutant un aspect tactile assez sympathique.\u00a0 Le jeu est fourni avec un sac contenant 12 pi\u00e8ces en fa\u00efence et lorsqu\u2019on doit faire deviner un mot, on plonge sa main dans le sac\u00a0\ud83d\ude09 et on s\u2019inspire d\u2019une des pi\u00e8ces (juste par le touch\u00e9) pour penser \u00e0 un mot.\u00a0 Les autres joueurs ont 3 tours de table pour deviner ce mot gr\u00e2ce \u00e0 leurs questions, \u00e0 la vision de la pi\u00e8ce en question et \u00e0 l\u2019obtention de certains indices donn\u00e9s \u00e0 chaque tour.<\/p>\n<p>Chaque jeu contient 12 pi\u00e8ces en fa\u00efence et ce qui est comique c&rsquo;est que c&rsquo;est pi\u00e8ces sont mis au hasard dans chaque boite ce qui fait que chaque jeu est diff\u00e9rent.\u00a0 Attention \u00e0 ceux qui souffrent de collectionnite aig\u00fce \ud83d\ude09<\/p>\n<p>The mystery of Dattakamo n\u2019est pas plus compliqu\u00e9 que \u00e7a. \u00a0Il est dommage qu\u2019il n\u2019y ait que 12 pi\u00e8ces en fa\u00efence dans la boite r\u00e9duisant par l\u00e0 m\u00eame la dur\u00e9e de vie du jeu.\u00a0 De plus, le jeu manque l\u00e9g\u00e8rement de tension et on est plut\u00f4t dans un jeu calme et pos\u00e9 que dans un jeu d\u2019excit\u00e9s \u00e0 la Time\u2019s up\u00a0\ud83d\ude42\u00a0 L\u2019ajout de ces pi\u00e8ces de fa\u00efence est bien trouv\u00e9 car elles donnent une dimension nouvelle au jeu et une certaine inventivit\u00e9 nouvelle et int\u00e9ressante.\u00a0 On peut \u00eatre \u00e9tonn\u00e9 de l\u2019esprit cr\u00e9atif de ses enfants en jouant \u00e0 Dattakamo\u00a0!<\/p>\n<p style=\"text-align: center;\">_______________________________________________________<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2015\/10\/1125-Dattakamo-2-e1444078164131.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-11800\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2015\/10\/1125-Dattakamo-2-e1444078164131-768x1024.jpg\" alt=\"1125 Dattakamo 2\" width=\"720\" height=\"960\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2015\/10\/1125-Dattakamo-2-e1444078164131-768x1024.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2015\/10\/1125-Dattakamo-2-e1444078164131-225x300.jpg 225w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2015\/10\/1125-Dattakamo-2-e1444078164131-120x160.jpg 120w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2015\/10\/1125-Dattakamo-2-e1444078164131-183x245.jpg 183w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2015\/10\/1125-Dattakamo-2-e1444078164131-255x340.jpg 255w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p> Jouez-vous de temps en temps avec vos enfants dans la bagnole lors de vos longs trajets vacanciers\u00a0?\u00a0 Si oui, je vous conseille bien entendu Sur la Route, mais aussi le simple jeu de devinette o\u00f9 l\u2019on ne peut r\u00e9pondre que par oui ou par non et o\u00f9&#46;&#46;&#46;<\/p>\n","protected":false},"author":3,"featured_media":11801,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[5],"tags":[7],"class_list":["post-11799","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-famille","tag-swatsh","annee-996","auteurs-takashi-hamada","editeurs-japon-brand"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/11799","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/comments?post=11799"}],"version-history":[{"count":0,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/11799\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media\/11801"}],"wp:attachment":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media?parent=11799"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/categories?post=11799"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/tags?post=11799"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}