{"id":120,"date":"2009-11-05T12:00:00","date_gmt":"2009-11-05T11:00:00","guid":{"rendered":"http:\/\/www.vindjeu.eu\/2009\/11\/05\/arcana\/"},"modified":"2010-03-17T21:24:14","modified_gmt":"2010-03-17T20:24:14","slug":"arcana","status":"publish","type":"post","link":"https:\/\/www.vindjeu.eu\/prd\/2009\/11\/05\/arcana\/","title":{"rendered":"Arcana"},"content":{"rendered":"<p><strong><em><span style=\"color: #663366;\">2009 &#8211; 2 \u00e0 4 joueurs &#8211; Moyen<\/span><\/em><\/strong><br \/>\n<a href=\"http:\/\/2.bp.blogspot.com\/_ea2yja0GmY8\/SvKyfWWoGZI\/AAAAAAAAAig\/5-fnpuXQIDw\/s1600-h\/109+Arcana+1.JPG\"><img decoding=\"async\" id=\"BLOGGER_PHOTO_ID_5400575154816817554\" style=\"margin: 0px 10px 10px 0px; width: 136px; float: left; height: 250px;\" src=\"http:\/\/2.bp.blogspot.com\/_ea2yja0GmY8\/SvKyfWWoGZI\/AAAAAAAAAig\/5-fnpuXQIDw\/s400\/109+Arcana+1.JPG\" border=\"0\" alt=\"\" \/><\/a><\/p>\n<p><span style=\"color: #9999ff;\"><strong><span id=\"SPELLING_ERROR_0\" class=\"blsp-spelling-error\">Philrey<\/span>212<\/strong><\/span>:<span style=\"color: #ff6666;\"><strong> 6\/10<\/strong><\/span><br \/>\nJe reste un peu \u00ab\u00a0entre deux\u00a0\u00bb \u00e0 propos d&rsquo;Arcana. SwatSh m&rsquo;avait lou\u00e9 ce jeu car il se basait sur Dominion. Apr\u00e8s la partie, c&rsquo;est paas si \u00e9vident.<br \/>\nPremi\u00e8rement, il y a 3 zones de jeu sur la table: une pour chaque joueur + une \u00ab\u00a0neutre\u00a0\u00bb. A chaque manche, nous prenons 4 cartes de notre pioche et les jouons une \u00e0 une chacun \u00e0 son tour. Si on joue une carte dans notre zone, on la met face cach\u00e9e, dans les deux autres zones, face visible.<br \/>\nLes zones des deux joueurs poss\u00e8dent 2 tas de cartes, la zone neutre, une seule.<br \/>\nCelui qui est majoritaire pour une carte \u00e0 la fin de la manche remporte la carte et l&rsquo;ajoute \u00e0 sa pioche.<br \/>\nPerso, je pense que l&rsquo;id\u00e9e est excellente. Surtout que chaque carte demande un \u00ab\u00a0type\u00a0\u00bb de majorit\u00e9 (politique, militaire, etc) parmi 4 valeurs (ou serait-ce 5? \ud83d\ude09<br \/>\nUne carte de votre main peut donc \u00eatre faible militairement mais puissante politiquement. Ou peut-\u00eatre moyenne dans les deux.<br \/>\nMais, contrairement \u00e0 Dominion, une partie est fort longue et &#8230; lente. C&rsquo;est un peu logique puisqu&rsquo;il faut r\u00e9fl\u00e9chir un peu plus: l&rsquo;interactivit\u00e9 entre les joueurs est nettement sup\u00e9rieure qu&rsquo;\u00e0 Dominion!<br \/>\nVoil\u00e0, j&rsquo;\u00e9tais d\u00e9\u00e7u apr\u00e8s une partie mais \u00e0 t\u00eate repos\u00e9e, et bien je me dis qu&rsquo;il n&rsquo;est pas si mal comme jeu! En plus, format de poche, facile \u00e0 emporter (pas comme Dominion \ud83d\ude09<\/p>\n<p><strong><span style=\"color: #9999ff;\"><span id=\"SPELLING_ERROR_1\" class=\"blsp-spelling-error\">SwatSh<\/span><\/span><\/strong>:<span style=\"color: #ff6666;\"><strong> 5 \/10<\/strong><\/span><br \/>\n<span id=\"SPELLING_ERROR_2\" class=\"blsp-spelling-error\">Arcana<\/span> se base sur le principe de Dominion: peu \u00e0 peu on construit son <span id=\"SPELLING_ERROR_3\" class=\"blsp-spelling-error\">deck<\/span> en acqu\u00e9rant les cartes <span id=\"SPELLING_ERROR_4\" class=\"blsp-spelling-corrected\">disponibles<\/span> sur la table.<\/p>\n<p>Un des grands principes <span id=\"SPELLING_ERROR_5\" class=\"blsp-spelling-error\">innovants<\/span> par rapport \u00e0 Dominion est qu&rsquo;on se dispute avec les autres joueurs les cartes \u00e0 prendre.  Chaque carte n&rsquo;est <span id=\"SPELLING_ERROR_6\" class=\"blsp-spelling-corrected\">disponible<\/span> qu&rsquo;en un seul exemplaire et si elle nous int\u00e9resse, on place \u00e0 c\u00f4t\u00e9 certaines de nos cartes en main en essayant d&rsquo;obtenir la majorit\u00e9 sur la <span id=\"SPELLING_ERROR_7\" class=\"blsp-spelling-corrected\">caract\u00e9ristique<\/span> pr\u00e9dominante (<span id=\"SPELLING_ERROR_8\" class=\"blsp-spelling-error\">l&rsquo;Arcane<\/span>!) de la carte convoit\u00e9e parmi les 4 <span id=\"SPELLING_ERROR_9\" class=\"blsp-spelling-corrected\">caract\u00e9ristiques<\/span> composant chaque carte (valeur politique, militaire, or, et en influence).  De plus, chaque carte poss\u00e8de un certain nombre de points de victoire&#8230;<\/p>\n<p>Il s&rsquo;agit donc plus d&rsquo;un combat de majorit\u00e9 qu&rsquo;autre chose, surtout que notre <span id=\"SPELLING_ERROR_10\" class=\"blsp-spelling-error\">deck<\/span> personnel ne tourne pas souvent (j&rsquo;ai d\u00fb, sur la partie, le m\u00e9langer 3 fois!).  Autrement dit, m\u00eame s&rsquo;il est bas\u00e9 sur le principe \u00ab\u00a0Dominion\u00a0\u00bb, l&rsquo;aspect construction du <span id=\"SPELLING_ERROR_11\" class=\"blsp-spelling-error\">deck<\/span> est assez marginal par rapport au gain des majorit\u00e9 sur les cartes.<\/p>\n<p>De plus, j&rsquo;ai un doute sur l&rsquo;utilit\u00e9 de certaines cartes.  Les objets d&rsquo;abord qui ne nous ont quasi jamais aid\u00e9s.  Les immeubles ensuite qui sont plus int\u00e9ressants pour leur points de victoire que pour leur effet souvent ridicule.<\/p>\n<p><span id=\"SPELLING_ERROR_12\" class=\"blsp-spelling-error\">Arcana<\/span> est donc un jeu de majorit\u00e9 moyen bas\u00e9 sur le principe de Dominion sans avoir pu profiter de ses grands avantages.<\/p>\n<p><a href=\"http:\/\/2.bp.blogspot.com\/_ea2yja0GmY8\/SvKyQfi0NnI\/AAAAAAAAAiY\/g9luHfdZcyM\/s1600-h\/109+Arcana+2.JPG\"><img decoding=\"async\" id=\"BLOGGER_PHOTO_ID_5400574899585824370\" style=\"margin: 0px auto 10px; text-align: center; width: 400px; display: block; height: 300px;\" src=\"http:\/\/2.bp.blogspot.com\/_ea2yja0GmY8\/SvKyQfi0NnI\/AAAAAAAAAiY\/g9luHfdZcyM\/s400\/109+Arcana+2.JPG\" border=\"0\" alt=\"\" \/><\/a> Notez que les illustrations sont tr\u00e8s jolies.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>2009 &#8211; 2 \u00e0 4 joueurs &#038;# Je reste un peu \u00ab\u00a0entre deux\u00a0\u00bb \u00e0 propos d&rsquo;Arcana. SwatSh m&rsquo;avait lou\u00e9 ce jeu car il se basait sur Dominion. Apr\u00e8s la partie, c&rsquo;est paas si \u00e9vident. Premi\u00e8rement, il y a 3 zones de jeu sur la table: une pour&#46;&#46;&#46;<\/p>\n","protected":false},"author":2,"featured_media":9014,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[4848],"tags":[6,7],"class_list":["post-120","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-initie","tag-philrey212","tag-swatsh"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/120","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/comments?post=120"}],"version-history":[{"count":0,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/120\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media\/9014"}],"wp:attachment":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media?parent=120"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/categories?post=120"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/tags?post=120"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}