{"id":12178,"date":"2015-11-29T12:11:18","date_gmt":"2015-11-29T11:11:18","guid":{"rendered":"http:\/\/www.vindjeu.eu\/?p=12178"},"modified":"2015-11-29T12:11:19","modified_gmt":"2015-11-29T11:11:19","slug":"guns-steel","status":"publish","type":"post","link":"https:\/\/www.vindjeu.eu\/prd\/2015\/11\/29\/guns-steel\/","title":{"rendered":"Guns &#038; Steel"},"content":{"rendered":"<p><a href=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2015\/11\/1158-Guns-and-Steel-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-12180\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2015\/11\/1158-Guns-and-Steel-1.jpg\" alt=\"1158 Guns and Steel 1\" width=\"410\" height=\"281\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2015\/11\/1158-Guns-and-Steel-1.jpg 500w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2015\/11\/1158-Guns-and-Steel-1-300x205.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2015\/11\/1158-Guns-and-Steel-1-160x109.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2015\/11\/1158-Guns-and-Steel-1-357x245.jpg 357w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2015\/11\/1158-Guns-and-Steel-1-495x340.jpg 495w\" sizes=\"auto, (max-width: 410px) 100vw, 410px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><strong><span style=\"color: #333399;\">SwatSh<\/span>:\u00a0<span style=\"color: #800000;\"> 7\/10<\/span><\/strong><\/p>\n<p>Guns &amp; Steel est un petit jeu de cartes de civilisation Ta\u00efwannais assez bien imagin\u00e9.<\/p>\n<p>Au d\u00e9but du jeu, on dispose toutes les 25 cartes civilisation sur la table comme un arbre g\u00e9n\u00e9alogique.\u00a0 Cette disposition influence le co\u00fbt d\u2019acquisition de chaque carte car une carte qui a d\u2019autres cartes sous elle co\u00fbte plus cher qu\u2019une carte qui n\u2019en a pas ou plus.<\/p>\n<p>A son tour, on va jouer 2 de nos cartes pour soit\u00a0:<br \/>\n-Acqu\u00e9rir de nouvelles cartes et am\u00e9liorer son deck comme tout bon jeu de deckbuilding<br \/>\n-Attaquer ses adversaires<br \/>\n-Acqu\u00e9rir une merveille (=PVs) en fournissant l\u2019objectif requis<\/p>\n<p>Tout comme dans <a href=\"http:\/\/www.vindjeu.eu\/2014\/01\/13\/concordia\/\" target=\"_blank\">Concordia <\/a>(d\u00e9cid\u00e9ment, cet excellent jeu (Votre <a href=\"http:\/\/www.vindjeu.eu\/2014\/11\/12\/vin-djeu-dlannee-2014\/\" target=\"_blank\">Vin d\u2019jeu d\u2019l\u2019ann\u00e9e 2014<\/a>) en aura inspir\u00e9 plus d\u2019un), la particularit\u00e9 de Guns &amp; Steel, est qu\u2019on a toutes nos cartes en main et qu\u2019on choisit quelles cartes de notre main on joue.\u00a0 On n\u2019est donc pas soumis au hasard de la pioche.\u00a0 Le tour o\u00f9 on n\u2019a plus de cartes en main, on r\u00e9cup\u00e8re toutes ses cartes jou\u00e9es et acquises.\u00a0 Chouette m\u00e9canique apportant pas mal de contr\u00f4le.\u00a0 Tout est d\u2019ailleurs sous contr\u00f4le dans Guns &amp; Steel.\u00a0 Non seulement le choix des cartes que vous jouez mais \u00e9galement le choix des cartes \u00e0 acqu\u00e9rir puisque, comme dans <a href=\"http:\/\/www.vindjeu.eu\/2009\/01\/24\/dominion\/\" target=\"_blank\">Dominion<\/a>, elles sont toutes \u00e0 votre disposition d\u00e8s le d\u00e9but de la partie.<a href=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2015\/11\/1158-Guns-and-Steel-2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-full wp-image-12181\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2015\/11\/1158-Guns-and-Steel-2.jpg\" alt=\"1158 Guns and Steel 2\" width=\"500\" height=\"332\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2015\/11\/1158-Guns-and-Steel-2.jpg 500w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2015\/11\/1158-Guns-and-Steel-2-300x199.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2015\/11\/1158-Guns-and-Steel-2-160x106.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2015\/11\/1158-Guns-and-Steel-2-368x245.jpg 368w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a><\/p>\n<p>Malheureusement, la rejouabilit\u00e9 de Guns &amp; Steel est fort limit\u00e9e puisque le nombre de cartes civilisation est tr\u00e8s limit\u00e9 (25) et on dispose toujours des m\u00eames 25 cartes \u00e0 chaque partie.\u00a0 Et \u00e7a c\u2019est vraiment dommage car le jeu est bon.\u00a0 Mais voir toujours les m\u00eames cartes implique une strat\u00e9gie toujours la m\u00eame.\u00a0 De plus, les r\u00e8gles ne sont pas toujours tr\u00e8s claires et sont sujettes \u00e0 interpr\u00e9tation.<\/p>\n<p>Comme dans tout jeu de civilisation, vous avez 2 grandes voies de d\u00e9veloppement\u00a0: les ressources ou la guerre.\u00a0 Et comme bien souvent, la guerre prend le dessus et sans arm\u00e9e forte, vous ne pourrez pr\u00e9tendre \u00e0 la victoire.\u00a0 Ca limite forc\u00e9ment vos choix puisque vous allez devoir vous investir dans la guerre avant tout\u00a0!<\/p>\n<p>Un autre aspect sympa de Guns &amp; Steel est la gestion double face de ses cartes.\u00a0 D\u2019un c\u00f4t\u00e9 ce sont des cartes actions, de l\u2019autre ce sont des ressources.\u00a0 A certains tours vous allez vouloir utiliser le pouvoir d\u2019une carte tandis qu\u2019\u00e0 d\u2019autres vous pr\u00e9f\u00e9rerez profiter de la ressource qu\u2019elle produit.<\/p>\n<p>Guns &amp; Steel fourmille de bonnes id\u00e9es, est tr\u00e8s contr\u00f4lable et est tr\u00e8s agr\u00e9able \u00e0 jouer quelques fois.\u00a0 On attend avec impatience des extensions pour pouvoir mieux varier les parties et diminuer l\u00e9g\u00e8rement la force du pouvoir militaire.<\/p>\n<p style=\"text-align: center;\">______________________________________________<\/p>\n<p><a href=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2015\/11\/1158-Guns-and-Steel-4.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-12179\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2015\/11\/1158-Guns-and-Steel-4.jpg\" alt=\"1158 Guns and Steel 4\" width=\"1024\" height=\"768\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2015\/11\/1158-Guns-and-Steel-4.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2015\/11\/1158-Guns-and-Steel-4-300x225.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2015\/11\/1158-Guns-and-Steel-4-160x120.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2015\/11\/1158-Guns-and-Steel-4-326x245.jpg 326w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2015\/11\/1158-Guns-and-Steel-4-453x340.jpg 453w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p> Guns &amp; Steel est un petit jeu de cartes de civilisation Ta\u00efwannais assez bien imagin\u00e9. Au d\u00e9but du jeu, on dispose toutes les 25 cartes civilisation sur la table comme un arbre g\u00e9n\u00e9alogique.\u00a0 Cette disposition influence le co\u00fbt d\u2019acquisition de chaque carte car une carte qui a&#46;&#46;&#46;<\/p>\n","protected":false},"author":3,"featured_media":12180,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[4848],"tags":[7],"class_list":["post-12178","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-initie","tag-swatsh","annee-996","auteurs-jesse-li","editeurs-moaideas-game-design"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/12178","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/comments?post=12178"}],"version-history":[{"count":0,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/12178\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media\/12180"}],"wp:attachment":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media?parent=12178"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/categories?post=12178"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/tags?post=12178"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}