{"id":12343,"date":"2016-01-02T14:55:26","date_gmt":"2016-01-02T13:55:26","guid":{"rendered":"http:\/\/www.vindjeu.eu\/?p=12343"},"modified":"2016-04-13T23:07:01","modified_gmt":"2016-04-13T21:07:01","slug":"colt-express-chevaux-diligence","status":"publish","type":"post","link":"https:\/\/www.vindjeu.eu\/prd\/2016\/01\/02\/colt-express-chevaux-diligence\/","title":{"rendered":"Colt Express: Chevaux &#038; Diligence"},"content":{"rendered":"<p><a href=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2015\/11\/1180-Colt-Express-ext-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-12345\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2015\/11\/1180-Colt-Express-ext-1.jpg\" alt=\"1180 Colt Express ext 1\" width=\"250\" height=\"438\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2015\/11\/1180-Colt-Express-ext-1.jpg 700w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2015\/11\/1180-Colt-Express-ext-1-171x300.jpg 171w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2015\/11\/1180-Colt-Express-ext-1-585x1024.jpg 585w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2015\/11\/1180-Colt-Express-ext-1-91x160.jpg 91w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2015\/11\/1180-Colt-Express-ext-1-140x245.jpg 140w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2015\/11\/1180-Colt-Express-ext-1-194x340.jpg 194w\" sizes=\"auto, (max-width: 250px) 100vw, 250px\" \/><\/a><\/p>\n<p><strong><span style=\"color: #333399;\">SwatSh<\/span>:\u00a0 <span style=\"color: #800000;\">7,5 \/10<\/span><\/strong><\/p>\n<p>Outre des nouvelles cartes de tour, Chevaux et Diligence, la nouvelle extension de <a href=\"http:\/\/www.vindjeu.eu\/2014\/10\/14\/colt-express\/\" target=\"_blank\">l\u2019excellent Spiel Des Jahres 2015<\/a>, apporte principalement 4 nouveaut\u00e9s\u00a0qui se jouent ensemble (on ne parle pas ici de 4 modules qui peuvent se jouer s\u00e9par\u00e9ment):<br \/>\n<strong>1) La diligence<br \/>\n<\/strong>C\u2019est le \u00ab\u00a0module\u00a0\u00bb qui m\u2019a le plus enthousiasm\u00e9.\u00a0 Maintenant, outre le pactole se trouvant dans la locomotive sous le sh\u00e9rif, les joueurs vont pouvoir se battre pour un second pactole\u00a0: celui de la diligence.\u00a0 Cette valise est \u00e9galement gard\u00e9e et il va falloir jouer des poings contre son gardien pour pouvoir la prendre\u00a0\ud83d\ude42<\/p>\n<p>C\u2019est vraiment tr\u00e8s sympa comme ajout car \u00e7a permet des strat\u00e9gies vari\u00e9es.\u00a0 Alors que dans le jeu de base, il y avait une certaine course \u00e0 pouvoir s\u2019emparer en premier de la valise du sh\u00e9rif, avec cette extension, certains joueurs vont plut\u00f4t attaquer la diligence variant, par-l\u00e0, les possibilit\u00e9s et permettant \u00e0 un joueur un peu \u00e0 la traine pour la valisette du sh\u00e9rif de se rattraper en attaquant la diligence, et vice-versa.\u00a0 Bien vu\u00a0!<\/p>\n<p><strong>2)Les chevaux<br \/>\n<\/strong>Pour pouvoir attaquer la diligence, il va falloir sauter sur vos chevaux, logique\u00a0!\u00a0 Les chevaux sont jolis et bien dans le th\u00e8me et c\u2019est pour \u00e7a qu\u2019on les aime.\u00a0 Sinon, ils n\u2019apportent pas grand-chose car permettent juste de se d\u00e9placer plus vite entre les wagons et d\u2019attaquer la diligence.\u00a0 J\u2019aurais bien vu une attaque au lasso tient\u00a0\ud83d\ude00<br \/>\nIl est dommage que les figurines de bandit se d\u00e9posent simplement sur les chevaux.\u00a0 Ca aurait \u00e9t\u00e9 plus chouette s\u2019ils pouvaient les enfourcher (comme pour la nouvelle extension de l\u2019excellent <a href=\"http:\/\/www.vindjeu.eu\/2015\/09\/28\/flickem-up\/\" target=\"_blank\">Flick\u2019 em up\u00a0<\/a>!).<\/p>\n<p><strong>3) les bouteilles de Whisky<br \/>\n<\/strong>Les bouteilles de Whisky se placent comme les bourses et rubis dans les wagons et se r\u00e9cup\u00e8rent de la m\u00eame mani\u00e8re.\u00a0 Une bouteille de Whisky permet au joueur de piocher 3 cartes et d\u2019en jouer une en une seule action, et ce, 2 fois par bouteille de Whisky.<br \/>\nC\u2019est pas mal mais c\u2019est triste de sacrifier une action qui permettrait de gagner de l\u2019argent pour \u00e7a.\u00a0 Ca n\u2019augmente donc pas les choix mais permet une compensation si on se retrouve d\u00e9muni lorsqu\u2019on d\u00e9cide de ramasser un butin.<a href=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2015\/11\/1180-Colt-Express-ext-4.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-12346\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2015\/11\/1180-Colt-Express-ext-4-1024x768.jpg\" alt=\"1180 Colt Express ext 4\" width=\"400\" height=\"300\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2015\/11\/1180-Colt-Express-ext-4-1024x768.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2015\/11\/1180-Colt-Express-ext-4-300x225.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2015\/11\/1180-Colt-Express-ext-4-160x120.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2015\/11\/1180-Colt-Express-ext-4-326x245.jpg 326w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2015\/11\/1180-Colt-Express-ext-4-453x340.jpg 453w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/a><\/p>\n<p><strong>4)Les otages<br \/>\n<\/strong>L\u2019id\u00e9e des otages est bien trouv\u00e9e.\u00a0 D\u00e8s qu\u2019un bandit saute dans la diligence, il doit prendre un otages parmi les otages disponibles.<br \/>\nChaque otage apporte de l\u2019argent suppl\u00e9mentaire selon certaines conditions\u00a0:<br \/>\n-+1.000$ si on poss\u00e8de une valise<br \/>\n-+250$ par bourse qu\u2019on poss\u00e8de<br \/>\n-+500$ si on poss\u00e8de un rubis<br \/>\n-&#8230;<br \/>\nMais aussi, chaque otage prend de la place et apporte une contrainte\u00a0:<br \/>\n-Avec cet otage, on ne peut plus monter \u00e0 cheval<br \/>\n-Avec tel autre, on ne peut se d\u00e9placer que de 1 wagon maximum \u00e0 la fois<br \/>\n-Avec celui-l\u00e0, on doit toujours jouer ses cartes face visible m\u00eame dans les tunnels<br \/>\n-&#8230;<br \/>\nL\u2019id\u00e9e est sympa mais apporte des complications inutiles&#8230;<\/p>\n<p><strong><a href=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2015\/11\/1180-Colt-Express-ext-2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-12347\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2015\/11\/1180-Colt-Express-ext-2-1024x768.jpg\" alt=\"1180 Colt Express ext 2\" width=\"400\" height=\"300\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2015\/11\/1180-Colt-Express-ext-2-1024x768.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2015\/11\/1180-Colt-Express-ext-2-300x225.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2015\/11\/1180-Colt-Express-ext-2-160x120.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2015\/11\/1180-Colt-Express-ext-2-326x245.jpg 326w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2015\/11\/1180-Colt-Express-ext-2-453x340.jpg 453w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/a>Complications et incoh\u00e9rences<br \/>\n<\/strong>En effet, l\u00e0 o\u00f9 Chevaux et Diligence p\u00e8che, c\u2019est au niveau de la complexit\u00e9 accrue qu\u2019elle apporte et l\u2019incoh\u00e9rence par rapport au th\u00e8me de ses r\u00e8gles.\u00a0 Quelques exemples\u00a0:<br \/>\n-On peut atteindre la diligence avec les chevaux mais aussi en passant par le toit du train.\u00a0 Il faut croire que la diligence roule vraiment \u00e0 c\u00f4t\u00e9 du train.\u00a0 Si au moins c\u2019\u00e9tait la diligence qui attaquait le train, je pourrais comprendre mais comme ici ce sont les bandits du train qui attaquent la diligence, il doit \u00eatre sacr\u00e9ment tap\u00e9 le conducteur de la diligence pour rouler \u00e0 c\u00f4t\u00e9 du train\u00a0!!!\u00a0 On oublie d\u2019ailleurs facilement cette possibilit\u00e9 de sauter du train dans la diligence.<br \/>\n-Et cette diligence, elle roule vraiment tout \u00e0 c\u00f4t\u00e9 du train car un cowboy dans le wagon du train se trouvant \u00e0 c\u00f4t\u00e9 de la diligence peut donner un coup de poing \u00e0 quelqu\u2019un dans la diligence\u00a0!!!\u00a0 Non seulement elle roule juste \u00e0 c\u00f4t\u00e9 du train, mais en plus elle roule les portes ouvertes\u00a0!!!\u00a0\ud83d\ude00\u00a0 L\u00e0 aussi les joueurs ont tendance \u00e0 oublier qu\u2019ils peuvent donner des coups de poings \u00e0 travers les vitres de la diligence et du train\u00a0!<br \/>\n-L\u2019autre r\u00e8gle qu\u2019on oublie facilement est qu\u2019on prend un otage la premi\u00e8re fois qu\u2019on met les pieds dans la diligence.\u00a0 Rien ne le rappelle (aucun pictogramme sur la diligence) et \u00e7a ne colle pas super au th\u00e8me.\u00a0 Si au moins les otages avaient \u00e9t\u00e9 repr\u00e9sent\u00e9s par des pions, on aurait pu facilement se rappeler qu\u2019on devait prendre un otage avec soit, en plus, le pion otage aurait pu alors accompagner le cowboy.\u00a0 Mais l\u00e0, rien\u00a0!\u00a0 En plus, vous imaginez-vous sautant sur la diligence, prenant un otage, montant sur le toit de la diligence puis assommant le gardien pour lui piquer sa valise, puis sautant sur votre <a href=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2015\/11\/1180-Colt-Express-ext-3.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-12348\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2015\/11\/1180-Colt-Express-ext-3-1024x768.jpg\" alt=\"1180 Colt Express ext 3\" width=\"400\" height=\"300\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2015\/11\/1180-Colt-Express-ext-3-1024x768.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2015\/11\/1180-Colt-Express-ext-3-300x225.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2015\/11\/1180-Colt-Express-ext-3-160x120.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2015\/11\/1180-Colt-Express-ext-3-326x245.jpg 326w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2015\/11\/1180-Colt-Express-ext-3-453x340.jpg 453w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/a>cheval, tout \u00e7a avec votre otage.\u00a0 Et ce n\u2019est pas fini, une fois sur votre cheval avec votre otage, il faudra sauter dans l\u2019train&#8230;\u00a0 On est vraiment des super cowboys\u00a0\ud83d\ude00\u00a0 C\u2019est pas tr\u00e8s th\u00e9matique et \u00e7a embrouille un peu les r\u00e8gles.<br \/>\n-La derni\u00e8re r\u00e8gle loufoque est que pour prendre l\u2019argent de la diligence, il faut frapper le gardien.\u00a0 Mais, le comble c\u2019est que vous le frappez tellement fort qu\u2019il atterrit dans le train\u00a0!!!<\/p>\n<p>Toutes ces r\u00e8gles peu th\u00e9matiques non seulement apportent une certaine confusion mais complexifient \u00e9galement inutilement le jeu le rendant moins \u00ab\u00a0familial\u00a0\u00bb que le jeu de base.\u00a0 <a href=\"http:\/\/www.vindjeu.eu\/2014\/10\/14\/colt-express\/\" target=\"_blank\">Le jeu de base <\/a>est indiqu\u00e9 pour 10 ans minimum, j\u2019augmenterais cet \u00e2ge minimum \u00e0 12 ans avec l\u2019extension.\u00a0 Mais gardons l\u2019\u00e9glise au milieu du village, enfin, plut\u00f4t, gardons le train sur ses rails\u00a0\ud83d\ude00\u00a0: Chevaux et Diligence apporte principalement 2 chouettes \u00e9l\u00e9ments \u00e0 l\u2019excellent<a href=\"http:\/\/www.vindjeu.eu\/2014\/10\/14\/colt-express\/\" target=\"_blank\"> Colt Express\u00a0<\/a>: les chevaux super th\u00e9matiques et la diligence qui va apporter une belle vari\u00e9t\u00e9 au jeu en multipliant les choix et en offrant d\u2019autres strat\u00e9gies aux joueurs qui pourront s\u2019orienter vers autre chose que le pactole du Sh\u00e9rif.<\/p>\n<p style=\"text-align: center;\">___________________________________________________<\/p>\n<p><a href=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2015\/11\/1180-Colt-Express-ext-5.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-12344\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2015\/11\/1180-Colt-Express-ext-5.jpg\" alt=\"1180 Colt Express ext 5\" width=\"1200\" height=\"900\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2015\/11\/1180-Colt-Express-ext-5.jpg 4000w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2015\/11\/1180-Colt-Express-ext-5-300x225.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2015\/11\/1180-Colt-Express-ext-5-1024x768.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2015\/11\/1180-Colt-Express-ext-5-160x120.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2015\/11\/1180-Colt-Express-ext-5-326x245.jpg 326w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2015\/11\/1180-Colt-Express-ext-5-453x340.jpg 453w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p> Outre des nouvelles cartes de tour, Chevaux et Diligence, la nouvelle extension de l\u2019excellent Spiel Des Jahres 2015, apporte principalement 4 nouveaut\u00e9s\u00a0qui se jouent ensemble (on ne parle pas ici de 4 modules qui peuvent se jouer s\u00e9par\u00e9ment): 1) La diligence C\u2019est le \u00ab\u00a0module\u00a0\u00bb qui m\u2019a le&#46;&#46;&#46;<\/p>\n","protected":false},"author":3,"featured_media":12345,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[4848],"tags":[7],"class_list":["post-12343","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-initie","tag-swatsh","annee-996","auteurs-christophe-raimbault","editeurs-ludonaute","illustrateurs-jordi-valbuena","distributeurs-asmodee"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/12343","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/comments?post=12343"}],"version-history":[{"count":0,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/12343\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media\/12345"}],"wp:attachment":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media?parent=12343"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/categories?post=12343"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/tags?post=12343"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}