{"id":12831,"date":"2016-03-09T20:43:14","date_gmt":"2016-03-09T19:43:14","guid":{"rendered":"http:\/\/www.vindjeu.eu\/?p=12831"},"modified":"2021-10-03T11:47:54","modified_gmt":"2021-10-03T09:47:54","slug":"grand-austria-hotel","status":"publish","type":"post","link":"https:\/\/www.vindjeu.eu\/prd\/2016\/03\/09\/grand-austria-hotel\/","title":{"rendered":"Grand Austria Hotel"},"content":{"rendered":"<p><a href=\"http:\/\/www.vindjeu.eu\/2016\/03\/09\/grand-austria-hotel\/1217-grand-austria-hotel-1\/\" rel=\"attachment wp-att-12834\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-12834\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2016\/01\/1217-Grand-Austria-Hotel-1.jpg\" alt=\"1217 Grand Austria Hotel 1\" width=\"357\" height=\"500\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2016\/01\/1217-Grand-Austria-Hotel-1.jpg 357w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2016\/01\/1217-Grand-Austria-Hotel-1-214x300.jpg 214w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2016\/01\/1217-Grand-Austria-Hotel-1-114x160.jpg 114w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2016\/01\/1217-Grand-Austria-Hotel-1-174x245.jpg 174w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2016\/01\/1217-Grand-Austria-Hotel-1-242x340.jpg 242w\" sizes=\"auto, (max-width: 357px) 100vw, 357px\" \/><\/a><\/p>\n<p>\u00a0<\/p>\n<p><strong><span style=\"color: #333399;\">SwatSh<\/span><\/strong>:\u00a0<strong><span style=\"color: #800000;\"> 10\/10<\/span><\/strong><\/p>\n<p>On peut dire qu\u2019avec Grand Austria Hotel &amp; <a href=\"http:\/\/www.vindjeu.eu\/2016\/02\/23\/isle-of-skye\/\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #ff00ff;\">Isle of Skye<\/span><\/a>, <a href=\"http:\/\/www.vindjeu.eu\/editeurs\/mayfair-games\/\" target=\"_blank\" rel=\"noopener\">Mayfair games <\/a>(et <a href=\"http:\/\/www.vindjeu.eu\/editeurs\/lookout-games\/\" target=\"_blank\" rel=\"noopener\">Lookout games <\/a>par la m\u00eame occasion\u00a0\ud83d\ude09 ) ont r\u00e9alis\u00e9 2 excellents jeux pour le dernier salon d\u2019Essen.<\/p>\n<p>Il faut dire que les 2 auteurs de Grand Austria Hotel sont loin d\u2019\u00eatre des novices.\u00a0 Ils ont en effet d\u00e9j\u00e0 r\u00e9alis\u00e9, s\u00e9par\u00e9ment, d\u2019excellents jeux tels que <a href=\"http:\/\/www.vindjeu.eu\/2010\/01\/27\/egizia\/\" target=\"_blank\" rel=\"noopener\">Egizia<\/a>, <a href=\"http:\/\/www.vindjeu.eu\/2009\/10\/18\/leonardo-da-vinci\/\" target=\"_blank\" rel=\"noopener\">Leonardo Da Vinci<\/a>, <a href=\"http:\/\/www.vindjeu.eu\/2015\/11\/30\/council-of-four\/\" target=\"_blank\" rel=\"noopener\">Council of Four<\/a>, <a href=\"http:\/\/www.vindjeu.eu\/2013\/03\/11\/tzolkin-the-mayan-calendar\/\" target=\"_blank\" rel=\"noopener\">Tzolkin <\/a>(notre <a href=\"http:\/\/www.vindjeu.eu\/vin-djeu-dlannee\/2013-2\/\" target=\"_blank\" rel=\"noopener\">Vin d\u2019jeu d\u2019l\u2019ann\u00e9e 2013<\/a>) et <a href=\"http:\/\/www.vindjeu.eu\/2015\/07\/29\/les-voyages-de-marco-polo\/\" target=\"_blank\" rel=\"noopener\">Les Voyages de Marco Polo<\/a>.<\/p>\n<p>Quand on ouvre le jeu, la premi\u00e8re chose qui frappe est la beaut\u00e9 de ses illustrations.\u00a0 On a l\u2019impression de bien conna\u00eetre ce type d\u2019illustrations et d\u2019\u00eatre un peu chez soi&#8230;\u00a0 Et c\u2019est normal car Franz Klemens, l\u2019illustrateur, a d\u00e9j\u00e0 une solide exp\u00e9rience avec des jeux qu\u2019on appr\u00e9cie beaucoup chez Vin d\u2019jeu et qui ont \u00e9t\u00e9 publi\u00e9s principalement par <a href=\"http:\/\/www.vindjeu.eu\/editeurs\/lookout-games\/\" target=\"_blank\" rel=\"noopener\">Lookout Games\u00a0<\/a>: <a href=\"http:\/\/www.vindjeu.eu\/2011\/05\/08\/agricola\/\" target=\"_blank\" rel=\"noopener\">Agricola<\/a>, <a href=\"http:\/\/www.vindjeu.eu\/2011\/01\/24\/le-havre\/\" target=\"_blank\" rel=\"noopener\">Le Havre<\/a>, <a href=\"http:\/\/www.vindjeu.eu\/2011\/03\/21\/aux-portes-de-loyang\/\" target=\"_blank\" rel=\"noopener\">Aux Portes de Loyang<\/a>, <a href=\"http:\/\/www.vindjeu.eu\/2010\/12\/01\/luna\/\" target=\"_blank\" rel=\"noopener\">Luna<\/a>, <a href=\"http:\/\/www.vindjeu.eu\/2011\/12\/19\/welcome-to-walnut-grove\/\" target=\"_blank\" rel=\"noopener\">Walnut Grove<\/a>, <a href=\"http:\/\/www.vindjeu.eu\/2012\/06\/12\/ora-et-labora-aide-de-jeu\/\" target=\"_blank\" rel=\"noopener\">Ora et Labora<\/a>,&#8230;<\/p>\n<p><strong>La phase de draft<\/strong><br \/>A l\u2019image de <a href=\"http:\/\/www.vindjeu.eu\/2012\/11\/06\/seasons\/\" target=\"_blank\" rel=\"noopener\">Seasons <\/a>et d\u2019<a href=\"http:\/\/www.vindjeu.eu\/2011\/05\/08\/agricola\/\" target=\"_blank\" rel=\"noopener\">Agricola<\/a>, Grand Austria Hotel commence par une phase de draft durant laquelle les joueurs vont acqu\u00e9rir 6 cartes qui apporteront des bonus, des comp\u00e9tences et mani\u00e8res alternatives de gagner des PVs uniques et sp\u00e9cifiques \u00e0 chaque joueur.\u00a0 Le d\u00e9part est donc asym\u00e9trique, chacun ayant ses propres comp\u00e9tences et fa\u00e7ons de scorer des points suppl\u00e9mentaires.\u00a0 Mais \u00e0 la diff\u00e9rence d\u2019autres jeux asym\u00e9triques et \u00e0 l\u2019image du d\u00e9but dans <a href=\"http:\/\/www.vindjeu.eu\/2013\/03\/11\/tzolkin-the-mayan-calendar\/\" target=\"_blank\" rel=\"noopener\">Tzolkin<\/a>, ces comp\u00e9tences sont issues des choix des joueurs.\u00a0 Miam miam\u00a0\ud83d\ude42\u00a0 A noter que ces 6 cartes ne sont pas directement actives et qu\u2019il faudra d\u00e9penser une action et des ressources pour pouvoir en b\u00e9n\u00e9ficier.\u00a0 L\u00e0 aussi il faudra faire des choix car il ne sera pas n\u00e9cessairement b\u00e9n\u00e9fique de les jouer toutes&#8230;\u00a0 Le co\u00fbt pour jouer chaque carte est diff\u00e9rent et d\u00e9pend de la puissance de son bonus ce qui permet d\u2019\u00e9quilibrer le pouvoir des diff\u00e9rentes cartes.\u00a0 Certaines nous ont n\u00e9anmoins sembl\u00e9 d\u00e9s\u00e9quilibr\u00e9es comme, par exemple, celle qui permet d\u2019acqu\u00e9rir une ressource suppl\u00e9mentaire \u00e0 chaque action de collecte de ressource et ce pour seulement 2 pi\u00e8ces&#8230; Gr\u00e2ce \u00e0 cette phase, les parties seront \u00e0 chaque fois diff\u00e9rentes et on aura vite l\u2019envie d\u2019en refaire une avec d\u2019autres cartes pouvoir.<\/p>\n<p><strong>La m\u00e9canique de base<a href=\"http:\/\/www.vindjeu.eu\/2016\/03\/09\/grand-austria-hotel\/1217-grand-austria-hotel-2\/\" rel=\"attachment wp-att-12838\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-12838\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2016\/01\/1217-Grand-Austria-Hotel-2-e1452808713999-768x1024.jpg\" alt=\"1217 Grand Austria Hotel 2\" width=\"550\" height=\"733\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2016\/01\/1217-Grand-Austria-Hotel-2-e1452808713999-768x1024.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2016\/01\/1217-Grand-Austria-Hotel-2-e1452808713999-225x300.jpg 225w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2016\/01\/1217-Grand-Austria-Hotel-2-e1452808713999-120x160.jpg 120w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2016\/01\/1217-Grand-Austria-Hotel-2-e1452808713999-183x245.jpg 183w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2016\/01\/1217-Grand-Austria-Hotel-2-e1452808713999-255x340.jpg 255w\" sizes=\"auto, (max-width: 550px) 100vw, 550px\" \/><\/a><\/strong><br \/>La m\u00e9canique de base de Grand Austria Hotel est une m\u00e9canique, inspir\u00e9e d\u2019<a href=\"http:\/\/www.vindjeu.eu\/2010\/09\/29\/yspahan-ext-ystari-box\/\" target=\"_blank\" rel=\"noopener\">Yspahan<\/a> et de <a href=\"http:\/\/www.vindjeu.eu\/2015\/07\/18\/la-granja\/\" target=\"_blank\" rel=\"noopener\">La Granja <\/a>(entre autre), de choix d\u2019action d\u00e9termin\u00e9 par un jet de d\u00e9s.\u00a0 Au d\u00e9but de chaque tour, un joueur lance les 12 d\u00e9s et les place, selon leur r\u00e9sultat, dans la case d\u2019action correspondante.\u00a0 Certaines actions ne seront pas toujours disponibles tandis que d\u2019autres contiendront beaucoup ou peu de d\u00e9s.\u00a0 Ces actions, par contre, pourront \u00eatre choisies autant de fois qu\u2019il y a de d\u00e9s dans leur case et leur puissance d\u00e9pendra du nombre de d\u00e9s pr\u00e9sents au moment o\u00f9 l\u2019action est choisie.\u00a0 Quand on choisit une action, on prend un des d\u00e9s de la case d\u2019action.<\/p>\n<p><strong>Les clients<br \/><\/strong>Avant de choisir une action, on peut prendre une des 5 cartes client qui font la file devant le resto de l\u2019h\u00f4tel pour le placer sur une de nos 3 tables.\u00a0 Tout comme dans le mythique <a href=\"http:\/\/www.vindjeu.eu\/2011\/05\/09\/through-the-ages\/\" target=\"_blank\" rel=\"noopener\">Through the Ages<\/a>, le prix pour attirer un client est de plus en plus \u00e9lev\u00e9 au plus on choisit un client \u00e9loign\u00e9 dans la file.\u00a0 Ces clients sont de diff\u00e9rentes couleurs ce qui influence le type de chambre qu\u2019ils veulent.\u00a0 Ils exigent une combinaison sp\u00e9cifique de nourriture (combinaison de cubes ressource de 4 couleurs possibles) et offrent un bonus quand on satisfait \u00e0 leur demande de nourriture, autrement dit, quand on remplit l\u2019objectif de la carte.\u00a0 D\u00e8s qu\u2019un client est rassasi\u00e9, il montre dans une chambre de la couleur qu\u2019il a demand\u00e9e et qu\u2019on aura pris le temps de lui pr\u00e9parer \u00e0 l\u2019avance. \u00a0Il va falloir bien planifier\u00a0\ud83d\ude42<\/p>\n<p><strong>Les actions<\/strong><br \/>Les actions qu\u2019on peut r\u00e9aliser gr\u00e2ce aux d\u00e9s permettent bien entendu de gagner des ressources mais aussi de jouer des cartes comp\u00e9tences acquises lors du draft d\u2019intro, de pr\u00e9parer une chambre pour un futur client ou de gagner de l\u2019argent.<\/p>\n<p>Tout comme dans <a href=\"http:\/\/www.vindjeu.eu\/2016\/02\/23\/isle-of-skye\/\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #ff00ff;\">Isle of Skye<\/span><\/a>, Grand Austria Hotel adopte la m\u00e9canique \u00e0 la mode des objectifs de partie vari\u00e9s.\u00a0 On tire 3 cartes qui vont indiquer \u00e0 tous les joueurs 3 objectifs qui permettront de gagner des points suppl\u00e9mentaires.\u00a0 Et ces objectifs proposent une course entre les joueurs puisque le premier joueur \u00e0 en atteindre un va gagner plus de points que le second ou le 3<sup>\u00e8me<\/sup>.\u00a0 Cette m\u00e9canique li\u00e9e \u00e0 celle des cartes comp\u00e9tence draft\u00e9e donne au jeu une rejouabilit\u00e9 et une envie d\u2019y revenir tr\u00e8s importantes.\u00a0 M\u00eame si l\u2019on peut ergoter sur l\u2019\u00e9quilibre des cartes et sur le hasard des lancers de d\u00e9s qui peuvent avantager un joueur ou l\u2019autre qui avait pr\u00e9vu de r\u00e9aliser telle ou telle action \u00e0 ce tour, Grand Austria Hotel est une belle r\u00e9ussite ludique tant il est tr\u00e8s plaisant \u00e0 jouer et tr\u00e8s vari\u00e9. \u00a0Le jeu exige une certaine planification et propose des choix difficiles.\u00a0 Les objectifs permettent des variations dans les strat\u00e9gies et augmentent consid\u00e9rablement l\u2019interaction entre les joueurs qui se doivent de remporter l\u2019une ou l\u2019autre course aux points.\u00a0 C\u2019est d\u00e9cid\u00e9, cet \u00e9t\u00e9, je vais dans un h\u00f4tel Viennois mon excellent jeu sous le bras\u00a0\ud83d\ude00<\/p>\n<h2><span style=\"color: #800080;\">Nouvelles parties<\/span><\/h2>\n<p>Quand on rejoue maintenant \u00e0 Grand Austria Hotel, on se rend compte que ce jeu a \u00e9t\u00e9 un pr\u00e9curseur aux jeux modulables, aux cartes multi-effets, \u00e0 l&rsquo;obtention d&rsquo;une multitude de bonus, \u00e0 la course aux objectifs communs, aux capacit\u00e9s asym\u00e9triques et au draft de d\u00e9s.\u00a0 Et non seulement Grand Austria Hotel a \u00e9t\u00e9 un des pionniers en la mati\u00e8re mais en plus il est extr\u00eamement plaisant \u00e0 jouer.\u00a0 Et le tout est baign\u00e9 dans un th\u00e8me assez bien rendu.\u00a0 Le jeu a d\u00e9j\u00e0 6 ans mais il est toujours tr\u00e8s actuel et n&rsquo;a pas pris une ride.\u00a0 Un grand jeu!\u00a0 J&rsquo;augmente ma note \u00e0 10 tout simplement.<\/p>\n<p>\u00a0<\/p>\n<hr \/>\n<p><strong><span style=\"color: #333399;\"><a href=\"http:\/\/www.vindjeu.eu\/2016\/03\/09\/grand-austria-hotel\/1217-grand-austria-hotel-3\/\" rel=\"attachment wp-att-12839\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-12839\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2016\/01\/1217-Grand-Austria-Hotel-3-1024x768.jpg\" alt=\"1217 Grand Austria Hotel 3\" width=\"550\" height=\"413\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2016\/01\/1217-Grand-Austria-Hotel-3-1024x768.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2016\/01\/1217-Grand-Austria-Hotel-3-300x225.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2016\/01\/1217-Grand-Austria-Hotel-3-160x120.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2016\/01\/1217-Grand-Austria-Hotel-3-326x245.jpg 326w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2016\/01\/1217-Grand-Austria-Hotel-3-453x340.jpg 453w\" sizes=\"auto, (max-width: 550px) 100vw, 550px\" \/><\/a>Philrey212<\/span><\/strong>:<strong><span style=\"color: #800000;\">\u00a0 \u00a0 9\/10<\/span><\/strong><\/p>\n<p>Grand Austria Hotel, \u00e0 prime abord, n&rsquo;attire pas l&rsquo;oeil. Pourtant, ce serait dommage de passer \u00e0 c\u00f4t\u00e9, et pour plusieurs raisons (subjectives, je l&rsquo;accorde amplement).<\/p>\n<p>Grand Austria Hotel (GAH) reprend la m\u00e9canique de base de Yspahan. A savoir: tous les d\u00e9s sont lanc\u00e9s, class\u00e9s et plac\u00e9s par valeur sur les cases actions correspondantes. A partir de l\u00e0, dans l&rsquo;ordre du tour qui est particulier, j&rsquo;y reviens, chaque joueur pourra prendre un d\u00e9 et effectuer l&rsquo;action correspondante. Au plus la case action poss\u00e8de de d\u00e9s, au plus l&rsquo;action est puissante. Du classique \u00e0 ce point vue l\u00e0. Le d\u00e9 est retir\u00e9 (\u00e9videmment, rendant l&rsquo;action un peu moins int\u00e9ressante pour le joueur suivant) et plac\u00e9 sur la tuile d&rsquo;ordre de tour du joueur.<\/p>\n<p>Ceci me permet de parler plus en d\u00e9tail de\u00a0l&rsquo;ordre du tour. Chaque joueur re\u00e7oit une tuile qui se compose de 2 cases (de la taille d&rsquo;un d\u00e9) num\u00e9rot\u00e9es de 1 \u00e0 8 (\u00e0 4 joueurs). Lorsqu&rsquo;un joueur prend un d\u00e9 pour effectuer une action, il le place sur le num\u00e9ro le plus petit. Les tuiles sont ainsi fa\u00eetes que le premier joueur a le 1 et le 8, le deuxi\u00e8me le 2 et le 7. Ce qui signifie que le premier joueur sera premier pour choisir un d\u00e9 mais sans doute dernier pour choisir son deuxi\u00e8me d\u00e9. En effet, l&rsquo;ordre est d\u00e9termin\u00e9 par les valeurs des tuiles \u00ab\u00a0ordre de tour\u00a0\u00bb encore visibles (c\u00e0d pas cach\u00e9es par un d\u00e9).<\/p>\n<p>Afin de donner un peu plus de chances aux joueurs peu int\u00e9ress\u00e9s par les d\u00e9s sortis (les actions ne conviennent pas), un joueur peut passer. Auquel cas, il se retire d\u00e9lib\u00e9r\u00e9ment de la phase de s\u00e9lection de d\u00e9s jusqu&rsquo;\u00e0 ce que tous les autre joueurs aient effectu\u00e9 leurs deux actions ou ont pass\u00e9. En respectant l&rsquo;ordre du tour (plus petit chiffre visible), on relance tous les d\u00e9s sauf un, on les classe et on continue ainsi jusqu&rsquo;\u00e0 ce que tous les joueurs ont couvert leurs 2 cases sur leur tuile \u00ab\u00a0ordre de tour\u00a0\u00bb ou qu&rsquo;il n&rsquo;y ait plus de d\u00e9s disponible (ce qui ne devrait pas arriver).<\/p>\n<p>D&rsquo;autres \u00e9l\u00e9ments viennent \u00e9videmment complexifier le jeu (les clients et leurs commandes \u00e0 respecter, les chambres de l&rsquo;h\u00f4tel \u00e0 pr\u00e9parer pour accueillir les clients, les employ\u00e9s qui aident en offrant des avantages, les objectifs variables de partie en partie, etc.) pour le rendre complet et int\u00e9ressant, offrant des combos plus qu&rsquo;int\u00e9ressantes (demander au gagnant de notre partie).<\/p>\n<p>Deux petites remarques n\u00e9gatives:<br \/>1) le design ne donne pas trop envie (d&rsquo;accord, c&rsquo;est une question de go\u00fbts);<br \/>2) la dur\u00e9e est un peu longue (sans doute parce que je m&rsquo;attendais \u00e0 un jeu de moindre gabarit).<\/p>\n<p>Globalement, Grand Austria Hotel permet de passer une bonne soir\u00e9e si vous accrochez au th\u00e8me et ne vous sentez pas largu\u00e9 trop vite dans la partie (comme pas mal d&rsquo;autres jeux, d&rsquo;ailleurs)<\/p>\n<h2><span style=\"color: #800080;\">Nouvelles parties<\/span><\/h2>\n<p>Grand Austria Hotel reste une valeur s\u00fbre. Les choix sont difficiles, ce qui fait bien travailler les neurones.\u00a0<\/p>\n<p>C&rsquo;est clair que le hasard est pr\u00e9sent et peut frustrer, surtout si les d\u00e9s que vous recherchez ne sortent pas en nombre suffisant, voir pas du tout. Mais c&rsquo;est la m\u00eame chose pour tous le monde. On ne s&rsquo;arr\u00eatera donc pas trop \u00e0 cela et, si votre partie vous a frustr\u00e9, recommencez en une tout de suite \ud83d\ude09<\/p>\n<p>L&rsquo;ordre du tour est \u00e9galement tr\u00e8s important et influence vos choix (ou ceux qui restent). Il faut en tenir compte!<\/p>\n<p>Et si attendre votre tour vous est inacceptable, vous risquez de ne pas trop appr\u00e9cier Grand Austria H\u00f4tel.<\/p>\n<hr \/>\n<p><strong><span style=\"color: #333399;\">Pascal<\/span><\/strong>:<strong><span style=\"color: #800000;\">\u00a0\u00a0\u00a0\u00a0 8.5\/10<a href=\"http:\/\/www.vindjeu.eu\/2016\/03\/09\/grand-austria-hotel\/1217-grand-austria-hotel-4\/\" rel=\"attachment wp-att-13164\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-13164\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2016\/03\/1217-Grand-Austria-Hotel-4-1024x768.jpg\" alt=\"1217 Grand Austria Hotel 4\" width=\"520\" height=\"390\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2016\/03\/1217-Grand-Austria-Hotel-4-1024x768.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2016\/03\/1217-Grand-Austria-Hotel-4-300x225.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2016\/03\/1217-Grand-Austria-Hotel-4-160x120.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2016\/03\/1217-Grand-Austria-Hotel-4-326x245.jpg 326w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2016\/03\/1217-Grand-Austria-Hotel-4-453x340.jpg 453w\" sizes=\"auto, (max-width: 520px) 100vw, 520px\" \/><\/a><\/span><\/strong><\/p>\n<p>Au premier coup d&rsquo;\u0153il, Grand Austria Hotel et ses dessins assez vifs\u00a0ne m&rsquo;attirait pas plus que\u00a0\u00e7a.<\/p>\n<p>Mais au del\u00e0 de ce point, le jeu est bien pens\u00e9\u00a0et ses m\u00e9canismes\u00a0bien orchestr\u00e9s.\u00a0 Vous devez organiser votre h\u00f4tel en pr\u00e9parant des mets cuisin\u00e9s pour vos clients et en leur mettant \u00e0 disposition des chambres pour qu&rsquo;ils s&rsquo;y reposent. Th\u00e8me assez original et assez bien retranscrit.<\/p>\n<p>Vous\u00a0choisirez vos clients en fonction de leurs attentes (nourriture et couleur de chambre) et en fonction du bonus qu&rsquo;ils octroient.\u00a0 A votre tour, vous choisirez une valeur de d\u00e9 pour effectuer une action.\u00a0 Chose tr\u00e8s int\u00e9ressante, au plus il y a de d\u00e9s disponibles de cette valeur, au plus votre action aura de l&rsquo;effet.\u00a0 Vous serez donc tenter d&rsquo;effectuer l&rsquo;action avec le plus de d\u00e9s disponibles.\u00a0 Par contre, si aucun d\u00e9 d&rsquo;une valeur n&rsquo;est disponible, cette action n&rsquo;est pas disponible.<\/p>\n<p>Les bonus octroy\u00e9s par les cartes objectifs peuvent \u00eatre tr\u00e8s importants, et il semble impossible de gagner\u00a0sans en obtenir certains.<\/p>\n<p>Ajoutez encore la phase de draft en d\u00e9but de partie, \u00a0\u00a0et vous obtenez un tout tr\u00e8s bien ficel\u00e9 et avec une rejouabilit\u00e9 importante gr\u00e2ce aux cartes objectifs et bonus suffisamment vari\u00e9s.<\/p>\n<p>Petit point n\u00e9gatif tout de m\u00eame : le temps d&rsquo;attente\u00a0peut \u00eatre long \u00e0 4 joueurs.\u00a0 L&rsquo;ordre du tour est respect\u00e9 puis invers\u00e9 pour le tour suivant.\u00a0 Cela signifie que si vous \u00eates premier joueur, vous devrez attendre que les 3 autres joueurs jouent 2 fois avant de rejouer<\/p>\n<hr \/>\n<p>\u00a0<\/p>\n<p><a href=\"http:\/\/www.vindjeu.eu\/2016\/03\/09\/grand-austria-hotel\/1217-grand-austria-hotel-6\/\" rel=\"attachment wp-att-12833\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-12833\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2016\/01\/1217-Grand-Austria-Hotel-6.jpg\" alt=\"1217 Grand Austria Hotel 6\" width=\"1200\" height=\"900\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2016\/01\/1217-Grand-Austria-Hotel-6.jpg 4000w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2016\/01\/1217-Grand-Austria-Hotel-6-300x225.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2016\/01\/1217-Grand-Austria-Hotel-6-1024x768.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2016\/01\/1217-Grand-Austria-Hotel-6-160x120.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2016\/01\/1217-Grand-Austria-Hotel-6-326x245.jpg 326w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2016\/01\/1217-Grand-Austria-Hotel-6-453x340.jpg 453w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/a><\/p>\n<hr \/>\n<p>\u00a0<\/p>\n<p><a href=\"http:\/\/www.vindjeu.eu\/2016\/03\/09\/grand-austria-hotel\/1217-grand-austria-hotel-7\/\" rel=\"attachment wp-att-12832\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-12832\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2016\/01\/1217-Grand-Austria-Hotel-7-e1452518675327-768x1024.jpg\" alt=\"1217 Grand Austria Hotel 7\" width=\"720\" height=\"960\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2016\/01\/1217-Grand-Austria-Hotel-7-e1452518675327-768x1024.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2016\/01\/1217-Grand-Austria-Hotel-7-e1452518675327-225x300.jpg 225w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2016\/01\/1217-Grand-Austria-Hotel-7-e1452518675327-120x160.jpg 120w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2016\/01\/1217-Grand-Austria-Hotel-7-e1452518675327-183x245.jpg 183w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2016\/01\/1217-Grand-Austria-Hotel-7-e1452518675327-255x340.jpg 255w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><\/a><\/p>\n<p style=\"text-align: center;\">Un Chinon vieilles vignes exceptionnel qui devrait \u00eatre servi dans tous les bons h\u00f4tels du monde \ud83d\ude42<\/p>\n\n\n<p> <\/p>\n","protected":false},"excerpt":{"rendered":"<p> On peut dire qu\u2019avec Grand Austria Hotel &amp; Isle of Skye, Mayfair games (et Lookout games par la m\u00eame occasion\u00a0\ud83d\ude09 ) ont r\u00e9alis\u00e9 2 excellents jeux pour le dernier salon d\u2019Essen. Il faut dire que les 2 auteurs de Grand Austria Hotel sont loin d\u2019\u00eatre des novices.\u00a0&#46;&#46;&#46;<\/p>\n","protected":false},"author":3,"featured_media":12834,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[4849],"tags":[817,6,7],"class_list":["post-12831","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-expert","tag-pascal","tag-philrey212","tag-swatsh","annee-996","auteurs-simone-luciani","auteurs-virginio-gigli","editeurs-mayfair-games","illustrateurs-klemens-franz","recompenses-vin-djeu-dcoups-dcoeur"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/12831","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/comments?post=12831"}],"version-history":[{"count":0,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/12831\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media\/12834"}],"wp:attachment":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media?parent=12831"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/categories?post=12831"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/tags?post=12831"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}