{"id":129,"date":"2010-11-20T11:18:00","date_gmt":"2010-11-20T10:18:00","guid":{"rendered":"http:\/\/www.vindjeu.eu\/2009\/11\/11\/vasco-da-gama\/"},"modified":"2011-10-30T10:57:06","modified_gmt":"2011-10-30T09:57:06","slug":"vasco-da-gama","status":"publish","type":"post","link":"https:\/\/www.vindjeu.eu\/prd\/2010\/11\/20\/vasco-da-gama\/","title":{"rendered":"Vasco da Gama"},"content":{"rendered":"<p><span style=\"color: #663366;\"><strong><em><br \/>\n<\/em><\/strong><\/span><a href=\"http:\/\/4.bp.blogspot.com\/_ea2yja0GmY8\/SvsOwbw5j_I\/AAAAAAAAAkw\/MiCyoQ1eenc\/s1600-h\/117+Vasco+da+gamma+1.JPG\"><img decoding=\"async\" id=\"BLOGGER_PHOTO_ID_5402928403210407922\" style=\"margin: 0px 10px 10px 0px; width: 250px; float: left; height: 250px;\" src=\"http:\/\/4.bp.blogspot.com\/_ea2yja0GmY8\/SvsOwbw5j_I\/AAAAAAAAAkw\/MiCyoQ1eenc\/s400\/117+Vasco+da+gamma+1.JPG\" border=\"0\" alt=\"\" \/><\/a><\/p>\n<p><strong><span style=\"color: #9999ff;\"><span id=\"SPELLING_ERROR_1\" class=\"blsp-spelling-error\"><span style=\"color: #333399;\">Ana\u00eblle<\/span><\/span><\/span><\/strong>:<span style=\"color: #ff6666;\"><strong> <span style=\"color: #800000;\">8,5\/10<\/span><\/strong><\/span><\/p>\n<p><span style=\"color: #9999ff;\"><strong><span id=\"SPELLING_ERROR_2\" class=\"blsp-spelling-error\"><span style=\"color: #333399;\">Seb<\/span><\/span><\/strong><\/span>:<span style=\"color: #ff6666;\"><strong> <span style=\"color: #800000;\">9\/10<\/span><\/strong><\/span><\/p>\n<p>Les r\u00e8gles de Vasco de Gama m&rsquo;avaient largement mis l&rsquo;eau \u00e0 la bouche. Le moins que l&rsquo;on puisse dire est que je n&rsquo;ai pas \u00e9t\u00e9 d\u00e9\u00e7u. L&rsquo;auteur de Ur nous r\u00e9gale une fois de plus avec une merveilleuse m\u00e9canique dont il semble avoir le secret. Le choix des action num\u00e9rot\u00e9es peut donner le vertige car le syst\u00e8me est tr\u00e8s riche: il faut veiller \u00e0 l&rsquo;ordre du tour, la chronologie des ses propres actions, la gestion des ressources, tout cela en devant pr\u00e9voir les actions des autres et la possibilit\u00e9 de savoir payer, ou pas. Cette incertitude li\u00e9e au choix des actions est d&rsquo;ailleurs tr\u00e8s bien vu car il introduit une notion de prise de risque salvatrice dans un jeu qui aurait \u00e9t\u00e9 trop pr\u00e9visible sans cela. La phase de navigation, qui distribue les r\u00e9compenses, est assez peu intuitive et on aurait peut-\u00eatre aim\u00e9 que le syst\u00e8me soit adapt\u00e9 \u00e0 quelque chose de plus pur. Mais on est clairement dans un jeu qui demande plusieurs parties pour l&rsquo;apprivoiser et je les jouerai avec plaisir!<\/p>\n<p><strong><span style=\"color: #333399;\"><span id=\"SPELLING_ERROR_3\" class=\"blsp-spelling-error\">Philrey<\/span>212<\/span><\/strong>:<span style=\"color: #ff6666;\"><strong> <span style=\"color: #800000;\">10\/10<\/span><\/strong><\/span><br \/>\nEt bien, c&rsquo;est la bonne surprise de la soir\u00e9e. Ici aussi, j&rsquo;avais lu les r\u00e8gles pour Essen et j&rsquo;\u00e9tais rest\u00e9 asser mitig\u00e9.<br \/>\nLa grande force de Vasco Da Gama est le choix des actions qui est imbriqu\u00e9 avec l&rsquo;ordre de leur r\u00e9solution: vraiment tr\u00e8s original comme syst\u00e8me. Tout est bas\u00e9 l\u00e0-dessus:<br \/>\nVous prenez un num\u00e9ro (c&rsquo;est vraiment \u00e7a!), puis vous le liez \u00e0 votre pion que vous placez sur l&rsquo;action de votre choix. Et chacun \u00e0 son tour fait de m\u00eame avec ses 4 pions action dispo au d\u00e9but du tour!<br \/>\nApr\u00e8s, peu importe o\u00f9 se trouve vos pions, on r\u00e9soud dans l&rsquo;ordre croissant des num\u00e9ros! G\u00e9nial non? Si, si, g\u00e9nial!<\/p>\n<p>Cette m\u00e9canique doit sans doute encore \u00eatre un peu \u00ab\u00a0apprivois\u00e9e\u00a0\u00bb: entendez par l\u00e0 que cela engendre un peu de chaos, cela donne un jeu peu linaire et exige pas mal de r\u00e9flexion. Mais \u00e7a augmente aussi l&rsquo;interactivit\u00e9, voir l&rsquo;interd\u00e9pendance, entre les joueurs.<\/p>\n<p>Comptez quand m\u00eame 2 bonnes heures \u00e0 4!<\/p>\n<p><span style=\"color: #008000;\"><strong>Nouvelle partie<\/strong><\/span><\/p>\n<p><span style=\"color: #008000;\"><strong><span style=\"color: #000000;\">Toujours aussi bon. Et cette partie ne fait pas exception. La place du gagnant s&rsquo;est jou\u00e9 sur le dernier tour, Thierry me devan\u00e7ant dans la livraison de contrats. Superbe partie. C&rsquo;est quand vous voulez pour en refaire une! J&rsquo;en ai d&rsquo;ailleurs modifi\u00e9 ma cote \u00e0 la hausse \ud83d\ude42<\/span><\/strong><\/span><\/p>\n<p><span style=\"color: #666699;\"><strong><span style=\"color: #333399;\">Swatsh<\/span>:<\/strong><\/span> <span style=\"color: #ff0000;\"><strong><span style=\"color: #800000;\">9,5 \/10<\/span><\/strong><\/span><br \/>\nEn lisant les r\u00e8gles de\u00a0Vasco\u00a0Da\u00a0Gama, je m&rsquo;attendais \u00e0 un bon jeu sans plus, et j&rsquo;ai eu plus!<\/p>\n<p>Dans\u00a0Vasco\u00a0Da\u00a0Gama, on ach\u00e8te des projets pour construire des\u00a0bateaux, on y place nos marins et on les lance en mer. Le principe est assez classique:<br \/>\nChacun\u00a0\u00e0 son tour place un de ses 4 disques action dans une des 4 types d&rsquo;actions\u00a0disponibles: acheter des projets, recruter des marins, lancer nos\u00a0bateaux\u00a0en mer ou demander de l&rsquo;aide d&rsquo;un des personnages\u00a0influents. Mais \u00e0 ce m\u00e9canisme est greff\u00e9 un de g\u00e9nie: en m\u00eame temps qu&rsquo;on place notre disque d&rsquo;action, on prend un disque num\u00e9ro que l&rsquo;on place sur notre disque action.<br \/>\nCe disque num\u00e9ro a 3 fonctions:<\/p>\n<p>1) Il indique l&rsquo;ordre des actions<br \/>\nL\u00e0, c&rsquo;est d\u00e9j\u00e0 tr\u00e8s tr\u00e8s fort puisqu&rsquo;on va devoir g\u00e9rer l&rsquo;ordre de nos actions: \u00ab\u00a0je veux faire ceci avant cela,&#8230; \u00a0\u00bb et l&rsquo;ordre de nos actions par rapport \u00e0 celles de nos adversaires: \u00ab\u00a0je veux faire cette action le premier et ce n&rsquo;est pas trop grave si je suis dernier \u00e0 cette action,&#8230;\u00a0\u00bb<br \/>\nMagnifique!<\/p>\n<p>2) Il indique le prix \u00e0 payer pour ex\u00e9cuter notre action.<br \/>\nC&rsquo;est le seul m\u00e9canisme qui me d\u00e9range l\u00e9g\u00e8rement puisque toutes les actions seront gratuites \u00e0 ex\u00e9cuter si leur num\u00e9ro est au-dessus d&rsquo;un num\u00e9ro qui sera tir\u00e9 au hasard. On a juste une vague id\u00e9e qu&rsquo;il pourrait varier entre 6 num\u00e9ros. Donc, au plus on voudra absolument ex\u00e9cuter une action avant ses adversaires, au plus on devra prendre des risques et \u00eatre pr\u00eat \u00e0 payer cher. Quelques fois, le hasard gratifiera le ou les joueurs ayant pris beaucoup de risques, d&rsquo;autres non&#8230;<\/p>\n<p>3) Il indique le revenu qu&rsquo;on peut recevoir si nous d\u00e9cidons de ne pas ex\u00e9cuter notre action.<\/p>\n<p>Les navigations sont \u00e9galement originales. Nos\u00a0bateaux\u00a0vont naviguer d&rsquo;escale en escale et \u00e0 chaque fois rapporter des points. Mais au plus on voudra faire des escales au plus on risquera que notre\u00a0bateau\u00a0se perde en mer&#8230;<\/p>\n<p>Mais il ne faut pas que des m\u00e9canismes originaux pour me plaire! Le jeu en lui m\u00eame est magnifique, tr\u00e8s strat\u00e9gique, on r\u00e9fl\u00e9chit plusieurs coups \u00e0 l&rsquo;avance afin d&rsquo;atteindre nos objectifs long terme. J&rsquo;ai pris un tr\u00e8s grand plaisir \u00e0 y jouer!<\/p>\n<p><strong><span style=\"color: #008000;\">Soir\u00e9e 2<\/span><\/strong><br \/>\nVasco est vraiment tr\u00e8s bon. Au plus je fais des parties, au plus j&rsquo;en savoure les subtilit\u00e9s. Evidemment, le principe du -3 \/ -3 influence toujours. C&rsquo;est du hasard certes, mais le m\u00eame pour tous les joueurs. C&rsquo;est juste une prise de risque qu&rsquo;il faut de temps en temps prendre ou pas&#8230;<\/p>\n<p>Ce qui m&rsquo;a le plus frapp\u00e9 lors des derni\u00e8res parties c&rsquo;est la grande interaction entre les joueurs. Sur toutes les actions, on regarde ce que font les joueurs pour se favoriser un maximum tout en d\u00e9favorisant les autres. On peut m\u00eame bloquer certains joueurs,&#8230;<\/p>\n<p>Ce jeu est trop bon, j&rsquo;en redemande!<\/p>\n<p><span style=\"color: #008000;\"><strong>Nouvelle partie<\/strong><\/span><\/p>\n<p>Les parties de Vasco da Gama s&rsquo;encha\u00eenent pour moi mais ne se ressemblent pas! \u00a0 Encore une partie m\u00e9morable hier soir. \u00a0On planifie ses coups \u00e0 l&rsquo;avance, sa mijote \u00e0 mort dans nos petites t\u00eates et \u00e7a donne des coups fumants. \u00a0Un r\u00e9gal.<\/p>\n<p><strong><span style=\"color: #3366ff;\"><span style=\"color: #333399;\">Thierry<\/span>:<\/span><\/strong> <span style=\"color: #ff0000;\"><strong><span style=\"color: #800000;\">9,5\/10<\/span><\/strong><\/span><br \/>\nGros coup de coeur pour ce superbe jeu ! Rarement j&rsquo;ai pu voir un jeu si interactif, toutes les actions \u00e9tant li\u00e9es (que ce soit les siennes ou vis-\u00e0-vis des autres), ce qui le rend passionnant et tr\u00e8s dynamique (on ne peut s&rsquo;endormir en attendant son tour). Si l&rsquo;ordre de certaines actions parait parfois assez \u00e9vident, celui-ci est r\u00e9guli\u00e8rement perturb\u00e9 par le choix des autres et, pour chaque action, les options sont multiples (choix des bateaux, choix des personnages, choix de la place des bateaux,&#8230;). C&rsquo;est donc un jeu tr\u00e8s tactique qui n\u00e9cessite beaucoup de r\u00e9activit\u00e9, avec un niveau de chance qui est proportionnel au risque pris (on peut donc aussi tenter des trucs!).<\/p>\n<p>Le syst\u00e8me des disques num\u00e9ro avec ses multiples fonctions repr\u00e9sente \u00e9videmment l&rsquo;originalit\u00e9 de la m\u00e9canique mais l&rsquo;organisation du plateau (tr\u00e8s beau) permet \u00e9galement d&rsquo;impliquer tout le le monde dans le jeu (\u00e0 l&rsquo;inverse parfois de jeu avec plateaux individuels) car le jeu de tous les joueurs est tr\u00e8s visible. C&rsquo;est clair, apr\u00e8s y avoir go\u00fbt\u00e9, une seule envie, d&rsquo;y rejouer, j&rsquo;ai ador\u00e9!!<\/p>\n<p><span style=\"color: #008000;\"><strong>Nouvelle partie:<\/strong><\/span><\/p>\n<p><span style=\"color: #000000;\">Enfin, \u00e7a faisait des lustres que je voulais rejouer \u00e0\u00a0Vasco da Gama\u00a0 et je peux vous dire que c&rsquo;est toujours aussi bon.\u00a0 Ce jeu est incroyablement bien \u00e9quilibr\u00e9, classique (4 actions possibles) et&#8230; original (gestion des actions par les disques\/phase de navigation).\u00a0 La planification et l&rsquo;interaction sont maximales car toutes vos actions doivent parfaitement s&#8217;embo\u00eeter (pas question d&rsquo;en n\u00e9gliger ni de mal encha\u00eener) tout en d\u00e9pendant aussi du choix des autres joueurs (qui peuvent passer avant vous et prendre le personnage ou l&rsquo;argent que vous souhaitiez p.e.) &#8211; coup de coeur confirm\u00e9 et plaisir assur\u00e9 !<\/span><\/p>\n<p><span style=\"color: #3366ff;\"><strong><span style=\"color: #333399;\">Beno\u00eet<\/span>:<\/strong><\/span> <span style=\"color: #ff0000;\"><strong><span style=\"color: #800000;\">9,4\/10<\/span><\/strong><\/span><br \/>\nTout a \u00e9t\u00e9 \u00e9crit ci-dessus sur l&rsquo;excellent Vasco de Gama.<\/p>\n<p>En r\u00e9sum\u00e9, ce qui en fait un \u00ab\u00a0jeu \u00e0 ne rater sous aucun pr\u00e9texte\u00a0\u00bb:<\/p>\n<ul>\n<li>un th\u00e8me historique int\u00e9ressant et bien rendu<\/li>\n<li>au centre du plateau (et du jeu!), les disques num\u00e9rot\u00e9s de choix des actions cr\u00e9ent une dynamique et une interaction entre les joueurs passionnante<\/li>\n<li>la chance ou plut\u00f4t le risque calcul\u00e9 bien pr\u00e9sent offre des rebondissements possibles<\/li>\n<li>&#8230; et ce qui ne g\u00e2che rien, un tr\u00e8s joli plateau de jeu et un mat\u00e9riel de qualit\u00e9<\/li>\n<\/ul>\n<p>Voil\u00e0, tout est dit, foncez!<\/p>\n<p><span style=\"color: #333399;\"><strong>Raf<\/strong><\/span>:<span style=\"color: #800000;\"><strong> 6.8\/10<\/strong><\/span><\/p>\n<p><span style=\"color: #333333;\">Aie, j&rsquo;ai un peu honte de ma cote quand je vois, les commentaires des autres&#8230;.<\/span><\/p>\n<p><span style=\"color: #333333;\">Voil\u00e0 pr\u00e8s d&rsquo;un an que la premi\u00e8re partie de vasco a \u00e9t\u00e9 faite et je n&rsquo;\u00e9tais pas l\u00e0, je n&rsquo;ai pu me consoler quand lisant les commentaires, j&rsquo;en avais l&rsquo;eau \u00e0 la bouche&#8230;<\/span><\/p>\n<p><span style=\"color: #333333;\">Les r\u00eagles ont tr\u00e8s bien \u00e9t\u00e9 expliqu\u00e9es et vite assimil\u00e9es, on peut commencer&#8230;<\/span><\/p>\n<p><span style=\"color: #333333;\">Le plateau est splendide<\/span><\/p>\n<p><span style=\"color: #333333;\">Tirage au sort et je suis dernier, super je vais pouvoir voir ce que font les autres&#8230;<\/span><\/p>\n<p><span style=\"color: #333333;\">De nature prudente je laisse les autres devant moi dans le tours de jeu et pas de chance -2 dans le syst\u00e8me de num\u00e9rotation, il fallait prendre le risque&#8230;pas de chance. Deuxi\u00e8me tour rebelote avec -1, troisi\u00e8me\u00a0tous les n\u00e9gatifs sont sortis sauf le -3 statistiquement vaut mieux \u00eatre prudent ce tour ci, c&rsquo;est ma chance&#8230;.et&#8230;-3,\u00a0encore pas de chance&#8230;d\u00e9j\u00e0 que je ne suis jamais parvenu a rentrer dans le jeu\u00a0si en plus la chance n&rsquo;est pas avec moi!<\/span><\/p>\n<p><span style=\"color: #333333;\">En discutant de\u00a0ma frustration, les autres joueurs me disent, Raf tu ne prends pas assez de risque, ok, et si j&rsquo;en avais pris et que c&rsquo;\u00e9tait un +3 qui sortait, Raf, t&rsquo;as pris trop de risque&#8230;je r\u00e9sumerai plutot en disant Raf t&rsquo;as pas de chance, voil\u00e0 un mot que j&rsquo;adore dans un jeu! Ca frustre et moi \u00e7a m&rsquo;a gach\u00e9 ma partie, dommage car pour le reste pas mal du tout!.<\/span><\/p>\n<p><span style=\"color: #333333;\">On a beau me dire qu&rsquo;il faut essayer d&rsquo;avoir de l&rsquo;or pour compenser, pour \u00e7a faut arriver \u00e0 le prendre avant les autres ou bien sacrifier des actions pour \u00eatre sur d&rsquo;en avoir, belle mentalit\u00e9 de&#8230;&#8230;&#8230; looser!<\/span><\/p>\n<p><span style=\"color: #333333;\">La chance doit \u00eatre avec vous au moins une fois sur 2 durant les 2 premiers tours apr\u00e8s il est possible de compenser, si c&rsquo;est pas le cas vous allez vivre mon enfer!<\/span><\/p>\n<p><strong><span style=\"color: #3366ff;\"><span style=\"color: #333399;\">Olivier<\/span>:<\/span><\/strong> <strong><span style=\"color: #800000;\">9,5\/10<\/span><\/strong><\/p>\n<p>Une belle d\u00e9couverte pour ce jeu, que dire de plus tout ayant d\u00e9j\u00e0 \u00e9t\u00e9 dit,<br \/>\nLes r\u00e8gles m&rsquo;ont un peu surpris (longues explications) un peu de confusion due \u00e0 toutes les informations \u00e0 assimiler, mais une fois le premier tour commenc\u00e9 \u00e7a va tout seul.<br \/>\nVraiment un jeu incontournable.<\/p>\n<p><a href=\"http:\/\/2.bp.blogspot.com\/_ea2yja0GmY8\/SvsOerleaDI\/AAAAAAAAAko\/uGRfNTYEghE\/s1600-h\/117+Vasco+da+gamma+2.JPG\"><img decoding=\"async\" id=\"BLOGGER_PHOTO_ID_5402928098219812914\" style=\"text-align: center; margin: 0px auto 10px; width: 400px; display: block; height: 300px;\" src=\"http:\/\/2.bp.blogspot.com\/_ea2yja0GmY8\/SvsOerleaDI\/AAAAAAAAAko\/uGRfNTYEghE\/s400\/117+Vasco+da+gamma+2.JPG\" border=\"0\" alt=\"\" \/><\/a> En haut \u00e0 gauche: les <span id=\"SPELLING_ERROR_18\" class=\"blsp-spelling-corrected\">bateaux<\/span> naviguent d&rsquo;escale en escale<br \/>\nEn haut \u00e0 droite: on recrute des marins et capitaines pour nos bateaux. Pour chaque bateau, il faut des marins de couleur diff\u00e9rente. Mais le recrutement <span id=\"SPELLING_ERROR_19\" class=\"blsp-spelling-corrected\">co\u00fbte<\/span> cher: recruter un nombre quelconque de marins d&rsquo;une couleur co\u00fbte 1 <span id=\"SPELLING_ERROR_20\" class=\"blsp-spelling-error\">Real<\/span>, de 2 couleurs diff\u00e9rentes 3 <span id=\"SPELLING_ERROR_21\" class=\"blsp-spelling-error\">Reals<\/span>, 3 couleurs 6 <span id=\"SPELLING_ERROR_22\" class=\"blsp-spelling-error\">Reals<\/span>, 4 couleurs 10 <span id=\"SPELLING_ERROR_23\" class=\"blsp-spelling-error\">Reals<\/span>. Pour le capitaine c&rsquo;est l&rsquo;inverse: son prix est \u00e9gal au nombre de marins recrut\u00e9s. Bonjour les calculs \ud83d\ude42<br \/>\nEn bas \u00e0 gauche: achat de projets<br \/>\nEn bas \u00e0 droite: demande de l&rsquo;aide de personnages donnant des bonus diff\u00e9rents (1 missionnaire = 1 marin blanc, 1 <span id=\"SPELLING_ERROR_24\" class=\"blsp-spelling-corrected\">bateau<\/span>, premier joueur, 1 disque d&rsquo;action suppl\u00e9mentaire).<\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2009\/11\/234-Vasco-Da-Gama-3.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-1520  aligncenter\" title=\"234 Vasco Da Gama 3\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2009\/11\/234-Vasco-Da-Gama-3-1024x768.jpg\" alt=\"\" width=\"734\" height=\"571\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p> Les r\u00e8gles de Vasco de Gama m&rsquo;avaient largement mis l&rsquo;eau \u00e0 la bouche. Le moins que l&rsquo;on puisse dire est que je n&rsquo;ai pas \u00e9t\u00e9 d\u00e9\u00e7u. L&rsquo;auteur de Ur nous r\u00e9gale une fois de plus avec une merveilleuse m\u00e9canique dont il semble avoir le secret. Le&#46;&#46;&#46;<\/p>\n","protected":false},"author":2,"featured_media":9022,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[4849],"tags":[8,6,10,7,276],"class_list":["post-129","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-expert","tag-benoit","tag-philrey212","tag-raf","tag-swatsh","tag-thierry","annee-19","auteurs-paolo-mori","editeurs-iello","editeurs-whats-your-game"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/129","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/comments?post=129"}],"version-history":[{"count":0,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/129\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media\/9022"}],"wp:attachment":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media?parent=129"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/categories?post=129"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/tags?post=129"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}