{"id":12909,"date":"2016-03-21T20:50:38","date_gmt":"2016-03-21T19:50:38","guid":{"rendered":"http:\/\/www.vindjeu.eu\/?p=12909"},"modified":"2016-08-01T20:18:56","modified_gmt":"2016-08-01T18:18:56","slug":"clochemerle-my-village","status":"publish","type":"post","link":"https:\/\/www.vindjeu.eu\/prd\/2016\/03\/21\/clochemerle-my-village\/","title":{"rendered":"Clochemerle (My Village)"},"content":{"rendered":"<p><a href=\"http:\/\/www.vindjeu.eu\/2016\/03\/21\/clochemerle-my-village\/1224-clochmerle-1\/\" rel=\"attachment wp-att-12911\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-12911\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2016\/01\/1224-Clochmerle-1.jpg\" alt=\"1224 Clochmerle 1\" width=\"351\" height=\"350\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2016\/01\/1224-Clochmerle-1.jpg 500w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2016\/01\/1224-Clochmerle-1-150x150.jpg 150w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2016\/01\/1224-Clochmerle-1-300x300.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2016\/01\/1224-Clochmerle-1-160x160.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2016\/01\/1224-Clochmerle-1-245x245.jpg 245w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2016\/01\/1224-Clochmerle-1-340x340.jpg 340w\" sizes=\"auto, (max-width: 351px) 100vw, 351px\" \/><\/a><\/p>\n<p><a href=\"http:\/\/www.vindjeu.eu\/2016\/03\/21\/clochemerle-my-village\/1224-clochmerle-1-1\/\" rel=\"attachment wp-att-12912\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-12912\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2016\/01\/1224-Clochmerle-1.1.jpg\" alt=\"1224 Clochmerle 1.1\" width=\"350\" height=\"350\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2016\/01\/1224-Clochmerle-1.1.jpg 500w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2016\/01\/1224-Clochmerle-1.1-150x150.jpg 150w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2016\/01\/1224-Clochmerle-1.1-300x300.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2016\/01\/1224-Clochmerle-1.1-160x160.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2016\/01\/1224-Clochmerle-1.1-245x245.jpg 245w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2016\/01\/1224-Clochmerle-1.1-340x340.jpg 340w\" sizes=\"auto, (max-width: 350px) 100vw, 350px\" \/><\/a><\/p>\n<p><strong><span style=\"color: #333399;\">SwatSh<\/span><\/strong>:\u00a0 <strong><span style=\"color: #800000;\">7,5\/10<\/span><\/strong><\/p>\n<p>Bien que \u00ab\u00a0Clochemerle\u00a0\u00bb signifie \u00a0\u00ab\u00a0village d\u00e9chir\u00e9 par des querelles burlesques \u00bb (sic\u00a0\ud83d\ude42 ), il est assez \u00e9tonnant que <a href=\"http:\/\/www.vindjeu.eu\/editeurs\/gigamic\/\" target=\"_blank\">Gigamic <\/a>ait d\u00e9cid\u00e9 d\u2019appeler ce jeu \u00ab\u00a0Clochemerle\u00a0\u00bb\u00a0\ud83d\ude42\u00a0 <a href=\"http:\/\/www.vindjeu.eu\/editeurs\/pegasus-spiele\/\" target=\"_blank\">Pegasus <\/a>l\u2019a, quant \u00e0 lui, appel\u00e9 \u00ab\u00a0My Village\u00a0\u00bb.\u00a0 Je comprends beaucoup mieux \u00ab\u00a0My Village\u00a0\u00bb puisque le jeu est la version d\u00e9s de \u00ab\u00a0<a href=\"http:\/\/www.vindjeu.eu\/2012\/03\/25\/descendance-aide-de-jeu\/\" target=\"_blank\">Village\u00a0<\/a>\u00bb.\u00a0 En fran\u00e7ais \u00e7a donnerait\u00a0: \u00ab\u00a0Ma Descendance\u00a0\u00bb est la version jeu de d\u00e9s de \u00ab\u00a0<a href=\"http:\/\/www.vindjeu.eu\/2012\/03\/25\/descendance-aide-de-jeu\/\" target=\"_blank\">Descendance\u00a0<\/a>\u00bb.\u00a0 C\u2019est plus logique que Clochemerle non\u00a0?\u00a0 Enfin&#8230;\u00a0: Clochemerle est donc la version d\u00e9s de l\u2019excellentissime <a href=\"http:\/\/www.vindjeu.eu\/2012\/03\/25\/descendance-aide-de-jeu\/\" target=\"_blank\">Descendance<\/a>, notre <a href=\"http:\/\/www.vindjeu.eu\/vin-djeu-dlannee\/vin-djeu-dlannee-2012\/\" target=\"_blank\">Vin d\u2019jeu d\u2019l\u2019ann\u00e9e 2012<\/a> des m\u00eames auteurs.<\/p>\n<p>Bien qu\u2019inspir\u00e9e d\u2019<a href=\"http:\/\/www.vindjeu.eu\/2010\/09\/29\/yspahan-ext-ystari-box\/\" target=\"_blank\">Yspahan<\/a> et des Colons (mais alors de tr\u00e8s tr\u00e8s loin\u00a0\ud83d\ude09 ), la m\u00e9canique du choix des d\u00e9s est excellente\u00a0: En fonction du nombre de joueurs, le premier joueur jette un certain nombre de d\u00e9s blancs &amp; noirs.\u00a0 Puis, chacun \u00e0 son tour en choisit 2 et ex\u00e9cute une action dont le chiffre fait la somme des 2 d\u00e9s (\u00e0 chaque action correspond un chiffre).\u00a0 Si on prend un d\u00e9 noir, tout comme les cubes noirs de <a href=\"http:\/\/www.vindjeu.eu\/2012\/03\/25\/descendance-aide-de-jeu\/\" target=\"_blank\">Descendance<\/a>, on perd 2 temps qui vont nous rapprocher d\u2019une mort certaine&#8230;\u00a0 La m\u00e9canique est excellente en effet mais il faut admettre que les choix sont forts peu limit\u00e9s car on obtient bien souvent le nombre qu\u2019on d\u00e9sirait et, au pire, on peut changer la valeur d\u2019un d\u00e9 assez facilement.\u00a0 Que le jeu des d\u00e9s ne limite pas plus que \u00e7a les choix donne un c\u00f4t\u00e9 un peu bizarre.\u00a0 D\u2019un autre c\u00f4t\u00e9, aucun joueur ne pourra se plaindre ni de la malchance aux d\u00e9s\u00a0\ud83d\ude42 ni des choix trop limit\u00e9s de Clochemerle\u00a0\ud83d\ude42<\/p>\n<p>Les 2 actions possibles sont\u00a0:<br \/>\n&#8211; <strong>Acheter une des nombreuses cartes<\/strong> disponibles \u00e0 l\u2019achat.\u00a0 Tenez-vous bien, il y en a au moins 30 disponibles \u00e0 l\u2019achat\u00a0!!!\u00a0 Faudra pas vous plaindre du nombre de choix dans<a href=\"http:\/\/www.vindjeu.eu\/2016\/03\/21\/clochemerle-my-village\/1224-clochmerle-2\/\" rel=\"attachment wp-att-12913\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-12913\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2016\/01\/1224-Clochmerle-2-1024x768.jpg\" alt=\"1224 Clochmerle 2\" width=\"500\" height=\"375\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2016\/01\/1224-Clochmerle-2-1024x768.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2016\/01\/1224-Clochmerle-2-300x225.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2016\/01\/1224-Clochmerle-2-160x120.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2016\/01\/1224-Clochmerle-2-326x245.jpg 326w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2016\/01\/1224-Clochmerle-2-453x340.jpg 453w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a> Clochemerle\u00a0(bis \ud83d\ude09\u00a0). \u00a0La somme de vos d\u00e9s doit correspondre au chiffre de la carte achet\u00e9e.<br \/>\n&#8211; <strong>R\u00e9aliser toutes les actions<\/strong> de vos cartes achet\u00e9es qui portent le m\u00eame nombre que les d\u00e9s choisis.\u00a0 Et \u00e7a, c\u2019est une m\u00e9canique subliminale dont je ne peux que souligner l\u2019ing\u00e9niosit\u00e9.\u00a0 Si on a achet\u00e9 par exemple 3 cartes action de valeur 8, lorsqu\u2019on d\u00e9cide de r\u00e9aliser l\u2019action \u00ab\u00a08\u00a0\u00bb, ces 3 cartes r\u00e9alisent leur action.\u00a0 C\u2019est vraiment malin car d\u2019un c\u00f4t\u00e9, on a int\u00e9r\u00eat \u00e0 avoir un maximum de cartes de m\u00eame valeur pour optimiser nos actions et d\u2019un autre, on a int\u00e9r\u00eat \u00e0 s\u2019\u00e9parpiller un minimum au cas o\u00f9 le r\u00e9sultat des d\u00e9s ne permettrait pas de r\u00e9aliser cette action.\u00a0 C\u2019est l\u00e0 aussi qu\u2019intervient le c\u00f4t\u00e9 Colons, puisque vos actions de valeur 6 ou 8 seront plus facilement r\u00e9alisables que celles de valeur 2 ou 12&#8230;<\/p>\n<p>Tout comme dans <a href=\"http:\/\/www.vindjeu.eu\/2012\/03\/25\/descendance-aide-de-jeu\/\" target=\"_blank\">Descendance<\/a>, Clochemerle permet de diversifier sa strat\u00e9gie entre 3 \u00e9l\u00e9ments\u00a0:<br \/>\n&#8211;<strong> Les clients du march\u00e9<\/strong><br \/>\nLa strat\u00e9gie est assez simple\u00a0: Avoir des cartes permettant de produire les 4 biens demand\u00e9s par les clients\u00a0: des charrettes, des charrues, des parchemins ou des chevaux et prendre des cartes clients puis leur livrer leur d\u00fb.<br \/>\n&#8211;<strong> Les voyages<\/strong><br \/>\nLes voyages co\u00fbtent soit des pi\u00e8ces soit des biens (les m\u00eames que pour les clients) \u00e0 la place des pi\u00e8ces, au choix du joueur.<br \/>\nLa strat\u00e9gie est \u00e9galement assez simple\u00a0: Trouver une m\u00e9canique pour produire des pi\u00e8ces et payer les co\u00fbts des voyages.<br \/>\n<strong>&#8211; L\u2019\u00e9glise<\/strong><br \/>\nLes co\u00fbts sont un m\u00e9lange de pi\u00e8ces et de biens.\u00a0 Chaque construction d\u2019\u00e9glise rapporte des PVs (exponentiels au plus on en a) et des bonus one shot.<\/p>\n<p>Toutes ces m\u00e9caniques sont extr\u00eamement bien pens\u00e9es et tr\u00e8s originales.\u00a0 J\u2019adore.\u00a0 Ce qui est plus dommage dans Clochemerle est son ex\u00e9cution.\u00a0 Le jeu dure un peu trop longtemps et \u00e0 partir d\u2019un moment on tourne en rond et le jeu en devient fort r\u00e9p\u00e9titif.\u00a0 Et \u00e0 cause de cette dur\u00e9e exag\u00e9r\u00e9e, la strat\u00e9gie voyage + \u00e9glise est intenable car on va arriver au bout des voyages et de la construction de l\u2019\u00e9glise avant la fin de la partie.\u00a0 On sera alors tenu de s\u2019investir dans le march\u00e9 alors que ses adversaires concentr\u00e9s sur cette strat\u00e9gie s\u2019en seront <a href=\"http:\/\/www.vindjeu.eu\/2016\/03\/21\/clochemerle-my-village\/1224-clochmerle-3\/\" rel=\"attachment wp-att-12914\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-12914\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2016\/01\/1224-Clochmerle-3-1024x768.jpg\" alt=\"1224 Clochmerle 3\" width=\"500\" height=\"375\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2016\/01\/1224-Clochmerle-3-1024x768.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2016\/01\/1224-Clochmerle-3-300x225.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2016\/01\/1224-Clochmerle-3-160x120.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2016\/01\/1224-Clochmerle-3-326x245.jpg 326w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2016\/01\/1224-Clochmerle-3-453x340.jpg 453w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a>mis \u00e0 coeur joie et auront pu construire une m\u00e9canique beaucoup plus efficace.\u00a0 Vous devez donc construire une strat\u00e9gie march\u00e9 obligatoirement et l\u2019agr\u00e9menter d\u2019une strat\u00e9gie voyage ou \u00e9glise.\u00a0 Ca limite un peu trop la vari\u00e9t\u00e9 des parties qui ont, qui plus est, un c\u00f4t\u00e9 un peu r\u00e9p\u00e9titif g\u00eanant.\u00a0 Pour le reste, c\u2019est un pur bonheur de d\u00e9couvrir une m\u00e9canique de jeu de d\u00e9s innovante et inventive qui arrive \u00e0 diminuer le hasard \u00e0 peau de chagrin.\u00a0 La vari\u00e9t\u00e9 des cartes et des choix est impressionnante et procure un grand plaisir de jeu.<\/p>\n<p><strong><span style=\"text-decoration: underline;\"><span style=\"color: #800080; text-decoration: underline;\">Nouvelle partie<\/span><\/span><br \/>\n<\/strong>J\u2019ai toujours un sentiment partag\u00e9 pour Clochemerle.\u00a0 J\u2019ai vraiment envie d\u2019aimer ce jeu tant j\u2019aime Descendance.\u00a0 Je trouve que les diff\u00e9rentes cartes et leurs pouvoirs sont vraiment bien imagin\u00e9es et apportent pas mal de possibilit\u00e9s et de strat\u00e9gies diff\u00e9rentes.<\/p>\n<p>D\u2019un autre c\u00f4t\u00e9, je trouve ce jeu de d\u00e9s beaucoup trop lent et plus de 2 heures par partie est exag\u00e9r\u00e9.\u00a0 Evidemment, les nombreux choix que propose Clochemerle n\u2019y sont pas pour rien et les r\u00e9duire r\u00e9duirait l\u2019attrait du jeu \u00e9galement.\u00a0 C\u2019est \u00e9videmment un \u00e9quilibre difficile \u00e0 trouver mais le m\u00eame jeu en plus dynamique, comme Descendance en fait, me comblerait mieux.<\/p>\n<p>Ce qui m\u2019a \u00e9galement frapp\u00e9 lors de cette partie est de voir le d\u00e9roulement de la partie compl\u00e8tement changer entre une partie \u00e0 2 ou 4 joueurs. \u00a0A 2 joueurs, le jeu est clairement trop long et on arrive au bout du paquet clients.\u00a0 A 4, on n\u2019a pas le temps d\u2019en servir beaucoup.\u00a0 Le juste \u00e9quilibre\u00a0?\u00a0 Peut-\u00eatre \u00e0 3 joueurs&#8230;\u00a0\ud83d\ude42<\/p>\n<hr \/>\n<p><strong><span style=\"color: #333399;\">Pascal<\/span><\/strong>:<strong><span style=\"color: #800000;\">\u00a0\u00a0\u00a0\u00a0 8,5\/10<\/span><\/strong><\/p>\n<p>Clochemerle, c&rsquo;est pas tout \u00e0 fait une variante de Descendance avec des d\u00e9s, mais quand m\u00eame un petit peu.<\/p>\n<p>Le th\u00e8me est pareil, les voies de d\u00e9veloppement portent les m\u00eames noms (voyage, march\u00e9, \u00e9glise, commune\/politique, &#8230;),\u00a0les meeples vont aussi mourir, &#8230;\u00a0 Si vous avez jou\u00e9\u00a0\u00e0 l&rsquo;original,\u00a0vous ne serez pas d\u00e9pays\u00e9.\u00a0 (Si pas,\u00a0choisissez vite l&rsquo;un de nos sponsors et commandez votre bo\u00eete tout de suite : Descendance est et reste un de mes jeux pr\u00e9f\u00e9r\u00e9s !).<\/p>\n<p>Mais votre achat de Clochermerle\u00a0sera tout \u00e0 fait justifi\u00e9 par la m\u00e9canique de jeu totalement diff\u00e9rente, bas\u00e9e cette \u00a0fois-ci sur des d\u00e9s.<\/p>\n<p>Au d\u00e9but de manche, les d\u00e9s sont lanc\u00e9s.\u00a0 A votre tour, vous devrez choisir 2 d\u00e9s,\u00a0dont le total vous permettra de faire une ou plusieurs actions.<\/p>\n<p>Qui dit jeu de d\u00e9, dit jeu de hasard &#8230; et ce qui m&rsquo;int\u00e9resse toujours est de voir comment le hasard est att\u00e9nu\u00e9.\u00a0 Dans Clochermerle, le hasard est bien s\u00fbr pr\u00e9sent, mais assez ma\u00eetrisable : vous pouvez toujours payer pour augmenter ou diminuer la valeur d&rsquo;un d\u00e9.\u00a0 Une des cartes constructibles permet aussi de choisir la valeur qui nous int\u00e9resse, ind\u00e9pendamment du lanc\u00e9 de d\u00e9 initial.\u00a0 Et finalement, on lance plus\u00a0de d\u00e9s que n\u00e9cessaires, pour qu&rsquo;il y ait toujours un choix minimum.<\/p>\n<p>Petite d\u00e9ception par rapport\u00a0au jeu original, la gestion de la mortalit\u00e9 a \u00e9t\u00e9 (un peu trop ?)\u00a0simplifi\u00e9e, rendant la gestion et les choix\u00a0un peu moins int\u00e9ressants.\u00a0 Il n&#8217;emp\u00eache que si vous n&rsquo;avez plus de meeple d&rsquo;un certain type (voyageur, moine, marchand), vous ne pouvez plus effectuer l&rsquo;action correspondante.<\/p>\n<p>La m\u00e9canique est fluide et le jeu tourne tr\u00e8s bien.\u00a0 Mais dans notre partie \u00e0 2 joueurs, elle a \u00e9t\u00e9 un poil trop longue et les derniers tours ont \u00e9t\u00e9 un peu trop r\u00e9p\u00e9titifs.\u00a0Comme nous sommes partis sur des strat\u00e9gies diam\u00e9tralement oppos\u00e9es, on ne s&rsquo;est pas trop g\u00ean\u00e9.\u00a0\u00a0A priori,\u00a0ces petits soucis\u00a0sont li\u00e9s \u00e0 la configuration \u00e0 2 joueurs.\u00a0 A plus, je suis certain que l&rsquo;interactivit\u00e9 sera bien plus importante et les choix d&rsquo;autant plus int\u00e9ressants.<\/p>\n<p>La comparaison avec Descendances est quasi in\u00e9vitable &#8230; de mon point de vue, le jeu est plus l\u00e9ger, et le hasard un peu plus important dans Clochemerle.\u00a0 Il a donc un c\u00f4t\u00e9 un rien plus familial, plus abordable, mais sans qu&rsquo;il soit simple pour autant.\u00a0 Ils ne jouent donc pas vraiment dans la m\u00eame cat\u00e9gorie.\u00a0Je donnerais donc un ex-aequo : les 2 bo\u00eetes sont tout aussi indispensables l&rsquo;une que l&rsquo;autre (\u00e0 ceci pr\u00e8s que Clochemerle me semble plus adapt\u00e9 \u00e0 3 ou 4 joueurs).<\/p>\n<p><span style=\"text-decoration: underline;\"><strong><span style=\"color: #800080; text-decoration: underline;\">Nouvelle partie<\/span><\/strong><\/span>:<br \/>\nCette fois, nous y avons jou\u00e9 \u00e0 4.\u00a0 C&rsquo;est dans cette configuration que j&rsquo;ai le plus appr\u00e9ci\u00e9 le jeu. Le temps d&rsquo;attente entre 2 tours de jeu\u00a0est in\u00e9vitablement augment\u00e9, mais dans l&rsquo;ensemble, \u00a0le jeu m&rsquo;est apparu moins r\u00e9p\u00e9titif et donc plus plaisant.\u00a0 Une m\u00eame\u00a0strat\u00e9gie\u00a0est forc\u00e9ment\u00a0suivie par plusieurs joueurs, et l&rsquo;interaction (=la g\u00eane entre joueurs)\u00a0est donc plus importante.\u00a0 Mais il est tr\u00e8s difficile de suivre ce que font les autres joueurs en vue de\u00a0les bloquer\u00a0!\u00a0 Mons avis est toujours tr\u00e8s positif : c&rsquo;est d\u00e9finitivement un bon jeu !<\/p>\n<hr \/>\n<p><strong><span style=\"color: #333399;\">Thierry<\/span><\/strong>:<strong><span style=\"color: #800000;\">\u00a0\u00a08,8\/10<\/span><\/strong><\/p>\n<p>S&rsquo;il n&rsquo;atteint pas le niveau de Descendance, Clochemerle est incontestablement un tr\u00e8s bon jeu.\u00a0 Les d\u00e9s remplacent les cubes pour le choix des actions \u00e0 ex\u00e9cuter et par l\u00e0, pr\u00e9sentent quelques originalit\u00e9s en terme d&rsquo;activation de cartes. A 4 joueurs, la partie m&rsquo;a sembl\u00e9 fluide et les scores extr\u00eamement serr\u00e9s en fin de jeu m&rsquo;incite \u00e0 dire que Clochemerle est un jeu bien \u00e9quilibr\u00e9 (car chaque joueur avait opt\u00e9 pour une strat\u00e9gie diff\u00e9rente).\u00a0 Pour ma part, mes points se sont r\u00e9partis entre l&rsquo;\u00e9glise, le marchand et le maire (en archivant les \u00e9crits), tout en m&rsquo;appuyant sur le politique pour l&rsquo;octroi de ressources.\u00a0 Il me semble contre-productif de vouloir se diversifier trop.\u00a0 A recommander.<\/p>\n<hr \/>\n<p>&nbsp;<\/p>\n<p><a href=\"http:\/\/www.vindjeu.eu\/2016\/03\/21\/clochemerle-my-village\/1224-clochmerle-4\/\" rel=\"attachment wp-att-12910\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-12910\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2016\/01\/1224-Clochmerle-4.jpg\" alt=\"1224 Clochmerle 4\" width=\"1200\" height=\"900\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2016\/01\/1224-Clochmerle-4.jpg 4000w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2016\/01\/1224-Clochmerle-4-300x225.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2016\/01\/1224-Clochmerle-4-1024x768.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2016\/01\/1224-Clochmerle-4-160x120.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2016\/01\/1224-Clochmerle-4-326x245.jpg 326w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2016\/01\/1224-Clochmerle-4-453x340.jpg 453w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p> Bien que \u00ab\u00a0Clochemerle\u00a0\u00bb signifie \u00a0\u00ab\u00a0village d\u00e9chir\u00e9 par des querelles burlesques \u00bb (sic\u00a0\ud83d\ude42 ), il est assez \u00e9tonnant que Gigamic ait d\u00e9cid\u00e9 d\u2019appeler ce jeu \u00ab\u00a0Clochemerle\u00a0\u00bb\u00a0\ud83d\ude42\u00a0 Pegasus l\u2019a, quant \u00e0 lui, appel\u00e9 \u00ab\u00a0My Village\u00a0\u00bb.\u00a0 Je comprends beaucoup mieux \u00ab\u00a0My Village\u00a0\u00bb puisque le jeu est la version d\u00e9s de \u00ab\u00a0Village\u00a0\u00bb.\u00a0&#46;&#46;&#46;<\/p>\n","protected":false},"author":3,"featured_media":12911,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[4848],"tags":[817,7,276],"class_list":["post-12909","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-initie","tag-pascal","tag-swatsh","tag-thierry","annee-996","auteurs-inka-brand","auteurs-markus-brand","editeurs-gigamic","editeurs-pegasus-spiele"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/12909","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/comments?post=12909"}],"version-history":[{"count":0,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/12909\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media\/12911"}],"wp:attachment":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media?parent=12909"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/categories?post=12909"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/tags?post=12909"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}