{"id":1364,"date":"2010-11-03T01:25:32","date_gmt":"2010-11-03T00:25:32","guid":{"rendered":"http:\/\/www.vindjeu.eu\/?p=1364"},"modified":"2010-11-03T01:25:32","modified_gmt":"2010-11-03T00:25:32","slug":"safranito","status":"publish","type":"post","link":"https:\/\/www.vindjeu.eu\/prd\/2010\/11\/03\/safranito\/","title":{"rendered":"Safranito"},"content":{"rendered":"<p><a href=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2010\/10\/211-Safranito-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-1365\" title=\"211 Safranito 1\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2010\/10\/211-Safranito-1.jpg\" alt=\"\" width=\"246\" height=\"250\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2010\/10\/211-Safranito-1.jpg 246w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2010\/10\/211-Safranito-1-147x150.jpg 147w\" sizes=\"auto, (max-width: 246px) 100vw, 246px\" \/><\/a><\/p>\n<p><span style=\"color: #333399;\"><strong>SwatSh<\/strong><\/span>:<span style=\"color: #800000;\"><strong> 5 \/10<\/strong><\/span><\/p>\n<p>Safranito offre l&rsquo;originalit\u00e9 d&rsquo;\u00eatre un jeu mariant habilit\u00e9 et strat\u00e9gie.<\/p>\n<p>En effet, le but du jeu est de r\u00e9colter des ingr\u00e9dients n\u00e9cessaires \u00e0 pr\u00e9parer des plats (qui demandent un assortiment d&rsquo;ingr\u00e9dients).\u00a0 Mais pour r\u00e9colter ces ingr\u00e9dients, il va falloir les acheter et on arrive un moment donn\u00e9\u00a0\u00e0 court d&rsquo;argent.\u00a0 Il va donc falloir vendre certains ingr\u00e9dients lorsque leur valeur est haute.\u00a0 Voil\u00e0 pour la partie strat\u00e9gie.<\/p>\n<p>Pour la partie habilit\u00e9, et bien, tous ces ingr\u00e9dients se r\u00e9coltent via les jetons que chaque joueur lance sur le plateau en essayant de viser les bons ingr\u00e9dients ou certaines cases \u00ab\u00a0action bonus\u00a0\u00bb.<\/p>\n<p>De plus, il n&rsquo;est alors pas rare de combattre pour l&rsquo;un ou l&rsquo;autre ingr\u00e9dient.\u00a0 On lance alors son jeton dans le but d&rsquo;\u00e9jecter le jeton d&rsquo;un autre joueur.<\/p>\n<p>C&rsquo;est bien trouv\u00e9 mais cela reste dans le fond un simple jeu d&rsquo;adresse.\u00a0 Celui qui visera le mieux, gagnera.\u00a0 Et moi, je suis pas trop friands des jeu d&rsquo;adresses \u00e0 part les jeux tr\u00e8s fun comme Pitch Car que j&rsquo;adore.\u00a0 Mais ici, c&rsquo;est pas fun du tout et c&rsquo;est assez frustrant de lancer toujours \u00e0 c\u00f4te \ud83d\ude41<\/p>\n<p><span style=\"color: #333399;\"><strong>Philrey212<\/strong><\/span>:<span style=\"color: #800000;\"><strong> 6,5\/10<\/strong><\/span><\/p>\n<p><span style=\"color: #000000;\">Etonnant le commentaire de SwatSh. Dans ce d\u00e9but de partie sur le stand de Zoch, c&rsquo;est lui qui \u00e9tait en t\u00eate \ud83d\ude09<\/span><\/p>\n<p><span style=\"color: #000000;\">Safranito est en effet un jeu qui allie addresse et &#8230; je ne dirais pas strat\u00e9gie mais plut\u00f4t gestion. En effet, il faut rassembler les \u00e9pices n\u00e9cessaires aux trois recettes disponibles. Mais comme les recettes sont remplac\u00e9es d\u00e9s qu&rsquo;on a r\u00e9ussi \u00e0 r\u00e9unir les ingr\u00e9dients, le jeu consiste alors plus \u00e0 bien lancer\/viser ses jetons. La gestion intervient dans le fait que 3 jetons sur les 6 disponibles sont lanc\u00e9s sur le tableau de jeu. Les jetons ont une valeur de 10 \u00e0 60. Cette valeur sert \u00e0 d\u00e9terminer le prix d&rsquo;achat des \u00e9pices et \u00e9galement le prix de vente. <\/span><\/p>\n<p><span style=\"color: #000000;\">Les cartes \u00e9pices r\u00e9colt\u00e9es vont \u00e9galement servir \u00e0 vous renflouer financi\u00e8rement car il n&rsquo;y pas d&rsquo;autre source de revenu. <\/span><\/p>\n<p><span style=\"color: #000000;\">Bref, un jeu d&rsquo;adresse et de gestion qui ravira un public jeune. Certains appr\u00e9cieront plus le jet des jetons, d&rsquo;autre plus l&rsquo;aspect gestion. Il est clair qu&rsquo;un joueur plus habile que les autres gagnera facielement!<\/span><\/p>\n<p><a href=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2010\/10\/211-Safranito-2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-1366\" title=\"211 Safranito 2\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2010\/10\/211-Safranito-2-768x1024.jpg\" alt=\"\" width=\"542\" height=\"663\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p> Safranito offre l&rsquo;originalit\u00e9 d&rsquo;\u00eatre un jeu mariant habilit\u00e9 et strat\u00e9gie. En effet, le but du jeu est de r\u00e9colter des ingr\u00e9dients n\u00e9cessaires \u00e0 pr\u00e9parer des plats (qui demandent un assortiment d&rsquo;ingr\u00e9dients).\u00a0 Mais pour r\u00e9colter ces ingr\u00e9dients, il va falloir les acheter et on arrive un moment donn\u00e9\u00a0\u00e0&#46;&#46;&#46;<\/p>\n","protected":false},"author":2,"featured_media":1365,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[5],"tags":[6,7],"class_list":["post-1364","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-famille","tag-philrey212","tag-swatsh","annee-222","auteurs-teubner-marco","editeurs-zoch"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/1364","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/comments?post=1364"}],"version-history":[{"count":0,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/1364\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media\/1365"}],"wp:attachment":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media?parent=1364"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/categories?post=1364"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/tags?post=1364"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}