{"id":139,"date":"2009-12-13T20:26:00","date_gmt":"2009-12-13T19:26:00","guid":{"rendered":"http:\/\/www.vindjeu.eu\/2009\/12\/13\/um-ruhm-ehre-rhum-honneur-familial-2006-2-a-6-joueurs\/"},"modified":"2010-06-20T16:56:23","modified_gmt":"2010-06-20T15:56:23","slug":"um-ruhm-ehre-rhum-honneur","status":"publish","type":"post","link":"https:\/\/www.vindjeu.eu\/prd\/2009\/12\/13\/um-ruhm-ehre-rhum-honneur\/","title":{"rendered":"Um Ruhm &amp; Ehre (Rhum &amp; Honneur)"},"content":{"rendered":"<p><a href=\"http:\/\/1.bp.blogspot.com\/_ea2yja0GmY8\/SyVHzbccurI\/AAAAAAAAAok\/Vlo3eIs8hsI\/s1600-h\/Rhum&amp;Honneur00.JPG\"><img decoding=\"async\" id=\"BLOGGER_PHOTO_ID_5414813075848870578\" style=\"float: left; margin: 0px 10px 10px 0px; width: 175px; height: 250px;\" src=\"http:\/\/1.bp.blogspot.com\/_ea2yja0GmY8\/SyVHzbccurI\/AAAAAAAAAok\/Vlo3eIs8hsI\/s400\/Rhum%26Honneur00.JPG\" border=\"0\" alt=\"\" \/><\/a><\/p>\n<div><strong><span style=\"color: #66cccc;\">Philrey212:<\/span><\/strong> <strong><span style=\"color: #ff6666;\">7,2\/10<\/span><\/strong><\/div>\n<div>Um Ruhm &amp; Ehre (\u00e0 vos souhaits) Est un jeu de Stefan Feld (L&rsquo;Ann\u00e9e du Dragon, Les Pilliers de la Terre, Notre Dame) dan slequel les joueurs incarnent de courageux flibustiers arpentant les rues plus ou moins \u00e9clair\u00e9es du repaire des pirates.<\/div>\n<div>Rhum et Honneur (en fran\u00e7ais, c&rsquo;est plus facile) est un jeu l\u00e9ger qui plaira aux jeunes mais aussi aux adultes, \u00e0 condition de se laisser porter par le th\u00e8me et l&rsquo;ambiance!<\/div>\n<div>Parlons-en du th\u00e8me! Que font des flibustiers dans un repaire pirate? Tripots, coffres et cartes \u00e0 tr\u00e9sor, rendez-vous roses sont les actions possibles. C&rsquo;est du beau, pour les enfants!<\/div>\n<div>Heureusement qu&rsquo;il y a quelques gardes qui circulent dans ces rues plus ou moins \u00e9clair\u00e9es, un peu moins que plus!<\/div>\n<div>Le principe est assez simple. Chaque joueur a \u00e0 sa disposition 5 ou plus pirates. A son tour, on en place dans une rue (on remplit la rue enti\u00e8rement) pour d\u00e9placer le corsaire rouge. La case d&rsquo;arriv\u00e9e indique l&rsquo;action \u00e0 effectuer. On a aussi le choix de placer des pirates dans le bateau pour une bonne rixe.<\/div>\n<div>Le principe tient bien la route. Rien \u00e0 redire. Le th\u00e8me est aussi tr\u00e8s pr\u00e9sent et l&rsquo;interaction est tr\u00e8s pr\u00e9sente aussi car le joueur suivant devra partir de la nouvelle position du corsaire rouge.<\/div>\n<div>Quand tous les pirates sont plac\u00e9s, on r\u00e9soud la rixe. Et l\u00e0, pr\u00e9parez-vous \u00e0 lancer le d\u00e9 \u00e0 maintes reprises. C&rsquo;est un peu trop \u00e0 mon go\u00fbt (un peu trop r\u00e9p\u00e9titif) mais cela n&rsquo;enl\u00e8ve rien \u00e0 la bonne ambiance qui ne peut que se d\u00e9velopper autour de la table.<\/div>\n<div>En bref, un jeu familial par excellence, qui remplacera facilement le classique Monopoly!<\/div>\n<p><strong><span style=\"color: #33ccff;\">Beno\u00eet:<\/span><\/strong> <strong><span style=\"color: #ff6666;\">7,5\/10<\/span><\/strong><\/p>\n<div>Tr\u00e8s chouette a jouer avec les enfants (&gt; 8ans). J&rsquo;aime particuli\u00e8rement les invitations au bistro ou l&rsquo;on peut gagner pas mal de points de victoire. La r\u00e9solution de la rixe est un point faible du jeu&#8230; du moins pour les grands &#8211; il vaut mieux avoir du bol!<br \/>\nDiversit\u00e9 d&rsquo;action, bon rythme, simple mais pas d\u00e9bile, un bon jeu familial quoi!<\/div>\n<div><strong><span style=\"color: #33ccff;\">Maxime (9 ans):<\/span><\/strong> <span style=\"color: #ff6666;\"><strong>10\/10<\/strong><\/span><\/div>\n<p><img decoding=\"async\" id=\"BLOGGER_PHOTO_ID_5414811660947802722\" style=\"display: block; margin: 0px auto 10px; width: 400px; height: 300px; text-align: center;\" src=\"http:\/\/3.bp.blogspot.com\/_ea2yja0GmY8\/SyVGhEhvymI\/AAAAAAAAAoc\/SJOPq3iDaDQ\/s400\/Rhum%26Honneur01.JPG\" border=\"0\" alt=\"\" \/>On remarque les pirates qui remplissent les rues du repaire. A droite, le mat du b\u00e2teau qui sert de base pour r\u00e9soudre la rixe.<\/p>\n<div>Remarquez le casier de rangement. Du jamais vu. Similaire \u00e0 celui de Smallworld mais nettement plus pratique avec le fond en oblique.<\/div>\n","protected":false},"excerpt":{"rendered":"<p> Um Ruhm &amp; Ehre (\u00e0 vos souhaits) Est un jeu de Stefan Feld (L&rsquo;Ann\u00e9e du Dragon, Les Pilliers de la Terre, Notre Dame) dan slequel les joueurs incarnent de courageux flibustiers arpentant les rues plus ou moins \u00e9clair\u00e9es du repaire des pirates. Rhum et Honneur (en fran\u00e7ais, c&rsquo;est&#46;&#46;&#46;<\/p>\n","protected":false},"author":2,"featured_media":9032,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[5],"tags":[8,6],"class_list":["post-139","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-famille","tag-benoit","tag-philrey212","annee-29","auteurs-stefan-feld","editeurs-alea"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/139","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/comments?post=139"}],"version-history":[{"count":0,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/139\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media\/9032"}],"wp:attachment":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media?parent=139"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/categories?post=139"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/tags?post=139"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}