{"id":143,"date":"2009-12-20T17:40:00","date_gmt":"2009-12-20T16:40:00","guid":{"rendered":"http:\/\/www.vindjeu.eu\/2009\/12\/20\/roads-boats\/"},"modified":"2013-09-18T08:15:37","modified_gmt":"2013-09-18T07:15:37","slug":"roads-boats","status":"publish","type":"post","link":"https:\/\/www.vindjeu.eu\/prd\/2009\/12\/20\/roads-boats\/","title":{"rendered":"Roads &amp; Boats"},"content":{"rendered":"<p><a href=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2009\/12\/628-Roads-Boats-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-5851\" title=\"628 Roads &amp; Boats 1\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2009\/12\/628-Roads-Boats-1.jpg\" alt=\"\" width=\"306\" height=\"500\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2009\/12\/628-Roads-Boats-1.jpg 306w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2009\/12\/628-Roads-Boats-1-183x300.jpg 183w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2009\/12\/628-Roads-Boats-1-91x150.jpg 91w\" sizes=\"auto, (max-width: 306px) 100vw, 306px\" \/><\/a><br \/>\n<span style=\"color: #333399;\"><strong><span id=\"SPELLING_ERROR_2\" class=\"blsp-spelling-error\">SwatSh<\/span><\/strong><\/span>:<span style=\"color: #800000;\"><strong> 8 \/10<\/strong><\/span><br \/>\nJ&rsquo;attendais beaucoup de ce ma\u00eetre du <span id=\"SPELLING_ERROR_3\" class=\"blsp-spelling-error\">Pick<\/span> <span id=\"SPELLING_ERROR_4\" class=\"blsp-spelling-error\">up<\/span> &amp; <span id=\"SPELLING_ERROR_5\" class=\"blsp-spelling-error\">Delivery<\/span> qu&rsquo;est <span id=\"SPELLING_ERROR_6\" class=\"blsp-spelling-error\">Roads<\/span> &amp; <span id=\"SPELLING_ERROR_7\" class=\"blsp-spelling-error\">Boats<\/span> et je n&rsquo;ai pas \u00e9t\u00e9 d\u00e9\u00e7u.<\/p>\n<p><span id=\"SPELLING_ERROR_8\" class=\"blsp-spelling-error\">Roads<\/span> &amp; <span id=\"SPELLING_ERROR_9\" class=\"blsp-spelling-error\">Boats<\/span> est un jeu de civilisation mais au lieu de faire grandir nos villes, ici, on doit faire \u00e9voluer nos moyens de transport!<\/p>\n<p>La <span style=\"color: #009900;\"><strong>m\u00e9canique<\/strong><\/span> n&rsquo;est pas <span id=\"SPELLING_ERROR_10\" class=\"blsp-spelling-error\">innovante<\/span> (et pour cause puisqu&rsquo;il a d\u00e9j\u00e0 10 ans) mais fonctionne tr\u00e8s bien. En partant de rien, ou presque (quelques maigres ressources), on va construire des b\u00e2timents qui nous permettront de r\u00e9colter des mati\u00e8res premi\u00e8res qui nous permettront de construire de meilleurs b\u00e2timents qui transformeront la mati\u00e8re premi\u00e8re en mati\u00e8re qui nous permettra de faire \u00e9voluer nos moyens de transport et de fabriquer des billets de banque, <span id=\"SPELLING_ERROR_11\" class=\"blsp-spelling-corrected\">synonymes<\/span> de points de victoire.<\/p>\n<p>Toute la m\u00e9canique repose sur la qualit\u00e9 de nos moyens de transport qui pourront se d\u00e9placer plus loin et transporter plus de mati\u00e8re.<\/p>\n<p><span id=\"SPELLING_ERROR_12\" class=\"blsp-spelling-error\">Roads<\/span> &amp; <span id=\"SPELLING_ERROR_13\" class=\"blsp-spelling-error\">Boats<\/span> est tr\u00e8s <span style=\"color: #009900;\"><strong>strat\u00e9gique<\/strong><\/span> et tr\u00e8s tactique. Tout en optimalisant ses coups, on se doit d&rsquo;avoir une vue long terme afin de rester coh\u00e9rent dans ses choix de construction. En effet, une grande partie de la difficult\u00e9 du jeu est l\u00e0. Les cartes sont relativement petites et on ne sait pas tout construire.<br \/>\nDe plus, vu le nombre de constructions possibles, les strat\u00e9gies possibles sont tr\u00e8s nombreuses et j&rsquo;ai h\u00e2te de recommencer une partie en modifiant ma strat\u00e9gie.<\/p>\n<p>Le plateau est compos\u00e9 de diff\u00e9rents <span style=\"color: #009900;\"><strong>hexagones<\/strong><\/span> comme pour les Colons de <span id=\"SPELLING_ERROR_14\" class=\"blsp-spelling-error\">Catane<\/span>, ce qui permet une tr\u00e8s grande vari\u00e9t\u00e9 des parties et un nombre infini de possibilit\u00e9s. Apr\u00e8s l&rsquo;avoir constitu\u00e9, on doit placer dessus une feuille en plastique transparent afin de pouvoir y dessiner nos routes. J&rsquo;avais tr\u00e8s peur de cet aspect et craignais que ce plastique ne s&rsquo;enroule trop souvent. Mais pas du tout! En le collant avec du papier collant sur chaque c\u00f4t\u00e9s, nous n&rsquo;avons eu aucun probl\u00e8me.<\/p>\n<p>Le tout gros d\u00e9faut du jeu est sa <span style=\"color: #009900;\"><strong>dur\u00e9e<\/strong><\/span>. A deux joueurs, vous devez compter 4 heures de jeu. A plus de deux, je n&rsquo;ose imaginer&#8230; Personnellement, \u00e7a me bloque un peu un jeu trop long. Car terminer \u00e0 2 heures du matin, c&rsquo;est dur pour le lendemain&#8230;<\/p>\n<p><span style=\"text-decoration: underline;\"><span style=\"color: #808000; text-decoration: underline;\">Nouvelle partie:<\/span><\/span><\/p>\n<p>L\u00e9g\u00e8rement d\u00e9\u00e7u par cette partie \u00e0 3 joueurs.\u00a0 Bon Roads &amp; Boats reste un ma\u00eetre du genre \u00ab\u00a0pick up &amp; delivery\u00a0\u00bb gr\u00e2ce \u00e0 plusieurs \u00e9l\u00e9ments: son c\u00f4t\u00e9 jeu de civilisation o\u00f9 l&rsquo;ont passe \u00e0 travers les \u00e2ges en d\u00e9veloppant ses b\u00e2timents et moyens de transport.\u00a0 Son plateau totalement modulable permet une vari\u00e9t\u00e9 de parties infinie, des \u00e9changes de \u00ab\u00a0sc\u00e9narios\u00a0\u00bb,&#8230;<\/p>\n<p>N\u00e9anmoins, Roads &amp; Boats m&rsquo;a l\u00e9g\u00e8rement d\u00e9\u00e7u vu surtout son c\u00f4t\u00e9 \u00ab\u00a0vieillot\u00a0\u00bb.\u00a0 Et oui, Roads &amp; Boats a vieilli et reste un jeu \u00e0 l&rsquo;ancienne:<br \/>\n&#8211; D&rsquo;abord ses r\u00e8gles fort compliqu\u00e9es qui s&rsquo;expliquent en plus d&rsquo;une heure et dont les joueurs ne retiennent pas tout directement, doivent poser des questions en cours de jeu et oublient une partie influen\u00e7ant la qualit\u00e9 de la partie.\u00a0 Son mat\u00e9riel vieillot n&rsquo;aide pas non plus dans la m\u00e9morisation des r\u00e8gles: pas de rappel de certains points de r\u00e8gles sur le plateau, les tuiles b\u00e2timent n&rsquo;indiquent pas leur co\u00fbt ni leur effet,&#8230;<br \/>\n&#8211; De plus, me matos est too much: plein de petites pi\u00e8ces diverses en carton fin, on a difficile \u00e0 s&rsquo;en sortir.<br \/>\n&#8211; Enfin, et pour moi le plus grand reproche: une dur\u00e9e de jeu excessivement longue, plus de 5 heures de jeu \u00e0 3 joueurs, on se lasse \u00e0 la fin.\u00a0 Surtout que la m\u00e9canique est assez r\u00e9p\u00e9titive: produire des mati\u00e8res, les transporter \u00e0 d&rsquo;autres endroits pour en produire d&rsquo;autres ou construire de nouveaux b\u00e2timents.\u00a0 Apr\u00e8s 5 heures de jeu, m\u00eame si le jeu \u00e9volue et l&rsquo;interactivit\u00e9 devient de plus en plus grande au fil du temps, une certaine lassitude arrive et on en a marre de faire toujours la m\u00eame chose.<\/p>\n<p>Roads &amp; Boats reste donc un jeu culte, le ma\u00eetre des jeux de pick up &amp; delivery mais devrait \u00eatre revu pour avoir un mat\u00e9riel plus agr\u00e9able, des r\u00e8gles plus simples et surtout une dur\u00e9e de jeu raccourcie.<\/p>\n<p style=\"text-align: center;\">___________________<\/p>\n<p>\u00a0<span style=\"color: #333399;\"><strong><span id=\"SPELLING_ERROR_15\" class=\"blsp-spelling-error\">Philrey<\/span>212<\/strong><\/span>:<span style=\"color: #800000;\"><strong> 8\/10<\/strong><\/span><\/p>\n<p>Roads &amp; Boats est mon deuxi\u00e8me Splotter en peu de temps. Je dois dire que celui-ci me convainc beaucoup plus que le premier (Duck Dealer).<br \/>\nDans les plus:<br \/>\n+ In fine, les r\u00e8gles, bien qu&rsquo;asser nombreuses, ne sont pas complexes \u00e0 assimiler;<br \/>\n+ Le fait que les usines et ressources n&rsquo;appartiennent \u00e0 personnes lorsque d\u00e9pos\u00e9es sur le plateau. Dans notre partie, \u00e9tant le premier \u00e0 construire des barques, je f\u00fbt le seul \u00e0 construire des plateformes p\u00e9troli\u00e8res. Apr\u00e8s la phase de production, SwatSh est venu se servir dans MES plateformes;<br \/>\n+ Les joueurs effectuent chaque phase simultan\u00e9ment, tant qu&rsquo;il n&rsquo;y a pas de conflit potentiel;<br \/>\n+ L&rsquo;\u00e9volution des anes en chariots pui en camions. Bien pens\u00e9, car impossible de passer directement au camion pour le transport;<br \/>\n+ Le jeu se d\u00e9roule sans pause, quasi, ce qui fait qu&rsquo;on ne voit pas le temps passer<br \/>\n+ Roads &amp; Boats est strat\u00e9gique, laissant une vision long terme sur la partie;<br \/>\nDans les moins:<br \/>\n&#8211; Et bien, on n&rsquo;a pas termin\u00e9 la partie, apr\u00e8s 3 heures de jeu. Et \u00e0 deux en plus;<br \/>\n&#8211; Dans notre partie \u00e0 2 joueurs, pas d&rsquo;interactivit\u00e9, chacun se d\u00e9veloppait dans son coin. M\u00eame si, je pense, on commen\u00e7ait \u00e0 se rapprocher et l&rsquo;impact des actions de l&rsquo;un sur l&rsquo;autre (et vice versa) auraient sans doute pris plus d&rsquo;importance. On n&rsquo;aurait sans doute plus pu jouer les phases simultan\u00e9ment, ce qui aurait ralentit le jeu;<br \/>\n&#8211; Enorm\u00e9ment de petites pi\u00e8ces et de \u00ab\u00a0micro-gestion\u00a0\u00bb, entendez par l\u00e0 beaucoup de manipulation (ajouter un tronc, l&rsquo;\u00e9changer contre deux planches, \u00e9changer les deux planches en papier, etc.;<br \/>\n&#8211; Les tours de jeu sont asser r\u00e9p\u00e9titifs, m\u00eame si pas ennuyant du tout car chacun est dans sa r\u00e9flexion de strat\u00e9gie;<br \/>\n&#8211; Je questionne l&rsquo;utilit\u00e9 de certaines ressources: par exemple la mine d&rsquo;argile qui permet d&rsquo;obtenir des briques, que l&rsquo;on obtient d\u00e9j\u00e0, \u00e0 moindre d\u00e9bit, ailleurs. Surtout compte tenu que la brique n&rsquo;est demand\u00e9 que pour les route est 1 ou 2 b\u00e2timents. On peut voir ci-dessous le joueur qui qui avait le plus de brique car il a le r\u00e9seau routier le plus d\u00e9velopp\u00e9.<br \/>\n&#8211; La dur\u00e9e d&rsquo;une partie est longue, tr\u00e8s longue. Mais bon, chez Vin d&rsquo;Jeu, \u00e7a nous ne emb\u00eate pas \ud83d\ude09<br \/>\nConclusion:<br \/>\nEt bien, ce f\u00fbt une agr\u00e9able surprise, surtout apr\u00e8s le premier Splotter que j&rsquo;ai trouv\u00e9 plus moyen.<br \/>\nJe me pose quand m\u00eame quelques questions:<br \/>\n. Roads&amp;Boats ne devient-il pas plus chaotique \u00e0 4 joueurs?<br \/>\n. Le jeu est-il plus interactif \u00e0 plus que 2 joueurs?<br \/>\n. Le fait d&rsquo;\u00eatre plus interactif (plus de joueurs) impacte-t-il la dur\u00e9e d&rsquo;une partie?<br \/>\nIl faudra donc qu&rsquo;on r\u00e9serve une autre apr\u00e8s-midi ou longue soir\u00e9e pour refaire une partie!<\/p>\n<p style=\"text-align: center;\">\n<p style=\"text-align: center;\">_______________<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<div><a href=\"http:\/\/3.bp.blogspot.com\/_ea2yja0GmY8\/Sy5T8LqymDI\/AAAAAAAAAps\/GMVTOM0ZG-M\/s1600-h\/126+Roads+and+boats+2.JPG\"><img decoding=\"async\" id=\"BLOGGER_PHOTO_ID_5417359695162808370\" style=\"display: block; margin: 0px auto 10px; width: 400px; cursor: hand; height: 300px; text-align: center;\" src=\"http:\/\/3.bp.blogspot.com\/_ea2yja0GmY8\/Sy5T8LqymDI\/AAAAAAAAAps\/GMVTOM0ZG-M\/s400\/126+Roads+and+boats+2.JPG\" alt=\"\" border=\"0\" \/><\/a> Notre partie n&rsquo;a pas \u00e9t\u00e9 tr\u00e8s interactive: Un joueur s&rsquo;est d\u00e9velopp\u00e9 \u00e0 droite et l&rsquo;autre \u00e0 gauche.<\/div>\n<div>Mais ce n&rsquo;est pas un reproche que je fais au jeu, il suffit d&rsquo;avoir une carte moins allong\u00e9e et on l&rsquo;aura notre <span id=\"SPELLING_ERROR_16\" class=\"blsp-spelling-error\"><span style=\"color: #009900;\"><strong>interactivit\u00e9<\/strong><\/span><\/span>!<\/div>\n<div><\/div>\n<div><a href=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2009\/12\/628-Roads-Boats-2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-5852\" title=\"628 Roads &amp; Boats 2\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2009\/12\/628-Roads-Boats-2-1024x768.jpg\" alt=\"\" width=\"819\" height=\"614\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2009\/12\/628-Roads-Boats-2-1024x768.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2009\/12\/628-Roads-Boats-2-300x225.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2009\/12\/628-Roads-Boats-2-150x112.jpg 150w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2009\/12\/628-Roads-Boats-2-400x300.jpg 400w\" sizes=\"auto, (max-width: 819px) 100vw, 819px\" \/><\/a><\/div>\n<div><\/div>\n","protected":false},"excerpt":{"rendered":"<p> J&rsquo;attendais beaucoup de ce ma\u00eetre du Pick up &amp; Delivery qu&rsquo;est Roads &amp; Boats et je n&rsquo;ai pas \u00e9t\u00e9 d\u00e9\u00e7u. Roads &amp; Boats est un jeu de civilisation mais au lieu de faire grandir nos villes, ici, on doit faire \u00e9voluer nos moyens de transport! La m\u00e9canique&#46;&#46;&#46;<\/p>\n","protected":false},"author":2,"featured_media":5851,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[4849],"tags":[6,7],"class_list":["post-143","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-expert","tag-philrey212","tag-swatsh","annee-181","auteurs-jeroen-doumen","editeurs-splotter-spellen"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/143","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/comments?post=143"}],"version-history":[{"count":0,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/143\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media\/5851"}],"wp:attachment":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media?parent=143"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/categories?post=143"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/tags?post=143"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}