{"id":15749,"date":"2017-01-10T20:46:22","date_gmt":"2017-01-10T19:46:22","guid":{"rendered":"http:\/\/www.vindjeu.eu\/?p=15749"},"modified":"2017-01-10T20:46:22","modified_gmt":"2017-01-10T19:46:22","slug":"small-star-empires","status":"publish","type":"post","link":"https:\/\/www.vindjeu.eu\/prd\/2017\/01\/10\/small-star-empires\/","title":{"rendered":"Small Star Empires"},"content":{"rendered":"<p><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-15750 size-medium\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2016\/12\/box_smallStarE-300x300.jpg\" alt=\"box_smallstare\" width=\"300\" height=\"300\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2016\/12\/box_smallStarE-300x300.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2016\/12\/box_smallStarE-150x150.jpg 150w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2016\/12\/box_smallStarE-160x160.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2016\/12\/box_smallStarE-245x245.jpg 245w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2016\/12\/box_smallStarE-340x340.jpg 340w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2016\/12\/box_smallStarE.jpg 500w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><a href=\"http:\/\/www.vindjeu.eu\/2017\/01\/08\/istanbul-brief-siegel\/phil-4\/\" rel=\"attachment wp-att-15724\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-thumbnail wp-image-15724\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2016\/12\/Phil-4-150x150.jpg\" alt=\"phil-4\" width=\"150\" height=\"150\" \/><\/a><\/strong><\/p>\n<p><strong><span style=\"color: #333399;\">Philrey<\/span><\/strong>:<strong><span style=\"color: #800000;\">\u00a07,5\/10<\/span><\/strong><\/p>\n<p>Small Star Empires est un jeu qui est pr\u00e9sent\u00e9 dans une petite bo\u00eete, avec de petites tuiles. Les photos que l&rsquo;on retrouve sur le net sont parfois trompeuses.<\/p>\n<p>On a ici affaire \u00e0 un petit jeu bien l\u00e9ger dont la m\u00e9canique me fait penser \u00e0 Battle Sheep et \u00e0 Splitz. En effet, le d\u00e9placement est similaire.<\/p>\n<p><strong>Un tour de jeu:<\/strong><\/p>\n<p>D\u00e9placer un vaisseau. La r\u00e8gle de base est qu&rsquo;on d\u00e9place son vaisseau d&rsquo;autant de cases que l&rsquo;on veut mais en ligne droite (et oui, nous venons tout juste de d\u00e9couvrir le voyage interstellaire). On colonise ensuite la case d&rsquo;arriv\u00e9e en pla\u00e7ant soit une colonie soit un comptoir commercial. Dans les deux cas, nous contr\u00f4lons d\u00e8s lors ce syst\u00e8me. Nos colonies et comptoirs commerciaux emp\u00eachent le d\u00e9placement des vaisseaux adverses.<\/p>\n<p><strong>Fin:<\/strong><\/p>\n<p>Petit \u00e0 petit, le plateau se remplit et la fin de la partie approche: lorsqu&rsquo;on on ne parvient plus \u00e0 d\u00e9placer aucun de nos vaisseaux.<br \/>\n<a href=\"http:\/\/www.vindjeu.eu\/2017\/01\/10\/small-star-empires\/1402-small-star-empire-2\/\" rel=\"attachment wp-att-15758\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-15758\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2016\/12\/1402-Small-star-empire-2-1024x683.jpg\" alt=\"1402-small-star-empire-2\" width=\"620\" height=\"413\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2016\/12\/1402-Small-star-empire-2-1024x683.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2016\/12\/1402-Small-star-empire-2-300x200.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2016\/12\/1402-Small-star-empire-2-768x512.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2016\/12\/1402-Small-star-empire-2-160x107.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2016\/12\/1402-Small-star-empire-2-368x245.jpg 368w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2016\/12\/1402-Small-star-empire-2-510x340.jpg 510w\" sizes=\"auto, (max-width: 620px) 100vw, 620px\" \/><\/a><\/p>\n<p><strong>Les points:<\/strong><\/p>\n<p>Chaque syst\u00e8me (ou presque) poss\u00e8de de une \u00e0 trois plan\u00e8tes, donnant de un \u00e0 trois PV. D&rsquo;autres montrent des n\u00e9buleuses de plusieurs couleurs. En contr\u00f4ler plusieurs de m\u00eame couleur nous donnent des PV \u00e9galement. Enfin, notre zone la plus \u00e9tendue de syst\u00e8mes nous donne des PV \u00e9galement.<\/p>\n<p><strong>Conclusion:<\/strong><\/p>\n<p>Small Star Empires est un petit jeu rapide. Le d\u00e9but de partie est assez clair pour les joueurs qui se pr\u00e9cipitent vers les syst\u00e8mes \u00e0 PV (3 plan\u00e8tes et n\u00e9buleuses) mais demande de plus en plus de r\u00e9flexion au fur et \u00e0 mesure que la partie avance. En effet, on essaiera alors d&rsquo;\u00e9tendre son syst\u00e8me (pour \u00eatre le plus grand), de bloquer l&rsquo;adversaire tout en pr\u00eatant attention \u00e0 ne pas l&rsquo;\u00eatre soi m\u00eame.<\/p>\n<hr \/>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-thumbnail wp-image-14306\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2016\/07\/1P-Pascal1-150x150.jpg\" alt=\"???????????????????????????????\" width=\"150\" height=\"150\" \/><\/p>\n<p><strong><span style=\"color: #333399;\">Pascal<\/span><\/strong>:<strong><span style=\"color: #800000;\">\u00a07\/10<\/span><\/strong><\/p>\n<p>Le format de Small Star Empires est int\u00e9ressant : la bo\u00eete est petite, les r\u00e8gles sont simples et courtes. \u00a0La dur\u00e9e de jeu est tr\u00e8s contenue et plusieurs variantes permettent de varier les parties.<\/p>\n<p>Concernant la m\u00e9canique, rien de r\u00e9volutionnaire. \u00a0C&rsquo;est un jeu de placement et de blocage. \u00a0A votre tour, vous d\u00e9placez votre vaisseau en ligne droite, et sur la case d&rsquo;arriv\u00e9e, vous placez une colonie ou un comptoir commercial. \u00a0Cette case ne sera plus accessible aux adversaires.<\/p>\n<p>Le th\u00e8me est un peu trop plaqu\u00e9 pour que j&rsquo;accroche au jeu. \u00a0On est en effet \u00e0 la limite de l&rsquo;abstrait.<\/p>\n<hr \/>\n<p><a href=\"http:\/\/www.vindjeu.eu\/2017\/01\/10\/small-star-empires\/1402-small-star-empire-4\/\" rel=\"attachment wp-att-15757\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-15757\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2016\/12\/1402-Small-star-empire-4.jpg\" alt=\"1402-small-star-empire-4\" width=\"6000\" height=\"4000\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2016\/12\/1402-Small-star-empire-4.jpg 6000w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2016\/12\/1402-Small-star-empire-4-300x200.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2016\/12\/1402-Small-star-empire-4-768x512.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2016\/12\/1402-Small-star-empire-4-1024x683.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2016\/12\/1402-Small-star-empire-4-160x107.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2016\/12\/1402-Small-star-empire-4-368x245.jpg 368w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2016\/12\/1402-Small-star-empire-4-510x340.jpg 510w\" sizes=\"auto, (max-width: 6000px) 100vw, 6000px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p> Small Star Empires est un jeu qui est pr\u00e9sent\u00e9 dans une petite bo\u00eete, avec de petites tuiles. Les photos que l&rsquo;on retrouve sur le net sont parfois trompeuses. On a ici affaire \u00e0 un petit jeu bien l\u00e9ger dont la m\u00e9canique me fait penser \u00e0 Battle Sheep et \u00e0&#46;&#46;&#46;<\/p>\n","protected":false},"author":4,"featured_media":15750,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[5],"tags":[817,6],"class_list":["post-15749","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-famille","tag-pascal","tag-philrey212","annee-1090","auteurs-milan-tasevski","editeurs-archona-games"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/15749","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/comments?post=15749"}],"version-history":[{"count":0,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/15749\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media\/15750"}],"wp:attachment":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media?parent=15749"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/categories?post=15749"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/tags?post=15749"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}