{"id":1616,"date":"2011-02-28T12:09:00","date_gmt":"2011-02-28T11:09:00","guid":{"rendered":"http:\/\/www.vindjeu.eu\/?p=1616"},"modified":"2016-07-27T21:31:16","modified_gmt":"2016-07-27T19:31:16","slug":"the-boss","status":"publish","type":"post","link":"https:\/\/www.vindjeu.eu\/prd\/2011\/02\/28\/the-boss\/","title":{"rendered":"The Boss"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p><span style=\"color: #333399;\"><span style=\"color: #ff6600;\"><a href=\"http:\/\/www.vindjeu.eu\/2011\/02\/28\/the-boss\/1307-the-boss-1\/\" rel=\"attachment wp-att-14156\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-14156\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2011\/02\/1307-The-Boss-1.jpg\" alt=\"1307 The Boss 1\" width=\"388\" height=\"400\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2011\/02\/1307-The-Boss-1.jpg 388w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2011\/02\/1307-The-Boss-1-291x300.jpg 291w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2011\/02\/1307-The-Boss-1-155x160.jpg 155w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2011\/02\/1307-The-Boss-1-237x245.jpg 237w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2011\/02\/1307-The-Boss-1-329x340.jpg 329w\" sizes=\"auto, (max-width: 388px) 100vw, 388px\" \/><\/a><\/span><\/span><\/p>\n<p><span style=\"color: #333399;\"><strong>SwatSh<\/strong><\/span>:<span style=\"color: #800000;\"><strong> 7,5 \/10<\/strong><\/span><\/p>\n<p>Une bien belle surprise que ce The Boss.\u00a0 J&rsquo;avais lu les r\u00e8gles sur internet, et \u00e7a ne m&rsquo;avait pas l&rsquo;air trop \u00e0 mon go\u00fbt.\u00a0 Mais bon, tant que je n&rsquo;y avais pas go\u00fbt\u00e9&#8230; \ud83d\ude09<\/p>\n<p>Cette partie \u00e0 2 m&rsquo;a enchant\u00e9e.\u00a0 Ce qui parrait juste un petit jeu de majorit\u00e9 s&rsquo;av\u00e8re \u00eatre \u00e9galement un jeu de bluff, o\u00f9 l&rsquo;on d\u00e9voile progressivement les informations tout en en gardant pour soi et ou une tension montante op\u00e8re: mais quelle est cette derni\u00e8re carte sur laquelle j&rsquo;ai pari\u00e9?\u00a0 Pourquoi n&rsquo;ench\u00e9rit-il pas sur moi?,&#8230;<\/p>\n<p>Ces derniers jeux de cartes Fran\u00e7ais (The Boss, Hanabi) apportent de l&rsquo;air frais dans le monde ludique.\u00a0 Merci aux auteurs et \u00e9diteurs de nous livrer de si beaux joyaux \ud83d\ude09<\/p>\n<p><span style=\"color: #008000;\"><strong><span style=\"text-decoration: underline;\">Seconde partie:<\/span><\/strong><\/span><\/p>\n<p><span style=\"color: #000000;\">Ma premi\u00e8re partie \u00e0 plus de 2 joueurs.\u00a0\u00a0 On \u00e9tait 4 et il est clair qu&rsquo;\u00e0 4, c&rsquo;est plus chaotique.\u00a0 Difficile de ma\u00eetriser ce que les autres joueurs vont faire.\u00a0 Difficile de voir dans leur jeu.\u00a0 Je pr\u00e9f\u00e8re le jeu \u00e0 2 o\u00f9 la ma\u00eetrise est plus grande.<\/span><\/p>\n<p><strong><span style=\"color: #800080;\">Derni\u00e8re partie<\/span><\/strong>:<\/p>\n<p>The Boss est toujours aussi agr\u00e9able \u00e0 jouer bien que j\u2019ai ressenti un certain manque de contr\u00f4le.\u00a0 L\u2019ordre du jeu est beaucoup trop important et quand le tour arrive o\u00f9 vous jouez premier, il vous faudra beaucoup de circonstances favorables pour vous en sortir.\u00a0 Le jeu peut \u00e9galement \u00eatre frustrant car quand \u00e7a ne tourne pas pour vous, vous vous retrouvez vite distanc\u00e9 sans espoir de revenir.\u00a0 Ce qui n\u2019emp\u00eache que c\u2019est le genre de jeu \u00e0 demander une revanche qui se d\u00e9roulera certainement autrement.\u00a0 Son petit format et la facilit\u00e9 de ses r\u00e8gles en font un jeu id\u00e9al durant les vacances\u00a0\ud83d\ude42<\/p>\n<hr \/>\n<p><span style=\"color: #000080;\"><strong>Philrey:<\/strong><\/span> <span style=\"color: #800000;\"><strong>8\/10<a href=\"http:\/\/www.vindjeu.eu\/2011\/02\/28\/the-boss\/sony-dsc-187\/\" rel=\"attachment wp-att-14159\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-14159\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2011\/02\/1307-The-Boss-2-1024x681.jpg\" alt=\"SONY DSC\" width=\"500\" height=\"333\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2011\/02\/1307-The-Boss-2-1024x681.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2011\/02\/1307-The-Boss-2-300x199.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2011\/02\/1307-The-Boss-2-160x106.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2011\/02\/1307-The-Boss-2-368x245.jpg 368w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2011\/02\/1307-The-Boss-2-510x340.jpg 510w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a><\/strong><\/span><\/p>\n<p>Voil\u00e0 la plus belle surprise des jeux jou\u00e9s \u00e0 Essen cette ann\u00e9e. Ce petit jeu de carte est super interactif o\u00f9 le bluff est (presque) indispensable. C&rsquo;est aussi un jeu attentiste puisque qu&rsquo;il faut \u00e9viter de r\u00e9v\u00e9ler ses cartes \u00ab\u00a0ma\u00eetresses\u00a0\u00bb trop t\u00f4t. Vraiment super<\/p>\n<hr \/>\n<p><span style=\"color: #333399;\"><strong>Raf<\/strong><\/span>:<strong><span style=\"color: #800000;\"> 7\/10<\/span><\/strong><\/p>\n<p><span style=\"color: #000000;\">Une seule partie \u00e0 4, et force est de constater que le jeu a du potentiel mais qu&rsquo;il est difficile de l&rsquo;exploiter \u00e0 4, sur les 4 manches, j&rsquo;ai eu la chance d&rsquo;avoir 2 fois un tirage qui me permettait d&rsquo;influencer le jeu et donc de prendre un certain plaisir parcontre quand le tirage ne vous favorise pas et qu&rsquo;il faut juste subir le jeu sans rien pouvoir faire cela devient nettement moins drole d&rsquo;autant plus si les joueurs autour de la table prennent leur temps pour jouer!<\/span><\/p>\n<hr \/>\n<p><strong><span style=\"color: #333399;\">Thierry<\/span><\/strong>:<strong><span style=\"color: #800000;\">\u00a0\u00a09\/10<\/span><\/strong><\/p>\n<p>The Boss est un jeu de bluff sublime, j&rsquo;adore. Jeu d&rsquo;ambiance par excellence, il est accessible \u00e0 tous et s&rsquo;appr\u00e9cie d&rsquo;autant plus qu&rsquo;il y a de joueurs. Petit jeu transportable partout, il se joue rapidement et je vous le recommande particuli\u00e8rement pour vos vacances. Bon amusement.<\/p>\n<hr \/>\n<p><span style=\"color: #000080;\"><strong><a href=\"http:\/\/www.vindjeu.eu\/2011\/02\/28\/the-boss\/sony-dsc-188\/\" rel=\"attachment wp-att-14160\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-14160\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2011\/02\/1307-The-Boss-3-1024x681.jpg\" alt=\"SONY DSC\" width=\"550\" height=\"366\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2011\/02\/1307-The-Boss-3-1024x681.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2011\/02\/1307-The-Boss-3-300x199.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2011\/02\/1307-The-Boss-3-160x106.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2011\/02\/1307-The-Boss-3-368x245.jpg 368w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2011\/02\/1307-The-Boss-3-510x340.jpg 510w\" sizes=\"auto, (max-width: 550px) 100vw, 550px\" \/><\/a>Ren:<\/strong><\/span> <span style=\"color: #800000;\"><strong>9,5\/10<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\">Voil\u00e0 un superbe jeu, r\u00e9unissant une foule de qualit\u00e9s dans un petit format. Les joueurs incarnent des gangsters qui doivent essayer de prendre le contr\u00f4le des grandes villes am\u00e9ricaines. A chaque fin de tour celui qui contr\u00f4le la ville b\u00e9n\u00e9ficiera recevra une r\u00e9compense (carte cach\u00e9e), souvent positive (argent), parfois n\u00e9gative (gangster tu\u00e9, en prison, bless\u00e9&#8230;). Tous les joueurs re\u00e7oivent des cartes en d\u00e9but de tour, cartes qui repr\u00e9sentent les r\u00e9compenses possibles pour toutes les villes. Chaque joueur a donc une partie des informations (si j&rsquo;ai la carte 1000 dollars en main, je sais que ce n&rsquo;est pas la carte cach\u00e9e) mais pas toutes. A chaque round, un joueur pose une carte, face visible (et donc r\u00e9v\u00e8le une information aux autres joueurs) et pose \u00e9ventuellement un ou plusieurs gangsters sur une ville, pour en prendre provisoirement le contr\u00f4le. Si un ou plusieurs gangsters adverses sont d\u00e9j\u00e0 pr\u00e9sents, on ne peut poser ses propres gangsters que si on prend la majorit\u00e9. A la fin du tour celui qui a la majorit\u00e9 dans une ville gagne la r\u00e9compense. Tout le sel du jeu consiste donc \u00e0 donner les informations cruciales que l&rsquo;on d\u00e9tient le plus tard possible, tout en bluffant (je pose un gangster \u00e0 tel endroit pour faire croire que la r\u00e9compense est int\u00e9ressante, alors qu&rsquo;elle ne l&rsquo;est pas) et en prenant \u00e9ventuellement soi-m\u00eame des risques (je n&rsquo;ai pas toutes les informations sur telle ville, mais je tente quand m\u00eame). Astuce suppl\u00e9mentaire, lors du dernier tour c&rsquo;est le joueur qui a pos\u00e9 le moins de gangsters qui commence, et ainsi de suite jusqu&rsquo;au joueur qui en a pos\u00e9 le plus. Ceci favorise donc le joueur qui a pris des risques auparavant, puisqu&rsquo;il jouera en dernier et aura donc 100% des informations et pourra le cas \u00e9ch\u00e9ant prendre une majorit\u00e9 sans plus aucun risque.<\/p>\n<p style=\"text-align: justify;\">La tension monte au fur et \u00e0 mesure de la partie (qui ne dure pas longtemps, sauf quand on joue avec des lambins calculateurs, mais \u00e7a \u00e7a vaut pour tous les jeux&#8230;), il y a du bluff, aucune chance, le th\u00e8me est assez bien rendu, les illustrations tr\u00e8s belles, le jeu tient dans une petite bo\u00eete, le prix est raisonnable&#8230; bref un carton total!<\/p>\n<p>PS en plus j&rsquo;ai une bo\u00eete d\u00e9dicac\u00e9e par l&rsquo;auteur et l&rsquo;illustrateur, que je ne connais ni l&rsquo;un ni l&rsquo;autre, je pr\u00e9cise, mais \u00e7a le fait encore plus!<\/p>\n<p><strong><span style=\"color: #800080;\">Derni\u00e8re partie<\/span><\/strong>:<\/p>\n<p>Il faut remonter \u00e0 2010 d\u00e9j\u00e0 pour la sortie de The Boss et pour moi il n&rsquo;a pas pris une ride. C&rsquo;est typiquement le genre de jeu que je trouve (injustement) sous-estim\u00e9. Il est rapide, malin et plein de bluff. Il n&rsquo;est certes pas 100% contr\u00f4lable (le tirage des cartes joue clairement un r\u00f4le, pas dans le sens \u00ab\u00a0quelle malchance\u00a0\u00bb, mais plus dans le sens \u00ab\u00a0je peux bluffer sur telle ville car j&rsquo;ai une information cruciale\u00a0\u00bb) mais il est fun, et c&rsquo;est quand m\u00eame la chose la plus importante qu&rsquo;on demande \u00e0 un tel jeu! Petite bo\u00eete, r\u00e8gles expliqu\u00e9es en moins de 10 minutes et fun. Que demande le peuple?!<\/p>\n<hr \/>\n<p><a href=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2010\/11\/242-The-Boss-2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-1617  aligncenter\" title=\"242 The Boss 2\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2010\/11\/242-The-Boss-2-768x1024.jpg\" alt=\"\" width=\"577\" height=\"691\" \/><\/a><\/p>\n<hr \/>\n<p><a href=\"http:\/\/www.vindjeu.eu\/2011\/02\/28\/the-boss\/sony-dsc-186\/\" rel=\"attachment wp-att-14158\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-14158\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2011\/02\/1307-The-Boss-4.jpg\" alt=\"SONY DSC\" width=\"1200\" height=\"799\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2011\/02\/1307-The-Boss-4.jpg 4592w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2011\/02\/1307-The-Boss-4-300x199.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2011\/02\/1307-The-Boss-4-1024x681.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2011\/02\/1307-The-Boss-4-160x106.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2011\/02\/1307-The-Boss-4-368x245.jpg 368w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2011\/02\/1307-The-Boss-4-510x340.jpg 510w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p> Une bien belle surprise que ce The Boss.\u00a0 J&rsquo;avais lu les r\u00e8gles sur internet, et \u00e7a ne m&rsquo;avait pas l&rsquo;air trop \u00e0 mon go\u00fbt.\u00a0 Mais bon, tant que je n&rsquo;y avais pas go\u00fbt\u00e9&#8230; \ud83d\ude09 Cette partie \u00e0 2 m&rsquo;a enchant\u00e9e.\u00a0 Ce qui parrait juste un petit&#46;&#46;&#46;<\/p>\n","protected":false},"author":2,"featured_media":1618,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[5],"tags":[6,10,323,7,276],"class_list":["post-1616","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-famille","tag-philrey212","tag-raf","tag-ren","tag-swatsh","tag-thierry","annee-222","auteurs-alain-ollier","editeurs-blackrock-editions"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/1616","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/comments?post=1616"}],"version-history":[{"count":0,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/1616\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media\/1618"}],"wp:attachment":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media?parent=1616"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/categories?post=1616"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/tags?post=1616"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}