{"id":16315,"date":"2017-04-20T22:13:26","date_gmt":"2017-04-20T20:13:26","guid":{"rendered":"http:\/\/www.vindjeu.eu\/?p=16315"},"modified":"2017-04-20T22:13:26","modified_gmt":"2017-04-20T20:13:26","slug":"vikings-gone-wild-video","status":"publish","type":"post","link":"https:\/\/www.vindjeu.eu\/prd\/2017\/04\/20\/vikings-gone-wild-video\/","title":{"rendered":"Vikings Gone Wild (+ vid\u00e9o)"},"content":{"rendered":"<p><a href=\"http:\/\/www.vindjeu.eu\/2017\/04\/20\/vikings-gone-wild-video\/1436-vikings-go-wild-1-2\/\" rel=\"attachment wp-att-16318\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-16318\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/01\/1436-Vikings-go-wild-1-1.png\" alt=\"1436 Vikings go wild 1\" width=\"500\" height=\"498\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/01\/1436-Vikings-go-wild-1-1.png 500w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/01\/1436-Vikings-go-wild-1-1-150x150.png 150w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/01\/1436-Vikings-go-wild-1-1-300x300.png 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/01\/1436-Vikings-go-wild-1-1-160x160.png 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/01\/1436-Vikings-go-wild-1-1-246x245.png 246w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/01\/1436-Vikings-go-wild-1-1-341x340.png 341w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a><\/p>\n<p><a href=\"http:\/\/www.vindjeu.eu\/2017\/02\/24\/conan-video\/swa-7\/\" rel=\"attachment wp-att-16249\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-thumbnail wp-image-16249\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/01\/Swa-7-e1485004971468-150x150.jpg\" alt=\"Swa 7\" width=\"150\" height=\"150\" \/><\/a><\/p>\n<p><strong><span style=\"color: #333399;\">SwatSh<\/span><\/strong>: <strong><span style=\"color: #800000;\">8,5 \/10<\/span><\/strong><\/p>\n<p>Vikings Gone Wild est un jeu de deckbuilding orient\u00e9 pour les joueurs amateurs.\u00a0 L\u2019auteur et son \u00e9diteur ont r\u00e9ussi \u00e0 diminuer la complexit\u00e9 de ce type de jeu tout en gardant sa richesse et son int\u00e9r\u00eat.\u00a0 De plus, ils ont introduit un c\u00f4t\u00e9 humoristique tr\u00e8s amusant.<\/p>\n<h3>Le jeu de deckbuilding classique<\/h3>\n<p>Vous avez votre propre deck de cartes.\u00a0 Tous les joueurs d\u00e9butent avec le m\u00eame.\u00a0 Vous en piochez 5 et en jouez autant que vous voulez.\u00a0 A la fin du tour, vous vous d\u00e9faussez du reste de vos cartes en main et vous en repiochez 5.\u00a0 Pas de nouveaut\u00e9 de ce c\u00f4t\u00e9-l\u00e0 mais un syst\u00e8me qui reste tr\u00e8s simple.<\/p>\n<h3>Les ressources<\/h3>\n<p>Il y a 2 ressources dans Vikings Gone Wild\u00a0: la bi\u00e8re et l\u2019argent (normal pour des vikings\u00a0\ud83d\ude09 ).\u00a0 Vous allez gagner ces ressources en jouant les cartes qui en produisent temporairement (elles seront perdues en fin de tour, normal\u00a0\ud83d\ude09 ).\u00a0 Et ces ressources vont vous permettre d\u2019acheter des cartes.<\/p>\n<h3>Les cartes et leurs effets<a href=\"http:\/\/www.vindjeu.eu\/2017\/04\/20\/vikings-gone-wild-video\/1436-vikings-go-wild-2\/\" rel=\"attachment wp-att-16329\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-16329\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/01\/1436-Vikings-go-wild-2-1024x683.jpg\" alt=\"1436 Vikings go wild 2\" width=\"600\" height=\"400\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/01\/1436-Vikings-go-wild-2-1024x683.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/01\/1436-Vikings-go-wild-2-300x200.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/01\/1436-Vikings-go-wild-2-768x512.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/01\/1436-Vikings-go-wild-2-160x107.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/01\/1436-Vikings-go-wild-2-368x245.jpg 368w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/01\/1436-Vikings-go-wild-2-510x340.jpg 510w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a><\/h3>\n<p><strong>1) Les cartes de la file<\/strong><br \/>\nPlusieurs types de cartes permettent de produire plus de ressources.\u00a0 D\u2019abord, classiquement, comme dans <a href=\"http:\/\/www.vindjeu.eu\/2009\/01\/24\/dominion\/\">Dominion<\/a>, il y a des cartes qui produisent plus de ressources.\u00a0 Les cartes de votre deck de d\u00e9part ne produisent qu\u2019une ressource chacune.\u00a0 Vous allez pouvoir en acheter qui produisent 2 ressources.\u00a0 Ces cartes sont disponibles dans la rang\u00e9e de cartes qui suit un syst\u00e8me \u00e0 la <a href=\"http:\/\/www.vindjeu.eu\/2011\/05\/09\/through-the-ages\/\">Through the Ages<\/a>.\u00a0 Il y a 5 cartes disponibles \u00e0 l\u2019achat.\u00a0 Quand on en ach\u00e8te une, on les d\u00e9cale sur la droite et on en pioche une nouvelle.\u00a0 A la fin d\u2019un tour complet, on d\u00e9fausse la carte la plus \u00e0 droite pour la remplacer par une nouvelle.\u00a0 Ce sont ces cartes, entre autre, qui vont apporter de la vari\u00e9t\u00e9 \u00e0 vos parties car elles changent tout le temps et leurs effets sont vari\u00e9s\u00a0: piocher de nouvelles cartes,&#8230;<\/p>\n<p><strong>2) Les b\u00e2timents<br \/>\n<\/strong>Vous aurez la possibilit\u00e9 d\u2019acheter des b\u00e2timents.\u00a0 Les b\u00e2timents ont la particularit\u00e9 de rester devant vous et d\u2019apporter leur effet durant toute la dur\u00e9e du jeu.\u00a0 C\u2019est un des aspects les plus int\u00e9ressants de Vikings Gone Wild.\u00a0 Outre la gestion de votre deck, vous allez devoir g\u00e9rer vos b\u00e2timents et leurs effets.\u00a0 Les b\u00e2timents sont toujours disponibles \u00e0 l\u2019achat et il y en a de 3 types\u00a0:<br \/>\n&#8211; <strong>Les b\u00e2timents de production\u00a0<\/strong>: \u00e0 chaque tour, ils produisent la ressource indiqu\u00e9e.\u00a0 Si elle n\u2019est pas utilis\u00e9e, elle est perdue<br \/>\n&#8211; <strong>Les entrep\u00f4ts\u00a0<\/strong>: ils permettent de stocker les ressources produites par les b\u00e2timents de production et \u00e9vitent donc de les perdre en fin de tour<br \/>\n&#8211; <strong>Les effets deckbuildings\u00a0<\/strong>: ils permettent de piocher une carte de plus ou de garder des cartes en main pour le prochain tour<\/p>\n<p><strong><a href=\"http:\/\/www.vindjeu.eu\/2017\/04\/20\/vikings-gone-wild-video\/1436-vikings-go-wild-3\/\" rel=\"attachment wp-att-16330\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-16330\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/01\/1436-Vikings-go-wild-3-1024x683.jpg\" alt=\"1436 Vikings go wild 3\" width=\"600\" height=\"400\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/01\/1436-Vikings-go-wild-3-1024x683.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/01\/1436-Vikings-go-wild-3-300x200.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/01\/1436-Vikings-go-wild-3-768x512.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/01\/1436-Vikings-go-wild-3-160x107.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/01\/1436-Vikings-go-wild-3-368x245.jpg 368w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/01\/1436-Vikings-go-wild-3-510x340.jpg 510w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a>3) Les unit\u00e9s militaires<\/strong><br \/>\nUn peu comme dans l\u2019excellent <a href=\"http:\/\/www.vindjeu.eu\/2015\/06\/04\/star-realms\/\">Star Realms<\/a>, on va pouvoir attaquer les b\u00e2timents adverses avec des unit\u00e9s militaires.\u00a0 Le nombre de d\u00e9g\u00e2ts occasionn\u00e9 par les unit\u00e9s militaires doit \u00eatre sup\u00e9rieur ou \u00e9gal \u00e0 la valeur de d\u00e9fense du b\u00e2timent.\u00a0 Ce qui est particulier c\u2019est qu\u2019une attaque est tr\u00e8s \u00ab\u00a0soft\u00a0\u00bb dans Vikings Gone Wild car il n\u2019arrive rien de f\u00e2cheux au joueur attaqu\u00e9 m\u00eame si l\u2019attaquant l\u2019emporte.\u00a0 Il n\u2019arrive rien du tout d\u2019ailleurs sauf que l\u2019attaquant va gagner des PVs.\u00a0 Et il en gagnera beaucoup gr\u00e2ce \u00e0 \u00e7a.\u00a0 Au plus il r\u00e9ussira des attaques, au plus il en gagnera.\u00a0 Mais le d\u00e9fenseur n\u2019est pas d\u00e9muni et peut contrer ces attaques gr\u00e2ce \u00e0 ses unit\u00e9s d\u00e9fensives qu\u2019il peut jouer de sa main pour contrer une attaque et augmenter la valeur de d\u00e9fense de ses b\u00e2timents.\u00a0 S\u2019il arrive \u00e0 bien se d\u00e9fendre, il gagnera aussi de nombreux PVs au d\u00e9triment de l\u2019attaquant.\u00a0 Et cette compensation est excellente et ouvre la porte \u00e0 pas mal de strat\u00e9gies.\u00a0 Si vous n\u2019investissez rien dans vos d\u00e9fenses, ce n\u2019est pas grave car vous ne perdrez rien (ou tr\u00e8s peu) si on vous attaque.\u00a0 Si vous investissez dans une bonne d\u00e9fense, vous aurez l\u2019occasion de gagner de nombreux PVs.\u00a0 Si vous investissez dans une bonne attaque, mieux vaudra attaquer les joueurs plus faibles ou attaquer avec de nombreuses unit\u00e9s un b\u00e2timent afin d\u2019emp\u00eacher un adversaire de se d\u00e9fendre.\u00a0 Il va y avoir un petit jeu de bluff et d\u2019influence tr\u00e8s sympathique.<a href=\"http:\/\/www.vindjeu.eu\/2017\/04\/20\/vikings-gone-wild-video\/1436-vikings-go-wild-4\/\" rel=\"attachment wp-att-16331\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-16331\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/01\/1436-Vikings-go-wild-4-1024x683.jpg\" alt=\"1436 Vikings go wild 4\" width=\"600\" height=\"400\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/01\/1436-Vikings-go-wild-4-1024x683.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/01\/1436-Vikings-go-wild-4-300x200.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/01\/1436-Vikings-go-wild-4-768x512.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/01\/1436-Vikings-go-wild-4-160x107.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/01\/1436-Vikings-go-wild-4-368x245.jpg 368w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/01\/1436-Vikings-go-wild-4-510x340.jpg 510w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n<p><strong>4) Les cartes PVs<\/strong><br \/>\nQuand on d\u00e9passe certains seuils de PVs, on a le droit de gagner une carte sp\u00e9ciale qui va vous apporter des effets tr\u00e8s puissants et vari\u00e9s (aller chercher des cartes dans sa d\u00e9fausse, voler des ressources \u00e0 un adversaire,&#8230;).<\/p>\n<p><strong>5) Les cartes objectifs personnels<br \/>\n<\/strong>Ces cartes repr\u00e9sentent des petits challenges (acheter tel type de carte, attaquer tel type de b\u00e2timent, gagner tel type de ressource,&#8230;)\u00a0 Ces cartes vont guider l\u00e9g\u00e8rement vos actions car vous allez pouvoir gagner quelques PVs suppl\u00e9mentaires en les compl\u00e9tant sans pour autant \u00eatre primordiales dans votre strat\u00e9gie.\u00a0 Bien vu\u00a0!\u00a0 Il est juste tr\u00e8s dommage qu\u2019elles soient en nombre si limit\u00e9\u00a0et qu\u2019on ne puisse plus en piocher d\u00e8s le milieu de la partie.<\/p>\n<p><strong><a href=\"http:\/\/www.vindjeu.eu\/2017\/04\/20\/vikings-gone-wild-video\/1436-vikings-go-wild-5\/\" rel=\"attachment wp-att-16332\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-16332\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/01\/1436-Vikings-go-wild-5-1024x683.jpg\" alt=\"1436 Vikings go wild 5\" width=\"600\" height=\"400\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/01\/1436-Vikings-go-wild-5-1024x683.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/01\/1436-Vikings-go-wild-5-300x200.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/01\/1436-Vikings-go-wild-5-768x512.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/01\/1436-Vikings-go-wild-5-160x107.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/01\/1436-Vikings-go-wild-5-368x245.jpg 368w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/01\/1436-Vikings-go-wild-5-510x340.jpg 510w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a>6) Les cartes objectifs communs<\/strong><br \/>\nElles, elles rapportent pas mal de PVs \u00e0 condition d\u2019\u00eatre la joueuse qui l\u2019emporte.\u00a0 Elles introduisent d\u2019ailleurs un petit jeu de majorit\u00e9\u00a0: avoir r\u00e9ussi le plus d\u2019objectifs personnels, avoir le plus de cartes de tel type, avoir le plus de ressources de tel type dans ses entrep\u00f4ts,&#8230;\u00a0 M\u00eame si elles ne repr\u00e9sente pas un m\u00e9canisme r\u00e9volutionnaire, elles permettent de bien varier les strat\u00e9gies qui vont s\u2019\u00e9tendre entre les attaques, d\u00e9fenses, objectifs communs et objectifs personnels.\u00a0 Le jeu propose de jouer avec 4 cartes objectifs commun pour une partie \u00e0 piocher parmi une petite dizaine d\u2019objectifs communs diff\u00e9rents.\u00a0 Ceci permet une belle vari\u00e9t\u00e9 de parties \u00e9galement m\u00eame si, en quelques parties, on en aura fait le tour.\u00a0 L\u00e0 aussi, on aurait aim\u00e9 plus de cartes.<\/p>\n<p>Vikings Gone Wild est une agr\u00e9able surprise dans le syst\u00e8me deckbuilding dont on pensait avoir fait le tour.\u00a0 Il propose un niveau de difficult\u00e9 plus bas que la moyenne du genre permettant d\u2019y jouer avec des joueurs occasionnels et m\u00eame en famille avec de plus grands enfants.\u00a0 Et pourtant, il y a tr\u00e8s peu de hasard dans le jeu, voire m\u00eame aucun \u00e0 l\u2019exception de sa propre pioche de cartes.\u00a0 Gr\u00e2ce \u00e0 ses diff\u00e9rentes fa\u00e7ons de scorer il permet de multiples strat\u00e9gies diff\u00e9rentes qui peuvent varier l\u00e9g\u00e8rement (ce n\u2019est pas tout ou rien).\u00a0 De plus, l\u2019interaction est assez bien pr\u00e9sente aussi bien dans les combats que dans la course aux majorit\u00e9s.\u00a0 Enfin, la strat\u00e9gie de vos adversaires va influencer la v\u00f4tre et c\u2019est la joueuse qui aura su le mieux se positionner entre sa propre strat\u00e9gie et celles de ses adversaires qui aura le plus de chance de l\u2019emporter.\u00a0 Attention aux vikings, quand ils ont trop bu, la moindre p\u00e9pite d\u2019or les transforme en grosse brute\u00a0\ud83d\ude42<a href=\"http:\/\/www.vindjeu.eu\/2017\/04\/20\/vikings-gone-wild-video\/1436-vikings-go-wild-6\/\" rel=\"attachment wp-att-16333\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-16333\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/01\/1436-Vikings-go-wild-6-1024x683.jpg\" alt=\"1436 Vikings go wild 6\" width=\"580\" height=\"387\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/01\/1436-Vikings-go-wild-6-1024x683.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/01\/1436-Vikings-go-wild-6-300x200.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/01\/1436-Vikings-go-wild-6-768x512.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/01\/1436-Vikings-go-wild-6-160x107.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/01\/1436-Vikings-go-wild-6-368x245.jpg 368w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/01\/1436-Vikings-go-wild-6-510x340.jpg 510w\" sizes=\"auto, (max-width: 580px) 100vw, 580px\" \/><\/a><\/p>\n<hr \/>\n<p><a href=\"http:\/\/www.vindjeu.eu\/2017\/01\/08\/istanbul-brief-siegel\/phil-4\/\" rel=\"attachment wp-att-15724\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-thumbnail wp-image-15724\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2016\/12\/Phil-4-150x150.jpg\" alt=\"phil-4\" width=\"150\" height=\"150\" \/><\/a><strong><span style=\"color: #333399;\">Philrey<\/span><\/strong>:<strong><span style=\"color: #800000;\">\u00a0 \u00a0 \u00a08\/10<\/span><\/strong><\/p>\n<p>Bon, il est vrai que je ne suis pas un fan de la m\u00e9canique de deck building. Pourtant, je dois admettre que Vikings Gone Wild apporte du plaisir \u00e0 ce type de jeu (je rejoins donc l&rsquo;avis de Pascal).<\/p>\n<p>En effet, les cartes diff\u00e9rentes ne sont pas innombrables mais elle sont assez vari\u00e9es pour forcer les joueurs \u00e0 faire des choix strat\u00e9giques: cartes de d\u00e9fenses pour convaincre les autres de vous foutre la paix, les cartes attaques pour justement les titiller, des cartes de production et de stockage car il en faut.<\/p>\n<p>Quelques cartes \u00ab\u00a0h\u00e9ros\u00a0\u00bb que l&rsquo;on peut acqu\u00e9rir lorsqu&rsquo;on d\u00e9passe certains seuils de PV, \u00e0 ne pas n\u00e9gliger.<\/p>\n<p>A c\u00f4t\u00e9 de cela, une petite course \u00e0 4 objectifs de fin de partie.<\/p>\n<p>En bref, Vikings Gone Wild s\u00e9duit par ses illustrations \u00ab\u00a0wild\u00a0\u00bb qui collent bien au gabarit du jeu, offre un plaisir ludique ind\u00e9niable et convaincra m\u00eame ceux qui appr\u00e9cient un peu moins la m\u00e9canique de base, le Deck Building.<\/p>\n<hr \/>\n<p><a href=\"http:\/\/www.vindjeu.eu\/2017\/01\/12\/pillards-de-la-mer-du-nord-video\/sony-dsc-434\/\" rel=\"attachment wp-att-15770\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-thumbnail wp-image-15770\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2016\/12\/1P-Pascal-150x150.jpg\" alt=\"SONY DSC\" width=\"150\" height=\"150\" \/><\/a><strong><span style=\"color: #333399;\">Pascal<\/span><\/strong>:<strong><span style=\"color: #800000;\">\u00a0 \u00a0 \u00a08,5\/10<\/span><\/strong><\/p>\n<p>Encore un deck-building. La m\u00e9canique a \u00e9t\u00e9 vue, revue, modifi\u00e9e, &#8230; Qu&rsquo;est-ce que Vikings Gone Wild pourrait bien apporter de plus que les autres ? \u00a0Et bien, la r\u00e9ponse est simple : il apporte du FUN !<\/p>\n<p>Ici, on ne recherche pas des combinaisons de fou, et on ne fait pas tourner 50 fois son deck. \u00a0Non, l&rsquo;int\u00e9r\u00eat est ailleurs, il est dans les attaques que l&rsquo;on peut mener contre les autres joueurs.<\/p>\n<p>Le jeu est inspir\u00e9 d&rsquo;un jeu sur tablette (smartphone) du m\u00eame nom. \u00a0Non, non, ne partez pas, ca peut faire peur, mais la sauce prend vraiment ! On va en effet pouvoir am\u00e9liorer son h\u00f4tel de ville, les b\u00e2timents prennent un certain temps de construction pendant lequel il ne pourront pas \u00eatre utilis\u00e9s ni attaqu\u00e9s. \u00a0Oui, ca vout fait s\u00fbrement pens\u00e9 \u00e0 es jeux super connus sur mobile (style Clash of Clans &#8211; ou Vikings Gone Wild !).<\/p>\n<p>Et c&rsquo;est donc bien les attaques contre les autres villages qui apportent un vent de fra\u00eecheur ! \u00a0Vous pouvez attaquer un village adverse, et avec vos cartes \u00ab\u00a0attaque\u00a0\u00bb en provenance de votre deck. \u00a0Votre adversaire peut se d\u00e9fendre, pour peu qu&rsquo;il ait des cartes d\u00e9fenses dans sa main. \u00a0Si il se d\u00e9fend, il marque des points. \u00a0Si vous r\u00e9ussissez, plus vous aurez attaqu\u00e9 des b\u00e2timents, plus vous marquerez des points. \u00a0Mais pas de panique pour la victime d&rsquo;une attaque, les b\u00e2timents attaqu\u00e9s ne sont pas d\u00e9truits, et la p\u00e9nalit\u00e9 est inexistante ( ou faible pour les b\u00e2timents de stockage qui se voient d\u00e9pouill\u00e9s d&rsquo;une seule ressource par attaque). \u00a0En d&rsquo;autres mots, il n&rsquo;y a pas de risque de se faire attaqu\u00e9, au contraire, si vous arrivez \u00e0 vous d\u00e9fendre, vous marquez des points !<\/p>\n<p>M\u00eame si il n&rsquo;est pas parfait (le deck tourne peu et certaines cartes puissantes risquent de ne jamais \u00eatre jou\u00e9es), le jeu est tr\u00e8s accessible, tr\u00e8s fun, tr\u00e8s agr\u00e9able \u00e0 jouer. \u00a0Et en plus j&rsquo;adore les illustrations (et encore en plus j&rsquo;ai obtenu plein de cartes suppl\u00e9mentaires en pledgeant sur KS). Un coup de coeur dans la cat\u00e9gorie \u00ab\u00a0poids moyen\u00a0\u00bb !<\/p>\n<p>&nbsp;<\/p>\n<hr \/>\n<p><a href=\"http:\/\/www.vindjeu.eu\/2017\/01\/09\/voeux-2017-de-vin-djeu\/1432-voeux\/\" rel=\"attachment wp-att-16088\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-thumbnail wp-image-16088\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/01\/1432-Voeux-e1483984871659-150x150.jpg\" alt=\"1432-voeux\" width=\"150\" height=\"150\" \/><\/a><strong><span style=\"color: #333399;\">Ren<\/span><\/strong>:\u00a0<strong><span style=\"color: #800000;\">\u00a07\/10<\/span><\/strong><\/p>\n<p>Vikings Gone Wild nous donne une bonne occasion aujourd&rsquo;hui de nous pencher sur un ph\u00e9nom\u00e8ne qui est une vraie lame de fond dans le monde du jeu aujourd&rsquo;hui (et pas seulement dans le monde du jeu d&rsquo;ailleurs): le crowdfunding. Ou financement participatif en bon fran\u00e7ais de chez nous. Je ne vous ferai pas l&rsquo;injure d&rsquo;expliquer ce que c&rsquo;est. Mais la critique de Vikings Gone Wild nous donne l&rsquo;opportunit\u00e9 d&rsquo;en toucher deux mots, car il est pour moi bien repr\u00e9sentatif d&rsquo;une des 4 principales cat\u00e9gories de projets qu&rsquo;on peut trouver sur les plateformes de financement participatif:<\/p>\n<p><strong>1. les jeux tout pourri<\/strong> qui n&rsquo;auraient jamais trouv\u00e9 un \u00e9diteur (et qui seront \u00e9ventuellement financ\u00e9s sur une plateforme gr\u00e2ce \u00e0 maman, papa, les cousins, les amis, les scouts&#8230;)<br \/>\n<strong>2. les jeux hyper ambitieux<\/strong>, et\/ou avec un mat\u00e9riel de ouf (genre 80 figurines de 25cm, peintes \u00e0 la main avec des poils de Z\u00e9bu tremp\u00e9s dans de la peinture bio-organique parfum\u00e9e aux milles essences des fleurs de lotus cueillies au matin du solstice d&rsquo;\u00e9t\u00e9 en haut de la montagne sacr\u00e9e). Le tout vendu 139 euros pour la bo\u00eete de base, mais si vous prenez tous les add-on, indispensables pour \u00ab\u00a0avoir l&rsquo;exp\u00e9rience ultime du jeu\u00a0\u00bb, vous terminez \u00e0 672 euros. Ces jeux n&rsquo;auraient peut-\u00eatre pas trouv\u00e9 d&rsquo;\u00e9diteur non plus, mais clairement pas pour les m\u00eames raisons qu&rsquo;en 1&#8230;<br \/>\n<strong>3. les jeux tout \u00e0 fait novateurs<\/strong> (ils sont rares, soyons clairs), qui n&rsquo;auraient pas trouv\u00e9 d&rsquo;\u00e9diteur non plus car trop risqu\u00e9s<br \/>\n<strong>4. les jeux pas sp\u00e9cialement novateurs<\/strong>, reprenant des m\u00e9caniques connues, avec un mat\u00e9riel \u00ab\u00a0normal\u00a0\u00bb (bref comme la majorit\u00e9 des jeux \u00e9dit\u00e9s via les m\u00e9thodes classiques). L&rsquo;avantage ou plut\u00f4t l&rsquo;objectif dans cette cat\u00e9gorie \u00e9tant que vous allez fortement limiter le risque en \u00e9ditant le jeu, puisque vous allez toucher exactement les joueurs motiv\u00e9s par votre proposition (et sans devoir faire un marketing \u00e9norme via un r\u00e9seau de distribution tentaculaire). Exemple: si vous cr\u00e9ez un wargame tactique coop\u00e9ratif se passant en Italie pendant la premi\u00e8re guerre mondiale, ben vous allez int\u00e9resser les joueurs adorant les wargames tactiques coop\u00e9ratifs se passant en Italie pendant la premi\u00e8re guerre mondiale. Mais pas ceux qui aiment les wargames strat\u00e9giques coop\u00e9ratifs se passant en Italie pendant la premi\u00e8re guerre mondiale. Ni ceux qui aiment les wargames tactiques coop\u00e9ratifs se passant en France pendant la premi\u00e8re guerre mondiale. Quant \u00e0 ceux qui aiment les wargames tactiques semi-coop\u00e9ratifs se passant en Italie pendant la premi\u00e8re guerre mondiale, ils vont probablement se t\u00e2ter&#8230;<\/p>\n<p>Et bien pour moi nous sommes exactement dans ce quatri\u00e8me cas de figure avec Vikings Gone Wild. Est-ce un jeu r\u00e9volutionnaire? Non. Est-ce un jeu avec un mat\u00e9riel de ouf? Non (le mat\u00e9riel est tout \u00e0 fait ok, ne me comprenez pas mal) Est-ce un jeu correct qui donne du plaisir ludique \u00e0 ceux qui aiment les m\u00e9canismes utilis\u00e9s, qui tourne correctement et qui est facile \u00e0 expliquer? Oui.<\/p>\n<p>Dans Vikings Gone Wild on incarne des chefs de clans qui veulent prouver aux Dieux qui est le plus malabar. Le m\u00e9canisme de base du jeu est le deckbuilding, saupoudr\u00e9 de gestion de ressources. On va donc jouer avec un deck de cartes, qu&rsquo;on va essayer d&rsquo;optmiser pendant la partie pour \u00eatre le premier \u00e0 atteindre l&rsquo;objectif de points de victoire.<\/p>\n<p>Un tour de jeu est tout \u00e0 fait classique: on pioche 5 cartes de son deck (ou plus si on a construit pr\u00e9c\u00e9demment des b\u00e2timents sp\u00e9ciaux), puis on r\u00e9alise autant d&rsquo;actions qu&rsquo;on veut parmi les suivantes, tant qu&rsquo;on a les ressources ou les cartes pour les r\u00e9aliser:<\/p>\n<p><strong>1. acheter de nouvelles unit\u00e9s pour attaquer<\/strong> (=cartes qu&rsquo;on ajoutera \u00e0 son deck), des unit\u00e9s pour d\u00e9fendre (id) ou des cartes chemin d&rsquo;Odin (qui donnent des bonus imm\u00e9diats) &#8211; on paye en or ou en bi\u00e8re<br \/>\n<strong>2. construire des b\u00e2timents<\/strong> (= poser la carte correspondante devant soi, ce qui donnera un bonus aux tours suivants, e.g. piocher une carte en plus, recevoir un or, recevoir une bi\u00e8re, pouvoir stocker un or ou une bi\u00e8re d&rsquo;un tour \u00e0 l&rsquo;autre&#8230;)<br \/>\n<strong>3. attaquer un autre joueur ou un vampire<\/strong> (=monstre qu&rsquo;on peut toujours attaquer pour recevoir un bonus d\u00e9termin\u00e9 en cas de victoire) &#8211; attaquer consiste \u00e0 jouer des unit\u00e9s qu&rsquo;on a en main<br \/>\n<strong>4. am\u00e9liorer son b\u00e2timent principal<\/strong> (\u00ab\u00a0Town Hall\u00a0\u00bb), ce qui permet \u00e0 la fois de mieux le prot\u00e9ger d&rsquo;attaques adverses (mais dans le m\u00eame temps \u00e7a augmente le nombre de points de victoire qu&rsquo;un autre joueur gagnera si il r\u00e9ussit une attaque contre vous&#8230;) et d&rsquo;augmenter le nombre de b\u00e2timents qu&rsquo;on peut poser devant soi (cfr 2.)<br \/>\n<strong>5. r\u00e9ussir une mission<\/strong>, ce qui revient \u00e0 remplir une condition d\u00e9termin\u00e9e, ce qui vous donne imm\u00e9diatement la carte correspondante et les points de victoire qui vont avec<\/p>\n<p>A la fin de son tour on d\u00e9fausse les ressources qu&rsquo;on ne peut pas stocker et on passe au joueur suivant. Comment se r\u00e9sout une attaque? Simple: la force d&rsquo;attaque doit \u00eatre plus grande que la force de d\u00e9fense. Si l&rsquo;attaque est r\u00e9ussie on gagne les points de victoire correspondants \u00e0 la valeur de d\u00e9fense du b\u00e2timent. Il est important de noter que les b\u00e2timents ne sont pas d\u00e9truits\/perdus\/d\u00e9fauss\u00e9s. L&rsquo;attaquant a simplement r\u00e9ussi son raid et gagne donc des points de victoire. Et un joueur ne peut \u00eatre attaqu\u00e9 qu&rsquo;une seule fois par tour complet de tous les joueurs. D\u00e8s qu&rsquo;un joueur a atteint l&rsquo;objectif points de victoire, on termine le tour, on alloue les cartes bonus (connues d\u00e8s le d\u00e9part), et celui qui a le plus de points a gagn\u00e9.<\/p>\n<p>Au final, comme dit plus haut, un jeu qui pour moi rentre totalement dans la 4\u00e8me cat\u00e9gorie: pas r\u00e9volutionnaire et pas incroyable au niveau matos. Mais qui tourne correctement, avec des graphismes tr\u00e8s typ\u00e9s (on est dans du viking fantasy rigolo) et facile \u00e0 apprendre. Donc si vous aimez les jeux de deckbuilding familiaux saupoudr\u00e9s de gestion de ressources dans une th\u00e9matique viking fantasy rigolote et qui s&rsquo;apprennent facilement&#8230; ben vous avez sans doute d\u00e9j\u00e0 pledg\u00e9! \ud83d\ude42<\/p>\n<hr \/>\n<p><a href=\"http:\/\/www.vindjeu.eu\/2016\/09\/22\/million-club\/tapimoket\/\" rel=\"attachment wp-att-14734\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-thumbnail wp-image-14734\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2016\/09\/Tapimoket-150x150.png\" alt=\"tapimoket\" width=\"150\" height=\"150\" \/><\/a><\/p>\n<p><strong><span style=\"margin: 0px; color: navy; font-family: 'Georgia',serif;\">Tapimoket<\/span><\/strong><strong><span style=\"margin: 0px; color: blue; font-family: 'Georgia',serif;\">: \u00a0<\/span><\/strong><strong><span style=\"margin: 0px; color: maroon; font-family: 'Georgia',serif;\">8\/10<\/span><\/strong><\/p>\n<p><span style=\"margin: 0px; color: #333333; font-family: 'Georgia',serif;\">Viking Gone Wild reporte avec brio le jeu vid\u00e9o. Il utilise les m\u00e9caniques connues de deckbuilding et s&rsquo;appuie sur de tr\u00e8s belles illustrations et un beau mat\u00e9riel pour le rendre attrayant. Les r\u00e8gles sont assez simples et bas\u00e9es sur deux ressources que sont l&rsquo;or et la bi\u00e8re (On comprend vite l&rsquo;esprit du jeu). On acquiert ainsi des cartes pour construire des b\u00e2timents, pour les am\u00e9liorer, accomplir de petits objectifs. On pourra \u00e9galement se constituer une petite arm\u00e9e de guerriers ou de d\u00e9fenseurs pour attaquer ses adversaires ou se prot\u00e9ger. Les attaques seront sans cons\u00e9quence pour celui qui les subit, et rapporte des points pour l&rsquo;attaquant. De m\u00eame, les joueurs ne pourront pas s&rsquo;acharner tous sur le m\u00eame joueur durant le m\u00eame tour. Ainsi, la frustration sera moindre et il ne sera pas n\u00e9cessaire de devoir, sans cesse, reconstruire. Bien entendu, quelques cartes viendront apporter quelques bonus et fourberies pour mettre un peu de sel au jeu, comme voler des ressources. Enfin, on pourra accomplir des objectifs et prendre de grosses cartes bien balaises.<\/span><\/p>\n<p><span style=\"margin: 0px; color: #333333; font-family: 'Georgia',serif; font-size: 12pt;\">Le mat\u00e9riel est sympathique et parfaitement illustr\u00e9 par les m\u00eames personnes qui ont fait le jeu vid\u00e9o. On reste donc compl\u00e8tement dans l&rsquo;esprit et j&rsquo;ai trouv\u00e9 \u00e7a amusant et sympathique.<\/span><\/p>\n<hr \/>\n<p><a href=\"http:\/\/www.vindjeu.eu\/2017\/04\/20\/vikings-gone-wild-video\/1436-vikings-go-wild-9\/\" rel=\"attachment wp-att-16317\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-16317\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/01\/1436-Vikings-go-wild-9.jpg\" alt=\"1436 Vikings go wild 9\" width=\"6000\" height=\"4000\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/01\/1436-Vikings-go-wild-9.jpg 6000w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/01\/1436-Vikings-go-wild-9-300x200.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/01\/1436-Vikings-go-wild-9-768x512.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/01\/1436-Vikings-go-wild-9-1024x683.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/01\/1436-Vikings-go-wild-9-160x107.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/01\/1436-Vikings-go-wild-9-368x245.jpg 368w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/01\/1436-Vikings-go-wild-9-510x340.jpg 510w\" sizes=\"auto, (max-width: 6000px) 100vw, 6000px\" \/><\/a><\/p>\n<hr \/>\n<h2><span style=\"color: #800080;\">Vin d&rsquo;jeu d&rsquo;vid\u00e9o<\/span><\/h2>\n<h3>La d\u00e9gustation en 7 minutes par <span style=\"color: #333399;\">Ren<\/span><\/h3>\n<div class=\"video-container\"><iframe loading=\"lazy\" title=\"Vikings Gone Wild (Vin d&#039;jeu d&#039;vid\u00e9o)\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/GnaCOeFHJ4M?feature=oembed&#038;wmode=opaque\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n","protected":false},"excerpt":{"rendered":"<p> Vikings Gone Wild est un jeu de deckbuilding orient\u00e9 pour les joueurs amateurs.\u00a0 L\u2019auteur et son \u00e9diteur ont r\u00e9ussi \u00e0 diminuer la complexit\u00e9 de ce type de jeu tout en gardant sa richesse et son int\u00e9r\u00eat.\u00a0 De plus, ils ont introduit un c\u00f4t\u00e9 humoristique tr\u00e8s amusant. Le&#46;&#46;&#46;<\/p>\n","protected":false},"author":3,"featured_media":16318,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[4848],"tags":[817,6,323,7,877],"class_list":["post-16315","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-initie","tag-pascal","tag-philrey212","tag-ren","tag-swatsh","tag-tapimoket","annee-1290","auteurs-julien-vergonjeanne","editeurs-lucky-duck-games","illustrateurs-mateusz-komada","distributeurs-atalia"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/16315","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/comments?post=16315"}],"version-history":[{"count":0,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/16315\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media\/16318"}],"wp:attachment":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media?parent=16315"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/categories?post=16315"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/tags?post=16315"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}