{"id":16389,"date":"2017-03-08T09:04:00","date_gmt":"2017-03-08T08:04:00","guid":{"rendered":"http:\/\/www.vindjeu.eu\/?p=16389"},"modified":"2017-03-08T09:04:01","modified_gmt":"2017-03-08T08:04:01","slug":"la-foret-mysterieuse-video","status":"publish","type":"post","link":"https:\/\/www.vindjeu.eu\/prd\/2017\/03\/08\/la-foret-mysterieuse-video\/","title":{"rendered":"La For\u00eat Mysterieuse (+ vid\u00e9o)"},"content":{"rendered":"<p><a href=\"http:\/\/www.vindjeu.eu\/2017\/03\/08\/la-foret-mysterieuse-video\/1452-forest-myst-1\/\" rel=\"attachment wp-att-16391\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-16391\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/01\/1452-Forest-Myst-1.jpg\" alt=\"1452 Forest Myst 1\" width=\"500\" height=\"500\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/01\/1452-Forest-Myst-1.jpg 500w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/01\/1452-Forest-Myst-1-150x150.jpg 150w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/01\/1452-Forest-Myst-1-300x300.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/01\/1452-Forest-Myst-1-160x160.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/01\/1452-Forest-Myst-1-245x245.jpg 245w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/01\/1452-Forest-Myst-1-340x340.jpg 340w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a><\/p>\n<p><a href=\"http:\/\/www.vindjeu.eu\/2017\/01\/09\/voeux-2017-de-vin-djeu\/1432-voeux\/\" rel=\"attachment wp-att-16088\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-thumbnail wp-image-16088\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/01\/1432-Voeux-e1483984871659-150x150.jpg\" alt=\"1432-voeux\" width=\"150\" height=\"150\" \/><\/a><\/p>\n<p><strong><span style=\"color: #333399;\">Ren<\/span><\/strong>:\u00a0 <strong><span style=\"color: #800000;\">7\/10<\/span><\/strong><\/p>\n<p>Petite pause jeunesse aujourd&rsquo;hui dans Vin d&rsquo;Jeu avec ce test de La For\u00eat Myst\u00e9rieuse. On y incarne Jonas, un jeune aventurier qui va devoir traverser la For\u00eat Myst\u00e9rieuse, r\u00e9ussir de multiples \u00e9preuves et vaincre le monstre final pour triompher. Le jeu est tir\u00e9 de la bande dessin\u00e9e Wormworld Saga.<\/p>\n<p>La For\u00eat Myst\u00e9rieuse est un jeu coop\u00e9ratif de m\u00e9moire, o\u00f9 les joueurs vont devoir retenir ensemble les diff\u00e9rents \u00e9l\u00e9ments n\u00e9cessaires \u00e0 la travers\u00e9e de la for\u00eat et au succ\u00e8s dans le combat final (contre la reine de Draconia). La for\u00eat se pr\u00e9sente sous forme de cartes, qu&rsquo;on va aligner les unes \u00e0 la suite des autres, entre la maison de Jonas au d\u00e9part et la carte du monstre final \u00e0 la fin, en passant par une carte randonneur.<\/p>\n<p>Dans la premi\u00e8re phase du jeu les joueurs vont retourner toutes les cartes, une par une, et devoir retenir les \u00e9l\u00e9ments n\u00e9cessaires, indiqu\u00e9s sur le verso de la carte, pour passer \u00e0 la carte suivante. Par exemple une boussole et une cape. Ou une \u00e9p\u00e9e et de la corde. Ou deux gants et une briquet. On retourne donc une carte, on m\u00e9morise, puis on la remet sur son c\u00f4t\u00e9 verso. Puis on fait de m\u00eame avec la suivante. On retourne ainsi toutes les cartes, y compris la carte finale avec le monstre. Cette derni\u00e8re est particuli\u00e8rement importante puisqu&rsquo;il faut retenir pr\u00e9cis\u00e9ment les \u00e9l\u00e9ments n\u00e9cessaires pour vaincre le monstre. Pour toutes les autres cartes on peut retenir \u00ab\u00a0en tout il me faut 4 \u00e9p\u00e9es\u00a0\u00bb, mais pour la derni\u00e8re carte il faut retenir pr\u00e9cis\u00e9ment ce qu&rsquo;il faut. La coop\u00e9ration prend d\u00e9j\u00e0 tout son sens dans cette phase puisqu&rsquo;il y a beaucoup d&rsquo;objets \u00e0 retenir (potentiellement plus de 20 dans la version la plus difficile), donc il faut coop\u00e9rer et se r\u00e9partir les t\u00e2ches!<a href=\"http:\/\/www.vindjeu.eu\/2017\/03\/08\/la-foret-mysterieuse-video\/1452-forest-myst-5\/\" rel=\"attachment wp-att-16398\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-16398\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/01\/1452-Forest-Myst-5-e1485903108439-768x1024.jpg\" alt=\"1452 Forest Myst 5\" width=\"500\" height=\"667\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/01\/1452-Forest-Myst-5-e1485903108439-768x1024.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/01\/1452-Forest-Myst-5-e1485903108439-225x300.jpg 225w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/01\/1452-Forest-Myst-5-e1485903108439-120x160.jpg 120w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/01\/1452-Forest-Myst-5-e1485903108439-184x245.jpg 184w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/01\/1452-Forest-Myst-5-e1485903108439-255x340.jpg 255w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a><\/p>\n<p>Dans la deuxi\u00e8me phase du jeu on va jeter 4 d\u00e9s pour remplir le sac \u00e0 dos de Jonas des objets n\u00e9cessaires. A chaque jet on peut s\u00e9lectionner deux des d\u00e9s et prendre les objets correspondants. Il faut donc avoir bien retenu les objets n\u00e9cessaires et ne pas se tromper dans les choix. Sachant \u00e9galement que sur 2 des 4 d\u00e9s il y a une face \u00ab\u00a0Loki\u00a0\u00bb, qui est un petit animal de la for\u00eat qui va aider Jonas dans sa qu\u00eate. Chaque fois qu&rsquo;on tombe sur un Loki on est oblig\u00e9 de le prendre. Concr\u00e8tement cela signifie qu&rsquo;au lieu de prendre un objet pr\u00e9cis, on prend un jeton Loki, qui est en fait un joker qu&rsquo;on pourra utiliser pendant l&rsquo;aventure. Certains jokers permettent de remplacer n&rsquo;importe quel objet de son sac, d&rsquo;autres donnent simplement le choix entre 2 ou 3 objets d\u00e9termin\u00e9s (on ne le sait que lorsqu&rsquo;on utilise le joker, pendant l&rsquo;aventure). A noter que selon le niveau de difficult\u00e9 choisi on partira dans certains cas d&rsquo;office avec des jetons Loki dans son sac \u00e0 dos.<\/p>\n<p>Une fois le sac \u00e0 dos rempli, on part \u00e0 l&rsquo;aventure, qui est la 3\u00e8me et derni\u00e8re phase du jeu. On retourne les cartes une par une, et on fournit les jetons objets n\u00e9cessaires pour traverser cette partie de la for\u00eat jusqu&rsquo;\u00e0 la carte suivante. Et une fois arriv\u00e9 au monstre final on doit annoncer les objets dont on a besoin, avant de les fournir une fois la carte retourn\u00e9e. Le tout en passant par le randonneur qui, si on fournit ce qu&rsquo;il demande, nous donne l&rsquo;\u00e9p\u00e9e de cristal, permettant de cr\u00e9er 2 \u00e9quipements de notre choix!<\/p>\n<p>Au final nous sommes en pr\u00e9sence d&rsquo;un jeu simple et sympathique, appris en 5 minutes et qui offre plusieurs niveaux de difficult\u00e9 (de \u00ab\u00a0Explorateurs en herbe\u00a0\u00bb \u00e0 \u00ab\u00a0H\u00e9ros des for\u00eats\u00a0\u00bb, selon le nombre de cartes for\u00eats et le nombre de Loki avec lesquels on d\u00e9marrera l&rsquo;aventure). Si vous cherchez un jeu de m\u00e9moire pour jouer avec votre descendance qui a moins de 10 ans, et voulez un peu sortir du m\u00e9mory ou de Pique Plume, La For\u00eat Myst\u00e9rieuse fera parfaitement l&rsquo;affaire!<\/p>\n<hr \/>\n<p>&nbsp;<\/p>\n<p><a href=\"http:\/\/www.vindjeu.eu\/2017\/03\/08\/la-foret-mysterieuse-video\/1452-forest-myst-7\/\" rel=\"attachment wp-att-16397\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-16397\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/01\/1452-Forest-Myst-7-e1485903032210.jpg\" alt=\"1452 Forest Myst 7\" width=\"1300\" height=\"975\" \/><\/a><\/p>\n<hr \/>\n<h2><span style=\"color: #800080;\">Vin d&rsquo;jeu d&rsquo;vid\u00e9o<\/span><\/h2>\n<h3>La d\u00e9gustation en 6 minutes par <span style=\"color: #333399;\">Ren<\/span><\/h3>\n<div class=\"video-container\"><iframe loading=\"lazy\" title=\"La For\u00eat Mysterieuse (Vin d&#039;jeu d&#039;vid\u00e9o)\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/ZK9F3Z6-VRE?feature=oembed&#038;wmode=opaque\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p> Petite pause jeunesse aujourd&rsquo;hui dans Vin d&rsquo;Jeu avec ce test de La For\u00eat Myst\u00e9rieuse. On y incarne Jonas, un jeune aventurier qui va devoir traverser la For\u00eat Myst\u00e9rieuse, r\u00e9ussir de multiples \u00e9preuves et vaincre le monstre final pour triompher. Le jeu est tir\u00e9 de la bande dessin\u00e9e Wormworld&#46;&#46;&#46;<\/p>\n","protected":false},"author":3,"featured_media":16391,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[5],"tags":[323],"class_list":["post-16389","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-famille","tag-ren","annee-1090","auteurs-carlo-a-rossi","editeurs-iello","illustrateurs-daniel-lieske","distributeurs-iello"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/16389","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/comments?post=16389"}],"version-history":[{"count":0,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/16389\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media\/16391"}],"wp:attachment":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media?parent=16389"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/categories?post=16389"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/tags?post=16389"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}