{"id":16655,"date":"2017-04-01T11:24:26","date_gmt":"2017-04-01T09:24:26","guid":{"rendered":"http:\/\/www.vindjeu.eu\/?p=16655"},"modified":"2017-04-01T11:24:26","modified_gmt":"2017-04-01T09:24:26","slug":"the-colonists-video","status":"publish","type":"post","link":"https:\/\/www.vindjeu.eu\/prd\/2017\/04\/01\/the-colonists-video\/","title":{"rendered":"The Colonists (+ vid\u00e9o)"},"content":{"rendered":"<p><a href=\"http:\/\/www.vindjeu.eu\/2017\/04\/01\/the-colonists-video\/1464-colonists-1\/\" rel=\"attachment wp-att-16657\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-16657\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/02\/1464-Colonists-1.jpg\" alt=\"1464 Colonists 1\" width=\"357\" height=\"500\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/02\/1464-Colonists-1.jpg 357w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/02\/1464-Colonists-1-214x300.jpg 214w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/02\/1464-Colonists-1-114x160.jpg 114w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/02\/1464-Colonists-1-175x245.jpg 175w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/02\/1464-Colonists-1-243x340.jpg 243w\" sizes=\"auto, (max-width: 357px) 100vw, 357px\" \/><\/a><\/p>\n<p><a href=\"http:\/\/www.vindjeu.eu\/2017\/01\/08\/istanbul-brief-siegel\/swa-6\/\" rel=\"attachment wp-att-15723\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-thumbnail wp-image-15723\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2016\/12\/Swa-6-e1481492747233-150x150.jpg\" alt=\"swa-6\" width=\"150\" height=\"150\" \/><\/a><\/p>\n<p><strong><span style=\"color: #333399;\">SwatSh<\/span><\/strong>:<strong><span style=\"color: #800000;\"> 8,5\/10<\/span><\/strong><\/p>\n<p>Avec la chouette <a href=\"http:\/\/www.vindjeu.eu\/2016\/12\/24\/steam-map-expansion-5-video\/\">5\u00e8me extension de Steam<\/a>, l\u2019excellent <a href=\"http:\/\/www.vindjeu.eu\/2016\/12\/06\/agricola-family-edition-video\/\">Agricola Family Edition<\/a>, The Colonists \u00e9tait la grande et grosse sortie de <a href=\"http:\/\/www.vindjeu.eu\/editeurs\/mayfair-games\/\">Mayfair <\/a>au dernier salon d\u2019Essen.\u00a0 The Colonists est en effet une boite \u00e0 l\u2019image de <a href=\"http:\/\/www.vindjeu.eu\/2014\/02\/13\/caverna\/\">Caverna <\/a>aussi bien en taille qu\u2019en poids.\u00a0 Mais sa lourdeur ne s\u2019arr\u00eate pas l\u00e0 et vous pourrez y jouer entre 1h30 et 6 heures en fonction de la configuration choisie en sachant que la meilleure dure 6 heures\u00a0!\u00a0 Le livret des r\u00e8gles ne d\u00e9roge pas \u00e0 cette r\u00e8gle puisqu\u2019il comprend pas moins de 24 pages denses ainsi qu\u2019un appendix d\u2019une dizaine de pages suppl\u00e9mentaires.\u00a0 Que ceci ne vous effraye pas pour autant tant les r\u00e8gles sont faciles \u00e0 lire, bien expliqu\u00e9es et qu\u2019en 2 lectures vous pourrez d\u00e9j\u00e0 bien les ma\u00eetriser.\u00a0 Chose assez rare pour le moment, il est inutile d\u2019aller voir une quelconque faq tant tout y est limpide.<\/p>\n<h4>Et 1, et 2 et 3, et 4 \u00e8res<\/h4>\n<p>Une des grandes particularit\u00e9s de The Colonists est que les joueurs d\u00e9terminent eux-m\u00eames la dur\u00e9e du jeu.\u00a0 Le jeu complet se joue en 4 \u00e8res mais les joueurs sont libres de jouer 1 seule, 2 ou m\u00eame 3 \u00e8res.\u00a0 Et ils ne sont pas oblig\u00e9s de commencer \u00e0 la premi\u00e8re \u00e8re.\u00a0 Ca donne d\u00e9j\u00e0 pas mal de configurations diff\u00e9rentes et il est claire que c\u2019est une des grandes originalit\u00e9s du jeu.\u00a0 Ceci est bien beau dans la th\u00e9orie mais dans la pratique, on remarque que le jeu est mieux \u00e9quilibr\u00e9 si on le termine \u00e0 l\u2019\u00e8re 4.\u00a0 Je vous conseillerais alors de choisir le nombre d\u2019\u00e8res que vous souhaitez mais de toujours terminer \u00e0 l\u2019\u00e8re 4.\u00a0 Ca r\u00e9duit vachement les possibilit\u00e9s en effet mais le jeu y gagne en \u00e9quit\u00e9.\u00a0 Si vous vous arr\u00eatez avant, vous risquez d\u2019avoir un jeu poussif et r\u00e9p\u00e9titif o\u00f9 certaines actions seront inutiles car vous ne devrez pas vous pr\u00e9parer \u00e0 l\u2019\u00e8re suivante et d\u2019autres combinaisons tr\u00e8s fortes vous obligeant \u00e0 les r\u00e9aliser encore et encore (bien que totalement inutiles si vous jouez l\u2019\u00e8re suivante).<\/p>\n<p>De plus, commencer \u00e0 une autre \u00e8re que la premi\u00e8re va vous donner un sentiment \u00e9trange genre \u00ab\u00a0j\u2019ai rat\u00e9 quelque chose\u00a0?\u00a0\u00bb.\u00a0 Vous aurez un peu l\u2019impression d\u2019arriver en cours de route sans tr\u00e8s bien comprendre ce qu\u2019il s\u2019est pass\u00e9.<a href=\"http:\/\/www.vindjeu.eu\/2017\/04\/01\/the-colonists-video\/1464-colonists-2\/\" rel=\"attachment wp-att-16662\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-large wp-image-16662\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/02\/1464-Colonists-2-1024x683.jpg\" alt=\"1464 Colonists 2\" width=\"720\" height=\"480\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/02\/1464-Colonists-2-1024x683.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/02\/1464-Colonists-2-300x200.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/02\/1464-Colonists-2-768x512.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/02\/1464-Colonists-2-160x107.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/02\/1464-Colonists-2-368x245.jpg 368w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/02\/1464-Colonists-2-510x340.jpg 510w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><\/a><\/p>\n<p>Non, franchement, The Colonists est excellent si on joue aux 4 \u00e8res cons\u00e9cutivement.\u00a0 On a d\u2019ailleurs le sentiment qu\u2019il a \u00e9t\u00e9 fait pour \u00e7a et que c\u2019est un artifice que d\u2019avoir voulu le segmenter en diff\u00e9rents jeux moins longs.\u00a0 Mais pour jouer au jeu complet, il va vous falloir du temps\u00a0!\u00a0 Comptez 6 heures de jeu, 1 heure d\u2019explication et 1 heure de mise en place\/rangement et votre journ\u00e9e ou nuit est remplie\u00a0\ud83d\ude42<\/p>\n<h4>Le d\u00e9placement d\u2019ouvriers<\/h4>\n<p>La m\u00e9canique centrale de The Colonists n\u2019est pas nouvelle.\u00a0 A votre tour, vous d\u00e9placez 3 fois votre steward (=votre ouvrier) et ex\u00e9cutez, \u00e0 la fin de chacun des 3 mouvements, l\u2019action de la tuile sur laquelle il arrive.\u00a0 The Colonists est un jeu qui excelle dans son c\u00f4t\u00e9 \u00ab\u00a0crescendo\u00a0\u00bb et, en le sachant, vous ne serez pas \u00e9tonn\u00e9s d\u2019apprendre que vous d\u00e9buterez avec une capacit\u00e9 de d\u00e9placement d\u2019une seule case mais vous pourrez progresser jusque 4 cases avec, en plus, la possibilit\u00e9 de gagner jusque 3 autres stewards suppl\u00e9mentaires et m\u00eame des stewards \u00e0 partager avec d\u2019autres joueurs.<\/p>\n<h4><a href=\"http:\/\/www.vindjeu.eu\/2017\/04\/01\/the-colonists-video\/1464-colonists-3\/\" rel=\"attachment wp-att-16663\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-large wp-image-16663\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/02\/1464-Colonists-3-1024x683.jpg\" alt=\"1464 Colonists 3\" width=\"720\" height=\"480\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/02\/1464-Colonists-3-1024x683.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/02\/1464-Colonists-3-300x200.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/02\/1464-Colonists-3-768x512.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/02\/1464-Colonists-3-160x107.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/02\/1464-Colonists-3-368x245.jpg 368w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/02\/1464-Colonists-3-510x340.jpg 510w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><\/a>Les types d\u2019action<\/h4>\n<p>Rien de tr\u00e8s nouveau de ce c\u00f4t\u00e9 l\u00e0 puisque vous pourrez\u00a0:<br \/>\n&#8211;<strong>R\u00e9colter<\/strong> des ressources (au fur et \u00e0 mesure des \u00e8res, vous allez pouvoir r\u00e9colter des ressources de plus en plus rares et de plus en plus puissantes)<br \/>\n&#8211;<strong>Transformer<\/strong> des ressources<br \/>\n&#8211;<strong>D\u00e9penser<\/strong> des ressources<br \/>\n&#8211;<strong>Etre premier<\/strong> joueur<\/p>\n<p>Jusque-l\u00e0, en effet, rien de folichon si ce n\u2019est dans les mani\u00e8res de les d\u00e9penser\u00a0:<br \/>\n&#8211;<strong>Construire un b\u00e2timent<\/strong><br \/>\nC\u2019est l\u2019action la plus commune.\u00a0 Chaque tuile action \u00ab\u00a0construction\u00a0\u00bb vous permet de construire un b\u00e2timent sp\u00e9cifique.\u00a0 Pas de hasard ici, tous les b\u00e2timents sont disponibles \u00e0 tous, il suffit simplement de se placer sur la bonne tuile action.\u00a0 Les b\u00e2timents sont le c\u0153ur du jeu et ce sont eux qui vont forger votre strat\u00e9gie.\u00a0 Il y a diff\u00e9rents types de b\u00e2timents.\u00a0 Les <strong>b\u00e2timents de production<\/strong> qui vont produire des ressources \u00e0 chaque tour, les <strong>b\u00e2timents de stockage<\/strong> qui vont vous permettre de stocker de plus en plus de ressources ce qui est primordial dans l\u2019optimisation de vos actions (vous pouvez r\u00e9aliser plusieurs fois la majorit\u00e9 des actions en une seule action \u00e0 condition d\u2019avoir les ressources suffisantes en stock), les <strong>r\u00e9sidences<\/strong> qui vont vous apporter des colons qui sont essentiels pour activer vos b\u00e2timents (pour faire fonctionner un b\u00e2timent de production de bois par exemple, vous aurez besoin d\u2019un fermier), des <strong>productions de nourriture<\/strong> essentiels pour nourrir vos colons (au plus ils seront sp\u00e9cialis\u00e9s, au plus ils auront faim\u00a0\ud83d\ude09 mais au plus ils seront sp\u00e9cialis\u00e9s, au plus de b\u00e2timents puissants vous allez pouvoir activer) et d\u2019<strong>autres b\u00e2timents<\/strong> apportant d\u2019autres bonus int\u00e9ressants.<a href=\"http:\/\/www.vindjeu.eu\/2017\/04\/01\/the-colonists-video\/1464-colonists-4\/\" rel=\"attachment wp-att-16664\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-large wp-image-16664\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/02\/1464-Colonists-4-1024x683.jpg\" alt=\"1464 Colonists 4\" width=\"720\" height=\"480\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/02\/1464-Colonists-4-1024x683.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/02\/1464-Colonists-4-300x200.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/02\/1464-Colonists-4-768x512.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/02\/1464-Colonists-4-160x107.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/02\/1464-Colonists-4-368x245.jpg 368w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/02\/1464-Colonists-4-510x340.jpg 510w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><\/a><\/p>\n<p>&#8211;<strong>Construire une ambassade<br \/>\n<\/strong>C\u2019est un des \u00e9l\u00e9ments les plus enthousiasmants de The Colonists.\u00a0 Lors de la mise en place, on va placer, au hasard, 4 ambassades sur les 9 du jeu.\u00a0 Chaque partie aura donc une combinaison de 4 ambassades unique ce qui va apporter pas mal de vari\u00e9t\u00e9.\u00a0 Chaque ambassade apporte des bonus permanents et non n\u00e9gligeables aux joueurs les ayant construites.\u00a0 Il est tr\u00e8s difficile de les construire toutes par contre en construire une ou 2 est essentiel.\u00a0 Chaque joueurs va donc \u00e9galement se construire sa propre strat\u00e9gie autour de ces ambassades.<\/p>\n<p>&#8211;<strong>Aller au march\u00e9<br \/>\n<\/strong>Le plateau modulaire central de The Colonists comprend plusieurs march\u00e9s.\u00a0 Les march\u00e9s ont la particularit\u00e9 que les stewards, pour un seul mouvement,\u00a0o\u00f9 qu\u2019ils soient sur le plateau, peuvent s\u2019y d\u00e9placer.\u00a0 On appelle \u00e7a un jump\u00a0\ud83d\ude42\u00a0 Ces march\u00e9s sont donc essentiels si on veut rapidement se d\u00e9placer sur le plateau pour utiliser les actions de tuiles \u00e9loign\u00e9es.\u00a0 Mais, quand on arrive sur un march\u00e9, il faut r\u00e9aliser son action.\u00a0 L\u2019aspect \u00e9galement tr\u00e8s ludique c\u2019est que l\u2019action qu\u2019on peut r\u00e9aliser au march\u00e9 change tous les 2 tours.\u00a0 Ca va provoquer des surprises et des opportunit\u00e9s\/d\u00e9ceptions assez sympas.<\/p>\n<p>&#8211;<strong>Piocher et jouer des cartes<\/strong><br \/>\nC\u2019est l\u2019action un peu faiblarde du jeu car on pioche ces cartes au hasard et il y a beaucoup de chance qu\u2019elles ne conviennent pas \u00e0 votre strat\u00e9gie surtout qu\u2019elles ne sont, en g\u00e9n\u00e9ral, pas tr\u00e8s fortes.\u00a0 On aurait pu s\u2019en passer&#8230;<\/p>\n<p>&#8211;<strong>Am\u00e9liorer un b\u00e2timents<\/strong><br \/>\nContre des ressources et en r\u00e9alisant l\u2019action associ\u00e9e, on peut retourner un b\u00e2timent c\u00f4t\u00e9 verso.\u00a0 Le b\u00e2timent devient alors beaucoup plus puissant.\u00a0 Cet aspect qui semble anodin (pourquoi ne pas construire tout simplement un nouveau b\u00e2timent\u00a0?) apporte une profondeur suppl\u00e9mentaire au jeu car vous allez construire des b\u00e2timents, non pas seulement pour l\u2019effet qu\u2019ils apportent maintenant mais pour les b\u00e9n\u00e9fices qu\u2019ils g\u00e9n\u00e8reront lorsqu\u2019ils seront am\u00e9lior\u00e9s.<\/p>\n<h4><a href=\"http:\/\/www.vindjeu.eu\/2017\/04\/01\/the-colonists-video\/1464-colonists-5\/\" rel=\"attachment wp-att-16665\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-large wp-image-16665\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/02\/1464-Colonists-5-1024x683.jpg\" alt=\"1464 Colonists 5\" width=\"720\" height=\"480\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/02\/1464-Colonists-5-1024x683.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/02\/1464-Colonists-5-300x200.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/02\/1464-Colonists-5-768x512.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/02\/1464-Colonists-5-160x107.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/02\/1464-Colonists-5-368x245.jpg 368w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/02\/1464-Colonists-5-510x340.jpg 510w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><\/a>La frustration<\/h4>\n<p>The Colonists est constamment frustrant\u00a0! \u00a0Et c\u2019est bon\u00a0\ud83d\ude00\u00a0 On n\u2019a jamais assez de tout\u00a0: assez de ressources, assez de places de stockages pour garder les ressources qu\u2019on a r\u00e9colt\u00e9es\/produites, assez de place pour construire des nouveaux b\u00e2timents (mieux vaut alors les am\u00e9liorer ou en d\u00e9truire certains pour faire de la place ou encore mieux, \u00e9viter d\u2019en construire des inutiles\u00a0\ud83d\ude09 ), assez de colons pour faire fonctionner tous nos b\u00e2timents, assez de nourriture pour nourrir tous nos colons, assez de points de mouvement pour atteindre telle ou telle action int\u00e9ressante,&#8230;\u00a0 Dans The Colonists, vous allez devoir g\u00e9rer tout \u00e7a&#8230;.<\/p>\n<p>The Colonists est un jeu mastodonte.\u00a0 Non seulement en taille et poids de la boite mais \u00e9galement en dur\u00e9e de jeu.\u00a0 Ne commencez pas une partie apr\u00e8s 16h00 si vous voulez la terminer le jour m\u00eame et ce, alors, sans manger.\u00a0 Il est soi-disant modulable et peut \u00eatre jou\u00e9 en un nombre diff\u00e9rents d\u2019\u00e8res mais il est clair qu\u2019il vaut mieux le jouer enti\u00e8rement qu\u2019\u00e0 moiti\u00e9.\u00a0 Il existe un syst\u00e8me de sauvegarde mais l\u00e0 aussi, il est pr\u00e9f\u00e9rable de vivre une partie compl\u00e8te d\u2019une traite.\u00a0 M\u00eame si le th\u00e8me est peu pr\u00e9sent, vous aurez le sentiment de vivre l\u2019Histoire avec l\u2019am\u00e9lioration de l\u2019efficacit\u00e9 de vos ouvriers, l\u2019am\u00e9lioration des collaborations diplomatiques, la productivit\u00e9 sans cesse croissante, la d\u00e9couverte de nouvelles ressources,&#8230;\u00a0 Cet aspect crescendo du jeu, les frustrations qu\u2019il engendre ainsi que les multiples gestions qu\u2019il n\u00e9cessite en font un jeu unique, un peu onli par son c\u00f4t\u00e9 mastodonte, mais que je vous souhaite au moins une fois de vivre tant ses sensations sont diff\u00e9rentes des jeux plus courts.\u00a0 The Colonists n\u2019a des Colons que les tuiles hexagonales et le bois.\u00a0 Pour le reste, c\u2019est du pur et long bonheur\u00a0!<\/p>\n<hr \/>\n<p><a href=\"http:\/\/www.vindjeu.eu\/2017\/02\/06\/key-to-the-city-london-video\/dan-2\/\" rel=\"attachment wp-att-16069\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-thumbnail wp-image-16069\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/01\/Dan-2-e1483913787418-150x150.jpg\" alt=\"dan-2\" width=\"150\" height=\"150\" \/><\/a><\/p>\n<p><strong><span style=\"color: #333399;\">Dan<\/span><\/strong>:<strong><span style=\"color: #800000;\">\u00a0\u00a07,5\/10<\/span><\/strong><\/p>\n<p>J&rsquo;ai un avis asseze partag\u00e9 sur ce jeu pour joueurs confirm\u00e9s.<\/p>\n<p>D&rsquo;un c\u00f4t\u00e9 la m\u00e9canique est fluide et le jeu m\u00eale tactique et strat\u00e9gie.\u00a0 Les options semblent nombreuses et les quatre \u00e8res du jeu proposent une \u00e9volution certaine (tuiles\/cartes de plus en lus int\u00e9ressantes).<\/p>\n<p>De l&rsquo;autre, sachant que nous nous sommes arr\u00eat\u00e9s \u00e0 la deuxi\u00e8me \u00e8re (ce que le jeu permet), autant la premi\u00e8re \u00e8re \u00e9tait excitante, autant la seconde m&rsquo;est apparue comme une r\u00e9p\u00e9tition d&rsquo;actions toujours identiques car plus rentables.\u00a0 Il n&rsquo;y avait, il est vrai, aucun int\u00e9r\u00eat \u00e0 pr\u00e9parer le futur.<\/p>\n<p>Bref, the Colonists propose du bon et du moins bon pour un jeu qui m\u00e9riterait d&rsquo;\u00eatre essay\u00e9 sur quatre \u00e8res pour se faire une opinion plus juste sur sa r\u00e9elle ampleur.\u00a0 Mais dans ce cas, pr\u00e9voyez au minimum 6 \u00e0 7 heures de jeu&#8230;<\/p>\n<hr \/>\n<p><a href=\"http:\/\/www.vindjeu.eu\/2017\/04\/01\/the-colonists-video\/1464-colonists-8\/\" rel=\"attachment wp-att-16656\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-16656\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/02\/1464-Colonists-8-e1487952998268.jpg\" alt=\"1464 Colonists 8\" width=\"1500\" height=\"1000\" \/><\/a><\/p>\n<hr \/>\n<h2><span style=\"color: #800080;\">Vin d&rsquo;jeu d&rsquo;avis<\/span><\/h2>\n<h3>La d\u00e9gustation en 9 minutes par <span style=\"color: #333399;\">SwatSh<\/span><\/h3>\n<div class=\"video-container\"><iframe loading=\"lazy\" title=\"The Colonists (Vin d&#039;jeu d&#039;video)\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/Bx-yIFgAiwA?feature=oembed&#038;wmode=opaque\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n","protected":false},"excerpt":{"rendered":"<p> Avec la chouette 5\u00e8me extension de Steam, l\u2019excellent Agricola Family Edition, The Colonists \u00e9tait la grande et grosse sortie de Mayfair au dernier salon d\u2019Essen.\u00a0 The Colonists est en effet une boite \u00e0 l\u2019image de Caverna aussi bien en taille qu\u2019en poids.\u00a0 Mais sa lourdeur ne s\u2019arr\u00eate pas&#46;&#46;&#46;<\/p>\n","protected":false},"author":3,"featured_media":16657,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[4849],"tags":[502,7],"class_list":["post-16655","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-expert","tag-dan","tag-swatsh","annee-1090","auteurs-tim-puls","editeurs-mayfair-games","illustrateurs-klemmens-franz","distributeurs-esdevium-games"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/16655","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/comments?post=16655"}],"version-history":[{"count":0,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/16655\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media\/16657"}],"wp:attachment":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media?parent=16655"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/categories?post=16655"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/tags?post=16655"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}