{"id":16723,"date":"2017-06-26T21:46:11","date_gmt":"2017-06-26T19:46:11","guid":{"rendered":"http:\/\/www.vindjeu.eu\/?p=16723"},"modified":"2017-09-20T23:02:02","modified_gmt":"2017-09-20T21:02:02","slug":"lorenzo-il-magnifico-video","status":"publish","type":"post","link":"https:\/\/www.vindjeu.eu\/prd\/2017\/06\/26\/lorenzo-il-magnifico-video\/","title":{"rendered":"Lorenzo Le Magnifique"},"content":{"rendered":"<p><a href=\"http:\/\/www.vindjeu.eu\/2017\/06\/26\/lorenzo-il-magnifico-video\/1553-lorenzo\/\" rel=\"attachment wp-att-18007\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-18007\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/06\/1553-Lorenzo.png\" alt=\"1553 Lorenzo\" width=\"308\" height=\"500\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/06\/1553-Lorenzo.png 308w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/06\/1553-Lorenzo-185x300.png 185w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/06\/1553-Lorenzo-99x160.png 99w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/06\/1553-Lorenzo-151x245.png 151w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/06\/1553-Lorenzo-209x340.png 209w\" sizes=\"auto, (max-width: 308px) 100vw, 308px\" \/><\/a><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-thumbnail wp-image-16690\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/02\/Swa-8-150x150.jpg\" alt=\"Swa 8\" width=\"150\" height=\"150\" \/><strong><span style=\"color: #333399;\">SwatSh<\/span><\/strong>:<strong><span style=\"color: #800000;\">\u00a09,5 \/10<\/span><\/strong><\/p>\n<p>Waouw, quelle claque il m\u2019a donn\u00e9 ce Lorenzo\u00a0!\u00a0 C\u2019est rare mais voil\u00e0 un jeu qui n\u2019a pas vraiment fait de buzz et qui passe un peu inaper\u00e7u alors qu\u2019il est excellent\u00a0!\u00a0 Il faut dire que son \u00e9diteur, <a href=\"http:\/\/www.vindjeu.eu\/editeurs\/cranio-creation\/\">Cranio Creation<\/a>, ne nous avait, jusqu\u2019\u00e0 pr\u00e9sent, pas habitu\u00e9s \u00e0 des jeux de cette profondeur et de cette qualit\u00e9.\u00a0 Avec des titres comme <a href=\"http:\/\/www.vindjeu.eu\/2014\/03\/09\/steam-park\/\">Steam Park<\/a>, <a href=\"http:\/\/www.vindjeu.eu\/2010\/11\/10\/escape-from-the-aliens-in-outer-space\/\">Escape From the Aliens<\/a>, <a href=\"http:\/\/www.vindjeu.eu\/2016\/12\/15\/unusual-suspects-burn-after-playing-video\/\">Unusual suspects <\/a>ou Dungeon Fighter, <a href=\"http:\/\/www.vindjeu.eu\/editeurs\/cranio-creation\/\">Cranio <\/a>visait un public diff\u00e9rent.\u00a0 Ceci dit, en 2015, l\u2019excellent <a href=\"http:\/\/www.vindjeu.eu\/2015\/11\/30\/council-of-four\/\">Council of 4<\/a> aurait d\u00fb d\u00e9j\u00e0 nous mettre la puce \u00e0 l\u2019oreille. \u00a0Mais il n\u2019y a pas que \u00e7a qui aurait d\u00fb nous titiller.\u00a0 La triplette\u00a0\ud83d\ude09 d\u2019auteurs n\u2019en est pas \u00e0 son coup d\u2019essai et a d\u00e9j\u00e0 r\u00e9alis\u00e9 d\u2019excellents jeux\u00a0dont <a href=\"http:\/\/www.vindjeu.eu\/2010\/01\/27\/egizia\/\">Egizia<\/a>, <a href=\"http:\/\/www.vindjeu.eu\/2016\/03\/09\/grand-austria-hotel\/\">Grand Austria Hotel <\/a>(un de nos <a href=\"http:\/\/www.vindjeu.eu\/2016\/09\/19\/vin-djeu-dlannee-2016\/\">coups de coeur 2016<\/a>), <a href=\"http:\/\/www.vindjeu.eu\/2013\/03\/11\/tzolkin-the-mayan-calendar\/\">Tzolkin <\/a>(<a href=\"http:\/\/www.vindjeu.eu\/vin-djeu-dlannee\/2013-2\/\">Vin d\u2019jeu d\u2019l\u2019ann\u00e9e 2013<\/a>), <a href=\"http:\/\/www.vindjeu.eu\/2015\/07\/29\/les-voyages-de-marco-polo\/\">Les Voyages de Marco Polo <\/a>et <a href=\"http:\/\/www.vindjeu.eu\/2015\/11\/30\/council-of-four\/\">council of 4<\/a>\u00a0!!!\u00a0 Oui, on a affaire \u00e0 du s\u00e9rieux\u00a0\ud83d\ude42<\/p>\n<p>Pourtant, de prime abord, Lorenzo Il Magnifico est un simple jeu de cartes avec une m\u00e9canique de placement d\u2019ouvriers pour leur acquisition.\u00a0 Rien de folichon folichon mais&#8230;<\/p>\n<h3>Du placement d\u2019ouvriers boost\u00e9 aux d\u00e9s<\/h3>\n<p>Les auteurs se sont probablement inspir\u00e9s de <a href=\"http:\/\/www.vindjeu.eu\/auteurs\/stefan-feld\/\">Feld <\/a>pour cr\u00e9er une m\u00e9canique utilisant les d\u00e9s tout en minimisant le hasard.\u00a0 Le jeu se joue en 6 tours et, \u00e0 chaque d\u00e9but de tour, on lance les 3 d\u00e9s (l\u2019orange, le blanc et le noir) qui d\u00e9terminent chacun la valeur des ouvriers de tous les joueurs.\u00a0 En effet, chaque joueuse a 4 ouvri\u00e8res\u00a0:<br \/>\n1) L\u2019ouvri\u00e8re noire qui a la valeur du d\u00e9 noir<br \/>\n2) L\u2019ouvri\u00e8re orange qui a la valeur du d\u00e9 orange<br \/>\n3) L\u2019ouvri\u00e8re blanche qui a la valeur de d\u00e9 blanc (non\u00a0?\u00a0 si si\u00a0\ud83d\ude42 )<br \/>\n4) L\u2019ouvri\u00e8re incolore qui vaut 0<\/p>\n<p>Et la valeur de chaque ouvri\u00e8re va d\u00e9terminer ses actions possibles.\u00a0 Au plus sa valeur est \u00e9lev\u00e9e, au plus de possibilit\u00e9s d\u2019action sa propri\u00e9taire aura.\u00a0 L\u2019ouvrier incolore de valeur 0 est inutilisable tel quel puisqu\u2019il faut une valeur de 1 minimum pour pouvoir ex\u00e9cuter une action, mais les auteurs ont bien entendu pr\u00e9vu une ressource (les assistantes) permettant d\u2019augmenter la valeur d\u2019une ouvri\u00e8re au co\u00fbt de 1 point par assistant.<\/p>\n<p>Et cette petite trouvaille, qui n\u2019a l\u2019air de rien comme \u00e7a, tourne du tonnerre.\u00a0 On va constamment devoir g\u00e9rer ses ouvri\u00e8res et les placer aux bons endroits en sachant qu\u2019on ne va pas n\u00e9cessairement commencer par placer ses ouvri\u00e8res de plus grande valeur car certaines actions exigeant des valeurs moins \u00e9lev\u00e9es peuvent \u00eatre plus pris\u00e9es que d\u2019autres.\u00a0 C\u2019est tr\u00e8s subtil comme m\u00e9canique.\u00a0 Il vous faudra \u00e9galement surveiller les possibilit\u00e9s des autres joueuses\u00a0en surveillant les ouvri\u00e8res qu\u2019elles ont d\u00e9j\u00e0 utilis\u00e9es et celles qui leur restent.<a href=\"http:\/\/www.vindjeu.eu\/2017\/06\/26\/lorenzo-il-magnifico-video\/1471-lorenzo-2\/\" rel=\"attachment wp-att-16841\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-full wp-image-16841\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/03\/1471-Lorenzo-2-e1490129816569.jpg\" alt=\"1471 Lorenzo 2\" width=\"450\" height=\"675\" \/><\/a><\/p>\n<h3>Les cartes<\/h3>\n<p>Comme d\u00e9j\u00e0 \u00e9crit plus haut, le coeur du jeu est un jeu de cartes.\u00a0 96 en tout.\u00a0 C\u2019est beaucoup, mais en m\u00eame temps j\u2019ai envie de dire seulement\u00a0\ud83d\ude09\u00a0 (Aaargh le joueur qui en veut toujours plus que je suis\u00a0\ud83d\ude00 ).\u00a0 En fait, \u00e0 chacun des 6 tours de jeux, 16 nouvelles cartes sont pr\u00e9sent\u00e9es \u00e0 l\u2019acquisition.\u00a0 Et 16 x 6 = quoi\u00a0?\u00a0 Je vous le donne dans l\u2019mille\u00a0: 96\u00a0!\u00a0 Autrement dit, \u00e0 chaque partie, on verra les m\u00eames 96 cartes d\u00e9filer.\u00a0 Seul leur ordre changera et encore car elles sont subdivis\u00e9es en 3 \u00e8res.\u00a0 1 \u00e8re pour chaque 2 tours. \u00a0Autrement dit, les 32 cartes de la premi\u00e8re \u00e8re seront disponibles \u00e0 l\u2019achat les 2 premiers tours, les 32 suivantes seront dispo les 3\u00e8me et 4\u00e8me tours,&#8230;\u00a0 Autant de choix, c\u2019est \u00e9norme bien entendu, surtout que les cartes sont bien vari\u00e9es dans leurs effets mais en m\u00eame temps, \u00e7a aurait \u00e9t\u00e9 super si le jeu contenait encore plus de cartes afin d\u2019encore mieux varier les parties (on ne jouerait qu\u2019\u00e0 une partie des cartes \u00e0 chaque partie, un peu comme dans <a href=\"http:\/\/www.vindjeu.eu\/2009\/01\/24\/dominion\/\">Dominion<\/a>).<\/p>\n<p>Ces cartes seront mises al\u00e9atoirement sur les 16 cases d\u2019achats, certaines n\u2019\u00e9tant disponibles qu\u2019aux ouvri\u00e8res de grande valeur.\u00a0 Certaines cartes seront donc plus difficilement \u00ab\u00a0achetables\u00a0\u00bb alors qu\u2019elles ne sont pas n\u00e9cessairement plus int\u00e9ressantes.\u00a0 C\u2019est juste l\u2019al\u00e9a de la disposition des cartes.\u00a0 Voil\u00e0 pourquoi il peut \u00eatre int\u00e9ressant de placer un ouvrier de faible valeur avant un ouvrier plus puissant.\u00a0 Ceci dit, l\u2019\u00e9quilibrage des cartes est un exemple du genre et jamais on ne va pester sur la puissance d\u2019une carte par rapport \u00e0 une autre.\u00a0 Les choix sont \u00e0 chaque fois corn\u00e9liens.\u00a0 Magnifique\u00a0\ud83d\ude42<\/p>\n<h3>Leur vari\u00e9t\u00e9<\/h3>\n<p>Ce qui est impressionnant dans Lorenzo il Magnifico, c\u2019est la vari\u00e9t\u00e9 des effets des cartes.\u00a0 \u00a0Il y a des cartes qui vous rapporteront des PVs ou des ressources en \u00e9change de certaines ressources, d\u2019autres qui vous apporteront des ressources gr\u00e2ce \u00e0 l\u2019action production ou \u00e0 l\u2019action r\u00e9colte, d\u2019autres qui vous donneront des choses directement, d\u2019autres qui vous apporteront des nouvelles capacit\u00e9s, des PVs, des ressources, des r\u00e9ductions,&#8230;\u00a0 Et tout cela se combine \u00e0 merveille et permet la mise en place de diverses strat\u00e9gies autant efficaces les unes que les autres.<\/p>\n<p>De plus, le jeu propose une variante experte avec des cartes leaders et des capacit\u00e9s de production diff\u00e9rentes pour chaque joueur.\u00a0 Cela donne des d\u00e9parts asym\u00e9triques et m\u00eame des strat\u00e9gies encore plus vari\u00e9es gr\u00e2ce aux effets des cartes leaders.\u00a0 Tout cela, encore une fois, est extr\u00eamement bien \u00e9quilibr\u00e9.\u00a0 Magnifique\u00a0\ud83d\ude00<\/p>\n<h3><a href=\"http:\/\/www.vindjeu.eu\/2017\/06\/26\/lorenzo-il-magnifico-video\/1471-lorenzo-3\/\" rel=\"attachment wp-att-16842\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-16842\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/03\/1471-Lorenzo-3-e1490129911547.jpg\" alt=\"1471 Lorenzo 3\" width=\"620\" height=\"413\" \/><\/a>Notre foi en l\u2019\u00e9glise<\/h3>\n<p>A l\u2019image d\u2019<a href=\"http:\/\/www.vindjeu.eu\/2011\/05\/08\/agricola\/\">Agricola<\/a>, de <a href=\"http:\/\/www.vindjeu.eu\/2013\/03\/11\/tzolkin-the-mayan-calendar\/\">Tzolkin <\/a>ou de tout autre jeu \u00e0 contraintes, Lorenzo Il Magnifico va \u00e9galement vous stresser, mais ici pas avec de la nourriture mais avec votre foi\u00a0!\u00a0 Vous allez devoir prouver votre pi\u00e9t\u00e9\u00a0\ud83d\ude09\u00a0 Pour cela, tous les 2 tours, vous allez devoir d\u00e9penser un nombre minimum de points de foi.\u00a0 Si vous ne le faites pas, vous serez excommuni\u00e9s et aurez un malus permanent\u00a0: la valeur de tous vos ouvriers vaut 1 en moins, si vous voulez acheter tel type de carte, la valeur de votre ouvrier que vous utiliserez diminue de -4, tel type de carte n\u2019apporte aucun PV,&#8230;\u00a0 Dans la boite, il y a \u00e9norm\u00e9ment de cons\u00e9quences n\u00e9fastes diff\u00e9rentes dont on en tire 3 pour chaque partie.\u00a0 Ceci permet pas mal de vari\u00e9t\u00e9 dans vos parties sans pour autant \u00eatre pr\u00e9pond\u00e9rant comme les b\u00e2timents dans <a href=\"http:\/\/www.vindjeu.eu\/2013\/03\/11\/tzolkin-the-mayan-calendar\/\">Tzolkin<\/a>.<\/p>\n<p>L\u2019aspect encore plus g\u00e9nial de ce syst\u00e8me c\u2019est que pour \u00e9viter d\u2019\u00eatre excommuni\u00e9, il va falloir d\u00e9penser la totalit\u00e9 de ses points de foi et repartir \u00e0 z\u00e9ro pour les 2 tours qui suivent.\u00a0 Hors, si on d\u00e9cide de ne pas les d\u00e9penser et de subir l\u2019excommunication, les PVs qu\u2019on gagnera sur la piste de foi seront exponentiellement plus int\u00e9ressants.\u00a0 Il est donc int\u00e9ressant d\u2019\u00eatre excommuni\u00e9 car on pourra gagner d\u2019autant plus de PVs mais on subira les cons\u00e9quences de l\u2019excommunication.\u00a0 Il faudra alors ajuster sa strat\u00e9gie en fonction des malus d\u2019excommunication.\u00a0 Et d\u00e8s le d\u00e9part de la partie on peut se forger une strat\u00e9gie qui tienne compte de ces malus et qui les int\u00e8gre.\u00a0 Fabuleux\u00a0!\u00a0 Magnifique\u00a0\ud83d\ude00<a href=\"http:\/\/www.vindjeu.eu\/2017\/06\/26\/lorenzo-il-magnifico-video\/1471-lorenzo-4\/\" rel=\"attachment wp-att-16843\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-full wp-image-16843\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/03\/1471-Lorenzo-4-e1490130089363.jpg\" alt=\"1471 Lorenzo 4\" width=\"650\" height=\"433\" \/><\/a><\/p>\n<p>Il y a tr\u00e8s peu de reproches \u00e0 formuler \u00e0 Lorenzo il Magnifico.\u00a0 Un th\u00e8me trop peu pr\u00e9sent et une vari\u00e9t\u00e9 des parties assur\u00e9e que par le tirage des cartes &amp; des sanctions de l\u2019excommunication en sont les principaux.\u00a0 On aurait aim\u00e9 avoir encore plus de cartes \u00e0 notre disposition afin d\u2019assurer une plus grande vari\u00e9t\u00e9 des parties.\u00a0 Mais mis \u00e0 part \u00e7a, Lorenzo Il Magnifico est un m\u00e9lange subtil de jeu de cartes et de placement d\u2019ouvriers soutenu par une m\u00e9canique originale et magnifiquement \u00e9quilibr\u00e9e de valeur d\u2019ouvriers fix\u00e9e par les d\u00e9s.\u00a0 La vari\u00e9t\u00e9 des cartes et les multiples combinaisons possibles ainsi que les possibilit\u00e9s des pistes de foi et de force arm\u00e9e en font un jeu profond, sans hasard, aux multiples strat\u00e9gies, aux choix corn\u00e9liens, \u00e0 la gestion des ouvri\u00e8res exigeante et \u00e0 l\u2019\u00e9quilibre parfait.\u00a0 Cerise sur le g\u00e2teau, \u00e0 l\u2019exception peut-\u00eatre des ouvriers qui auraient pu montrer une plus grande distinction dans la couleur des d\u00e9s qu\u2019ils repr\u00e9sentent, l\u2019iconographie est juste impeccable et les r\u00e8gles sont limpides.\u00a0 Un grand merci \u00e0 <a href=\"http:\/\/www.vindjeu.eu\/distributeurs\/atalia\/\">Atalia <\/a>d\u2019avoir effectu\u00e9 le travail de traduction Fran\u00e7aise que le jeu m\u00e9ritait pour pouvoir \u00eatre jou\u00e9 dans toute la francophonie.\u00a0 Ce serait dommage de passer \u00e0 c\u00f4t\u00e9 maintenant.<\/p>\n<p>Apr\u00e8s <a href=\"http:\/\/www.vindjeu.eu\/editeurs\/whats-your-game\/\">What\u2019s Your Game<\/a>, c\u2019est maintenant <a href=\"http:\/\/www.vindjeu.eu\/editeurs\/cranio-creation\/\">Cranio Creation <\/a>qui nous prouve que l\u2019Italie n\u2019a pas que des relents m\u00e9diterran\u00e9ens mais est \u00e9galement tr\u00e8s proche de l\u2019Allemagne.<\/p>\n<p>Magnifique jeu\u00a0\ud83d\ude00<\/p>\n<h4><span style=\"color: #008080;\">Nouvelles parties<\/span><\/h4>\n<p>Apr\u00e8s plusieurs parties, je ne puis que confirmer nos premi\u00e8res impressions\u00a0: ce jeu est fantastique.\u00a0 Ce qui m\u2019a particuli\u00e8rement bien plus lors de nos derni\u00e8res parties c\u2019est tout d\u2019abord la relative simplicit\u00e9 des r\u00e8gles qui permet \u00e0 chacun de se plonger facilement dans les r\u00e8gles m\u00eame les nouveaux venus.\u00a0 De plus, l\u2019iconographie est tellement bien faite qu\u2019il est inutile de les relire avant d\u2019y rejouer tant elles sont bien m\u00e9morisables.\u00a0 Enfin, ce qui est vraiment g\u00e9nial dans ce jeu c\u2019est qu\u2019il permet une multitude de strat\u00e9gies diff\u00e9rentes m\u00eame les plus mod\u00e9r\u00e9es.\u00a0 Les PVs exponentiels encouragent la sp\u00e9cialisation mais une joueuse qui ne se sp\u00e9cialise dans aucun type de b\u00e2timent ou d\u2019action peut \u00e9galement pr\u00e9tendre \u00e0 la victoire.\u00a0\u00a0 Du tout tout bon\u00a0!<\/p>\n<hr \/>\n<p><a href=\"http:\/\/www.vindjeu.eu\/2016\/11\/06\/between-two-cities\/ren-4\/\" rel=\"attachment wp-att-15188\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-thumbnail wp-image-15188\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2016\/10\/Ren-4-e1477136030904-150x150.jpg\" alt=\"ren-4\" width=\"150\" height=\"150\" \/><\/a><strong><span style=\"color: #333399;\">Ren<\/span><\/strong>:<strong><span style=\"color: #800000;\">\u00a0\u00a0\u00a09\/10<\/span><\/strong><\/p>\n<p>On vit une p\u00e9riode magnifique. Comme je le disais dans mon article sur Essen fin 2016, pour un amateur de jeu de soci\u00e9t\u00e9 on vit un \u00e2ge d\u2019or. Jugez plut\u00f4t les jeux top que j\u2019ai essay\u00e9s ces 6 derniers mois (je ne parle que de moi, pas des autres membres de Vin d\u2019Jeu, et pas non plus des nombreux jeux incroyables sortis ces derni\u00e8res ann\u00e9es, et dont il reste des dizaines de parties \u00e0 jouer avant de les conna\u00eetre vraiment): <a href=\"http:\/\/www.vindjeu.eu\/2016\/12\/28\/great-western-trail-video\/\">Great Western Trail<\/a>, <a href=\"http:\/\/www.vindjeu.eu\/2017\/03\/30\/a-la-gloire-dodin-video\/\">A la Gloire d\u2019Odin<\/a>, <a href=\"http:\/\/www.vindjeu.eu\/2016\/11\/16\/terraforming-mars-video\/\">Terraforming Mars<\/a>, <a href=\"http:\/\/www.vindjeu.eu\/2017\/01\/24\/deus-egypt-video\/\">Deus: Egypt<\/a>, <a href=\"http:\/\/www.vindjeu.eu\/2017\/02\/20\/round-house-videos\/\">Round House<\/a>\u2026 Bref de la bombe en veux-tu en voil\u00e0!<\/p>\n<p>Et la tendance se confirme aujourd\u2019hui avec Lorenzo Il Magnifico, un\u2026 magnifique jeu de Flaminia Brasini, Virginio Gigli et Simone Luciani, d\u00e9j\u00e0 auteurs (seuls ou ensemble) de, notamment, <a href=\"http:\/\/www.vindjeu.eu\/2010\/01\/27\/egizia\/\">Egizia<\/a>, <a href=\"http:\/\/www.vindjeu.eu\/2016\/03\/09\/grand-austria-hotel\/\">Grand Austria Hotel <\/a>ou <a href=\"http:\/\/www.vindjeu.eu\/2013\/03\/11\/tzolkin-the-mayan-calendar\/\">Tzolkin<\/a>. Pas exactement des daubes\u2026<\/p>\n<p>Dans Lorenzo on va incarner des familles nobles de Florence, qui vont essayer d\u2019asseoir leur influence. Mais comme souvent le th\u00e8me est peu important (m\u00eame si Klemens Franz, l\u2019illustrateur bien connu, tente un effort m\u00e9ritoire mais vain pour nous faire rentre dans le th\u00e8me), nous sommes en pr\u00e9sence d\u2019un classique jeu de pose d\u2019ouvriers. Tout \u00e0 fait classique certes, mais qui fonctionne superbement, et qui offre une multitude de choix tout en restant dans une dur\u00e9e relativement raisonnable (bon on reste dans du jeu de gestion hein!).<\/p>\n<p><a href=\"http:\/\/www.vindjeu.eu\/2017\/06\/26\/lorenzo-il-magnifico-video\/1337-essen-6-lorenzo-2-2\/\" rel=\"attachment wp-att-17063\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-17063\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/04\/1337-Essen-6-Lorenzo-2.jpg\" alt=\"1337 Essen 6 Lorenzo 2\" width=\"500\" height=\"350\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/04\/1337-Essen-6-Lorenzo-2.jpg 500w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/04\/1337-Essen-6-Lorenzo-2-300x210.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/04\/1337-Essen-6-Lorenzo-2-160x112.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/04\/1337-Essen-6-Lorenzo-2-350x245.jpg 350w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/04\/1337-Essen-6-Lorenzo-2-486x340.jpg 486w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a>Le m\u00e9canisme de base est donc la pose d\u2019ouvriers (4 par joueur, dont un \u00abneutre\u00bb), qu\u2019on va placer dans une case d\u2019action disponible dans une des 4 tours (on ach\u00e8tera alors une carte) ou sur un des autres cases d\u2019action disponibles. Vraiment classique de chez classique. Mais pas mal de petites ou grandes astuces vont tr\u00e8s solidement pimenter ce menu de base:<\/p>\n<p>&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 La valeur des 3 membres de sa famille va \u00eatre d\u00e9termin\u00e9e par un lancer de d\u00e9s, et cette valeur sera la m\u00eame pour chaque joueur. En d\u2019autres mots chaque joueur a un pion noir, un blanc et un orange. On jette un d\u00e9 pour chaque couleur. Et donc le joueur rouge aura un pion noir, un blanc et un orange. Le joueur vert idem\u2026 Et pour chacun le noir aura la valeur donn\u00e9e par le d\u00e9. Cette valeur est importante pour d\u00e9terminer les actions auxquelles on aura acc\u00e8s, sachant que plus on monte dans une tour plus il faut une valeur de d\u00e9 \u00e9lev\u00e9e.<\/p>\n<p>&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Les 2 \u00e9tages les plus hauts donnent un bonus quand on choisit une de leurs actions.<\/p>\n<p>&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Chaque tour pr\u00e9sente une orientation principale (production, r\u00e9colte, personnages influents, projets sp\u00e9cifiques). Et on aura int\u00e9r\u00eat \u00e0 bien combiner les cartes choisies pour maximiser les effets de ses choix (ce ne serait pas malin de produire si on a peu de cartes de production).<\/p>\n<p>&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Il y a une piste de foi, sur laquelle on doit aller suffisamment loin \u00e0 chaque \u00e8re (il y en a 3, avec 2 manches par \u00e8re, soit 6 manches en tout) sans quoi on est excommuni\u00e9 par l\u2019\u00e9glise (=on a une p\u00e9nalit\u00e9 sp\u00e9cifique jusqu\u2019\u00e0 la fin de la partie). Ceci met du piment dans la partie, car on doit choisir de prier suffisamment ou pas pour \u00e9viter, ou pas, l\u2019excommunication (\u00e7a peut \u00eatre int\u00e9ressant car selon sa strat\u00e9gie la p\u00e9nalit\u00e9 peut ne pas \u00eatre trop grave).<\/p>\n<p>&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Il y a un syst\u00e8me tr\u00e8s astucieux pour placer les pions (un membre de chaque famille par tour maximum, sachant que le neutre peut \u00eatre plac\u00e9 \u00e0 c\u00f4t\u00e9 d\u2019un membre d\u2019une famille + quand on place un pion dans une tour o\u00f9 il y a d\u00e9j\u00e0 un autre pion, \u00e0 soi ou \u00e0 un autre joueur, on doit payer pour pouvoir s\u2019y placer) qui rend cette pose bien plus excitante qu\u2019un jeu classique de pose d\u2019ouvriers (sachant \u00e9videmment que pour la plupart des actions un seul pion peut \u00eatre plac\u00e9 sur chaque case).<\/p>\n<p>&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 On peut modifier la valeur des d\u00e9s en d\u00e9pensant des serviteurs (qu\u2019on peut gagner via certaines actions).<\/p>\n<p>&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 La petite extension Leaders (int\u00e9gr\u00e9e au jeu) offre des choix suppl\u00e9mentaires, qui orientent et\/ou renforcent la strat\u00e9gie qu\u2019on choisit.<\/p>\n<p>Le tout donne un jeu certes classique dans son essence, mais avec quelques sp\u00e9cificit\u00e9s tr\u00e8s originales, et qui surtout tourne magnifiquement bien. Et dans une dur\u00e9e qui reste tout \u00e0 fait raisonnable par rapport \u00e0 la profondeur strat\u00e9gique offerte par le jeu. Moi je vous le dis, on vit une \u00e9poque magnifique en tant qu\u2019amateur de jeu de soci\u00e9t\u00e9&#8230;\u00a0&#x1f60a;<\/p>\n<hr \/>\n<p><a href=\"http:\/\/www.vindjeu.eu\/2015\/08\/27\/barony\/pascal-1\/\" rel=\"attachment wp-att-16074\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-thumbnail wp-image-16074\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2015\/08\/Pascal-1-150x150.jpg\" alt=\"pascal-1\" width=\"150\" height=\"150\" \/><\/a><strong><span style=\"color: #333399;\">Pascal<\/span><\/strong>:<strong><span style=\"color: #800000;\">\u00a0\u00a0\u00a0\u00a0\u00a0 9\/10<\/span><\/strong><\/p>\n<p>Rien qu&rsquo;avec son nom, ce jeu annonce la couleur.\u00a0 Magnifique, en effet, il m\u00e9rite bien ce qualificatif !<\/p>\n<p>Tout d&rsquo;abord les r\u00e8gles sont assez claires et, compar\u00e9 \u00e0 la profondeur de jeu, on peut presque parler de simplicit\u00e9.\u00a0 Attention quand m\u00eame, on est en face d&rsquo;un gros jeu, tr\u00e8s calculatoire et bien casse-t\u00eate.\u00a0 Le mat\u00e9riel est tout \u00e0 fait correct (l&rsquo;ic\u00f4nographie est top), mais je trouve les couleurs un peu terne et le plateau un peu trop charg\u00e9.<\/p>\n<p>Mais venons-en aux grosses qualit\u00e9s du jeu : la m\u00e9canique d&rsquo;actions bas\u00e9e sur des d\u00e9s qui donneront une force \u00e0 votre pion de la couleur correspondante (plus le d\u00e9 \u00e0 une valeur \u00e9lev\u00e9e, plus votre pion de la m\u00eame couleur pourra servir \u00e0 des actions).\u00a0 Mais cela vaut aussi pour vos adversaires ! Vous me direz : si il y a des d\u00e9s, il y a du hasard.\u00a0 Et c&rsquo;est bien vrai, mais il est possible de diminuer son effet en acqu\u00e9rant des cartes qui vous permettront d&rsquo;augmenter la valeur d&rsquo;une couleur de d\u00e9.<\/p>\n<p>Autre petite id\u00e9e int\u00e9ressante, la piste de foi, et le risque de vous voir excommunier.\u00a0 Des choix tr\u00e8s difficiles: des points \u00e0 gagner ou des p\u00e9nalit\u00e9s assez lourdes pour le reste de la partie.<\/p>\n<p>Je ne pense pas que le jeu de base propose une \u00e9norme rejouabilit\u00e9: toutes les cartes sont utilis\u00e9es \u00e0 chacune des parties.\u00a0 Elles arriveront dans un ordre diff\u00e9rent, mais je ne suis pas s\u00fbr que ce soit suffisant.\u00a0 Heureusement l&rsquo;extension Leader compense largement ce point : toute ma partie a \u00e9t\u00e9 guid\u00e9e par une carte leader que j&rsquo;ai obtenue en d\u00e9but de partie.<\/p>\n<p>Et finalement, un petit b\u00e9mol pour l&rsquo;interactivit\u00e9 qui est froide et indirecte (dans le choix des cartes sur le plateau, qui sera principalement guid\u00e9 par l&rsquo;ordre du tour qui heureusement peut \u00eatre modifi\u00e9 par une action), mais ce petit d\u00e9faut est assez fr\u00e9quent sur les jeux tr\u00e8s calculatoires !<\/p>\n<p>Excellent jeu, donc, je recommande aux \u00ab\u00a0hard gamers\u00a0\u00bb !<\/p>\n<hr \/>\n<p><a href=\"http:\/\/www.vindjeu.eu\/2016\/09\/22\/million-club\/tapimoket\/\" rel=\"attachment wp-att-14734\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-14734\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2016\/09\/Tapimoket.png\" alt=\"tapimoket\" width=\"125\" height=\"160\" \/><\/a><\/p>\n<p><span style=\"color: #333399;\"><strong>Tapimoket<\/strong><\/span><strong>: \u00a0<\/strong><span style=\"color: #800000;\"><strong>8,5\/10<\/strong><\/span><\/p>\n<p>J&rsquo;ai longtemps h\u00e9sit\u00e9 \u00e0 donner un avis sur Lorenzo. Lors de la premi\u00e8re partie, j&rsquo;avais plus l&rsquo;impression de \u00ab\u00a0survivre\u00a0\u00bb que de me d\u00e9velopper. J&rsquo;ai rarement vu un jeu avec autant de flux tendus. On manque de tout, de sous, de ressources, d&rsquo;actions&#8230; C&rsquo;est terrible! Les p\u00e9nalit\u00e9s de l&rsquo;excommunication sont tr\u00e8s punitives, ainsi on essaye de les \u00e9viter tout en essayant tant bien que mal de g\u00e9rer ses objectifs. Bref c&rsquo;est chaud !<\/p>\n<p>Mais finalement, en y rejouant, je savais cette fois \u00e0 quoi m&rsquo;attendre. Je savais qu&rsquo;il fallait optimiser chaque coup, pr\u00e9voir une strat\u00e9gie d\u00e8s le d\u00e9part, un axe \u00e0 suivre et esp\u00e9rer qu&rsquo;il sera gagnant. Disons-le tout de suite, Lorenzo ne vous fera pas de quartier, si vous ne savez pas comment aborder le jeu. Ceci veut dire qu&rsquo;il faut au moins une partie pour ma\u00eetriser la b\u00eate, ne serait-ce pour connaitre les cartes qui seront mises en jeu et pr\u00e9parer ce dont vous avez besoin pour chaque manche. Cependant, il faut savoir que\u00a0les r\u00e8gles ne\u00a0sont pas une usine \u00e0 gaz.<\/p>\n<p>La m\u00e9canique du jeu s&rsquo;appuyant aussi sur un jet de d\u00e9s, les restrictions pourront parfois \u00eatre telles qu&rsquo;on ne jouera que quelques actions durant toute une manche. Heureusement, tous les joueurs seront \u00e0 la m\u00eame enseigne. il faut juste esp\u00e9rer que tous les jets d\u00e9s ne soient pas trop bas.<\/p>\n<p>C\u00f4t\u00e9 th\u00e8me, illustrations et mat\u00e9riel, on reste dans le pur jeu \u00e0 l&rsquo;allemande (m\u00eame si Lorenzo est d&rsquo;Italie). Ce n&rsquo;est pas d\u00e9sagr\u00e9able, mais reste tr\u00e8s classique. Personnellement, j&rsquo;aime assez le design de la boite.<\/p>\n<p>Lorenzo fera le bonheur des joueurs experts. Les restrictions \u00e0 surmonter apportent le v\u00e9ritable d\u00e9fi du jeu et demanderont\u00a0pas mal de calculs, un r\u00e9gal pour les gros joueurs.<\/p>\n<hr \/>\n<p><a href=\"http:\/\/www.vindjeu.eu\/2017\/02\/06\/key-to-the-city-london-video\/dan-2\/\" rel=\"attachment wp-att-16069\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-thumbnail wp-image-16069\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/01\/Dan-2-e1483913787418-150x150.jpg\" alt=\"dan-2\" width=\"150\" height=\"150\" \/><\/a><\/p>\n<p><strong><span style=\"color: #333399;\">Dan<\/span><\/strong>:<strong><span style=\"color: #800000;\">\u00a0\u00a09,5 \/10<\/span><\/strong><\/p>\n<p>Lorenzo est, disons le d&#8217;embl\u00e9e, sans nul doute un excellent jeu.<\/p>\n<p>Pour commencer, la mise en place et les explications sont relativement rapides pour un jeu d&rsquo;une telle profondeur.<\/p>\n<p>Il s&rsquo;agit d&rsquo;un jeu de placement d&rsquo;ouvriers au d\u00e9part assez classique, si ce n&rsquo;est que le pouvoir de ses ouvriers d\u00e9pend du lancement de d\u00e9s effectu\u00e9 au d\u00e9but de chaque tour mais, pr\u00e9cisions)le, commun \u00e0 tous les joueurs, ce qui ne favorise personne tout en exigeant une bonne r\u00e9activit\u00e9 tactique.<\/p>\n<p>Lorenzo il Magnifico n&rsquo;a selon moi pas de d\u00e9faut si ce n&rsquo;est peut \u00eatre d&rsquo;\u00eatre fort calculatoire, mais sans pour autant l&rsquo;\u00eatre excessivement et nuire trop \u00e0 l&rsquo;interactivit\u00e9 qui est bien pr\u00e9sente au niveau du plateau, les joueurs convoitant peut-\u00eatre les m\u00eames actions parmi la vingtaine d&rsquo;actions disponibles.<\/p>\n<p>Il existe assur\u00e9ment des strat\u00e9gies diverses et bien \u00e9quilibr\u00e9es (favoriser la production ou la r\u00e9colte, le gain imm\u00e9diat de points ou l&rsquo;\u00e9volution sur les deux lignes de comp\u00e9tences (points de foi ou force militaire).<\/p>\n<p>6 tours de jeu avec le risque d&rsquo;\u00eatre excommuni\u00e9 tous les 2 tours (ce qui n\u00e9cessite une strat\u00e9gie \u00e0 court terme aussi), c&rsquo;est enfin la bonne dur\u00e9e pour garder ce jeu int\u00e9ressant de bout en bout.\u00a0 Les cartes leader sont la petite cerise sur le g\u00e2teau, poussant les joueurs \u00e0 des orientations strat\u00e9giques diff\u00e9rentes.<\/p>\n<p>Pour conclure, Lorenzo il Magnifico est donc incontestablement une r\u00e9ussite que je recommande sans h\u00e9siter aux joueurs experts ou m\u00eame aux amateurs.\u00a0 Le rejouabilit\u00e9 du jeu me semble assur\u00e9e (d\u00e9s, crit\u00e8res d&rsquo;excommunication, ordre des cartes changeant \u00e0 chaque partie) mais une extension avec quelques cartes additionnelles ne se refuserait pas!<\/p>\n<hr \/>\n<p><a href=\"http:\/\/www.vindjeu.eu\/2017\/02\/14\/watson-holmes-video\/thierry-1\/\" rel=\"attachment wp-att-16153\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-thumbnail wp-image-16153\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/01\/Thierry-1-e1484155191437-150x150.jpg\" alt=\"thierry-1\" width=\"150\" height=\"150\" \/><\/a><\/p>\n<p><strong><span style=\"color: #333399;\">Thierry<\/span><\/strong>:<strong><span style=\"color: #800000;\">\u00a0\u00a09,5 \/10<\/span><\/strong><\/p>\n<p>Magnifique ! Un vrai bonheur que de d\u00e9couvrir cet excellent jeu qui se profile d\u00e9j\u00e0 vers, \u00e0 tout le moins, un coup de c\u0153ur de l&rsquo;ann\u00e9e. Jeu de placements d&rsquo;ouvriers (sur base de d\u00e9 et donc limitant du m\u00eame coup l&rsquo;acc\u00e8s \u00e0 certaines actions selon la valeur des d\u00e9s) tendu (car actions limit\u00e9es \u00e0 4 par tour) et qui n\u00e9cessite une prise en compte de nombreuses contraintes (co\u00fbt des actions, besoin d&rsquo;acqu\u00e9rir des privil\u00e8ges \u00e0 l&rsquo;\u00e9glise ou encore de disposer d&rsquo;un niveau militaire suffisant). \u00a0Pour les amateurs de jeu de gestion, un must qui de plus reste abordable tant dans ses r\u00e8gles que dans sa dur\u00e9e (+\/- 2h). La seule l\u00e9g\u00e8re critique serait par rapport au mat\u00e9riel (design) et au nombre de cartes limit\u00e9es (pour le renouvellement des parties). De mon c\u00f4t\u00e9, c&rsquo;est s\u00fbr, va falloir pr\u00e9voir une place de plus dans ma ludoth\u00e8que \ud83d\ude09<\/p>\n<hr \/>\n<p><a href=\"http:\/\/www.vindjeu.eu\/2017\/06\/26\/lorenzo-il-magnifico-video\/1471-lorenzo-8\/\" rel=\"attachment wp-att-16724\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-16724\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/03\/1471-Lorenzo-8-e1488624980651.jpg\" alt=\"1471 Lorenzo 8\" width=\"1500\" height=\"1000\" \/><\/a><\/p>\n<hr \/>\n<h3><span style=\"color: #800080;\">Vin d&rsquo;jeu d&rsquo;vid\u00e9o<\/span><\/h3>\n<h4>La d\u00e9gustation en 11 minutes par <span style=\"color: #333399;\">Ren<\/span><\/h4>\n<div class=\"video-container\"><iframe loading=\"lazy\" title=\"Lorenzo il Magnifico (Vin d&#039;jeu d&#039;vid\u00e9o)\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/Q5Tlbm0Qjy8?feature=oembed&#038;wmode=opaque\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n","protected":false},"excerpt":{"rendered":"<p> Waouw, quelle claque il m\u2019a donn\u00e9 ce Lorenzo\u00a0!\u00a0 C\u2019est rare mais voil\u00e0 un jeu qui n\u2019a pas vraiment fait de buzz et qui passe un peu inaper\u00e7u alors qu\u2019il est excellent\u00a0!\u00a0 Il faut dire que son \u00e9diteur, Cranio Creation, ne nous avait, jusqu\u2019\u00e0 pr\u00e9sent, pas habitu\u00e9s \u00e0 des&#46;&#46;&#46;<\/p>\n","protected":false},"author":3,"featured_media":16725,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[4849],"tags":[502,817,323,7,877,276],"class_list":["post-16723","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-expert","tag-dan","tag-pascal","tag-ren","tag-swatsh","tag-tapimoket","tag-thierry","annee-1290","auteurs-flaminia-brasini","auteurs-simone-luciani","auteurs-virginio-gigli","editeurs-atalia","editeurs-cranio-creation","illustrateurs-andrea-kattnig","illustrateurs-andreas-resch","illustrateurs-klemmens-franz","distributeurs-atalia","recompenses-vin-djeu-dcoups-dcoeur"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/16723","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/comments?post=16723"}],"version-history":[{"count":0,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/16723\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media\/16725"}],"wp:attachment":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media?parent=16723"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/categories?post=16723"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/tags?post=16723"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}