{"id":17797,"date":"2017-07-15T14:41:11","date_gmt":"2017-07-15T12:41:11","guid":{"rendered":"http:\/\/www.vindjeu.eu\/?p=17797"},"modified":"2017-08-04T11:00:49","modified_gmt":"2017-08-04T09:00:49","slug":"arena-for-the-gods","status":"publish","type":"post","link":"https:\/\/www.vindjeu.eu\/prd\/2017\/07\/15\/arena-for-the-gods\/","title":{"rendered":"Arena: For the Gods!"},"content":{"rendered":"<p><a href=\"http:\/\/www.vindjeu.eu\/2017\/06\/16\/arena-for-the-gods-vin-djeu-dvideo\/1547-arena-for-the-gods-1-2\/\" rel=\"attachment wp-att-17795\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-17795\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/06\/1547-Arena-for-the-gods-1.2.png\" alt=\"1547 Arena for the gods 1.2\" width=\"500\" height=\"500\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/06\/1547-Arena-for-the-gods-1.2.png 500w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/06\/1547-Arena-for-the-gods-1.2-150x150.png 150w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/06\/1547-Arena-for-the-gods-1.2-300x300.png 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/06\/1547-Arena-for-the-gods-1.2-160x160.png 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/06\/1547-Arena-for-the-gods-1.2-245x245.png 245w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/06\/1547-Arena-for-the-gods-1.2-340x340.png 340w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a><\/p>\n<p><a href=\"http:\/\/www.vindjeu.eu\/2017\/07\/15\/arena-for-the-gods\/ren-8\/\" rel=\"attachment wp-att-17799\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-thumbnail wp-image-17799\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/06\/Ren-8-150x150.jpg\" alt=\"Ren 8\" width=\"150\" height=\"150\" \/><\/a><\/p>\n<p><strong><span style=\"color: #333399;\">Ren:<\/span><\/strong>\u00a0<strong><span style=\"color: #800000;\"> 9\/10<\/span><\/strong><\/p>\n<h5>Le pitch<\/h5>\n<p>Les Dieux sont taquins et joueurs, c&rsquo;est bien connu. Ils s&#8217;emb\u00eataient, alors pour passer le temps ils ont d\u00e9cid\u00e9 d&rsquo;envoyer leurs champions dans une ar\u00e8ne pour se mettre dessus all\u00e8grement. Du coup le programme<br \/>\ndu jour pour tous les joueurs est assez simple: je tape, je bouge, je tape, je bouge, je tape, je bouge. Et de temps en temps je pousse ou je r\u00e9cup\u00e8re de l&rsquo;\u00e9nergie.<\/p>\n<p>Dans Arena: For the Gods! chaque joueur incarne donc un h\u00e9ros repr\u00e9sentant un Dieu (de plein de mythologies diff\u00e9rentes, on est en 2017, peace and love \u00e0 tous les \u00e9tages\u2026) dans une ar\u00e8ne. Chaque partie se d\u00e9roule en deux phases: la phase d&rsquo;\u00e9quipement et la phase d&rsquo;affrontement.<\/p>\n<h5>Le jeu<\/h5>\n<p>Lors de la phase d&rsquo;\u00e9quipement chaque h\u00e9ros va s&rsquo;\u00e9quiper d&rsquo;une arme, d&rsquo;un moyen de transport, d&rsquo;un bouclier et d&rsquo;un sort. Les \u00e9quipements sont repr\u00e9sent\u00e9s par des cartes. Au d\u00e9but de la phase \u00e9quipement on tire d&rsquo;abord autant de cartes armes qu&rsquo;il y a de joueurs. Puis les joueurs vont acheter, aux ench\u00e8res, les armes disponibles. Chaque joueur commence en effet avec 20 cubes de vie, et il peut en miser autant qu&rsquo;il veut pour essayer de choisir en premier (ou en deuxi\u00e8me, en troisi\u00e8me\u2026) une arme qu&rsquo;il convoite. Puis on proc\u00e8de de m\u00eame pour les moyens de transport, les boucliers puis les sorts. C&rsquo;est un premier \u00e9l\u00e9ment sympa du jeu: on peut miser beaucoup de cubes pour s&rsquo;\u00e9quiper de mani\u00e8re plus puissante. Mais du coup on sera affaibli pour commencer le combat. A l&rsquo;inverse on peut laisser les autres choisir en priorit\u00e9, et h\u00e9riter d\u00e8s lors des \u00e9quipements qui ont l&rsquo;air plus faibles, mais au moins on sera r\u00e9sistant. Choisir c&rsquo;est renoncer\u2026<\/p>\n<p>Ensuite on peut passer aux choses s\u00e9rieuses, avec une bonne petite baston de derri\u00e8re les fagots pendant la phase d&rsquo;affrontement. Le principe est assez simple: il faut tuer ou \u00eatre tu\u00e9 (la partie s&rsquo;arr\u00eate d\u00e8s qu&rsquo;un h\u00e9ros meurt, le gagnant \u00e9tant celui \u00e0 qui il reste le plus de cubes de vie). Donc il faut taper. A distance ou au corps \u00e0 corps, avec des armes ou des sorts, en poussant, bref par tous les moyens possibles! Les h\u00e9ros \u00e9voluent dans une ar\u00e8ne, aux cases hexagonales. A son tour le joueur actif lance 7 d\u00e9s \u00e0 6 faces, ayant 2 faces pattes (plut\u00f4t pour se d\u00e9placer), 2 faces \u00e9p\u00e9es (plut\u00f4t pour taper), 1 face bouclier (plut\u00f4t pour pousser ou se d\u00e9fendre) et 1 face \u00e9toile (plut\u00f4t pour utiliser ses sorts ou taper qui on veut). Le joueur utilise autant de d\u00e9s qu&rsquo;il veut pour r\u00e9aliser soit les actions standard:<a href=\"http:\/\/www.vindjeu.eu\/2017\/07\/15\/arena-for-the-gods\/1547-arena-for-the-gods-2\/\" rel=\"attachment wp-att-18184\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-full wp-image-18184\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/07\/1547-Arena-for-the-gods-2-e1500122273598.jpg\" alt=\"1547 Arena for the gods 2\" width=\"550\" height=\"413\" \/><\/a><\/p>\n<ul>\n<li>2 \u00e9p\u00e9es = 1 d\u00e9g\u00e2t \u00e0 un h\u00e9ros adjacent<\/li>\n<li>2 \u00e9toiles = 1 d\u00e9g\u00e2t \u00e0 n&rsquo;importe quel h\u00e9ros, o\u00f9 qu&rsquo;il soit<\/li>\n<li>2 boucliers = pousser un h\u00e9ros adjacent (sachant que si ce dernier est au bord de l&rsquo;ar\u00e8ne, adjacent \u00e0 un autre h\u00e9ros ou adjacent \u00e0 un pilier il perd un cube de vie car il ne peut pas se d\u00e9placer, il est bloqu\u00e9 par l&rsquo;obstacle et il s&rsquo;\u00e9crase dessus)<\/li>\n<li>2 pattes = se d\u00e9placer d&rsquo;une case<\/li>\n<\/ul>\n<p>Soit les actions de ses cartes \u00e9quipements (il y a une quinzaine de cartes diff\u00e9rentes par type d&rsquo;\u00e9quipement). Il y a plein de combinaisons diff\u00e9rentes avec plein d&rsquo;effets marrants. Quelques exemples: se d\u00e9placer<br \/>\nsur la case de son choix, se d\u00e9placer de deux cases, infliger 2 d\u00e9g\u00e2ts, faire perdre un d\u00e9 pour le prochain tour d&rsquo;un adversaire\u2026<\/p>\n<p>A cela on ajoute qu&rsquo;il y a des piliers qui font obstacle (et peuvent faire mal si on est pouss\u00e9 dessus), des pi\u00e8ges qui font perdre un cube de vie si on passe dessus (ou si on y est pouss\u00e9) et des fontaines de vie qui font gagner un cube de vie si on passe dessus (jusqu&rsquo;\u00e0 \u00e9puisement, il y a 5 cubes par fontaine). Il y a \u00e9galement des sc\u00e9narios pr\u00e9d\u00e9finis qui organisent les diff\u00e9rents \u00e9l\u00e9ments sur le jeu, donnant des configurations diff\u00e9rentes (adapt\u00e9es notamment au nombre de joueurs) et du coup des sensations de jeu et des mani\u00e8res de jouer diff\u00e9rentes. On peut \u00e9videmment aussi jouer comme on le souhaite, sans suivre un sc\u00e9nario pr\u00e9d\u00e9fini, en installant les \u00e9l\u00e9ments librement.<\/p>\n<h5><a href=\"http:\/\/www.vindjeu.eu\/2017\/07\/15\/arena-for-the-gods\/1547-arena-for-the-gods-3\/\" rel=\"attachment wp-att-18185\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-18185\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/07\/1547-Arena-for-the-gods-3-e1500122363887.jpg\" alt=\"1547 Arena for the gods 3\" width=\"550\" height=\"733\" \/><\/a>Le verdict<\/h5>\n<p>Le tout donne une r\u00e9ussite impeccable. L&rsquo;\u00e9dition est nickel: le matos est cool (incluant des jolis piliers en 3D) et les dessins sont cool et parfaitement dans le th\u00e8me (on incarne des h\u00e9ros qui tapent, les mauviettes passez votre chemin). Les r\u00e8gles sont simples et faciles \u00e0 apprendre, ce qui sied parfaitement \u00e0 un jeu familial (elles pourraient \u00eatre un chou\u00efa mieux \u00e9crites, mais je chipote un peu). Il est tr\u00e8s tactique mais un peu strat\u00e9gique quand m\u00eame (vous jouerez diff\u00e9remment selon les \u00e9quipements choisis). Les jeunes y trouveront leur compte mais les plus exp\u00e9riment\u00e9s (pour ne pas \u00e9crire les vieux, restons politiquement correct, ne brusquons pas le lecteur lambda de Vin d&rsquo;Jeu dont l&rsquo;\u00e2ge moyen est celui d&rsquo;un grand cru class\u00e9 mis en cave le temps qu&rsquo;il fait pour d\u00e9velopper tous ses ar\u00f4mes) aimeront \u00e9galement.<\/p>\n<p>Et surtout le jeu donne exactement ce qu&rsquo;il promet (et ce que devrait promettre tout jeu digne de ce nom): du plaisir! Le jeu ne s&rsquo;affiche pas comme un Kubenbois, il n&rsquo;y a aucune tromperie sur la marchandise (les bons Kubenbois donnent beaucoup de plaisir, ne me comprenez pas mal :D). Le jeu s&rsquo;affiche comme un \u00ab\u00a0jeu plaisir\u00a0\u00bb, et c&rsquo;est exactement ce qu&rsquo;il donne, du plaisir imm\u00e9diat, jouissif, coupable. Comme quand vous prenez un \u00e9norme seau de pop corn au cin\u00e9: ce n&rsquo;est pas tr\u00e8s \u00e9quilibr\u00e9 au niveau alimentaire. Mais on s&rsquo;en fout parce que c&rsquo;est bon! Ben ici c&rsquo;est pareil. Il y a des d\u00e9s, du kingmaking \u00e9ventuel (\u00ab\u00a0tout le monde me tape dessus\u00a0\u00bb) et pas de possibilit\u00e9 d&rsquo;\u00e9changer 7 cubes bleu contre 2 cubes verts qui donneront +1 \u00e0 votre capacit\u00e9 de production de laine quand on sera au printemps et que vous aurez construit deux rouets et achet\u00e9 6 moutons apr\u00e8s avoir d\u00e9blay\u00e9 2 prairies et construit 1 \u00e9table? On s&rsquo;en fout parce que c&rsquo;est bon de taper, de couiner et d&rsquo;influencer les autres h\u00e9ros pour qu&rsquo;ils tapent sur le voisin!<\/p>\n<p>Bien jou\u00e9 Maxime!<\/p>\n<hr \/>\n<p><a href=\"http:\/\/www.vindjeu.eu\/2016\/09\/22\/million-club\/tapimoket\/\" rel=\"attachment wp-att-14734\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-14734\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2016\/09\/Tapimoket.png\" alt=\"tapimoket\" width=\"125\" height=\"160\" \/><\/a><\/p>\n<p><strong><span style=\"margin: 0px; color: black; font-family: 'Calibri',sans-serif; font-size: 12pt;\"><span style=\"color: #800000;\"><span style=\"color: #333399;\">Tapimoket<\/span>: 8\/10<\/span><\/span><\/strong><\/p>\n<p>Les h\u00e9ros entrent dans l&rsquo;ar\u00e8ne. Leur but : Se mettre sur la tronche ! Voil\u00e0 un pitch tr\u00e8s clair qui a le m\u00e9rite d&rsquo;aller droit au but sans faire de ronds de jambes, si ce n&rsquo;est pour se d\u00e9placer sur ce tr\u00e8s beau plateau o\u00f9 sont \u00e9rig\u00e9s des tours pr\u00eates \u00e0 vous empaler lorsque quelqu&rsquo;un vous poussera dessus. Bon sang ! il y en a partout en plus !<\/p>\n<p>Arena for the gods, \u00e0 l&rsquo;instar du must qu&rsquo;est king of tokyo, ne demande pas une grande strat\u00e9gie, mais r\u00e9clame juste quelques joueurs qui ont envie de se d\u00e9fouler en se tapant dessus. Pour cela, rien de plus simple, on balance quelques d\u00e9s, et on ex\u00e9cute le pouvoir de 4 cartes gr\u00e2ce aux faces obtenues. En g\u00e9n\u00e9ral, on y arrive souvent, car on a m\u00eame droit \u00e0 un relancer. Il faut, bien s\u00fbr, avoir bien mix\u00e9 ses cartes&#8230;. Bref on s&rsquo;\u00e9clate (et pas seulement la t\u00eate). C&rsquo;est archi simpliste mais assez amusant, ma foi.<\/p>\n<p>On pourrait m\u00eame croire que tout cela ne semble pas susciter beaucoup d&rsquo;int\u00e9r\u00eats, dirions nous ? Et bien si ! Car deux points essentiels viendront donner tout le sel au jeu.<a href=\"http:\/\/www.vindjeu.eu\/2017\/07\/15\/arena-for-the-gods\/1547-arena-for-the-gods-5\/\" rel=\"attachment wp-att-18186\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-full wp-image-18186\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/07\/1547-Arena-for-the-gods-5-e1500122441249.jpg\" alt=\"1547 Arena for the gods 5\" width=\"550\" height=\"413\" \/><\/a><\/p>\n<p>Le premier est la phase initiale qui, en option pour une premi\u00e8re partie, est absolument n\u00e9cessaire pour donner de la dimension au jeu. Il s&rsquo;agit de l&rsquo;achat des cartes. En effet, nos cartes seront mises aux ench\u00e8res, et le paiement se fera avec nos propres points de vie ! On aura donc envie d&rsquo;avoir les meilleures cartes, mais il faudra se sacrifier, gros dilemme !<\/p>\n<p>Le second \u00a0point sera que les points de vie de nos h\u00e9ros sont cach\u00e9s derri\u00e8re un paravent. Au fur et \u00e0 mesure de la partie, la tension va augmenter et on se demandera qui, des adversaires, en poss\u00e8de encore le plus. En effet, lorsqu&rsquo;un joueur meurt, la partie prend fin et le gagnant est celui qui en a le plus. De nouveau dilemme !<\/p>\n<p>Bref, j&rsquo;ai plut\u00f4t bien aim\u00e9, m\u00eame plus que King of Tokyo. Le nombre de cartes et les modes de jeu proposent une belle rejouabilit\u00e9. Cependant, mon plus grand regret viendra du fait qu&rsquo;on ne puissent pas changer de cartes en cours de partie. Cela aurait \u00e9t\u00e9 encore plus amusant ! Enfin, le mat\u00e9riel est tr\u00e8s sympa et bien illustr\u00e9, le tout \u00e0 un prix tr\u00e8s raisonnable. \u00c7a compte aussi !<\/p>\n<p>&nbsp;<\/p>\n<hr \/>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"http:\/\/www.vindjeu.eu\/2017\/07\/15\/arena-for-the-gods\/1547-arena-for-the-gods-6\/\" rel=\"attachment wp-att-17798\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-17798\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/06\/1547-Arena-for-the-gods-6-e1497430980427.jpg\" alt=\"1547 Arena for the gods 6\" width=\"1200\" height=\"900\" \/><\/a><\/p>\n<hr \/>\n<h4><span style=\"color: #800080;\">Vin d&rsquo;jeu d&rsquo;vid\u00e9o<\/span><\/h4>\n<h5>La d\u00e9gustation en 7 minutes par <strong><span style=\"color: #333399;\">Ren<\/span><\/strong><\/h5>\n<div class=\"video-container\"><iframe loading=\"lazy\" title=\"Arena: For the Gods! (Vin d&#039;jeu d&#039;vid\u00e9o)\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/FdCU6YzwBZI?feature=oembed&#038;wmode=opaque\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n","protected":false},"excerpt":{"rendered":"<p> Le pitch Les Dieux sont taquins et joueurs, c&rsquo;est bien connu. Ils s&#8217;emb\u00eataient, alors pour passer le temps ils ont d\u00e9cid\u00e9 d&rsquo;envoyer leurs champions dans une ar\u00e8ne pour se mettre dessus all\u00e8grement. Du coup le programme du jour pour tous les joueurs est assez simple: je tape, je&#46;&#46;&#46;<\/p>\n","protected":false},"author":3,"featured_media":17795,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[5],"tags":[323,877],"class_list":["post-17797","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-famille","tag-ren","tag-tapimoket","annee-1290","auteurs-maxime-rambourg","editeurs-iello","illustrateurs-paul-mafayon","distributeurs-iello"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/17797","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/comments?post=17797"}],"version-history":[{"count":0,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/17797\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media\/17795"}],"wp:attachment":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media?parent=17797"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/categories?post=17797"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/tags?post=17797"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}