{"id":1945,"date":"2011-02-20T19:12:35","date_gmt":"2011-02-20T18:12:35","guid":{"rendered":"http:\/\/www.vindjeu.eu\/?p=1945"},"modified":"2011-02-20T19:12:35","modified_gmt":"2011-02-20T18:12:35","slug":"le-secret-de-monte-cristo","status":"publish","type":"post","link":"https:\/\/www.vindjeu.eu\/prd\/2011\/02\/20\/le-secret-de-monte-cristo\/","title":{"rendered":"Le secret de Monte Cristo"},"content":{"rendered":"<p style=\"text-align: left;\"><a href=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2011\/02\/274-Monte-Cristo-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-1947\" title=\"274 Monte Cristo 1\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2011\/02\/274-Monte-Cristo-1.jpg\" alt=\"\" width=\"250\" height=\"249\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2011\/02\/274-Monte-Cristo-1.jpg 250w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2011\/02\/274-Monte-Cristo-1-150x149.jpg 150w\" sizes=\"auto, (max-width: 250px) 100vw, 250px\" \/><\/a><\/p>\n<p><span style=\"color: #333399;\"><strong>SwatSh<\/strong><\/span>:<span style=\"color: #800000;\"><strong> 8\u00a0 \/10<\/strong><\/span><\/p>\n<p>Le secret de Monte Cristo est le style de jeu l\u00e9ger qu&rsquo;on aime \u00e0 Vin d&rsquo;jeu.\u00a0 Bon, il est vrai que nous trouvons plus facilement notre compte dans les jeux plus complexes mais quand on peut retrouver tous les ingr\u00e9dients que nous aimons dans un jeu plus abordable, on est ravi.\u00a0 Et ravi, on l&rsquo;a \u00e9t\u00e9 avec Le Secret de Monte Cristo.<\/p>\n<p>Ce qui appara\u00eet d&rsquo;abord comme un simple jeu de majorit\u00e9 est piment\u00e9 par ce fameux nouveau m\u00e9canisme qu&rsquo;est \u00ab\u00a0l&rsquo;action slide\u00a0\u00bb.<\/p>\n<p>Mmmmmh, en lisant par-ci par-l\u00e0 des articles vantant cette \u00ab\u00a0action slide\u00a0\u00bb je craignais le pire: l&rsquo;effet bombe mouill\u00e9e!\u00a0\u00a0 Et bien non, cette \u00ab\u00a0action slide\u00a0\u00bb est bien innovante et pimente le jeu suffisamment pour qu&rsquo;il se d\u00e9marque d&rsquo;autres jeux de majorit\u00e9.<\/p>\n<p>\u00ab\u00a0L&rsquo;action Slide\u00a0\u00bb consiste en un pr\u00e9sentoir contenant diff\u00e9rentes billes aux couleurs des joueurs (cfr photo plus bas).\u00a0\u00a0 A chaque colonne correspond une action.\u00a0 Et on ex\u00e9cute une action de chacun des 4 types d&rsquo;action \u00e0 la fois.\u00a0 Autrement dit, un tour de jeu se d\u00e9roule comme ceci, le joueur ayant la bille en bas de la colonne 1 ex\u00e9cute l&rsquo;action 1 et d\u00e9place sa bille en haut de la file d&rsquo;une des 3 autres colonnes.\u00a0 Puis, le joueur ayant sa bille en bas de la colonne 2 ex\u00e9cute l&rsquo;action 2 et d\u00e9place sa bille,&#8230;<\/p>\n<p>Dans l&rsquo;exemple de la photo:<\/p>\n<p><a href=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2011\/02\/274-Monte-Cristo-4.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-1948\" title=\"274 Monte Cristo 4\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2011\/02\/274-Monte-Cristo-4-300x225.jpg\" alt=\"\" width=\"140\" height=\"119\" \/><\/a><\/p>\n<p>Bleu ex\u00e9cutera l&rsquo;action 1, puis vert l&rsquo;action 2, jaune l&rsquo;action 3 et 4.<\/p>\n<p>La subtilit\u00e9 du m\u00e9canisme r\u00e9side surtout dans le placement de sa bille apr\u00e8s l&rsquo;action puisqu&rsquo;on doit la placer en haut d&rsquo;une colonne d&rsquo;une des 3 <span style=\"text-decoration: underline;\">autres<\/span> actions.\u00a0 Il faudra donc choisir la bonne action \u00e0 ex\u00e9cuter et savoir quand celle-ci sera ex\u00e9cut\u00e9e \u00e0 savoir rapidement ou pas et dans combien de tours.\u00a0 Tout ceci fait que les choix ne seront pas toujours faciles et la tactique pas toujours \u00e9vidente.\u00a0 Sur la photo, vous voyez que pour l&rsquo;action 4, jaune a d\u00e9j\u00e0 pr\u00e9vu l&rsquo;ex\u00e9cuter dans 5 tours alors qu&rsquo;il aurait pu choisir l&rsquo;action 2 plusieurs fois en attendant&#8230;<\/p>\n<p>Une autre m\u00e9canique que j&rsquo;ai bien aim\u00e9e dans Le Secret de Monte Cristo est la mani\u00e8re dont \u00e0 la fin d&rsquo;une phase on prend les tr\u00e9sors.\u00a0 Le joueur majoritaire dans un donjon prend autant de tr\u00e9sors s&rsquo;y trouvant qu&rsquo;il d\u00e9sire \u00e0 condition d&rsquo;enlever de ce donjon un de ses bonshommes par tr\u00e9sor pris et d&rsquo;avoir un sac \u00e0 dos \u00e0 la couleur du tr\u00e9sor.\u00a0 Si le premier joueur n&rsquo;a pas assez de bonshommes ou pas les bons sacs \u00e0 dos, c&rsquo;est le second joueur qui peut prendre les tr\u00e9sors restants.\u00a0 Ce m\u00e9canisme fait qu&rsquo;il peut \u00eatre parfois int\u00e9ressant d&rsquo;\u00eatre le second joueur majoritaire avec ne fut-ce qu&rsquo;un seul bonhomme.<\/p>\n<p>Sinon les r\u00e8gles sont tr\u00e8s simples et contenues dans 4 pages!\u00a0 Cela faisait longtemps que je n&rsquo;avais plus jou\u00e9 \u00e0 un jeu o\u00f9 les r\u00e8gles \u00e9taient \u00e9crites en 4 pages!\u00a0 Mais je vous conseille d&rsquo;y \u00eatre assez attentifs car me disant que c&rsquo;\u00e9tait assez facile j&rsquo;avais oubli\u00e9 un petit d\u00e9tail qui a fait que nous n&rsquo;avons pas jou\u00e9 aux bonnes r\u00e8gles durant la moiti\u00e9 du jeu.\u00a0 Bon, ce n&rsquo;\u00e9tait pas trop grave mais quand m\u00eame&#8230; ce n&rsquo;est pas mon habitude.<\/p>\n<p>Le hasard intervient dans le jeu par la pioche des tr\u00e9sors ou des cartes bateaux.\u00a0 Mais bien qu&rsquo;il puisse faire grincer des dents de temps \u00e0 autre, il ne supplante pas du tout le jeu et en effectuant certaines actions il est possible de le ma\u00eetriser.\u00a0 Le tout est de faire le bon choix des bonnes actions aux bons moments!<\/p>\n<p>Au final donc, Le Secret de Monte Cristo est un jeu de majorit\u00e9 assez simple mais loin d&rsquo;\u00eatre simpliste gr\u00e2ce \u00e0 sa m\u00e9canique slide qui permet d&rsquo;avoir une certaine tactique\/strat\u00e9gie et des choix pas toujours faciles.\u00a0 Une belle r\u00e9ussite.<\/p>\n<p><span style=\"color: #333399;\"><strong>Philrey212<\/strong><\/span>:<span style=\"color: #800000;\"><strong> 8\/10<\/strong><\/span><\/p>\n<p><span style=\"color: #000000;\">J&rsquo;ai bien appr\u00e9ci\u00e9 Le Secret de Monte Cristo. Les action par \u00ab\u00a0sliding\u00a0\u00bb est vraiment original. Le boulier compteur indique les actions disponibles. Il y en 4. Et chacune sera ex\u00e9cut\u00e9e dans l&rsquo;ordre. Mais seulement le joueur qui poss\u00e8de la boule tout en bas pourra faire l&rsquo;action. Et ensuite, il doit d\u00e9placer sa boule et la placer en haut d&rsquo;une autre colonne (c\u00e0d d&rsquo;une autre action). C&rsquo;est le m\u00e9canisme le plus int\u00e9ressant du jeux car il exige une esp\u00e8ce de planification dans le temps: il faudra attendre que la boule de sa couleur \u00ab\u00a0touche le fond\u00a0\u00bb pour pouvoir effectuer cette action! Vraiment tr\u00e8s original.<\/span><\/p>\n<p>Le jeu a quand m\u00eame une grande part de hasard qui n&rsquo;est pas trop d\u00e9rangeant. Dans notre partie, elle le fut pas mal \u00e0 cause d&rsquo;une r\u00e8gle pas appliqu\u00e9e (sauf au dernier tour). Le Secret de Monte Cristo plaira certainement \u00e0 un large public. Et avec raison!<\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2011\/02\/274-Monte-Cristo-2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-1946  aligncenter\" title=\"274 Monte Cristo 2\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2011\/02\/274-Monte-Cristo-2-1024x768.jpg\" alt=\"\" width=\"817\" height=\"538\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p> Le secret de Monte Cristo est le style de jeu l\u00e9ger qu&rsquo;on aime \u00e0 Vin d&rsquo;jeu.\u00a0 Bon, il est vrai que nous trouvons plus facilement notre compte dans les jeux plus complexes mais quand on peut retrouver tous les ingr\u00e9dients que nous aimons dans un jeu plus&#46;&#46;&#46;<\/p>\n","protected":false},"author":2,"featured_media":1947,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[5],"tags":[6,7],"class_list":["post-1945","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-famille","tag-philrey212","tag-swatsh","annee-344","auteurs-arnaud-urbon","auteurs-charles-chevallier","editeurs-filosofia"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/1945","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/comments?post=1945"}],"version-history":[{"count":0,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/1945\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media\/1947"}],"wp:attachment":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media?parent=1945"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/categories?post=1945"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/tags?post=1945"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}