{"id":19592,"date":"2017-11-22T23:09:12","date_gmt":"2017-11-22T22:09:12","guid":{"rendered":"http:\/\/www.vindjeu.eu\/?p=19592"},"modified":"2018-05-28T20:13:34","modified_gmt":"2018-05-28T18:13:34","slug":"pulsar-2849","status":"publish","type":"post","link":"https:\/\/www.vindjeu.eu\/prd\/2017\/11\/22\/pulsar-2849\/","title":{"rendered":"Pulsar 2849"},"content":{"rendered":"<p><a href=\"http:\/\/www.vindjeu.eu\/2017\/11\/13\/pulsar-2849-vin-djeu-dvideo\/1630-pulsar-1\/\" rel=\"attachment wp-att-19590\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-19590\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/11\/1630-Pulsar-1.jpg\" alt=\"1630 Pulsar 1\" width=\"500\" height=\"500\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/11\/1630-Pulsar-1.jpg 500w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/11\/1630-Pulsar-1-150x150.jpg 150w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/11\/1630-Pulsar-1-300x300.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/11\/1630-Pulsar-1-160x160.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/11\/1630-Pulsar-1-245x245.jpg 245w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/11\/1630-Pulsar-1-340x340.jpg 340w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a><\/p>\n<p><a href=\"http:\/\/www.vindjeu.eu\/2016\/09\/26\/andor-chada-thorn-video\/chaps-1\/\" rel=\"attachment wp-att-14812\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-thumbnail wp-image-14812\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2016\/09\/Chaps-1-150x150.jpg\" alt=\"chaps-1\" width=\"150\" height=\"150\" \/><\/a><\/p>\n<h5><strong><span style=\"color: #333399;\">Chaps<\/span><\/strong>:\u00a0<strong><span style=\"color: #800000;\"> 8,5 \/10<\/span><\/strong><\/h5>\n<p>Que diriez-vous de parcourir la galaxie \u00e0 la d\u00e9couverte de nouveaux syst\u00e8mes plan\u00e9taires et de pulsars puisqu\u2019aujourd\u2019hui en 2849 nous pouvons extraire de l\u2019\u00e9nergie de ces pulsars ! Bon tout cela demande r\u00e9flexion et technologie en jouant sur moulte m\u00e9canismes forts malins. Vous \u00eates pr\u00eat ? 4\u20263\u20262\u2026 1\u2026Ignition..<\/p>\n<h2>Pulsar le pitch<\/h2>\n<p>Dans pulsar \u00e0 chacune des 8 manches de jeux vous prendrez 2 d\u00e9s au choix parmi [2*Nombre de joueur+1] puis \u00e0 votre tour vous ferez une action par d\u00e9 en fonction bien s\u00fbr de la valeur du d\u00e9. Eventuellement parfois vous pourrez faire une 3e action avec un d\u00e9 bonus. Donc 2 ou 3 actions pour construire des Gyrodynes sur des pulsars et les activer (machine \u00e0 produire de l\u2019\u00e9nergie, vous n\u2019\u00eates pas au fait de la technologie du XXIXe si\u00e8cle ?) et d\u00e9couvrir des syst\u00e8mes plan\u00e9taires o\u00f9 construire des stations relai d\u2019\u00e9nergie. Mais pour faire cela de nombreuses actions sont possible sur des plateaux entourant le plateau principal. <strong>C\u2019est tout le sel du jeu, peu d\u2019actions par manche mais beaucoup de possibilit\u00e9s<\/strong>.<br \/>\nMais pour chaque action possible il y a un d\u00e9 d\u2019une valeur pr\u00e9cise \u00e0 utiliser et bien s\u00fbr pour une valeur de d\u00e9 plusieurs actions possible, vous ne serez pas coinc\u00e9, si ce n\u2019est par un \u00e9ventuel paralysis Analysis\u2026<\/p>\n<h2>Comment on les gagne ces d\u00e9s, c\u2019est original au moins ?<a href=\"http:\/\/www.vindjeu.eu\/2017\/11\/22\/pulsar-2849\/1630-pulsar-2\/\" rel=\"attachment wp-att-19594\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-full wp-image-19594\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/11\/1630-Pulsar-2-e1510433247129.jpg\" alt=\"1630 Pulsar 2\" width=\"550\" height=\"413\" \/><\/a><\/h2>\n<p>Ho que oui ! Un plateau rien que pour \u00e7a. Donc dessus sont pos\u00e9s les d\u00e9s des diff\u00e9rentes valeurs (jet en d\u00e9but de manche), on en prend un (dans l\u2019ordre du tour des joueurs) puis un 2e (dans l\u2019ordre inverse du tour des joueurs). Et l\u00e0 prendre un d\u00e9 vous oblige \u00e0 bouger un marqueur sur une des 2 pistes du plateau : vous prenez un gros d\u00e9 ? Vous d\u00e9calerez votre marqueur dans le mauvais sens. Vous prenez un petit d\u00e9 ? \u00e7a va dans le bon sens. Mais c\u2019est connu gros c\u2019est mieux que petit, enfin pour les d\u00e9s\u2026 \ud83d\ude09<br \/>\nPetit ? Gros ? Oui par rapport \u00e0 la valeur m\u00e9diane des d\u00e9s sortis \u00e0 cette manche, donc \u00e7a change \u00e0 chaque manche ! Twist sympathique. Les gros d\u00e9s sont plus puissants pour les actions bien s\u00fbr.<br \/>\nLes pistes : Une d\u00e9cide de l\u2019ordre du tour \u00e0 la manche suivante et l\u2019autre du joueur qui ne gagnera pas de cube Ing\u00e9nierie \u00e0 la fin de cette manche\u2026 Les cubes Ing\u00e9nierie sont la seule ressource du jeu, je vous garantis que vous en voudrez. Pourquoi ? PVs en fin de partie et 4 utilis\u00e9s \u00e0 votre tour vous donne acc\u00e8s au d\u00e9-action bonus.<br \/>\nCette m\u00e9canique de gain de d\u00e9s renouvel\u00e9e \u00e0 chaque tour est excellente, interaction et strat\u00e9gie, il est amusant de voir au fil des manches les jetons des joueurs s\u2019\u00e9taler sur ces 2 pistes selon les choix de chacun. Si vous n\u2019avez pas de cubes en fin de manche car vous \u00eates le dernier sur la piste, rassurez-vous vous en aurez autrement. Un point tr\u00e8s positif du jeu, vous pouvez faire plein de choses de plein de fa\u00e7ons diff\u00e9rentes.<\/p>\n<h2><a href=\"http:\/\/www.vindjeu.eu\/2017\/11\/22\/pulsar-2849\/1630-pulsar-3\/\" rel=\"attachment wp-att-19595\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-19595\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/11\/1630-Pulsar-3-e1510433552236.jpg\" alt=\"1630 Pulsar 3\" width=\"500\" height=\"375\" \/><\/a>Que fait-on alors ?<\/h2>\n<p>En gros 2 types d\u2019action, Les d\u00e9placements sur le plateau principal (circulaire !) qui repr\u00e9sente la galaxie afin de construire des stations sur les plan\u00e8tes et de s\u2019accaparer des pulsars pour y construire des Gyrodynes. Ou alors activer moultes bonus pour nous faciliter la vie et les PVs sur les plateaux secondaires qui entourent le plateau principal.<\/p>\n<h2>D\u00e9placement galactique : \u00ab ho une porte, ho un pulsar, ho une plan\u00e8te\u2026 Heu capitaine on s\u2019arr\u00eate quand ? J\u2019ai tir\u00e9 un 6 on met la gomme jusqu\u2019\u00e0 6 ! \u00bb<\/h2>\n<p>On suit des trajectoires sur le plateau qui vont de \u00ab porte \u00bb en \u00ab porte \u00bb et aboutissent ou croisent des pulsars et des syst\u00e8mes plan\u00e9taires. Comme pour tout on se d\u00e9place avec 1 d\u00e9 d\u2019autant de porte\/pulsar\/syst\u00e8me que la valeur du d\u00e9, ni plus ni moins, pile la valeur. Vous finissez sur un pulsar, hop un anneau \u00e0 votre couleur il vous appartient mais pour l\u2019instant ne vous apporte rien, extraire l\u2019\u00e9nergie d\u2019un pulsar c\u2019est un peu plus compliqu\u00e9 quand m\u00eame, mais c\u2019est une premi\u00e8re \u00e9tape&#8230; Vous finissez sur un syst\u00e8me plan\u00e9taire (ce sont des tuiles \u00e0 placement variable), vous retournez la tuile et posez une station sur une plan\u00e8te habitable. Le syst\u00e8me a d\u00e9j\u00e0 \u00e9t\u00e9 visit\u00e9e, il n\u2019y a plus de plan\u00e8te habitable disponible ? Sur une plan\u00e8te non habitable alors. Ok, cons\u00e9quence ? Chaque syst\u00e8me a un bonus, vous vous arr\u00eatez dessus et construisez sur une plan\u00e8te habitable (et pas une inhabitable !), hop vous avez le bonus (ou au choix une tuile bonus d\u2019exploration cachant g\u00e9n\u00e9ralement des PVs). Ces bonus se sont g\u00e9n\u00e9ralement des actions des plateaux secondaires du coup sans utiliser de d\u00e9 ! Et \u00e7a c\u2019est tr\u00e8s bien. Si vous passez juste sur le syst\u00e8me sans vous arr\u00eater, vous posez une station (une seule \u00e0 votre couleur par syst\u00e8me ! ) mais pas de bonus\u2026 Ce n\u2019est pas trop grave, une station c\u2019est bien (mais vous n\u2019aurez alors jamais le bonus de ce syst\u00e8me).<a href=\"http:\/\/www.vindjeu.eu\/2017\/11\/22\/pulsar-2849\/1630-pulsar-4\/\" rel=\"attachment wp-att-19596\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-full wp-image-19596\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/11\/1630-Pulsar-4-e1510433751985.jpg\" alt=\"1630 Pulsar 4\" width=\"500\" height=\"375\" \/><\/a><\/p>\n<h2>Des plateaux tout autour du plateau<\/h2>\n<p>Oui les actions bonus que l\u2019on peut d\u00e9clencher avec un d\u00e9 (\u00e0 chaque fois d\u2019une valeur donn\u00e9e).<br \/>\nAinsi vous prendrez des tokens pour modifier la valeur d\u2019un d\u00e9 utilis\u00e9 par la suite (bien pratique +\/-1 ou +2).<br \/>\nVous prendrez un Gyrodyne ! Le truc que l\u2019on doit mettre dans nos pulsars pour avoir des PVs ! Pardon de l\u2019\u00e9nergie ! \ud83d\ude09 3 types plus ou moins puissants et sur le m\u00eame plateau 2 tuiles par type de Gyrodyne une \u00e0 7 PVs l\u2019autre \u00e0 4 PVs. Comment on les prend ces tuiles PVs ? Il faut avoir install\u00e9 au moins 2 gyrodynes du type donn\u00e9 sur des pulsars (et \u00eatre un des 2 premiers \u00e0 le faire&#8230;). On prend donc un Gyrodyne (niveau selon la valeur du d\u00e9 utilis\u00e9) on le garde ou on le pose sur un pulsar qui nous appartient, que l\u2019on a visit\u00e9 et donc qui a un anneau \u00e0 notre couleur\u2026 Haa\u2026,\u00e7a avance, je me pose sur un pulsar il m\u2019appartient, j\u2019ai pris un Gyrodyne pr\u00e9c\u00e9demment ou tout de suite d\u2019ailleurs, hop je le pose dans l\u2019anneau ! \u00e7a y est c\u2019est fini! Non\u2026<br \/>\nDonc si c\u2019est votre deuxi\u00e8me gyrodyne de ce type vous prenez 7 ou 4 PVs. Mais le gyrodyne n\u2019est pas encore construit, il est en construction\u2026 Sur chaque gyrodyne un d\u00e9 est dessin\u00e9, vous consommez ce d\u00e9 pour un gyrodyne en place sur un de vos pulsar, dans un anneau (vous suivez ?) paf, vous le retournez et l\u00e0 \u00e7a y est, il marche, il va vous rapporter des PVs ! Pardon de l\u2019\u00e9nergie.<br \/>\nDes tokens modifiant la valeur des d\u00e9s, les gyrodynes, il y a d\u2019autres plateaux secondaires ? Oui mais passons au paragraphe suivant.<\/p>\n<h2>Se balader dans la galaxie n\u00e9cessite quelques technologies\u2026<\/h2>\n<p>Un grand plateau secondaire modulaire avec des technologies arrang\u00e9es en 8 \u00e9tages, 8\u2026 hum\u2026 comme 8 manches ? Oui \ud83d\ude09 1ere manche vous avez acc\u00e8s aux technologies du premier niveau, deuxi\u00e8me manche du premier et du deuxi\u00e8me niveau, troisi\u00e8me manche, des trois premiers niveaux\u2026 etc\u2026 Et attention il n\u2019y a que 2 places par technologie donc chacune ne sera utilisable que par 2 joueurs. Sachez que ce sont plusieurs plateaux modulaires que l\u2019on assemble imprim\u00e9s recto verso, donc la variation technologique est importante de parties en parties, gage de rejouabilit\u00e9.<br \/>\nQue font ces technologies ? De tout, soit oneshot, soit \u00e0 chaque manche, soit des PVs lors d\u2019action sp\u00e9cifique, soit des PVs en fin de partie\u2026 etc\u2026 Avec des d\u00e9s bonus, des gyrodynes \u00e0 gagner, des anneaux pour des pulsars\u2026 C\u2019est tr\u00e8s vari\u00e9, Les technologies sont tr\u00e8s importantes, on a peu d\u2019action par manche il faut optimiser ! Et n\u2019oubliez pas il n\u2019y a que 2 places par techno et pour certaines un seul joueur peut la revendiquer lors d\u2019une manche. Les techno sont une part importante du jeu avec interaction et concurrence entre les joueurs, mais il y a toujours d\u2019autres mani\u00e8res de faire\u2026<\/p>\n<h2><a href=\"http:\/\/www.vindjeu.eu\/2017\/11\/22\/pulsar-2849\/1630-pulsar-8\/\" rel=\"attachment wp-att-19597\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-19597\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/11\/1630-Pulsar-8-e1510433850148.jpg\" alt=\"1630 Pulsar 8\" width=\"500\" height=\"375\" \/><\/a>Autre chose autour du plateau ?<\/h2>\n<p>Oui des tuiles transmetteurs (th\u00e9matiquement d\u2019\u00e9nergie), 3 disponibles par manche (on pioche dans un tas ordonn\u00e9 donc leurs effets s\u2019adaptent au moment de la partie). Pour en prendre un il faut\u2026 un d\u00e9 d\u2019une certaine valeur, mais encore faudra-t\u2019il ensuite activer le transmetteur ! Un autre d\u00e9 est alors n\u00e9cessaire ou deux ou pas, oui certains n\u00e9cessite qu\u2019un seul d\u00e9, d\u2019autre 1 pour prendre la tuile et un autre pour l\u2019activer, voire 2\u2026 Et on active quand on le souhaite, c\u2019est d\u2019autant plus important que 2 transmetteurs activ\u00e9s et connect\u00e9s (oui ils se connectent, si on le souhaite) peuvent vous donner un d\u00e9 bonus \u00e0 utilisation imm\u00e9diate !<br \/>\nComme pour les technologies, les transmetteurs apportent des bonus oneshot ou \u00e0 chaque fin de manche, des cubes ing\u00e9nieries, PV\u2026 etc\u2026 Une autre mani\u00e8re de faire\u2026 Tout le sel du jeu, choisissez bien votre voie de d\u00e9veloppement.<\/p>\n<h2>Encore autre chose autour du plateau ?<\/h2>\n<p>Non mais par contre en face de chaque joueur oui, un plateau \u00ab Headquarter \u00bb, \u00e0 nouveau des actions bonus, OneShot uniquement, \u00e0 activer avec des d\u00e9s. Les plateaux sont double face, une plus orient\u00e9e strat\u00e9gie Pulsar, l\u2019autre plus orient\u00e9e strat\u00e9gie stations plan\u00e9taires (on choisit en d\u00e9but de partie). Les bonus sont organis\u00e9s en pyramide. Vous voulez le bonus n\u00b01 ou 2 ou 3 ou 4 allez-y si vous avez le d\u00e9. Vous voulez le 5 ? \u2026 Ha il faut avoir valid\u00e9 le 1 et le 2, vous voulez le 6 ? Ha il faut avoir valid\u00e9 le 3 et le 4\u2026 (9 au total). On retrouve les m\u00eames genres de bonus que vu pr\u00e9c\u00e9demment, gyrodyne, d\u00e9 bonus\u2026 plus un particulier le \u00ab Gate run \u00bb. Si je l\u2019active avec un d\u00e9, \u00e0 partir de maintenant quand je veux dans la partie je pourrais faire un \u00ab gate run \u00bb (1 seule fois). Lorsque je l\u2019utilise je d\u00e9place mon vaisseau (valeur d\u2019un d\u00e9 pour la distance), chaque passage par une porte du type indiqu\u00e9 sur l\u2019action \u00ab gate run \u00bb me rapporte autant de points qu\u2019indiqu\u00e9 sur le dit \u00ab gate run \u00bb, PVs oneshot, \u00e0 utiliser au bon moment.<a href=\"http:\/\/www.vindjeu.eu\/2017\/11\/22\/pulsar-2849\/1630-pulsar-9\/\" rel=\"attachment wp-att-19598\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-full wp-image-19598\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/11\/1630-Pulsar-9-e1510433940228.jpg\" alt=\"1630 Pulsar 9\" width=\"500\" height=\"375\" \/><\/a><\/p>\n<h2>Ho\u2026 D\u2019ailleurs, j\u2019oubliais\u2026 Les PVs, le but en somme, le pourquoi de tout ce que vous avez fait.<\/h2>\n<p>On gagne des PVs \u00e0 la fin de chaque manche en fonction du nombre de gyrodyne que l\u2019on a activ\u00e9, en fonction de vos technologies et en fonction tuiles transmetteurs activ\u00e9s (si PVs fin de manche dessus). Chaque gyrodyne vous rapporte des PVs \u00e9quivalent \u00e0 son niveau (1, 2 ou 3) mais en plus il y a des PVs bonus par gyrodyne \u00e0 chaque manche. Dans le setup de ma partie, bonus de 0 \u00e0 4 dont 4 \u00e0 la derni\u00e8re manche, vous avez 3 gyrodynes actifs ? mettons deux 3 et un 2 ? cela vous fait en derni\u00e8re manche 3+4+3+4+2+4 = 20 points, juste pour une manche.<\/p>\n<p>Et il y a des PVs en fin de partie, plusieurs petits scoring que je ne d\u00e9taille pas, un scoring de 2 \u00e0 7 points qui d\u00e9pend de l\u2019ordre du dernier tour et deux gros scoring :<\/p>\n<ul>\n<li>Des tuiles Objectifs fin de partie que l\u2019on pose autour du plateau (en d\u00e9but de partie): il y en a plusieurs recto-verso (rejouabilit\u00e9 assur\u00e9e), chacune se divise en 3 \u00e9tages, le premier une condition (3 gyrodynes diff\u00e9rents actifs ou encore 9 stations sur des plan\u00e8tes ou encore 5 technologies\u2026) si elle est remplie hop PVs \u00e0 la clef et vous avez gagn\u00e9 le droit d\u2019essayer de remplir la condition n\u00b02 g\u00e9n\u00e9ralement des cubes ing\u00e9nierie, si vous le faite PVs ! Et vous avez le droit d\u2019essayer de remplir la condition n\u00b03 g\u00e9n\u00e9ralement des cubes ing\u00e9nierie \u00e0 nouveau mais moins et PVs. Au total sur les 3 \u00e9tages 12, 15, 20 PVs par tuile objectif.<\/li>\n<li>Les stations sur les plan\u00e8tes : selon le nombre en fin de partie on gagne des PVs, de plus en plus ce n\u2019est pas lin\u00e9aire, 13 stations ? \u2026 50 PVs \u2026 Rien que \u00e7a !!<\/li>\n<\/ul>\n<p>Au bilan soit vous faites un maximum de pulsars activ\u00e9s et scorez pendant la partie et quelques stations plan\u00e9taire, soit un ou deux gyrodynes et 13 plan\u00e8tes soit un peu des deux\u2026 A vous de voir et bien s\u00fbr au moins 2 tuiles objectif fin de partie compl\u00e8tes (stockez du cube !) ! Mais on score aussi avec les \u00ab gate run \u00bb, les tuiles transmetteurs, les technologies\u2026<\/p>\n<p>En conclusion Pulsar 2849 est pour moi un bon jeu o\u00f9 les strat\u00e9gies vous feront balancer entre gyrodyne sur les pulsars et stations plan\u00e9taires en gardant un \u0153il sur les 3 objectifs fin de partie, mais le chemin pour faire cela est tr\u00e8s vari\u00e9, entre les technologies, les transmetteurs, les headquarters\u2026 Ajoutez \u00e0 cela la bonne interaction : concurrence pour construire des stations sur les plan\u00e8tes, concurrence pour les transmetteurs, concurrence pour les technologies, du coup je conseille de jouer \u00e0 4 c\u2019est plus tendu. Et bien s\u00fbr concurrence sur la m\u00e9canique de prise des d\u00e9s et sur les pistes initiative et ing\u00e9nierie, o\u00f9 tout d\u00e9pend de la mani\u00e8re dont les autres se placent.<br \/>\nPour ce qui est du th\u00e8me, gr\u00e2ce au plateau principal et \u00e0 l\u2019iconographie tr\u00e8s SF \u00e9pur\u00e9e efficace je l\u2019ai ressenti, je n\u2019\u00e9tais pas certains de pulsar, maintenant que j\u2019y ai jou\u00e9 je n\u2019ai qu\u2019une envie c\u2019est relancer une partie, il y a tant de choses possibles \u00e0 faire avec peu d\u2019action et les technologies sont variables comme le positionnement des tuiles syst\u00e8me plan\u00e9taire et les tuiles PVs fin de partie, ce qui assure la rejouabilit\u00e9.<\/p>\n<p>Et si vous vous perdez un peu en premi\u00e8re partie face \u00e0 tout ce que vous pouvez faire, rappelez-vous cette phrase d\u2019Albert Einstein : \u00ab Je n\u2019ai pas \u00e9chou\u00e9, j\u2019ai trouv\u00e9 dix mille moyens qui ne fonctionnent pas \u00bb<\/p>\n<hr \/>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-22142 alignleft\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2018\/03\/tapi-e1521499595232.png\" alt=\"tapimokat2\" width=\"150\" height=\"194\" \/><\/p>\n<h5><strong><span style=\"color: #333399;\">Tapimoket<\/span>:<span style=\"color: #800000;\">\u00a0 8\/10<\/span><\/strong><\/h5>\n<p>Je ne vais pas rentrer dans tous les d\u00e9tails d&rsquo;explications puisque Chaps vous a r\u00e9serv\u00e9 tout \u00e7a&#8230; Inutile de vous dire que <strong>Pulsar 2849<\/strong> est un jeu pour experts et que nous serons confront\u00e9s \u00e0 une galaxie (salade) de points et d&rsquo;actions. <strong>Pulsar 2849<\/strong> pr\u00e9sente de nombreux axes de strat\u00e9gies \u00e0 d\u00e9couvrir, et il faudra plusieurs parties pour en faire le tour complet.<\/p>\n<p>Personnellement, je trouve le mat\u00e9riel, un poil aust\u00e8re, mais s&rsquo;il est vrai qu&rsquo;il est difficile de mettre de la couleur dans le vide spatial. Ceci dit, je pense qu&rsquo;on aurait pu quand m\u00eame y mettre des illustrations plus attrayantes comme celles de <a href=\"http:\/\/www.vindjeu.eu\/2015\/04\/30\/xia-legends-of-a-drift-system\/\"><em>Xia<\/em><\/a><\/p>\n<p>Mais en dehors des ternes illustrations, <strong>Pulsar 2849<\/strong> est un tr\u00e8s bon jeu costaud qui offre des m\u00e9caniques originales et, notamment sur son syst\u00e8me de choix de d\u00e9s. Il donne \u00e9galement un bonne sensation de voyage et colonisation dans l&rsquo;espace qui arrive, finalement, \u00e0 nous plonger dans le th\u00e8me. Le jeu fera le bonheur des gros joueurs qui prendront plaisir \u00e0 en exploiter toutes les possibilit\u00e9s.<\/p>\n<p>&nbsp;<\/p>\n<hr \/>\n<p><a href=\"http:\/\/www.vindjeu.eu\/2017\/11\/22\/pulsar-2849\/1630-pulsar-10\/\" rel=\"attachment wp-att-19599\"><br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-19599\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/11\/1630-Pulsar-10-e1510434111515.jpg\" alt=\"1630 Pulsar 10\" width=\"1200\" height=\"900\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<hr \/>\n<h2><span style=\"color: #800080;\">Vin d&rsquo;jeu d&rsquo;vid\u00e9o<\/span><\/h2>\n<h3>La bouteille de <span style=\"color: #333399;\">Chaps<\/span> en 50 minutes<\/h3>\n<div class=\"video-container\"><iframe loading=\"lazy\" title=\"Explication et analyse du jeu Pulsar 2849\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/w4Ajj_sf1i8?feature=oembed&#038;wmode=opaque\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<hr \/>\n<div id=\"attachment_19600\" style=\"width: 498px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/www.vindjeu.eu\/2017\/11\/22\/pulsar-2849\/1630-pulsar-11\/\" rel=\"attachment wp-att-19600\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-19600\" class=\"size-full wp-image-19600\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/11\/1630-Pulsar-11-e1510434252745.jpg\" alt=\"Une sucrerie...\" width=\"488\" height=\"650\" \/><\/a><p id=\"caption-attachment-19600\" class=\"wp-caption-text\">Une sucrerie&#8230;<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p> Que diriez-vous de parcourir la galaxie \u00e0 la d\u00e9couverte de nouveaux syst\u00e8mes plan\u00e9taires et de pulsars puisqu\u2019aujourd\u2019hui en 2849 nous pouvons extraire de l\u2019\u00e9nergie de ces pulsars ! Bon tout cela demande r\u00e9flexion et technologie en jouant sur moulte m\u00e9canismes forts malins. Vous \u00eates pr\u00eat ? 4\u20263\u20262\u2026&#46;&#46;&#46;<\/p>\n","protected":false},"author":3,"featured_media":19590,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[4849],"tags":[1309,877],"class_list":["post-19592","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-expert","tag-chaps","tag-tapimoket","annee-1290","auteurs-vladimir-suchy","editeurs-czech-games-edition","illustrateurs-soren-meding","nombre_conseille-1355"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/19592","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/comments?post=19592"}],"version-history":[{"count":0,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/19592\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media\/19590"}],"wp:attachment":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media?parent=19592"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/categories?post=19592"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/tags?post=19592"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}