{"id":19799,"date":"2017-11-26T16:36:47","date_gmt":"2017-11-26T15:36:47","guid":{"rendered":"http:\/\/www.vindjeu.eu\/?p=19799"},"modified":"2017-11-26T16:36:47","modified_gmt":"2017-11-26T15:36:47","slug":"queendomino","status":"publish","type":"post","link":"https:\/\/www.vindjeu.eu\/prd\/2017\/11\/26\/queendomino\/","title":{"rendered":"Queendomino"},"content":{"rendered":"<p><a href=\"http:\/\/www.vindjeu.eu\/2017\/11\/26\/queendomino\/1645-queendomino-1-2\/\" rel=\"attachment wp-att-19801\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-19801\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/11\/1645-Queendomino-1-1.png\" alt=\"1645 Queendomino 1\" width=\"497\" height=\"500\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/11\/1645-Queendomino-1-1.png 497w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/11\/1645-Queendomino-1-1-150x150.png 150w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/11\/1645-Queendomino-1-1-298x300.png 298w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/11\/1645-Queendomino-1-1-160x160.png 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/11\/1645-Queendomino-1-1-244x245.png 244w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/11\/1645-Queendomino-1-1-338x340.png 338w\" sizes=\"auto, (max-width: 497px) 100vw, 497px\" \/><\/a><\/p>\n<p><a href=\"http:\/\/www.vindjeu.eu\/?attachment_id=19684\" rel=\"attachment wp-att-19684\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-thumbnail wp-image-19684\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/11\/Swa-18-150x150.jpg\" alt=\"Swa 18\" width=\"150\" height=\"150\" \/><\/a><\/p>\n<h2><span style=\"color: #333399;\">SwatSh<\/span>: <span style=\"color: #800000;\">9 \/10<\/span><\/h2>\n<p>Apr\u00e8s l\u2019\u00e9norme succ\u00e8s de l\u2019excellent <a href=\"http:\/\/www.vindjeu.eu\/2017\/04\/09\/kingdomino-video\/\">Kingdomino <\/a>qui a re\u00e7u le Spiel des Jahres 2017, soit le plus prestigieux des prix (apr\u00e8s le <a href=\"http:\/\/www.vindjeu.eu\/2017\/09\/19\/vin-djeu-dlannee-2017\/\">Vin d\u2019jeu d\u2019l\u2019ann\u00e9e<\/a> bien entendu \ud83d\ude09 ), <a href=\"http:\/\/www.vindjeu.eu\/auteurs\/bruno-cathala\/\">Bruno Cathala<\/a> et son \u00e9diteur <a href=\"http:\/\/www.vindjeu.eu\/editeurs\/blue-orange\/\">Blue Orange<\/a> ont d\u00e9cid\u00e9 de remettre le couvert avec Queendomino.<\/p>\n<p>Queendomino aurait pu \u00eatre une extension \u00e0 <a href=\"http:\/\/www.vindjeu.eu\/2017\/04\/09\/kingdomino-video\/\">Kingdomino<\/a>. Mais, \u00e0 mon sens, plus pour des raisons de mat\u00e9riel que de marketing, ils ont d\u00e9cid\u00e9 de sortir un nouveau jeu plut\u00f4t qu\u2019une extension.<\/p>\n<h2>Extension<\/h2>\n<h3>Les m\u00eames r\u00e8gles<\/h3>\n<p>Queendomino reprend la majorit\u00e9 des r\u00e8gles de <a href=\"http:\/\/www.vindjeu.eu\/2017\/04\/09\/kingdomino-video\/\">Kingdomino<\/a>. On r\u00e9partit les tuiles domino de la m\u00eame mani\u00e8re en pla\u00e7ant son roi sur la tuile voulue qui est class\u00e9e par ordre d\u2019int\u00e9r\u00eat. Plus on choisit une tuile int\u00e9ressante, moins bien on sera plac\u00e9 pour le choix d\u2019une nouvelle tuile. Ce syst\u00e8me tr\u00e8s ing\u00e9nieux et tr\u00e8s juste est remarquable de puret\u00e9 et tourne \u00e0 merveille.<br \/>\nLes r\u00e8gles de pose des tuiles domino sont \u00e9galement les m\u00eames : on doit faire correspondre un c\u00f4t\u00e9 de domino lors du placement tout en restant dans un carr\u00e9 virtuel de 5&#215;5 ou 7&#215;7 selon le nombre de joueuses.<br \/>\nOn gagne les PVs de la m\u00eame mani\u00e8re en fonction du nombre de tuiles composant chaque type de terrain multipli\u00e9 par le nombre de couronnes apparaissant sur ces tuiles. Il y a juste les PVs bonus (comme avoir son ch\u00e2teau au centre de son royaume) qui ne sont pas repris dans Queendomino.<\/p>\n<h3>Les b\u00e2timents<a href=\"http:\/\/www.vindjeu.eu\/2017\/11\/26\/queendomino\/1645-queendomino-2\/\" rel=\"attachment wp-att-19803\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-full wp-image-19803\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/11\/1645-Queendomino-2-e1511208747912.jpg\" alt=\"1645 Queendomino 2\" width=\"500\" height=\"333\" \/><\/a><\/h3>\n<p>A ce syst\u00e8me de base repris \u00e0 100% de <a href=\"http:\/\/www.vindjeu.eu\/2017\/04\/09\/kingdomino-video\/\">Kingdomino <\/a>viennent s\u2019ajouter les b\u00e2timents. Les b\u00e2timents apparaissent de mani\u00e8re classique avec une rivi\u00e8re de b\u00e2timents. Le b\u00e2timent le plus \u00e0 droite co\u00fbte 0 tandis que le plus \u00e0 gauche co\u00fbte 5.\u00a0 A la fin de chaque tour, on d\u00e9cale le tout vers la droite et on remplit les trous.<br \/>\nEn plus de l\u2019action de prendre et de placer une tuile domino, une joueuse peut, \u00e0 son tour, acheter un b\u00e2timent et le placer sur une de ses tuiles chantier. Les chantiers sont des nouveaux paysages de couleur rouge-ocre. Pour pouvoir construire un b\u00e2timent, il faut une tuile chantier sur lequel le placer.<br \/>\nLa b\u00e2timents vont apporter des bonus assez vari\u00e9s :<\/p>\n<ul>\n<li>\n<h4>Des soldats<\/h4>\n<p>Les soldats sont n\u00e9cessaires pour r\u00e9colter de l\u2019argent qui servira \u00e0 acheter des b\u00e2timents ainsi qu\u2019\u00e0 obtenir des PVs suppl\u00e9mentaires en fin de partie.<\/li>\n<li>\n<h4>Des donjons<\/h4>\n<p>La joueuse majoritaire en donjon accueille au sein de son Royaume Madame La Reine. Et Madame La Reine procure 2 avantages : une r\u00e9duction permanente d\u2019un sous \u00e0 l\u2019achat d\u2019un b\u00e2timent (tr\u00e8s utile en cours de partie) et une couronne \u00e0 placer sur son territoire le plus grand en fin de partie (tr\u00e8s utile en fin de partie \ud83d\ude09 ). C\u2019est extr\u00eamement bien vu car \u00e7a rend la reine constamment int\u00e9ressante.\u00a0 La bataille pour la Reine sera rude \ud83d\ude42 \u00a0 Qui la s\u00e9duira le plus avec ses donjons?<\/li>\n<li>\n<h4>Des PVs<a href=\"http:\/\/www.vindjeu.eu\/2017\/11\/26\/queendomino\/1645-queendomino-3\/\" rel=\"attachment wp-att-19804\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-full wp-image-19804\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/11\/1645-Queendomino-3-e1511208809714.jpg\" alt=\"1645 Queendomino 3\" width=\"500\" height=\"333\" \/><\/a><\/h4>\n<p>Les PVs des b\u00e2timents peuvent venir d\u2019une multitude de sources : du nombre de soldats, du nombre de donjons, du nombre de zones contenant un type de paysage (plus on a de zones avec ce type de paysage, plus on score, on a donc int\u00e9r\u00eat \u00e0 avoir une multitude de petites zones qui va \u00e0 l\u2019encontre de la strat\u00e9gie voulant avoir de grandes \u00e9tendues, chouette \ud83d\ude09 ),&#8230;<\/li>\n<li>\n<h4>Des habilit\u00e9s<\/h4>\n<p>Certains b\u00e2timents permettent de gagner plus de sous en fonction de certaines conditions,&#8230;<\/li>\n<\/ul>\n<h2>Mat\u00e9riel<\/h2>\n<p>Avec les m\u00eames r\u00e8gles auxquelles on ajoute les b\u00e2timents, on a tendance \u00e0 se dire qu\u2019une extension suffirait. C\u2019est sans penser que ce simple ajout renouvelle tout le mat\u00e9riel du jeu : un nouveau type de paysage vient s\u2019ajouter : les chantiers, il faut donc revoir toutes les tuiles domino ce qui donne un nouveau jeu : Queendomino !<\/p>\n<h2>Le dragon<\/h2>\n<p><a href=\"http:\/\/www.vindjeu.eu\/2017\/11\/26\/queendomino\/1645-queendomino-4\/\" rel=\"attachment wp-att-19805\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-19805\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/11\/1645-Queendomino-4-e1511208880680.jpg\" alt=\"1645 Queendomino 4\" width=\"500\" height=\"333\" \/><\/a>Le dernier petit truc sympa de Queendomino c\u2019est le dragon. Ce petit truc d\u00e9montre une nouvelle fois tout le g\u00e9nie de <a href=\"http:\/\/www.vindjeu.eu\/auteurs\/bruno-cathala\/\">Bruno Cathala<\/a>. C\u2019est un petit ajout tout b\u00eate mais il fallait y penser ! Une fois par tour, une joueuse peut payer un sous au dragon qui, pour la cause, s\u2019en va d\u00e9truire un b\u00e2timent de la rivi\u00e8re de b\u00e2timents disponibles \u00e0 l&rsquo;achat.<br \/>\nDans tout jeu de draft ou avec une rivi\u00e8re, on dit souvent : \u00ab si on veut emp\u00eacher une joueuse de pouvoir acqu\u00e9rir une carte\/tuile, il suffit que la joueuse qui la pr\u00e9c\u00e8de s\u2019en empare avant elle. Oui mais c\u2019est bien souvent sans penser au co\u00fbt super \u00e9lev\u00e9 de cette action : on doit sacrifier la carte\/tuile qui nous int\u00e9resse au prix de quelque chose qui ne nous int\u00e9resse pas tout \u00e7a pour emp\u00eacher une autre joueuse de s\u2019en emparer. Dans la pratique, on le fait rarement et, d\u00e8s lors, on ne s\u2019occupe pas beaucoup de ce que les autres font. <a href=\"http:\/\/www.vindjeu.eu\/auteurs\/bruno-cathala\/\">Bruno<\/a>, lui, a pr\u00e9vu le Dragon. Si on voit qu\u2019un b\u00e2timent risque de trop avantager une joueuse, on peut payer le dragon, pour un co\u00fbt raisonnable, pour qu\u2019il d\u00e9truise ce b\u00e2timent. Ca force beaucoup plus les joueuses \u00e0 s\u2019int\u00e9resser \u00e0 ce que les autres font pour les emp\u00eahcer de combotter de trop ou de prendre certaines majorit\u00e9s tout en veillant \u00e0 ne pas \u00eatre soi-m\u00eame vis\u00e9 par le dragon. G\u00e9nial !<\/p>\n<h2>Conclusion<\/h2>\n<p>Queendomino peut \u00eatre consid\u00e9r\u00e9 comme une extension stand alone de <a href=\"http:\/\/www.vindjeu.eu\/2017\/04\/09\/kingdomino-video\/\">Kingdomino<\/a>.\u00a0 Il reprend tous les principes de son a\u00een\u00e9 en y ajoutant les b\u00e2timents qui procurent une s\u00e9rie d&rsquo;avantages que les joueuses pourront combiner.\u00a0 Queendomino apporte donc une certaine profondeur au jeu par la multitude des b\u00e2timents disponibles et par la gestion de l&rsquo;argent qu&rsquo;elle induit.\u00a0 Cette profondeur reste n\u00e9anmoins tout \u00e0 fait g\u00e9rable et le jeu peut toujours se jouer en milieu familial bien qu&rsquo;il pourra plus plaire aux joueurs adultes que <a href=\"http:\/\/www.vindjeu.eu\/2017\/04\/09\/kingdomino-video\/\">Kingdomino<\/a>.\u00a0 Enfin, Queendomino apporte plus d&rsquo;interaction au jeu puisque les joueurs vont non seulement se battre pour les tuiles domino, mais \u00e9galement pour les b\u00e2timents et surtout pour la Reine!\u00a0 God save the Queen!<\/p>\n<hr \/>\n<p><a href=\"http:\/\/www.vindjeu.eu\/2017\/11\/26\/queendomino\/1645-queendomino-8\/\" rel=\"attachment wp-att-19800\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-19800\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/11\/1645-Queendomino-8-e1511207779975.jpg\" alt=\"1645 Queendomino 8\" width=\"1200\" height=\"800\" \/><\/a><\/p>\n<hr \/>\n<h2><span style=\"color: #800080;\">Vin d&rsquo;jeu d&rsquo;vid\u00e9o<\/span><\/h2>\n<h3>La d\u00e9gustation en 10 minutes par <span style=\"color: #333399;\">SwatSh<\/span><\/h3>\n<div class=\"video-container\"><iframe loading=\"lazy\" title=\"Queendomino (Vin d&#039;jeu d&#039;vid\u00e9o)\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/LYPt3FM1znE?feature=oembed&#038;wmode=opaque\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<hr \/>\n<h2><span style=\"color: #800080;\">Vin d&rsquo;jeu d&rsquo;music<\/span><\/h2>\n<div class=\"video-container\"><iframe loading=\"lazy\" title=\"The Smiths - The Queen is Dead\" width=\"500\" height=\"375\" src=\"https:\/\/www.youtube.com\/embed\/sT0-OkIl0Dw?feature=oembed&#038;wmode=opaque\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p> Apr\u00e8s l\u2019\u00e9norme succ\u00e8s de l\u2019excellent Kingdomino qui a re\u00e7u le Spiel des Jahres 2017, soit le plus prestigieux des prix (apr\u00e8s le Vin d\u2019jeu d\u2019l\u2019ann\u00e9e bien entendu \ud83d\ude09 ), Bruno Cathala et son \u00e9diteur Blue Orange ont d\u00e9cid\u00e9 de remettre le couvert avec Queendomino. Queendomino aurait pu&#46;&#46;&#46;<\/p>\n","protected":false},"author":3,"featured_media":19801,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[4848],"tags":[7],"class_list":["post-19799","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-initie","tag-swatsh","annee-1290","auteurs-bruno-cathala","editeurs-blue-orange","illustrateurs-cyril-bouquet"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/19799","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/comments?post=19799"}],"version-history":[{"count":0,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/19799\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media\/19801"}],"wp:attachment":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media?parent=19799"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/categories?post=19799"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/tags?post=19799"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}