{"id":19852,"date":"2017-12-21T21:50:14","date_gmt":"2017-12-21T20:50:14","guid":{"rendered":"http:\/\/www.vindjeu.eu\/?p=19852"},"modified":"2017-12-21T21:50:15","modified_gmt":"2017-12-21T20:50:15","slug":"les-aventuriers-du-rail-france","status":"publish","type":"post","link":"https:\/\/www.vindjeu.eu\/prd\/2017\/12\/21\/les-aventuriers-du-rail-france\/","title":{"rendered":"Les Aventuriers du Rail: France"},"content":{"rendered":"<p><a href=\"http:\/\/www.vindjeu.eu\/2017\/11\/20\/les-aventuriers-du-rail-france-vin-djeu-dvideo\/1647-aventuriers-du-rail-france-1\/\" rel=\"attachment wp-att-19788\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-19788\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/11\/1647-Aventuriers-du-Rail-France-1.jpg\" alt=\"1647 Aventuriers du Rail France 1\" width=\"500\" height=\"500\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/11\/1647-Aventuriers-du-Rail-France-1.jpg 500w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/11\/1647-Aventuriers-du-Rail-France-1-150x150.jpg 150w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/11\/1647-Aventuriers-du-Rail-France-1-300x300.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/11\/1647-Aventuriers-du-Rail-France-1-160x160.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/11\/1647-Aventuriers-du-Rail-France-1-245x245.jpg 245w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/11\/1647-Aventuriers-du-Rail-France-1-340x340.jpg 340w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a><\/p>\n<p><a href=\"http:\/\/www.vindjeu.eu\/2017\/11\/28\/feelings-2017\/swa-18\/\" rel=\"attachment wp-att-19684\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-thumbnail wp-image-19684\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/11\/Swa-18-150x150.jpg\" alt=\"Swa 18\" width=\"150\" height=\"150\" \/><\/a><\/p>\n<h3><span style=\"color: #333399;\">SwatSh<\/span>: <span style=\"color: #800000;\">9,5 \/10<\/span><\/h3>\n<p>Autant j\u2019ai \u00e9t\u00e9 d\u00e9\u00e7u par l&rsquo;extension <a href=\"http:\/\/www.vindjeu.eu\/2017\/10\/02\/les-aventuriers-du-rail-allemagne\/\">Allemagne <\/a>&amp; <a href=\"http:\/\/www.vindjeu.eu\/2016\/10\/18\/les-aventuriers-du-rail-autour-du-monde\/\">autour du monde<\/a>, les deux pr\u00e9c\u00e9dentes extensions des <a href=\"http:\/\/www.vindjeu.eu\/2009\/11\/06\/les-aventuriers-du-rail\/\">Aventuriers du Rail<\/a>, autant celle-ci m\u2019a bluff\u00e9.\u00a0 Elle propose 2 nouvelles cartes\u00a0:<\/p>\n<h3>1) La France<\/h3>\n<p>Le plateau de la France est g\u00e9nial.\u00a0 A quelques exceptions pr\u00e8s, toutes ses connections sont en chantier.\u00a0 On ne peut pas construire dessus sans y avoir au pr\u00e9alable construit des rails.\u00a0 Les rails sont des barrettes qui vont indiquer la couleur des cartes \u00e0 jouer si on veut r\u00e9aliser la connexion.\u00a0 On place ces barrettes lorsqu\u2019on r\u00e9alise l\u2019action \u00ab\u00a0piocher 2 cartes\u00a0\u00bb.\u00a0 Apr\u00e8s avoir pioch\u00e9 les 2 cartes, on doit choisir une des barrettes encore disponibles et la placer sur une connexion en chantier.\u00a0 Dor\u00e9navant, on pourra placer nos wagons sur cette connexion \u00e0 condition de jouer autant de cartes de la couleur de la barrette que sa longueur.<\/p>\n<h4>1789, la r\u00e9volution<\/h4>\n<p>Le d\u00e9faut du syst\u00e8me c\u2019est que le jeu est moins joli.\u00a0 Toutes les connexions sont super droites pour correspondre aux barrettes et les barrettes, justement, sont en carton pas tr\u00e8s tops.\u00a0 Mais \u00e0 part \u00e7a, c\u2019est un ajout r\u00e9volutionnaire\u00a0!\u00a0 Les joueurs vont vouloir placer les barrettes aux endroits qu\u2019ils veulent investir.\u00a0 S\u2019ils ont de nombreuses cartes d\u2019une couleur ou d\u2019une autre, ils vont plut\u00f4t placer les barrettes de ces couleurs sur les liaisons qu\u2019ils envisagent.\u00a0 Mais par-l\u00e0, ils donneront une indication aux autres sur le chemin qu\u2019ils comptent prendre.\u00a0 Cela va donc attiser les envies de <strong>blocage<\/strong> de toute sorte.\u00a0 Aussi bien en terme de placement de barrette (surtout qu\u2019on va pouvoir bloquer des routes gr\u00e2ce aux barrettes) que de placement de wagons.\u00a0 Mais ce n\u2019est pas tout\u00a0!\u00a0 Le <strong>bluff<\/strong> rentre aussi dans le jeu et un joueur peut tr\u00e8s bien se servir des barrettes pour donner de fausses indications \u00e0 ses adversaires.\u00a0 G\u00e9nial\u00a0!<\/p>\n<p>La carte est \u00e9galement extr\u00eamement bien faite et les blocages seront faciles et nombreux.\u00a0 Autant vous dire qu\u2019il vous sera tr\u00e8s difficile de r\u00e9ussir tous vos contrats\u00a0!\u00a0 Voil\u00e0 qui rend le jeu encore plus tendu et la strat\u00e9gie de l\u2019accumulation de cartes encore plus caduque.<a href=\"http:\/\/www.vindjeu.eu\/2017\/12\/21\/les-aventuriers-du-rail-france\/1647-aventuriers-du-rail-france-2\/\" rel=\"attachment wp-att-19858\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-full wp-image-19858\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/11\/1647-Aventuriers-du-Rail-France-2-e1511543242366.jpg\" alt=\"1647 Aventuriers du Rail France 2\" width=\"400\" height=\"600\" \/><\/a><\/p>\n<p>Enfin, gr\u00e2ce \u00e0 ces barrettes, plus aucune liaison n\u2019aura la m\u00eame couleur d\u2019une partie \u00e0 l\u2019autre.\u00a0 Pire, certaines liaisons seront bloqu\u00e9es.\u00a0 Cela va apporter encore plus de <strong>vari\u00e9t\u00e9<\/strong> au jeu et une certaine <strong>modularit\u00e9<\/strong> dont <a href=\"http:\/\/www.vindjeu.eu\/2009\/11\/06\/les-aventuriers-du-rail\/\">Les Aventuriers du Rail<\/a> pouvait souffrir.<\/p>\n<h3>2) Old West<\/h3>\n<p>Le vieux western\u00a0\ud83d\ude09 est quant \u00e0 lui plus classique mais int\u00e9ressant.\u00a0 Il permet aux joueuses de placer une ville sur une des extr\u00e9mit\u00e9s d\u2019une route qu\u2019ils viennent de construire.\u00a0 Dor\u00e9navant, toute joueuse construisant une route menant \u00e0 cette ville, donne les points de construction de la route \u00e0 la propri\u00e9taire de la ville.\u00a0 Ca peut faire mal.\u00a0 Les choix seront alors plus difficiles\u00a0: mieux vaut-il contourner la ville adverse ou sacrifier les points de construction pour raccourcir le trajet et atteindre plus d\u2019objectifs\u00a0?\u00a0 Une course tendue aux villes les plus strat\u00e9giques aura \u00e9galement lieu entre les joueuses.<\/p>\n<h4>Alvin<\/h4>\n<p>Le jeu propose \u00e9galement une petite variante amusante\u00a0: La premi\u00e8re joueuse \u00e0 raccorder Roswell prend le jeton alien \u00ab\u00a0Alvin\u00a0\u00bb et le place sur une de ses villes.\u00a0 Une joueuse raccordant une de ses routes \u00e0 cette ville, fait gagner \u00e0 sa proprio les points de la construction comme d\u2019habitude mais gagne aussi 10 PVs gr\u00e2ce \u00e0 Alvin et doit le placer dans une de ses villes.\u00a0 Cela r\u00e9duit un peu la puissance des villes et apporte un peu de fun et de rebondissements \u00e0 la partie.<\/p>\n<p>Il \u00e9tait temps que <a href=\"http:\/\/www.vindjeu.eu\/editeurs\/days-of-wonder\/\">Days Of Wonder<\/a>, l\u2019\u00e9diteur Parisien des <a href=\"http:\/\/www.vindjeu.eu\/2009\/11\/06\/les-aventuriers-du-rail\/\">Aventuriers du Rail<\/a>, publie la carte de la France.\u00a0 Ils ont d\u00fb attendre 13 ans pour enfin sortir cette carte.\u00a0 Mais vu la toute grande qualit\u00e9 de cette version r\u00e9volutionnaire, on a bien fait d\u2019attendre\u00a0\ud83d\ude42\u00a0 Vivement celle sur Paris\u00a0\ud83d\ude1b<\/p>\n<hr \/>\n<p><a href=\"http:\/\/www.vindjeu.eu\/2017\/12\/21\/les-aventuriers-du-rail-france\/1647-aventuriers-du-rail-france-8\/\" rel=\"attachment wp-att-19857\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-19857\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/11\/1647-Aventuriers-du-Rail-France-8-e1511542827859.jpg\" alt=\"1647 Aventuriers du Rail France 8\" width=\"1200\" height=\"800\" \/><\/a><\/p>\n<hr \/>\n<h3><span style=\"color: #800080;\">Vin d&rsquo;jeu d&rsquo;vid\u00e9o<\/span><\/h3>\n<h4>La d\u00e9gustation en 10 minutes par <span style=\"color: #333399;\">SwatSh<\/span><\/h4>\n<div class=\"video-container\"><iframe loading=\"lazy\" title=\"Aventuriers du Rail &amp; extension France (Vin d&#039;jeu d&#039;vid\u00e9o)\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/cWKCZSf87mk?feature=oembed&#038;wmode=opaque\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<hr \/>\n<h3><span style=\"color: #800080;\">Vin d&rsquo;jeu d&rsquo;music<\/span><\/h3>\n<div class=\"video-container\"><iframe loading=\"lazy\" title=\"Barbara - L&#039;aigle Noir\" width=\"500\" height=\"375\" src=\"https:\/\/www.youtube.com\/embed\/kwTFAWwAHaA?feature=oembed&#038;wmode=opaque\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n","protected":false},"excerpt":{"rendered":"<p> Autant j\u2019ai \u00e9t\u00e9 d\u00e9\u00e7u par l&rsquo;extension Allemagne &amp; autour du monde, les deux pr\u00e9c\u00e9dentes extensions des Aventuriers du Rail, autant celle-ci m\u2019a bluff\u00e9.\u00a0 Elle propose 2 nouvelles cartes\u00a0: 1) La France Le plateau de la France est g\u00e9nial.\u00a0 A quelques exceptions pr\u00e8s, toutes ses connections sont en&#46;&#46;&#46;<\/p>\n","protected":false},"author":3,"featured_media":19788,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[5],"tags":[7],"class_list":["post-19852","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-famille","tag-swatsh","annee-1290","auteurs-alan-r-moon","editeurs-days-of-wonder","illustrateurs-cyrille-daujean","illustrateurs-julien-delval","distributeurs-asmodee"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/19852","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/comments?post=19852"}],"version-history":[{"count":0,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/19852\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media\/19788"}],"wp:attachment":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media?parent=19852"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/categories?post=19852"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/tags?post=19852"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}