{"id":20088,"date":"2017-12-29T13:02:47","date_gmt":"2017-12-29T12:02:47","guid":{"rendered":"http:\/\/www.vindjeu.eu\/?p=20088"},"modified":"2017-12-29T13:02:48","modified_gmt":"2017-12-29T12:02:48","slug":"photosynthesis","status":"publish","type":"post","link":"https:\/\/www.vindjeu.eu\/prd\/2017\/12\/29\/photosynthesis\/","title":{"rendered":"Photosynthesis"},"content":{"rendered":"<p><a href=\"http:\/\/www.vindjeu.eu\/2017\/12\/29\/photosynthesis\/1663-photosynthesis-1\/\" rel=\"attachment wp-att-20090\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-20090\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/12\/1663-Photosynthesis-1-e1512745988466.jpg\" alt=\"1663 Photosynthesis 1\" width=\"500\" height=\"499\" \/><\/a><\/p>\n<p><a href=\"http:\/\/www.vindjeu.eu\/2017\/10\/05\/sun-tzu\/tofque-1\/\" rel=\"attachment wp-att-18712\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-thumbnail wp-image-18712\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/09\/Tofque-1-e1505163010611-150x150.jpg\" alt=\"Tofque 1\" width=\"150\" height=\"150\" \/><\/a><\/p>\n<h4><span style=\"color: #333399;\">Tofque<\/span>:\u00a0 <span style=\"color: #800000;\">7,5\/10<\/span><\/h4>\n<p>Photosynthesis est un jeu de Hjalmar Hach qui surfe sur la vague des jeux \u00ab \u00e9cologiques \u00bb sortis cette ann\u00e9e tels que Arboria ou encore L\u2019Arbre pour ne citer qu\u2019eux.<\/p>\n<p>La premi\u00e8re impression positive se fait sur la qualit\u00e9 du mat\u00e9riel. C\u2019est en effet tr\u00e8s mignon et tr\u00e8s d\u00e9taill\u00e9, on sent qu\u2019ils ont boss\u00e9 pour nous rendre un rendu impeccable. Bravo \u00e0 eux sur ce point.<\/p>\n<h4>Le pr\u00e9jug\u00e9 subjectif<\/h4>\n<p>A titre personnel, le th\u00e8me ne me parle pas du tout. Ne me faites pas dire ce que je n\u2019ai pas dit, je ne suis pas contre l\u2019\u00e9cologie, mais \u00e0 choisir entre faire pousser des arbres sur un plateau et par exemple d\u00e9glinguer des menaces Alien dans <a href=\"http:\/\/www.vindjeu.eu\/2010\/10\/24\/space-alert\/\">Space Alert<\/a>, je choisis la deuxi\u00e8me option. Mais on s\u2019\u00e9gare, ces deux jeux n\u2019ont rien \u00e0 voir et cette r\u00e9flexion est purement subjective. La preuve en est que j\u2019ai pos\u00e9 la question \u00e0 ma femme, et elle a la r\u00e9flexion oppos\u00e9e. En m\u00eame temps vous avez d\u00e9j\u00e0 vu une femme qui aime d\u00e9glinguer de l\u2019Alien ? Et voil\u00e0, je me suis mis les f\u00e9ministes \u00e0 dos maintenant\u2026<\/p>\n<h4>Et si on jugeait le jeu sur sa m\u00e9canique ?<\/h4>\n<p>Dans Photosynthesis, vous devez\u2026 planter des arbres, et r\u00e9colter l\u2019\u00e9nergie qui en d\u00e9gage lorsque le soleil les \u00e9claire. Un arbre poss\u00e8de 4 \u00e2ges distincts : l\u2019\u00e9tat de graine (les jetons), et 3 phases de croissance (petit, moyen et grand).<\/p>\n<p>Initialement nous pla\u00e7ons chacun 2 petits arbres de notre couleur sur le bord ext\u00e9rieur du plateau de jeu (sur les cases dot\u00e9es d\u2019une seule feuille). Plus on se rapproche du centre, plus il y aura de feuilles. Et plus il y a de feuilles lorsque nous coupons notre arbre (seulement possible lorsqu\u2019il est grand), plus on aura de points de victoire.<\/p>\n<p>Le jeu se r\u00e9partit en 3 tours de jeu. Pour chaque tour de jeu, il y a 6 rounds. Lors de chaque round, on effectue d\u2019abord la phase d\u2019\u00e9clairage : on regarde si nos arbres sont \u00e9clair\u00e9s par le soleil (repr\u00e9sent\u00e9 par une grande tuile \u00e0 l\u2019ext\u00e9rieur du plateau). Si l\u2019on peut tracer une ligne droite entre le soleil et notre arbre, il est \u00e9clair\u00e9. Si notre arbre est cach\u00e9 pas un autre, il n\u2019est pas \u00e9clair\u00e9. Les grands arbres cachent 3 cases cons\u00e9cutives, les moyens 2 cases et les petits une case. Pour chaque arbre \u00e9clair\u00e9, le joueur marque de 1 \u00e0 3 points de luminosit\u00e9 (1 pour les petits, 2 pour les moyens et 3 pour les grands). Chaque joueur joue ensuite \u00e0 tour de r\u00f4le (suivant un marqueur premier joueur qui suit un sens horaire) et d\u00e9pense les points de luminosit\u00e9 ainsi obtenus (ainsi que ceux accumul\u00e9s au tour pr\u00e9c\u00e9dent qui n\u2019ont pas \u00e9t\u00e9 d\u00e9pens\u00e9s) en effectuant les actions possibles suivantes :<\/p>\n<ul>\n<li>Acheter un arbre ou une graine de son plateau personnel pour le mettre dans sa r\u00e9serve<\/li>\n<li>Planter une graine de sa r\u00e9serve sur le plateau, \u00e0 une case d\u2019un petit arbre, deux cases maximum d\u2019un moyen arbre ou trois cases maximum d\u2019un grand arbre<\/li>\n<li>Faire pousser un arbre. L\u2019arbre ainsi obtenu doit provenir de la r\u00e9serve personnelle et on d\u00e9fausse l\u2019ancien arbre que l\u2019on replace sur le plateau individuel. S\u2019il n\u2019y a plus de place celui-ci est remis dans la boite pour le restant de la partie. L\u2019action de faire pousser un arbre coute :\n<ul>\n<li>1 point de luminosit\u00e9 (d\u2019une graine \u00e0 un petit arbre) ;<\/li>\n<li>2 points de luminosit\u00e9 (d\u2019un petit arbre \u00e0 un moyen arbre) ;<\/li>\n<li>3 points de luminosit\u00e9 (d\u2019un moyen arbre \u00e0 un grand arbre).<\/li>\n<\/ul>\n<\/li>\n<li>Couper un grand arbre : on le remet sur notre plateau individuel et on prend une tuile de points de victoire sur la pile de tuiles correspondant au nombre de feuilles de la case o\u00f9 l\u2019arbre est abattu. Plus il y a de feuilles plus importants seront les points.<\/li>\n<\/ul>\n<p>Lorsque tous les joueurs ont d\u00e9pens\u00e9 leurs points de luminosit\u00e9, on fait pivoter le soleil dans le sens horaire, et on recommence les \u00e9tapes pr\u00e9c\u00e9dentes jusqu\u2019\u00e0 6 fois pour finir une r\u00e9volution compl\u00e8te du soleil. On recommence ensuite l\u2019op\u00e9ration pour atteindre 3 r\u00e9volutions du soleil (donc 18 rounds au total). Le gagnant sera celui avec le plus de points de victoire.<\/p>\n<h4>Conclusion<\/h4>\n<p>Photosynthesis est au final un jeu de placement assez plaisant et original, et malgr\u00e9 le fait qu\u2019il manque l\u00e9g\u00e8rement de fun autour de la table, les parties s\u2019enchainent assez vite et la m\u00e9canique est parfaitement huil\u00e9e. Si le th\u00e8me peut en rebuter certain d\u2019un premier abord (moi en premier), on se surprend \u00e0 prendre plaisir \u00e0 faire pousser ses petites plantations et \u00e0 bloquer ses adversaires en leur faisant de l\u2019ombre avec nos arbres. Toute la difficult\u00e9 r\u00e9side dans le fait de couper son arbre au bon moment, sachant que l\u2019on perdra les points de luminosit\u00e9 qu\u2019il nous aurait rapport\u00e9 au tour suivant.<br \/>\nLes r\u00e8gles tr\u00e8s simples (mais pas simplistes) et le design vraiment attachant font qu\u2019il ferait un choix id\u00e9al pour offrir sous le sapin \u00e0 un n\u00e9ophyte tout comme un passionn\u00e9.<\/p>\n<hr \/>\n<p><a href=\"http:\/\/www.vindjeu.eu\/2016\/09\/22\/million-club\/tapimoket\/\" rel=\"attachment wp-att-14734\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-14734\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2016\/09\/Tapimoket.png\" alt=\"tapimoket\" width=\"125\" height=\"160\" \/><\/a><\/p>\n<h4><span style=\"color: #333399;\">Tapimoket<\/span>:\u00a0 <span style=\"color: #800000;\">8,5 \/10<\/span><\/h4>\n<p>Superbe&#8230;!<\/p>\n<p>Voil\u00e0 ma premi\u00e8re r\u00e9action lorsque j&rsquo;ai aper\u00e7u Photosynthesys la premi\u00e8re fois. Avouons que tous ces arbres color\u00e9s plac\u00e9s sur le plateau sont du plus bel effet, sans oublier l&rsquo;illustration de la boite, \u00e0 la fois captivante et myst\u00e9rieuse de Sabrina Miramon, l&rsquo;illustratrice&#8230;\u00a0Impossible de passer \u00e0 c\u00f4t\u00e9 sans tenter d&rsquo;y jouer une partie.<\/p>\n<p>Photosynthesys est, avant tout un jeu abstrait. Le principe \u00e9tant de faire pousser des arbres, le plus possible au centre pour amasser des points de victoire. A cela s&rsquo;ajoute une touche de gestion de son plateau individuel pour g\u00e9rer les arbres et les graines disponibles, car tout est question d&rsquo;\u00e9quilibre et de placement, un peu comme les lois de la nature. Il faudra d&rsquo;ailleurs utiliser judicieusement le soleil et les ombres qu&rsquo;il g\u00e9n\u00e8re pour exploiter au mieux ses possibilit\u00e9s.<\/p>\n<p>Cette m\u00e9canique avec le soleil et l&rsquo;ombre n&rsquo;est pas totalement nouvelle, car on la croisait d\u00e9j\u00e0 dans Arboria, jeu o\u00f9 l&rsquo;on devrait faire pousser au mieux ses fleurs. Un bon jeu \u00e9galement mais plus familial et plus court. Photosynthesys sera, quand \u00e0 lui, plus strat\u00e9gique et plus long, m\u00eame si les r\u00e8gles restent faciles \u00e0 assimiler. Dans ce dernier, le jeu demande plus de rigueur et d&rsquo;attentions.<\/p>\n<hr \/>\n<p><a href=\"http:\/\/www.vindjeu.eu\/2017\/12\/29\/photosynthesis\/1663-photosynthesis-3\/\" rel=\"attachment wp-att-20089\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-20089\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/12\/1663-Photosynthesis-3.jpg\" alt=\"1663 Photosynthesis 3\" width=\"1384\" height=\"778\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/12\/1663-Photosynthesis-3.jpg 1384w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/12\/1663-Photosynthesis-3-300x169.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/12\/1663-Photosynthesis-3-768x432.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/12\/1663-Photosynthesis-3-1024x576.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/12\/1663-Photosynthesis-3-160x90.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/12\/1663-Photosynthesis-3-436x245.jpg 436w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/12\/1663-Photosynthesis-3-605x340.jpg 605w\" sizes=\"auto, (max-width: 1384px) 100vw, 1384px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p> Photosynthesis est un jeu de Hjalmar Hach qui surfe sur la vague des jeux \u00ab \u00e9cologiques \u00bb sortis cette ann\u00e9e tels que Arboria ou encore L\u2019Arbre pour ne citer qu\u2019eux. La premi\u00e8re impression positive se fait sur la qualit\u00e9 du mat\u00e9riel. C\u2019est en effet tr\u00e8s mignon et tr\u00e8s&#46;&#46;&#46;<\/p>\n","protected":false},"author":3,"featured_media":20090,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[4848],"tags":[877],"class_list":["post-20088","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-initie","tag-tapimoket","annee-1290","auteurs-hjalmar-hach","editeurs-blue-orange","illustrateurs-sabrina-miramon"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/20088","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/comments?post=20088"}],"version-history":[{"count":0,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/20088\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media\/20090"}],"wp:attachment":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media?parent=20088"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/categories?post=20088"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/tags?post=20088"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}