{"id":20160,"date":"2018-01-02T11:33:06","date_gmt":"2018-01-02T10:33:06","guid":{"rendered":"http:\/\/www.vindjeu.eu\/?p=20160"},"modified":"2018-01-02T11:33:06","modified_gmt":"2018-01-02T10:33:06","slug":"lauberge-sanglante-les-forains","status":"publish","type":"post","link":"https:\/\/www.vindjeu.eu\/prd\/2018\/01\/02\/lauberge-sanglante-les-forains\/","title":{"rendered":"L&rsquo;Auberge Sanglante: Les Forains"},"content":{"rendered":"<p><a href=\"http:\/\/www.vindjeu.eu\/2018\/01\/02\/lauberge-sanglante-les-forains\/1655-auberge-forains-1\/\" rel=\"attachment wp-att-20162\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-20162\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/12\/1655-Auberge-forains-1.png\" alt=\"1655 Auberge forains 1\" width=\"500\" height=\"500\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/12\/1655-Auberge-forains-1.png 500w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/12\/1655-Auberge-forains-1-150x150.png 150w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/12\/1655-Auberge-forains-1-300x300.png 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/12\/1655-Auberge-forains-1-160x160.png 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/12\/1655-Auberge-forains-1-245x245.png 245w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/12\/1655-Auberge-forains-1-340x340.png 340w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"http:\/\/www.vindjeu.eu\/2017\/11\/28\/feelings-2017\/swa-18\/\" rel=\"attachment wp-att-19684\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-thumbnail wp-image-19684\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/11\/Swa-18-150x150.jpg\" alt=\"Swa 18\" width=\"150\" height=\"150\" \/><\/a><\/p>\n<h4><span style=\"color: #333399;\">SwatSh<\/span>: <span style=\"color: #800000;\">7\/10<\/span><\/h4>\n<p>La premi\u00e8re chose qui m\u2019a frapp\u00e9e lorsque j\u2019ai ouvert les r\u00e8gles de l\u2019extension de l\u2019excellente <a href=\"http:\/\/www.vindjeu.eu\/2016\/01\/11\/lauberge-sanglante\/\">Auberge Sanglante<\/a> (je ne compte plus le nombre de parties faites mais ce jeu me procure toujours autant de plaisir) c\u2019est les derni\u00e8res lignes de la derni\u00e8re page&#8230;<br \/>\nIl y est indiqu\u00e9 :<br \/>\n-Auteur : Nicolas Robert<br \/>\n-D\u00e9veloppement de l\u2019extension : <a href=\"http:\/\/www.vindjeu.eu\/editeurs\/pearl-games\/\">Pearl Games<\/a><br \/>\n-Illustrations : Weberson Stantiago<br \/>\n-Graphisme : Luis Francisco<br \/>\n-R\u00e9daction des r\u00e8gles : Renaud Eloy<\/p>\n<h4>Quelques r\u00e9flexions par rapport \u00e0 ces quelques lignes :<\/h4>\n<h5>-R\u00e9daction des r\u00e8gles : Renaud Eloy<\/h5>\n<p>Depuis plus d\u2019un an je pense, <a href=\"http:\/\/www.vindjeu.eu\/editeurs\/pearl-games\/\">Pearl Games<\/a> a doubl\u00e9 de volume puisqu\u2019il n\u2019est plus compos\u00e9 d\u2019un seul membre, <a href=\"http:\/\/www.vindjeu.eu\/auteurs\/sebastien-dujardin\/\">S\u00e9bastien Dujardin<\/a>, mais \u00e9galement d\u2019un second : Renaud Eloy. C\u2019est la premi\u00e8re fois que je vois son nom en tant que \u00ab r\u00e9dacteur des r\u00e8gles \u00bb et je ne puis que saluer l\u2019exercice. Les r\u00e8gles de cette extension sont limpides. On ne se pose aucune question. Inutile d\u2019aller voir sur les forums. C\u2019est assez rare pour le moment pour \u00eatre soulign\u00e9. Enfin des r\u00e8gles bien r\u00e9dig\u00e9es ! Merci Renaud \ud83d\ude09<\/p>\n<h5>-Graphisme : Luis Francisco<a href=\"http:\/\/www.vindjeu.eu\/2018\/01\/02\/lauberge-sanglante-les-forains\/1655-auberge-forains-2\/\" rel=\"attachment wp-att-20163\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-full wp-image-20163\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/12\/1655-Auberge-forains-2-e1512940390323.jpg\" alt=\"1655 Auberge forains 2\" width=\"500\" height=\"375\" \/><\/a><\/h5>\n<p>Les graphismes sont une nouvelle fois tr\u00e8s clairs bien que l\u2019oreiller (je ne sais pas si cela rel\u00e8ve du graphiste ou de l\u2019illustrateur) le soit moins.<br \/>\nDans les nouveaut\u00e9s apport\u00e9es par Les Forains, on a de nombreuses cartes \u00e0 co\u00fbt scind\u00e9 (vous voyez le lien ? Co\u00fbt scind\u00e9 -&gt; Coussin d\u00e9s -&gt; oreiller \ud83d\ude00 ). Tr\u00eave de plaisanterie, les co\u00fbts scind\u00e9s veulent dire que des cartes ont des co\u00fbts sp\u00e9cifiques pour certaines actions et diff\u00e9rents pour d\u2019autres. Cela se montre sur les cartes par :<\/p>\n<ul>\n<li>un co\u00fbt accompagn\u00e9 d\u2019un coussin : il indique le co\u00fbt si on veut le tuer ou l\u2019engager<\/li>\n<li>un co\u00fbt indiqu\u00e9 comme d\u2019habitude sur la d\u00e9pendance : il indique le co\u00fbt si on veut l\u2019enterrer ou construire sa d\u00e9pendance<\/li>\n<\/ul>\n<p>J\u2019ai trouv\u00e9 le choix de ce coussin peu judicieux. D\u2019abord, \u00e7a ressemble pas vraiment \u00e0 un coussin mais surtout \u00e7a pr\u00eate \u00e0 confusion. On ne sait jamais tr\u00e8s bien c\u2019est quelles actions qui co\u00fbtent quoi, on doit m\u00eame reprendre les r\u00e8gles pour s\u2019en souvenir. Montrer les ic\u00f4nes des actions aurait \u00e9t\u00e9 plus clair \u00e0 mon sens.<br \/>\nCa a l\u2019air de rien comme \u00e7a mais \u00e7a g\u00e2che un peu le plaisir. Quand on ne sait plus tr\u00e8s bien ce que repr\u00e9sente ce coussin, on passe la carte en se disant qu\u2019elle ne doit pas \u00eatre int\u00e9ressante plut\u00f4t que de demander une xi\u00e8me fois au joueur connaissant les r\u00e8gles ce que \u00e7a repr\u00e9sentait encore. OK, il y a une logique : coussin = co\u00fbt lorsqu\u2019il est dans sa chambre, \u00e7a ne percole pas facilement aupr\u00e8s des joueurs.<br \/>\nCette notion de double co\u00fbt alourdit inutilement le jeu.<\/p>\n<h5><a href=\"http:\/\/www.vindjeu.eu\/2018\/01\/02\/lauberge-sanglante-les-forains\/1655-auberge-forains-3\/\" rel=\"attachment wp-att-20164\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-20164\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/12\/1655-Auberge-forains-3-e1512940481185.jpg\" alt=\"1655 Auberge forains 3\" width=\"500\" height=\"667\" \/><\/a>-Illustrations : Weberson Stantiago<\/h5>\n<p>Et comme d\u2019habitude, Weberson a fait un travail remarquable. Rien que pour ses superbes illustrations, l\u2019extension vaut le d\u00e9tour. Je vous encourage \u00e0 regarder les photos. La femme \u00e0 barbe est juste magnifique et le reste est du m\u00eame acabit.<\/p>\n<h5>-D\u00e9veloppement de l\u2019extension : <a href=\"http:\/\/www.vindjeu.eu\/editeurs\/pearl-games\/\">Pearl Games<\/a><\/h5>\n<p>C\u2019est l\u00e0 o\u00f9 je voulais en venir \ud83d\ude09 C\u2019est marrant de lire \u00e7a. J\u2019ai l\u2019impression, quand je lis cette ligne, que l\u2019auteur n\u2019est pas intervenu dans la r\u00e9alisation de cette extension et que c\u2019est l\u2019\u00e9quipe de <a href=\"http:\/\/www.vindjeu.eu\/editeurs\/pearl-games\/\">Pearl Games<\/a> qui s\u2019en est charg\u00e9e. Apr\u00e8s consultation de <a href=\"http:\/\/www.vindjeu.eu\/auteurs\/sebastien-dujardin\/\">Sebastien<\/a>, il s\u2019av\u00e8re que cette extension a \u00e9t\u00e9 d\u00e9velopp\u00e9e main dans la main, auteur &amp; \u00e9diteur.<br \/>\nJ\u2019imagine que c\u2019est une pratique courante au sein du monde ludique o\u00f9 l\u2019auteur ne se charge que du jeu de base et o\u00f9 l\u2019\u00e9diteurs s\u2019occupe de sortir r\u00e9guli\u00e8rement des extensions pour faire vivre son jeu. Des \u00e9diteurs comme les <a href=\"http:\/\/www.vindjeu.eu\/editeurs\/space-cowboys\/\">Space Cowboys<\/a> le font r\u00e9guli\u00e8rement. Toutes les extension de <a href=\"http:\/\/www.vindjeu.eu\/2015\/10\/03\/t-i-m-e-stories\/\">Time Stories<\/a> ne sont pas sign\u00e9es par ses 2 auteurs et certains scenarii d\u2019<a href=\"http:\/\/www.vindjeu.eu\/2017\/08\/31\/unlock-mystery-adventures\/\">Unlock <\/a>sont m\u00eame sign\u00e9s par l\u2019\u00e9quipe des <a href=\"http:\/\/www.vindjeu.eu\/editeurs\/space-cowboys\/\">Space Cowboys<\/a> (si ma m\u00e9moire est bonne \ud83d\ude09 )!<\/p>\n<h4>Tr\u00eave de r\u00e9flexion \u00e0 2 balles \ud83d\ude09 , que nous r\u00e9serve cette extension ? Diff\u00e9rents modules qu\u2019on peut mixer \u00e0 souhait :<\/h4>\n<h5>1)Les forains &amp; les nouveaux nobles<\/h5>\n<p>Les forains apportent 14 nouveaux voyageurs et avec les nobles cela en fait 28 nouveaux. Il n\u2019y a rien de r\u00e9volutionnaire dans leurs m\u00e9canismes. Certains, comme les roulottes qui permettent, en gros, de construire une annexe sans pouvoir particulier mais \u00e0 un co\u00fbt r\u00e9duit, ne nous ont pas sembl\u00e9 tr\u00e8s int\u00e9ressants. D\u2019autres sont comiques comme les jumelles qui prennent 2 places dans une tombe mais qui rapportent beaucoup ou le nain qui lui, ne prend pas de place :-). Beaucoup apportent un b\u00e9n\u00e9fice conditionnel : \u00ab s\u2019il y a un cadavre non enterr\u00e9 \u00e0 la fin du tour \u00bb, \u00ab si un joueur d\u00e9passe les 40 sous \u00bb,&#8230; Les joueurs sont g\u00e9n\u00e9ralement frileux \u00e0 gagner des avantages conditionnels car ils ne sont jamais certains qu\u2019ils pourront en profiter&#8230;<\/p>\n<h5>2)Les \u00e9v\u00e9nements<a href=\"http:\/\/www.vindjeu.eu\/2018\/01\/02\/lauberge-sanglante-les-forains\/1655-auberge-forains-4\/\" rel=\"attachment wp-att-20165\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-full wp-image-20165\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/12\/1655-Auberge-forains-4-e1512940550166.jpg\" alt=\"1655 Auberge forains 4\" width=\"500\" height=\"375\" \/><\/a><\/h5>\n<p>Les \u00e9v\u00e9nements est le module qui satisfera le plus les amateurs de fun, ceux qui ne s\u2019amusaient pas assez avec le jeu de base et qui voulaient plus de rebondissements. L\u00e0, ils seront servis avec des \u00e9v\u00e9nements du genre :<\/p>\n<ul>\n<li>Tous les joueurs perdent la moiti\u00e9 de leurs sous<\/li>\n<li>Tous les joueurs perdent la moiti\u00e9 de leurs ch\u00e8ques<\/li>\n<li>Tous les joueurs perdent toutes les cartes de leur main<\/li>\n<li>&#8230;<\/li>\n<\/ul>\n<p>Ces \u00e9v\u00e9nements vont bouleverser le jeu et permettront, dans certains cas, plus facilement aux joueurs retardataires de se refaire une sant\u00e9 pour rattraper le joueur en t\u00eate. Mais pour le joueur en t\u00eate, qui se sera construit une strat\u00e9gie, ce type d\u2019\u00e9v\u00e9nement cassera tout et pourra \u00eatre frustrant. Tout d\u00e9pend de quel c\u00f4t\u00e9 vous vous situez. Si vous vous construisez une strat\u00e9gie avec une main de cartes importante permettant de r\u00e9aliser pas mal d\u2019actions en \u00e9vitant de se d\u00e9fausser des cartes et qui voit appara\u00eetre l\u2019\u00e9v\u00e9nement l\u2019obligeant \u00e0 se d\u00e9fausser de toutes ses cartes durement acquises, je peux vous dire que \u00e7a peut faire mal.<br \/>\nCe module est donc \u00e0 r\u00e9server aux joueurs qui n\u2019appr\u00e9ciaient pas particuli\u00e8rement la ma\u00eetrise apport\u00e9e par <a href=\"http:\/\/www.vindjeu.eu\/2016\/01\/11\/lauberge-sanglante\/\">le jeu de base<\/a>.<\/p>\n<h5>3) Les trucs et astuces de Tata Ginette \ud83d\ude42<a href=\"http:\/\/www.vindjeu.eu\/2018\/01\/02\/lauberge-sanglante-les-forains\/1655-auberge-forains-5\/\" rel=\"attachment wp-att-20166\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-full wp-image-20166\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/12\/1655-Auberge-forains-5-e1512940662843.jpg\" alt=\"1655 Auberge forains 5\" width=\"500\" height=\"375\" \/><\/a><\/h5>\n<p>Mais quel titre de module !! J\u2019adore ! C\u2019est d\u2019ores et d\u00e9j\u00e0 le titre de l\u2019ann\u00e9e ! Ca sent le v\u00e9cu \ud83d\ude42 C\u2019est clair que \u00e7a claque vachement mieux que \u00ab les objets \u00bb.<br \/>\nMais qu\u2019est-ce que vous croyiez ? Vous croyiez que vous \u00e9tiez des pr\u00e9curseurs dans le commerce des morts ? Tintin, Tata Ginette l\u2019a fait avant vous et vous vend ses trucs &amp; astuces pour mieux faire votre sale boulot ! Les trucs &amp; astuces sont repr\u00e9sent\u00e9s par 16 cartes objets que les joueurs vont drafter en d\u00e9but de partie pour en avoir 3 pour toute la partie. Ces objets vont apporter des aides ponctuelles qui vous donneront un petit coup de pouce au moment que vous jugerez le plus opportun comme par exemple :<\/p>\n<ul>\n<li>Le puit qui vous permet d\u2019y jeter un cadavre sans devoir l\u2019enterrer<\/li>\n<li>Le pi\u00e8ge qui permet de tuer un pensionnaire sans devoir d\u00e9penser de cartes<\/li>\n<li>Les dents en or qui rapportent plus<\/li>\n<li>Le tas de neige qui permet de dissimuler un cadavre lors de l\u2019enqu\u00eate des forces de l\u2019ordre<\/li>\n<\/ul>\n<p>C\u2019est sympa, \u00e7a varie un peu les parties, permet de faire des surprises et d\u2019optimiser les avantages re\u00e7us de ces objets. Le timing est d\u2019ailleurs tr\u00e8s important et vous devrez constamment tenir compte de vos cartes objet pour d\u00e9cider du moment id\u00e9al pour les jouer.<\/p>\n<p>Les Forains ne sont pas une extension indispensable. Ils ne r\u00e9volutionnent pas le jeu et apportent des petites variations l\u00e9g\u00e8res ainsi qu\u2019un certain chaos avec les \u00e9v\u00e9nements. Il n\u2019emp\u00eache que pour 11 Eur, ils nous permettent de prolonger l\u2019aventure de l\u2019<a href=\"http:\/\/www.vindjeu.eu\/2016\/01\/11\/lauberge-sanglante\/\">Auberge Sanglante<\/a>, aventure toujours autant palpitante.<\/p>\n<hr \/>\n<p><a href=\"http:\/\/www.vindjeu.eu\/2018\/01\/02\/lauberge-sanglante-les-forains\/1655-auberge-forains-8\/\" rel=\"attachment wp-att-20161\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-20161\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/12\/1655-Auberge-forains-8-e1512939288691.jpg\" alt=\"1655 Auberge forains 8\" width=\"1200\" height=\"900\" \/><\/a><\/p>\n<hr \/>\n<p><a href=\"http:\/\/www.vindjeu.eu\/2018\/01\/02\/lauberge-sanglante-les-forains\/1655-auberge-forains-6\/\" rel=\"attachment wp-att-20167\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-20167\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/12\/1655-Auberge-forains-6-e1512940732110-768x1024.jpg\" alt=\"1655 Auberge forains 6\" width=\"720\" height=\"960\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/12\/1655-Auberge-forains-6-e1512940732110-768x1024.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/12\/1655-Auberge-forains-6-e1512940732110-225x300.jpg 225w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/12\/1655-Auberge-forains-6-e1512940732110-120x160.jpg 120w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/12\/1655-Auberge-forains-6-e1512940732110-184x245.jpg 184w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/12\/1655-Auberge-forains-6-e1512940732110-255x340.jpg 255w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p> La premi\u00e8re chose qui m\u2019a frapp\u00e9e lorsque j\u2019ai ouvert les r\u00e8gles de l\u2019extension de l\u2019excellente Auberge Sanglante (je ne compte plus le nombre de parties faites mais ce jeu me procure toujours autant de plaisir) c\u2019est les derni\u00e8res lignes de la derni\u00e8re page&#8230; Il y est indiqu\u00e9&#46;&#46;&#46;<\/p>\n","protected":false},"author":3,"featured_media":20162,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[4848],"tags":[7],"class_list":["post-20160","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-initie","tag-swatsh","annee-1290","auteurs-nicolas-robert","editeurs-pearl-games","illustrateurs-weberson-santiago","distributeurs-asmodee"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/20160","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/comments?post=20160"}],"version-history":[{"count":0,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/20160\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media\/20162"}],"wp:attachment":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media?parent=20160"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/categories?post=20160"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/tags?post=20160"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}