{"id":21128,"date":"2018-03-21T23:05:49","date_gmt":"2018-03-21T22:05:49","guid":{"rendered":"http:\/\/www.vindjeu.eu\/?p=21128"},"modified":"2019-04-03T21:53:46","modified_gmt":"2019-04-03T19:53:46","slug":"spirit-island","status":"publish","type":"post","link":"https:\/\/www.vindjeu.eu\/prd\/2018\/03\/21\/spirit-island\/","title":{"rendered":"Spirit Island"},"content":{"rendered":"<p><a href=\"http:\/\/www.vindjeu.eu\/2018\/03\/21\/spirit-island\/1718-spirit-island-1\/\" rel=\"attachment wp-att-21130\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-21130\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2018\/02\/1718-Spirit-Island-1.png\" alt=\"1718 Spirit Island 1\" width=\"500\" height=\"500\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2018\/02\/1718-Spirit-Island-1.png 500w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2018\/02\/1718-Spirit-Island-1-150x150.png 150w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2018\/02\/1718-Spirit-Island-1-300x300.png 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2018\/02\/1718-Spirit-Island-1-160x160.png 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2018\/02\/1718-Spirit-Island-1-245x245.png 245w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2018\/02\/1718-Spirit-Island-1-340x340.png 340w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a><\/p>\n<p><a href=\"http:\/\/www.vindjeu.eu\/2018\/02\/09\/burgle-bros\/swa-15\/\" rel=\"attachment wp-att-20882\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-thumbnail wp-image-20882\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2018\/01\/Swa-15-150x150.jpg\" alt=\"Swa 15\" width=\"150\" height=\"150\" \/><\/a><\/p>\n<h5><strong><span style=\"color: #333399;\">SwatSh<\/span>:\u00a0 <span style=\"color: #800000;\">8 \/10<\/span><\/strong><\/h5>\n<p>Spirit Island est un jeu issu du syst\u00e8me de financement participatif.\u00a0 Il s&rsquo;agit d&rsquo;un jeu collaboratif dont le th\u00e8me est assez excellent.<\/p>\n<p>Nous sommes des esprits qui prot\u00e9geons une \u00eele paradisiaque.\u00a0 Malheureusement, les humains l&rsquo;ont d\u00e9couverte et s&rsquo;y installent.\u00a0 Mais nous, \u00e7a ne nous plait pas car ils d\u00e9rangent notre qui\u00e9tude.\u00a0 Nous allons alors d\u00e9ployer nos pouvoirs pour les d\u00e9loger \u00e0 coups de tonnerre, d&rsquo;inondations, de famines et d&rsquo;autres subterfuges tout en prot\u00e9geant les tribus autochtones respectueuses de leurs dieux \ud83d\ude42\u00a0 Dans Spirit Island nous allons donc nous battre contre des envahisseurs, un th\u00e8me somme toute assez d\u00e9licat en ces temps de migration.\u00a0 Quand on est de naturel plut\u00f4t accueillant, \u00e7a peut un peu grincer m\u00eame si l&rsquo;aspect fantastique \u00e9vite toute confusion.<\/p>\n<p>Spirit Island est une sorte de deckbuilding collaboratif asym\u00e9trique bas\u00e9 sur un plateau modulable.\u00a0 Chaque joueur repr\u00e9sente un dieu et re\u00e7oit sa fiche comprenant ses pouvoirs sp\u00e9cifiques ainsi que son deck de cartes de d\u00e9part.<\/p>\n<h4><a href=\"http:\/\/www.vindjeu.eu\/2014\/01\/13\/concordia\/\">Concordia<\/a><\/h4>\n<p>Un peu comme dans <a href=\"http:\/\/www.vindjeu.eu\/2014\/01\/13\/concordia\/\">Concordia<\/a>, chaque joueur a toutes ses cartes en main en d\u00e9but de partie et choisit celle(s) qu&rsquo;il veut et peut jouer.\u00a0 Les cartes jou\u00e9es vont dans sa d\u00e9fausse et il devra utiliser une action sp\u00e9cifique pour reprendre toutes ses cartes en main afin de pouvoir les jouer \u00e0 nouveau.<\/p>\n<h4>Pas de tour mais des phases<\/h4>\n<p>Spirit Island est d\u00e9coup\u00e9 en phases mais il n&rsquo;y a pas de tour de jeu.\u00a0 Tous les joueurs jouent et se coordonnent en m\u00eame temps.\u00a0 C&rsquo;est bien vu car \u00e7a dynamise bien le jeu m\u00eame s&rsquo;il n&rsquo;y a aucune contrainte sur le temps.\u00a0 Tous les joueurs r\u00e9fl\u00e9chissent en m\u00eame temps et font des propositions aux autres sur les actions qu&rsquo;ils comptent r\u00e9aliser.\u00a0 Ca discute donc, \u00e7a n\u00e9gocie pour arriver ensuite \u00e0 une sorte de compromis sur ce que chacun peut faire de mieux pour contrer les envahisseurs.<a href=\"http:\/\/www.vindjeu.eu\/2018\/03\/21\/spirit-island\/1718-spirit-island-5\/\" rel=\"attachment wp-att-21134\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-full wp-image-21134\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2018\/02\/1718-Spirit-Island-5-e1517838629452.jpg\" alt=\"1718 Spirit Island 5\" width=\"500\" height=\"375\" \/><\/a><\/p>\n<h4>Les co\u00fbts et contraintes des actions<\/h4>\n<p>Pour pouvoir jouer une carte de sa main, il va falloir payer son co\u00fbt en \u00e9nergie.\u00a0 Le nombre d&rsquo;\u00e9nergie gagn\u00e9 \u00e0 chaque tour par un joueur d\u00e9pend de son niveau d&rsquo;\u00e9nergie. Le nombre de cartes qu&rsquo;on va pouvoir jouer est \u00e9galement indiqu\u00e9 sur son plateau personnel.\u00a0 Ces 2 \u00e9l\u00e9ments (l&rsquo;\u00e9nergie gagn\u00e9e \u00e0 chaque tour et le nombre maximum de cartes \u00e0 jouer) vont devoir \u00eatre g\u00e9r\u00e9s par chaque joueur.\u00a0 Quasi \u00e0 chaque tour vous pourrez augmenter l&rsquo;une de ces \u00e9chelles d&rsquo;un cran.\u00a0 A vous \u00e0 bien choisir laquelle pour affiner votre strat\u00e9gie.<\/p>\n<p>De plus, la majorit\u00e9 des cartes vise une r\u00e9gion du plateau.\u00a0 En fonction de la carte, vous aurez \u00e0 avoir une simple ou double pr\u00e9sence (1 ou 2 jetons joueur) sur la r\u00e9gion vis\u00e9e, sur une r\u00e9gion adjacente ou plus ou moins \u00e9loign\u00e9e.\u00a0 Vous allez \u00e9galement pouvoir \u00e9tendre ou consolider votre pr\u00e9sence (=jetons joueur) sur le plateau.\u00a0 L\u00e0 aussi, une bonne vision strat\u00e9gique vous sera n\u00e9cessaire pour bien placer et \u00e9tendre votre pr\u00e9sence afin de pouvoir toucher un maximum de r\u00e9gion au fur et \u00e0 mesure de l&rsquo;avanc\u00e9e du jeu.<\/p>\n<h4>L&rsquo;am\u00e9lioration des cartes<\/h4>\n<p>Un autre \u00e9l\u00e9ment int\u00e9ressant de Spirit Island est qu&rsquo;on va pouvoir faire progresser son deck de cartes et, par l\u00e0 m\u00eame, les actions qu&rsquo;on va pouvoir r\u00e9aliser.\u00a0 En cours de partie, les joueurs auront la possibilit\u00e9 d&rsquo;\u00e9carter une carte de leur main d\u00e9finitivement de la partie pour la remplacer par une carte du paquet en en piochant 4 et en en choisissant une des 4 pioch\u00e9es.\u00a0 Spirit Island propose 2 niveaux de cartes et on a le choix de piocher dans l&rsquo;un ou l&rsquo;autre paquet en sachant que les cartes de niveau 2 sont beaucoup plus puissantes mais co\u00fbtent plus cher.\u00a0 Il va falloir savoir les payer&#8230;<\/p>\n<h4><a href=\"http:\/\/www.vindjeu.eu\/2018\/03\/21\/spirit-island\/1718-spirit-island-2\/\" rel=\"attachment wp-att-21135\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-21135\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2018\/02\/1718-Spirit-Island-2-e1517840226783.jpg\" alt=\"1718 Spirit Island 2\" width=\"500\" height=\"375\" \/><\/a>Les actions<\/h4>\n<p>Les actions sont un peu bourrines et sont inscrites sur les cartes qu&rsquo;on joue: d\u00e9truire des village et villes, \u00e9liminer des envahisseurs, d\u00e9placer et construire des huttes, emp\u00eacher des colonisations ou constructions, prot\u00e9ger les tribus autochtones,&#8230;\u00a0 Le jeu peine un peu face une variabilit\u00e9 limit\u00e9e des actions r\u00e9duisant par la les choix et les rendant assez simples et \u00e9vidents: on va jouer la ou les cartes les plus puissantes qu&rsquo;on sait se payer!<\/p>\n<h4>La peur<\/h4>\n<p>Les joueurs pourront \u00e9galement r\u00e9colter des jetons peur qui permettront de d\u00e9clencher des \u00e9v\u00e9nements qui vont les aider en cours de partie.\u00a0 M\u00eame s&rsquo;il y en a tr\u00e8s peu, c&rsquo;est un des \u00e9l\u00e9ments al\u00e9atoires du jeu.\u00a0 Les \u00e9v\u00e9nements b\u00e9n\u00e9fiques vont \u00eatre pioch\u00e9s et les joueurs ne les connaitront pas \u00e0 l&rsquo;avance.\u00a0 Ils sont tous b\u00e9n\u00e9fiques mais certains arriveront au bon moment tandis que d&rsquo;autres non.\u00a0 Les joueurs peuvent par exemple mettre beaucoup d&rsquo;\u00e9nergie pour nettoyer une zone alors que l&rsquo;\u00e9v\u00e9nement suivant l&rsquo;aurait fait \u00e0 leur place.<\/p>\n<h4>Les conditions de victoire \u00e9voluent<\/h4>\n<p>Un autre aspect g\u00e9nial de Spirit Island est que les conditions de victoire vont \u00e9voluer en cours de jeu.\u00a0 Du jamais vu!\u00a0 Au d\u00e9but de la partie vous devrez nettoyer l&rsquo;\u00eele de ses envahisseurs.\u00a0 Si vous n&rsquo;y arrivez pas rapidement, plus vous leur aurez fait peur en cours de partie, plus faible seront les conditions de victoire qui ne demanderont plus qu&rsquo;\u00e0 d\u00e9truire uniquement les villes pour l&#8217;emporter.<\/p>\n<p>Cette id\u00e9e permet aux joueurs de faire \u00e9voluer leur strat\u00e9gie en visant une victoire rapide, plus lente ou long terme.<a href=\"http:\/\/www.vindjeu.eu\/2018\/03\/21\/spirit-island\/1718-spirit-island-3\/\" rel=\"attachment wp-att-21137\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-full wp-image-21137\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2018\/02\/1718-Spirit-Island-3-e1517847906172.jpg\" alt=\"1718 Spirit Island 3\" width=\"500\" height=\"375\" \/><\/a><\/p>\n<h4><a href=\"http:\/\/www.vindjeu.eu\/2013\/11\/09\/zombicide\/\">Zombicide<\/a><\/h4>\n<p>Le rete du tour se d\u00e9roule de mani\u00e8re automatique.\u00a0 Les envahisseurs vont saccager les lieux o\u00f9 ils se trouvent, il vont se d\u00e9velopper et envahir l&rsquo;\u00eele.\u00a0 L&rsquo;aspect excellent de ce syst\u00e8me est que tout est pr\u00e9visible.\u00a0 On sait \u00e0 l&rsquo;avance sur quel type de terrain (for\u00eat, plaine, montagne ou marais) ils vont attaquer et o\u00f9 ils vont construire.\u00a0 Seul l&rsquo;endroit o\u00f9 ils apparaissent est inconnu mais quand ils apparaissent, ils ne font rien de mal.\u00a0 L&rsquo;aspect sympa aussi est que tout suit un ordre chronologique:<\/p>\n<ol>\n<li>Si ils apparaissent sur la plaine au tour 1<\/li>\n<li>Ils construiront un village ou une ville sur la plaine au tour 2<\/li>\n<li>Au tour 3, ils attaqueront sur la plaine.\u00a0 Leur force d&rsquo;attaque d\u00e9pendra du nombre de villes et villages pr\u00e9sents sur le terrain.\u00a0 Non seulement ils attaqueront les huttes des tribus autochtones (qui se d\u00e9fendront d&rsquo;ailleurs) mais ils pollueront la terre \u00e9galement avec un effet <a href=\"http:\/\/www.vindjeu.eu\/2018\/01\/05\/pandemic-legacy-saison-2\/\">pandemie <\/a>qui va \u00e9tendre leur pollution sur les r\u00e9gions adjacentes.<\/li>\n<\/ol>\n<h4>Le timing<\/h4>\n<p>La gestion du bon timing est tr\u00e8s importante dans Spirit Island.\u00a0 Les cartes action que vous jouerez auront effet soit avant les phases automatiques (ce sont les effets rapides) soit apr\u00e8s (les effets lents).\u00a0 Evidemment, \u00e7a change tout!\u00a0 Ex\u00e9cuter une action avant ou apr\u00e8s une attaque ou une construction n&rsquo;est pas la m\u00eame chose.\u00a0 Il est d&rsquo;ailleurs g\u00e9n\u00e9ralement inutile d&rsquo;attaquer des envahisseurs apr\u00e8s qu&rsquo;ils aient attaqu\u00e9.\u00a0 Mieux vaut les attaquer avant et donc anticiper leurs actions.\u00a0 C&rsquo;est un syst\u00e8me assez simple une fois qu&rsquo;on maitrise bien la m\u00e9canique mais suffisamment ing\u00e9nieux pour susciter la r\u00e9flexion.<\/p>\n<h4><a href=\"http:\/\/www.vindjeu.eu\/2018\/03\/21\/spirit-island\/1718-spirit-island-4\/\" rel=\"attachment wp-att-21142\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-21142\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2018\/02\/1718-Spirit-Island-4-e1517853681246.jpg\" alt=\"1718 Spirit Island 4\" width=\"500\" height=\"375\" \/><\/a>Les Esprits de l&rsquo;\u00eele<\/h4>\n<p>Spirit Island est un jeu dynamique et s\u00e9duisant.\u00a0 M\u00eame si les huttes autochtones en forme de champignon \u00e9tonnent un peu et contrastent par rapport au reste, le mat\u00e9riel et les illustrations sont splendides.\u00a0 Le jeu \u00e9tonne vu la faible place laiss\u00e9e au hasard ce qui est plut\u00f4t rare pour un jeu collaboratif. \u00a0 Le danger d&rsquo;un jeu collaboratif avec peu de hasard r\u00e9side en la vari\u00e9t\u00e9 des parties qui, de fait, p\u00e8che un peu ici dans sa version non kickstart\u00e9e.\u00a0 Pour vous assurer une belle rejouabilit\u00e9, vous aurez besoin de l&rsquo;extension qui apporte pas mal de nouveaux sc\u00e9narii ainsi que des nouvelles cartes indispensables.\u00a0 Bien que la m\u00e9canique de deckbuilding est assez classique, les autres m\u00e9caniques plus automatiques d\u00e9concertent: l&rsquo;arriv\u00e9e des envahisseurs, leur mani\u00e8re de construire des villes, de polluer la terre et d&rsquo;attaquer les aborig\u00e8nes sont uniques.\u00a0 La cerise sur le g\u00e2teau revient aux conditions de victoire \u00e9volutives!\u00a0 Le jeu est assez difficile et il vous faudra quelques parties pour bien sentir le jeu et vaincre ces envahisseurs toujours trop nombreux.\u00a0 Les actions assez bourrines vont un peu limiter vos choix mais, au final, gr\u00e2ce \u00e0 votre bonne gestion strat\u00e9giques des diff\u00e9rents \u00e9l\u00e9ments, \u00e0 l&rsquo;optimisation de vos pouvoirs et \u00e0 une bonne coordination au sein de votre \u00e9quipe, vous passerez un excellent moment sur l&rsquo;\u00eele aux esprits.<\/p>\n<h3><span style=\"color: #800080;\"><strong>Nouvelle partie<\/strong><\/span><\/h3>\n<p>Apr\u00e8s plusieurs parties, je descends l\u00e9g\u00e8rement ma note \u00e0 8\/10 car les parties de Spirit Island se ressemblent souvent.\u00a0 Il est quasi impossible de gagner la partie durant les \u00e2ges 1 &amp; 2.\u00a0 Par contre, d\u00e8s que l\u2019\u00e2ge 3 survient, il \u00ab\u00a0suffit\u00a0\u00bb de d\u00e9truire uniquement les grandes villes.\u00a0 Et l\u00e0, l\u2019objectif devient beaucoup plus atteignable.\u00a0 Les parties consistent bien souvent \u00e0 tenir le coup durant les \u00e2ges 1 &amp; 2 et de pr\u00e9parer le terrain pour qu\u2019en d\u00e9but de l\u2019\u00e2ge 3, la suppression des villes devienne une formalit\u00e9.\u00a0 C\u2019est l\u00e0 que le jeu devient passionnant pour arriver \u00e0 se sortir du casse-t\u00eate afin d\u2019\u00e9liminer toutes les villes le plus vite possible avant que le jeu ne prenne le dessus sur les joueurs.<\/p>\n<hr \/>\n<p><a href=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2016\/09\/Chaps-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-thumbnail wp-image-14812\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2016\/09\/Chaps-1-150x150.jpg\" alt=\"chaps-1\" width=\"150\" height=\"150\" \/><\/a><\/p>\n<h5><strong><span style=\"color: #333399;\">Chaps<\/span>:\u00a0 <span style=\"color: #800000;\">8,5\/10<\/span><\/strong><\/h5>\n<p>Je joue \u00e0 tr\u00e8s peu de coop\u2019. Donc je m\u2019y penche quand on me les conseille vraiment et je recherche un jeu th\u00e9matique, difficile, complexe avec beaucoup de pression et une obligation de coop\u00e9ration avec n\u00e9anmoins une vraie libert\u00e9 individuelle.<\/p>\n<p>J\u2019ai trouv\u00e9 tout cela dans Spirit Island. En plus des m\u00e9caniques bien pens\u00e9es et th\u00e9matiques, augmenter la peur pour rendre la victoire et la fuite des envahisseurs plus facile, utiliser les Dahans, les pouvoirs qui se d\u00e9clenchent en d\u00e9but ou fin de manche donc il faut bien calculer le timing. Enfin il y a une ressource \u00e0 g\u00e9rer, l\u2019\u00e9nergie.<\/p>\n<p>La pression est tr\u00e8s forte, ces envahisseurs se multiplient comme des lapins et les d\u00e9solations pleuvent si on n\u2019y prend garde, acc\u00e9l\u00e9rant d\u2019autant plus la d\u00e9faite. Le jeu est exigeant sous peine de perdre rapidement. Il faut bien garder en vue ses objectifs, surveiller avec vigueur les zones de ravage, faire peur aux envahisseurs. J\u2019ai retrouv\u00e9 tout ce que j\u2019aime dans un coop\u2019, complexit\u00e9, forte pression et th\u00e8me pr\u00e9sent.<\/p>\n<p>On d\u00e9veloppe son jeu individuellement notamment avec ses cartes pouvoirs, l\u2019orientation de son esprit, le jeu est asym\u00e9trique,\u00a0 j\u2019ai aussi appr\u00e9ci\u00e9 cela, mais il ne faut pas en oublier que c\u2019est un coop\u2019, \u00e0 trop jouer dans son coin d\u2019\u00eele sans trop regarder ce que font les autres on ouvre la porte \u00e0 une d\u00e9faite en 1h15\u2026 Oui c\u2019est du v\u00e9cu\u00a0\ud83d\ude09<\/p>\n<p>Enfin le mat\u00e9riel est de tr\u00e8s bonne facture et immerge dans le jeu.<\/p>\n<p>Pour finir j\u2019ai h\u00e2te de t\u00e2ter des sc\u00e9narios, je ne peux pas en parler mais rajouter des sc\u00e9narios avec des nations qui sont les envahisseurs (visiblement, je ne m\u2019y suis pas pench\u00e9 dessus) avec des plateaux double face adapt\u00e9s, cela permet de se dire que le jeu ne va pas prendre la poussi\u00e8re. J\u2019ai h\u00e2te de le ressortir pour pouvoir mieux contr\u00f4ler le jeu et \u00e9liminer ses envahisseurs pour enfin essayer les modes sc\u00e9narios. Le go\u00fbt de reviens-y est fort.<\/p>\n<p>Y-a-t\u2019il des points n\u00e9gatifs pour ne pas mettre une meilleure note\u00a0? D\u2019abord je n\u2019ai pas assez de parties \u00e0 mon actif et le sentiment de n\u2019avoir pas exploit\u00e9 le jeu pleinement donc ma note s\u2019am\u00e9liorera certainement avec le temps (je reste prudent). Ensuite c\u2019est un coop\u2019, l\u00e0 c\u2019est tr\u00e8s personnel, le plaisir de jeu, la sensation globale intervient dans la note et personnellement je pr\u00e9f\u00e8re le comp\u00e9titif donc je r\u00e9serve les excellentes notes pour ces jeux. Toute critique doit \u00eatre lue sans oublier qui est celui qui l\u2019\u00e9crit\u00a0\ud83d\ude09<\/p>\n<hr \/>\n<p><a href=\"http:\/\/www.vindjeu.eu\/2018\/03\/21\/spirit-island\/1718-spirit-island-10\/\" rel=\"attachment wp-att-21129\"><br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-21129\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2018\/02\/1718-Spirit-Island-10-e1517834892398.jpg\" alt=\"1718 Spirit Island 10\" width=\"1200\" height=\"900\" \/><\/a><\/p>\n<hr \/>\n<h2><span style=\"color: #800080;\">Vin d&rsquo;jeu d&rsquo;vid\u00e9o<\/span><\/h2>\n<h4>La bouteille de Chaps en 21 minutes<\/h4>\n<div class=\"video-container\"><iframe loading=\"lazy\" title=\"Spirit Island : Explication et analyse du jeu\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/aK9DrshP5jc?feature=oembed&#038;wmode=opaque\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n","protected":false},"excerpt":{"rendered":"<p> Spirit Island est un jeu issu du syst\u00e8me de financement participatif.\u00a0 Il s&rsquo;agit d&rsquo;un jeu collaboratif dont le th\u00e8me est assez excellent. Nous sommes des esprits qui prot\u00e9geons une \u00eele paradisiaque.\u00a0 Malheureusement, les humains l&rsquo;ont d\u00e9couverte et s&rsquo;y installent.\u00a0 Mais nous, \u00e7a ne nous plait pas car&#46;&#46;&#46;<\/p>\n","protected":false},"author":3,"featured_media":21130,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[4849],"tags":[7],"class_list":["post-21128","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-expert","tag-swatsh","annee-1290","auteurs-r-eric-reuss","editeurs-greater-than-games"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/21128","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/comments?post=21128"}],"version-history":[{"count":0,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/21128\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media\/21130"}],"wp:attachment":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media?parent=21128"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/categories?post=21128"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/tags?post=21128"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}