{"id":23987,"date":"2018-09-02T09:33:49","date_gmt":"2018-09-02T07:33:49","guid":{"rendered":"http:\/\/www.vindjeu.eu\/?p=23987"},"modified":"2018-09-08T13:31:16","modified_gmt":"2018-09-08T11:31:16","slug":"t-i-m-e-stories-freres-de-la-cote","status":"publish","type":"post","link":"https:\/\/www.vindjeu.eu\/prd\/2018\/09\/02\/t-i-m-e-stories-freres-de-la-cote\/","title":{"rendered":"T.I.M.E. Stories: Fr\u00e8res de la C\u00f4te"},"content":{"rendered":"<p><a href=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2018\/08\/1832-Time-stories-freres-1.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-23988\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2018\/08\/1832-Time-stories-freres-1.png\" alt=\"1832 Time stories freres 1\" width=\"355\" height=\"400\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2018\/08\/1832-Time-stories-freres-1.png 355w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2018\/08\/1832-Time-stories-freres-1-266x300.png 266w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2018\/08\/1832-Time-stories-freres-1-142x160.png 142w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2018\/08\/1832-Time-stories-freres-1-217x245.png 217w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2018\/08\/1832-Time-stories-freres-1-302x340.png 302w\" sizes=\"auto, (max-width: 355px) 100vw, 355px\" \/><\/a><\/p>\n<p><a href=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2018\/08\/Swa-21.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-thumbnail wp-image-23770\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2018\/08\/Swa-21-150x150.jpg\" alt=\"Swa 21\" width=\"150\" height=\"150\" \/><\/a><\/p>\n<h5><strong><span style=\"color: #333399;\">SwatSh<\/span>:\u00a0<span style=\"color: #800000;\">\u00a08\/10<\/span><\/strong><\/h5>\n<p>Fr\u00e8res de la C\u00f4te est la suite de l&rsquo;excellent petit sc\u00e9nario <strong><a href=\"http:\/\/www.vindjeu.eu\/2018\/01\/04\/t-i-m-e-stories-estrella-drive-santo-tomas-de-aquino\/\">Santo Tomas de Aquino<\/a><\/strong> qui nous avait permis de vous expliquer en long et en large le jeu aussi bien par \u00e9crit qu&rsquo;\u00e0 travers une vid\u00e9o.<\/p>\n<p>Nous retombons dans un mode anti-spoil obligatoire avec ces Fr\u00e8res de la C\u00f4te.\u00a0 D&rsquo;office, on a moins \u00e0 dire \ud83d\ude09<\/p>\n<p>C&rsquo;est toujours autant agr\u00e9able de se prendre pour des pirates des Caraibes et de naviguer dans ces eaux \u00e9quatoriales.<\/p>\n<p>Le sc\u00e9nario, toujours aussi bien ficel\u00e9,\u00a0est assez compliqu\u00e9.\u00a0 Il est important de bien faire attention aux petits d\u00e9tails car c&rsquo;est eux qui vous permettront de prendre les bonnes d\u00e9cisions.\u00a0 Plongez-vous dans le scenario et imaginez les cons\u00e9quences de vos d\u00e9cisions comme si vous y \u00e9tiez.\u00a0 Ne pas suivre ces conseils peut vous \u00eatre fatal!<\/p>\n<p>Cet \u00e9cueil pass\u00e9, on prend toujours autant son pied ludique \u00e0 suivre activement ce sc\u00e9nario avec de nombreux rebondissements qui raviront les joueurs les plus sujets aux surprises.\u00a0 On va m\u00eame d\u00e9couvrir de nouvelles m\u00e9caniques de navigation \ud83d\ude42\u00a0 Qui n&rsquo;a jamais r\u00eav\u00e9 de naviguer \u00e0 travers les splendides mers des Cara\u00efbes?<\/p>\n<hr \/>\n<p><a href=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2018\/08\/1832-Time-stories-freres-2.png\"><br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-23990\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2018\/08\/1832-Time-stories-freres-2.png\" alt=\"1832 Time stories freres 2\" width=\"900\" height=\"515\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2018\/08\/1832-Time-stories-freres-2.png 900w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2018\/08\/1832-Time-stories-freres-2-300x172.png 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2018\/08\/1832-Time-stories-freres-2-768x439.png 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2018\/08\/1832-Time-stories-freres-2-160x92.png 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2018\/08\/1832-Time-stories-freres-2-428x245.png 428w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2018\/08\/1832-Time-stories-freres-2-594x340.png 594w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<hr \/>\n<h2><span style=\"color: #800080;\">Vin d&rsquo;jeu d&rsquo;music<\/span><\/h2>\n<div class=\"video-container\"><iframe loading=\"lazy\" title=\"THE EXPLODING BOY - The Day (2018) \/\/ Official Lyric Video \/\/ Drakkar Entertainment\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/47EO82z6YHk?feature=oembed&#038;wmode=opaque\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n","protected":false},"excerpt":{"rendered":"<p> Fr\u00e8res de la C\u00f4te est la suite de l&rsquo;excellent petit sc\u00e9nario Santo Tomas de Aquino qui nous avait permis de vous expliquer en long et en large le jeu aussi bien par \u00e9crit qu&rsquo;\u00e0 travers une vid\u00e9o. Nous retombons dans un mode anti-spoil obligatoire avec ces Fr\u00e8res de la&#46;&#46;&#46;<\/p>\n","protected":false},"author":3,"featured_media":23988,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[4848],"tags":[7],"class_list":["post-23987","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-initie","tag-swatsh","annee-1616","auteurs-manuel-rozoy","auteurs-ulric-maes","editeurs-space-cowboys","illustrateurs-alexis-sentenac","illustrateurs-pascal-quidault","distributeurs-asmodee"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/23987","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/comments?post=23987"}],"version-history":[{"count":0,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/23987\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media\/23988"}],"wp:attachment":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media?parent=23987"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/categories?post=23987"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/tags?post=23987"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}