{"id":25450,"date":"2018-11-08T21:16:17","date_gmt":"2018-11-08T20:16:17","guid":{"rendered":"http:\/\/www.vindjeu.eu\/?p=25450"},"modified":"2018-11-08T21:43:43","modified_gmt":"2018-11-08T20:43:43","slug":"monster-bande","status":"publish","type":"post","link":"https:\/\/www.vindjeu.eu\/prd\/2018\/11\/08\/monster-bande\/","title":{"rendered":"Monster Bande"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-25447 alignleft\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2018\/11\/1895-Monster-Bande-1-300x300.jpg\" alt=\"1895 Monster Bande 1\" width=\"300\" height=\"300\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2018\/11\/1895-Monster-Bande-1-300x300.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2018\/11\/1895-Monster-Bande-1-150x150.jpg 150w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2018\/11\/1895-Monster-Bande-1-160x160.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2018\/11\/1895-Monster-Bande-1-245x245.jpg 245w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2018\/11\/1895-Monster-Bande-1-340x340.jpg 340w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2018\/11\/1895-Monster-Bande-1.jpg 600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-thumbnail wp-image-22962\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2015\/01\/Ren-11-150x150.jpg\" alt=\"Ren 11\" width=\"150\" height=\"150\" \/><strong><span style=\"color: #333399;\">Ren<\/span>:<span style=\"color: #800000;\"> 7,5\/10<\/span><\/strong><\/p>\n<p><strong>Premier retour d\u2019Essen<\/strong> en ce qui me concerne avec ce Monster Bande (Bande de Monstres, puisque le titre est en quatre langues sur les c\u00f4t\u00e9s du jeu) qui n\u2019a aucune raison de vous effrayer. Nous sommes en effet en pr\u00e9sence d\u2019un sympathique jeu familial mais qui pourra n\u00e9anmoins donner du fun aux joueurs plus aguerris.<\/p>\n<p>Dans Monster Bande on va jouer par \u00e9quipes et essayer de <strong>faire d\u00e9couvrir un monstre<\/strong> \u00e0 son partenaire. Le jeu est compos\u00e9 de paires de tuiles identiques, avec \u00e0 chaque fois une tuile ayant un dos rouge, sa jumelle ayant un dos bleu. Une joueuse va piocher une tuile face cach\u00e9e (par exemple \u00e0 dos rouge, si on a mis toutes les tuiles dos rouge face cach\u00e9e), et essayer de la faire deviner en la d\u00e9crivant. Sachant que toutes les tuiles \u00e0 dos bleu auront \u00e9t\u00e9 \u00e9tal\u00e9es sur la table, face visible.<\/p>\n<p>Jusque-l\u00e0 rien de bien folichon me direz-vous, et vous aurez raison ma foi. Mais il y a une <strong>astuce toute simple<\/strong> qui va pimenter quelque peu le jeu\u00a0: avant de commencer \u00e0 faire deviner on va lancer deux d\u00e9s. Les faces visibles donneront les caract\u00e9ristiques qu\u2019on ne pourra <u>pas<\/u> utiliser dans la description. Par exemple la couleur, la taille, les pattes ou jambes, le chapeau ou les lunettes \u00e9ventuelles, les poils ou les \u00e9cailles, les lignes ou les pois\u2026 Bref deux caract\u00e9ristiques dont on ne pourra absolument pas parler. Et \u00e7a change fortement le jeu \u00e9videmment, puisqu\u2019il faut toujours faire d\u00e9couvrir le plus de monstres possible le plus vite possible (on a la dur\u00e9e d\u2019un sablier \u00e0 son tour). Et si vous ne pouvez pas mentionner le nombre de patte ou les yeux d\u2019un monstre qui a 6 pattes et 4 yeux par exemple, et bien c\u2019est tout de suite moins facile\u00a0!<\/p>\n<p>Le jeu peut se jouer \u00e0 2 (on essaye simplement de faire d\u00e9couvrir tous les monstres en utilisant le moins de sabliers possible) mais <strong>prendra tout son sel par \u00e9quipes<\/strong>, o\u00f9 l\u2019adr\u00e9naline et la pression du sablier vont g\u00e9n\u00e9rer quelques bons moments de rigolade. Il faut ajouter que les graphismes sont tr\u00e8s r\u00e9ussis, avec des monstres rigolos et attachants (ce qui est indispensable, avec ce genre de jeux simples\u00a0: si les graphismes sont moches on ne va m\u00eame pas regarder le jeu). Le tout donne un chouette jeu familial dont les joueurs plus exp\u00e9riment\u00e9s appr\u00e9cieront aussi une partie entre deux gros jeux pour se d\u00e9tendre ou en d\u00e9but de soir\u00e9e pour s\u2019\u00e9chauffer\u00a0!<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-25456 alignleft\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2018\/11\/IMG_3354-e1541105379431-300x300.jpg\" alt=\"IMG_3354\" width=\"300\" height=\"300\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2018\/11\/IMG_3354-e1541105379431-300x300.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2018\/11\/IMG_3354-e1541105379431-150x150.jpg 150w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2018\/11\/IMG_3354-e1541105379431-768x768.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2018\/11\/IMG_3354-e1541105379431-1024x1024.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2018\/11\/IMG_3354-e1541105379431-160x160.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2018\/11\/IMG_3354-e1541105379431-245x245.jpg 245w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2018\/11\/IMG_3354-e1541105379431-340x340.jpg 340w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-25457 alignleft\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2018\/11\/IMG_3355-e1541105470855-300x300.jpg\" alt=\"IMG_3355\" width=\"300\" height=\"300\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2018\/11\/IMG_3355-e1541105470855-300x300.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2018\/11\/IMG_3355-e1541105470855-150x150.jpg 150w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2018\/11\/IMG_3355-e1541105470855-768x768.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2018\/11\/IMG_3355-e1541105470855-1024x1024.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2018\/11\/IMG_3355-e1541105470855-160x160.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2018\/11\/IMG_3355-e1541105470855-245x245.jpg 245w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2018\/11\/IMG_3355-e1541105470855-340x340.jpg 340w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Ils ne sont pas mignons comme tout ces jolis monstres? Et non ce n&rsquo;est pas mon filleul de 4 ans qui les a dessin\u00e9s ;-)))))<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<hr \/>\n<h4>La d\u00e9gustation en 3 minutes par Ren<\/h4>\n<div class=\"video-container\"><iframe loading=\"lazy\" title=\"Monster-Bande (Vin d&#039;jeu d&#039;vid\u00e9o)\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/97t7IuhBQvE?feature=oembed&#038;wmode=opaque\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n","protected":false},"excerpt":{"rendered":"<p> Premier retour d\u2019Essen en ce qui me concerne avec ce Monster Bande (Bande de Monstres, puisque le titre est en quatre langues sur les c\u00f4t\u00e9s du jeu) qui n\u2019a aucune raison de vous effrayer. Nous sommes en effet en pr\u00e9sence d\u2019un sympathique jeu familial mais qui pourra n\u00e9anmoins&#46;&#46;&#46;<\/p>\n","protected":false},"author":5,"featured_media":25447,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[5],"tags":[323],"class_list":["post-25450","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-famille","tag-ren","annee-1616","auteurs-florian-biege","editeurs-drei-hasen-in-der-abendsonne","illustrateurs-florian-biege"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/25450","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/comments?post=25450"}],"version-history":[{"count":0,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/25450\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media\/25447"}],"wp:attachment":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media?parent=25450"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/categories?post=25450"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/tags?post=25450"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}