{"id":25802,"date":"2018-12-04T20:37:06","date_gmt":"2018-12-04T19:37:06","guid":{"rendered":"http:\/\/www.vindjeu.eu\/?p=25802"},"modified":"2019-03-13T22:55:23","modified_gmt":"2019-03-13T21:55:23","slug":"caverna-the-forgotten-folk","status":"publish","type":"post","link":"https:\/\/www.vindjeu.eu\/prd\/2018\/12\/04\/caverna-the-forgotten-folk\/","title":{"rendered":"Caverna: The Forgotten Folk"},"content":{"rendered":"<p><a href=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2018\/11\/1922-Caverna-the-Forgotten-Folk-1-e1541931750623.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-25804\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2018\/11\/1922-Caverna-the-Forgotten-Folk-1-e1541931750623.jpg\" alt=\"1922 Caverna the Forgotten Folk 1\" width=\"357\" height=\"500\" \/><\/a><\/p>\n<p><a href=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2018\/10\/1886-Essen-2019-76-e1540761302596.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-thumbnail wp-image-25341\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2018\/10\/1886-Essen-2019-76-e1540761302596-150x150.jpg\" alt=\"1886 Essen 2019 76\" width=\"150\" height=\"150\" \/><\/a><\/p>\n<h5><strong><span style=\"color: #333399;\">SwatSh<\/span>:\u00a0 <span style=\"color: #800000;\">5\/10<\/span><\/strong><\/h5>\n<p>Voil\u00e0 une belle histoire que celle de The Forgotten Folk.\u00a0 Cette extension a \u00e9t\u00e9 d\u00e9velopp\u00e9e par Alex Wilber, un fan de notre <strong><a href=\"http:\/\/www.vindjeu.eu\/2014\/11\/12\/vin-djeu-dlannee-2014\/\">Vin d\u2019jeu d\u2019l\u2019ann\u00e9e 2014<\/a><\/strong>, <strong><a href=\"http:\/\/www.vindjeu.eu\/2014\/02\/13\/caverna\/\">Caverna\u00a0<\/a><\/strong>!\u00a0 Il l\u2019a publi\u00e9e sur BGG et l\u2019\u00e9diteur originel de <a href=\"http:\/\/www.vindjeu.eu\/2014\/02\/13\/caverna\/\">Caverna<\/a>, <strong><a href=\"http:\/\/www.vindjeu.eu\/editeurs\/lookout-games\/\">Lookout Games<\/a><\/strong> (<strong><a href=\"http:\/\/www.vindjeu.eu\/2011\/05\/08\/agricola\/\">Agricola<\/a><\/strong>, <strong><a href=\"http:\/\/www.vindjeu.eu\/2011\/01\/24\/le-havre\/\">Le Havre<\/a><\/strong>, <strong><a href=\"http:\/\/www.vindjeu.eu\/2012\/06\/12\/ora-et-labora-aide-de-jeu\/\">Ora et Labora<\/a><\/strong>,&#8230;) l\u2019a rep\u00e9r\u00e9, appr\u00e9ci\u00e9 et a d\u00e9cid\u00e9 de le publier\u00a0!<\/p>\n<p>The Forgotten Folk propose 8 diff\u00e9rentes races que peuvent endosser les joueurs.\u00a0 Lors de la mise en place, les joueurs vont pouvoir en choisir une parmi 2 re\u00e7ues.\u00a0 Ces races vont apporter une asym\u00e9trie \u00e0 <a href=\"http:\/\/www.vindjeu.eu\/2014\/02\/13\/caverna\/\">Caverna <\/a>chacune ayant ses avantages et inconv\u00e9nients.\u00a0 De plus, chaque race commence avec des pi\u00e8ces de d\u00e9part sp\u00e9cifiques ainsi que quelques pi\u00e8ces qui viennent remplacer certaines pi\u00e8ces communes permettant \u00e0 chacun de b\u00e9n\u00e9ficier des avantages de chaque race.\u00a0 2 nouvelles ressources, les gemmes fruits &amp; les champignons, voient \u00e9galement le jour et sont utilis\u00e9es par diff\u00e9rentes races.<\/p>\n<p>Fini les nains, maintenant, vous pouvez jouer \u00e0 <a href=\"http:\/\/www.vindjeu.eu\/2014\/02\/13\/caverna\/\">Caverna <\/a>en tant qu\u2019elfe, que Goblin ou m\u00eame troll\u00a0!!!<\/p>\n<h3><strong><span style=\"color: #008080;\">Nouvelle partie<\/span><\/strong><\/h3>\n<p>Je diminue ma note \u00e0 5 \u00e0 cause de 2 \u00e9l\u00e9ments.<\/p>\n<p>D&rsquo;abord, cette extension r\u00e9duit les choix du jeu de base.\u00a0 A partir du moment o\u00f9 vous avez une race qui prend avantage de certaines actions au d\u00e9triment d&rsquo;autres, vous allez concentrer vos actions sur les actions les plus b\u00e9n\u00e9fiques et d\u00e9laisser les moins avantageuses.\u00a0 Une des grandes saveurs de Caverna est l&rsquo;\u00e9tendue incroyable de ses choix et The Forgotten Folk les r\u00e9duit&#8230;<\/p>\n<p>De plus, cette extension est difficilement jouable avec la version Fran\u00e7aise du jeu.\u00a0 En effet, chaque race a des interactions avec des cartes actions ou des tuiles b\u00e2timents qui sont cit\u00e9s, sur la fiche de la race, par leur nom.\u00a0 Il est extr\u00eamement difficile de pouvoir retrouver ces b\u00e2timents ou actions tant leurs noms Fran\u00e7ais diff\u00e8rent des noms Anglais.\u00a0 Il est d\u00e8s lors difficile de savoir ce qu&rsquo;apporte r\u00e9ellement une race ou l&rsquo;autre et tout \u00e7a apporte pas mal de confusion.<\/p>\n<p>Il est vraiment tr\u00e8s dommage que Z-Man n&rsquo;aie pas traduit cette extension en Fran\u00e7ais.\u00a0 Cela nous d\u00e9montre, un nouvelle fois, que m\u00eame si le march\u00e9 du jeu se porte bien et est en pleine croissance, il a ses limites et certains titres, m\u00eame comme une extension d&rsquo;un des meilleurs jeux au monde, ne sont pas encore rentables en Fran\u00e7ais\u2026\u00a0 Dommage pour nous.<\/p>\n<hr \/>\n<p><a href=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2018\/11\/1922-Caverna-the-Forgotten-Folk-6-e1541931663565.jpg\"><br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-25803\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2018\/11\/1922-Caverna-the-Forgotten-Folk-6-e1541931663565.jpg\" alt=\"1922 Caverna the Forgotten Folk 6\" width=\"1200\" height=\"900\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p> Voil\u00e0 une belle histoire que celle de The Forgotten Folk.\u00a0 Cette extension a \u00e9t\u00e9 d\u00e9velopp\u00e9e par Alex Wilber, un fan de notre Vin d\u2019jeu d\u2019l\u2019ann\u00e9e 2014, Caverna\u00a0!\u00a0 Il l\u2019a publi\u00e9e sur BGG et l\u2019\u00e9diteur originel de Caverna, Lookout Games (Agricola, Le Havre, Ora et Labora,&#8230;) l\u2019a rep\u00e9r\u00e9, appr\u00e9ci\u00e9&#46;&#46;&#46;<\/p>\n","protected":false},"author":3,"featured_media":25804,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[4849],"tags":[7],"class_list":["post-25802","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-expert","tag-swatsh","annee-1616","auteurs-alex-wilber","auteurs-uwe-rosenberg","editeurs-lookout-games","illustrateurs-javier-gonzalez","illustrateurs-klemmens-franz"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/25802","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/comments?post=25802"}],"version-history":[{"count":0,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/25802\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media\/25804"}],"wp:attachment":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media?parent=25802"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/categories?post=25802"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/tags?post=25802"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}