{"id":26128,"date":"2018-12-18T21:37:27","date_gmt":"2018-12-18T20:37:27","guid":{"rendered":"http:\/\/www.vindjeu.eu\/?p=26128"},"modified":"2024-10-18T18:42:43","modified_gmt":"2024-10-18T16:42:43","slug":"blackhout-hong-kong","status":"publish","type":"post","link":"https:\/\/www.vindjeu.eu\/prd\/2018\/12\/18\/blackhout-hong-kong\/","title":{"rendered":"Blackout Hong Kong"},"content":{"rendered":"<p><a href=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2018\/11\/1931-Blackout-1-e1542986380170.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-26130 alignleft\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2018\/11\/1931-Blackout-1-e1542986380170.jpg\" alt=\"1931 Blackout 1\" width=\"500\" height=\"501\" \/><\/a><\/p>\n<p><a href=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2018\/10\/1886-Essen-2019-202.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-thumbnail wp-image-25361\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2018\/10\/1886-Essen-2019-202-150x150.jpg\" alt=\"1886 Essen 2019 202\" width=\"150\" height=\"150\" \/><\/a><\/p>\n<h5><strong><span style=\"color: #333399;\">SwatSh<\/span>: <span style=\"color: #800000;\">9\/10<\/span><\/strong><\/h5>\n<p>Pfff, apr\u00e8s Coimbra, <strong><a href=\"http:\/\/www.vindjeu.eu\/2018\/10\/21\/gugong\/\">Gugong<\/a><\/strong>, <strong><a href=\"http:\/\/www.vindjeu.eu\/2018\/11\/14\/a-pleasant-journey-to-neko\/\">A Pleasant Journey to Neko<\/a><\/strong> et Underwater Cities, on commence tout doucement \u00e0 en avoir marre de jouer \u00e0 d\u2019excellents jeux sortis lors du dernier salon d\u2019Essen\u00a0\ud83d\ude00\u00a0 Mais quel bon mill\u00e9sime ce 2018\u00a0\ud83d\ude42<\/p>\n<p>Apr\u00e8s <strong><a href=\"http:\/\/www.vindjeu.eu\/2016\/04\/07\/mombasa\/\">Mombasa <\/a><\/strong>(<strong><a href=\"http:\/\/www.vindjeu.eu\/2016\/09\/19\/vin-djeu-dlannee-2016\/\">Vin d\u2019jeu d\u2019l\u2019ann\u00e9e 2016<\/a><\/strong>) et <strong><a href=\"http:\/\/www.vindjeu.eu\/2016\/12\/28\/great-western-trail-video\/\">Great Wester Trail<\/a><\/strong> (<strong><a href=\"http:\/\/www.vindjeu.eu\/2017\/09\/19\/vin-djeu-dlannee-2017\/\">Vin d\u2019jeu d\u2019l\u2019ann\u00e9e Expert 2017<\/a><\/strong>), <strong><a href=\"http:\/\/www.vindjeu.eu\/auteurs\/alexander-pfister\/\">Alexander Pfister<\/a><\/strong> nous confirme son g\u00e9nie en mati\u00e8re de jeux profonds avec ce dernier Blackout Hong Kong\u00a0!\u00a0 On ne change pas une \u00e9quipe qui gagne et, comme ses deux pr\u00e9d\u00e9cesseurs, <strong><a href=\"http:\/\/www.vindjeu.eu\/auteurs\/alexander-pfister\/\">Alexander <\/a><\/strong>a r\u00e9alis\u00e9 ce dernier jeu avec l\u2019\u00e9diteur <strong><a href=\"http:\/\/www.vindjeu.eu\/editeurs\/eggertspiele\/\">Eggertspiele <\/a><\/strong>qui nous confirme \u00e9galement tout le bien qu\u2019on pense d\u2019eux.<\/p>\n<h3>Les cartes<\/h3>\n<p>D\u00e8s l\u2019explication des r\u00e8gles, on va vite passer outre le th\u00e8me farfelu d\u2019une coupure de courant \u00e0 Hong Kong pour se focaliser sur la m\u00e9canique g\u00e9niale du jeu de la carte.\u00a0 Blackout Hong Kong est un jeu subdivis\u00e9 en une s\u00e9rie de tours eux-m\u00eames subdivis\u00e9s en une s\u00e9rie de phases jou\u00e9es soit chaque joueuse \u00e0 son tour soit toutes simultan\u00e9ment.<a href=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2018\/11\/1931-Blackout-2-e1542986898436.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-full wp-image-26131\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2018\/11\/1931-Blackout-2-e1542986898436.jpg\" alt=\"1931 Blackout 2\" width=\"500\" height=\"375\" \/><\/a><\/p>\n<p>La premi\u00e8re, la principale, consiste \u00e0 placer 3 cartes (ou 4 quand on aura lib\u00e9r\u00e9 la quatri\u00e8me place) sur les 3 colonnes de cartes de son plateau personnel afin d\u2019ex\u00e9cuter l\u2019action de ces 3 cartes.\u00a0 Un peu comme dans <strong><a href=\"http:\/\/www.vindjeu.eu\/2014\/01\/13\/concordia\/\">Concordia<\/a><\/strong>, le truc g\u00e9nial c\u2019est le c\u00f4t\u00e9 \u00e9volutif du jeu qui va permettre, apr\u00e8s d\u00e9veloppement, de jouer une quatri\u00e8me carte et, surtout, de gagner de nouvelles cartes aux effets plus int\u00e9ressants.\u00a0 Surtout que la phase suivante permet d\u2019acqu\u00e9rir aussi bien des nouvelles cartes actions plus puissantes que des cartes apportant des PVs selon certaines conditions et des cartes donnant des capacit\u00e9s valables pour le reste de la partie.<\/p>\n<p>Les cartes vont former des colonnes qui n\u00e9cessiteront une gestion de votre part car vous ne pourrez r\u00e9cup\u00e9rer que les cartes de la colonne la plus importante en sachant que certains objectifs n\u00e9cessiteront d\u2019avoir certaines cartes dans une m\u00eame colonne.\u00a0 Tout s\u2019imbrique dans Blackout Hong Kong et c\u2019est \u00e7a qui est g\u00e9nial\u00a0!<\/p>\n<p><a href=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2018\/11\/1931-Blackout-3.jpg\"><br \/><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-26132\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2018\/11\/1931-Blackout-3-1024x768.jpg\" alt=\"1931 Blackout 3\" width=\"720\" height=\"540\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2018\/11\/1931-Blackout-3-1024x768.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2018\/11\/1931-Blackout-3-300x225.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2018\/11\/1931-Blackout-3-768x576.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2018\/11\/1931-Blackout-3-160x120.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2018\/11\/1931-Blackout-3-327x245.jpg 327w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2018\/11\/1931-Blackout-3-453x340.jpg 453w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><\/a><\/p>\n<h3>Les combats<\/h3>\n<p><a href=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2018\/11\/1931-Blackout-5-e1542987022654.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-26133\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2018\/11\/1931-Blackout-5-e1542987022654.jpg\" alt=\"1931 Blackout 5\" width=\"500\" height=\"375\" \/><\/a>Tout se combine aussi tr\u00e8s bien dans Blackout Hong Kong au niveau du plateau central.\u00a0 Les cartes acquises vont bien souvent vous permettre de placer un de vos jetons sur la carte centrale vous permettant d\u2019entourer des territoires vous apportant PVs et d\u2019autres ressources gr\u00e2ce \u00e0 un syst\u00e8me de combat assez plaisant.\u00a0 Pour combattre, on connait la force adverse avec certitude et on doit jouer des cartes action apportant autant de force que l\u2019adversaire pour le vaincre.\u00a0 Une des cartes ayant particip\u00e9 au combat se retrouvera bless\u00e9e et devra \u00eatre soign\u00e9e si vous voulez pouvoir la rejouer et b\u00e9n\u00e9ficier des PVs qu\u2019elle apporte.<\/p>\n<p>Blackout Hong Kong est un peu trop long et on est surpris de r\u00e9ussir \u00e0 tout d\u00e9velopper avant la fin.\u00a0 On aurait aim\u00e9 plus de tension en ayant un jeu l\u00e9g\u00e8rement raccourci.\u00a0 Il n\u2019emp\u00eache que le jeu est passionnant et on y est plong\u00e9 du d\u00e9but \u00e0 la fin sans voir le temps passer.\u00a0 Les nombreuses cartes diff\u00e9rentes rendent le jeu tr\u00e8s vari\u00e9 et donnent envie d\u2019y rejouer.\u00a0 Ses diff\u00e9rentes m\u00e9caniques m\u00ealant astucieusement le jeu de la carte, la r\u00e9alisation d\u2019objectifs, la production de ressources al\u00e9atoire, la construction de r\u00e9seaux sur la carte et les combats sans hasard surprennent par leur compl\u00e9mentarit\u00e9 et imbrication.\u00a0 Attention \u00e0 ne pas trop jouer \u00e0 Blackout pour \u00e9viter de faire blackout sur les autres tr\u00e8s bons jeux de <strong><a href=\"http:\/\/www.vindjeu.eu\/annee\/2018\/\">cette ann\u00e9e<\/a><\/strong>\u00a0\ud83d\ude42<\/p>\n<h3><span style=\"color: #800080;\">Nouvelles parties<\/span><\/h3>\n<p>La sortie de Blackout Hong Kong en Fran\u00e7ais \u00e9tait pour nous l&rsquo;occasion de rejouer \u00e0 un des bijoux de cette ann\u00e9e 2019.\u00a0 Bon, l&rsquo;\u00e9dition Fran\u00e7aise se r\u00e9sume \u00e0 quelques mots sur le plateau et des r\u00e8gles traduites.\u00a0 Le reste \u00e9tant ind\u00e9pendant de la langue, on voit pas trop la diff\u00e9rence.\u00a0 Mais ne g\u00e2chons pas notre plaisir, c&rsquo;est quand m\u00eame beaucoup plus agr\u00e9able d&rsquo;apprendre les r\u00e8gles quand elles sont \u00e9crites en Fran\u00e7ais!<a href=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/07\/2127-Blackout-2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-30421 alignright\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/07\/2127-Blackout-2-1024x683.jpg\" alt=\"\" width=\"720\" height=\"480\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/07\/2127-Blackout-2-1024x683.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/07\/2127-Blackout-2-300x200.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/07\/2127-Blackout-2-768x512.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/07\/2127-Blackout-2-160x107.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/07\/2127-Blackout-2-368x245.jpg 368w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/07\/2127-Blackout-2-510x340.jpg 510w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/07\/2127-Blackout-2.jpg 1200w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><\/a><\/p>\n<p>Ces nouvelles parties confirment tout le bien que je pense de ce jeu et de ses m\u00e9canismes ing\u00e9nieux et novateurs.\u00a0 Ce syst\u00e8me d&rsquo;achat de cartes qui se transforment en objectifs et qui permettent de placer des cubes \u00e0 certains endroits sur le plateau puis \u00e0 \u00eatre jou\u00e9es comme action est tout bonnement fabuleux.\u00a0 La longueur du jeu m&rsquo;a moins pes\u00e9e lorsqu&rsquo;on enchaine r\u00e9guli\u00e8rement les parties.\u00a0 Par contre on peut avoir quelques fois un sentiment d&rsquo;impuissance avec les cartes qu&rsquo;on a en main et une erreur peut se payer cash (si par exemple on prend trop de cartes sp\u00e9cialistes et qu&rsquo;on n\u00e9glige les volontaires).<\/p>\n<p>Balckout Hong Kong est clairement une des p\u00e9pites de cette ann\u00e9e avec plusieurs axes strat\u00e9giques possibles: cartes, objectifs, s\u00e9curisation et tuiles.\u00a0 Note maintenue \u00e0 9!<\/p>\n<hr \/>\n<p><a href=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2016\/09\/Chaps-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-thumbnail wp-image-14812\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2016\/09\/Chaps-1-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a><\/p>\n<h5><strong><span style=\"color: #333399;\">Chaps<\/span>: <span style=\"color: #800000;\">9\/10<\/span><\/strong><\/h5>\n<p>Alexander Pfister. Mombasa, Great Western Trail, je partais donc d\u2019un \u00e0 priori positif, sans compter que l\u2019auteur a un contact tr\u00e8s sympathique.<\/p>\n<h3>Un jeu de gestion de main de carte, presque du deckbuilding<\/h3>\n<p>La gestion des cartes, avec lesquelles on fait tout, est excellemment trouv\u00e9e. Inspir\u00e9e de Mombasa on n\u2019est n\u00e9anmoins pas tout \u00e0 fait dans la m\u00eame m\u00e9canique.<\/p>\n<p>J\u2019ai vraiment beaucoup aim\u00e9 cette m\u00e9canique de cartes, l\u2019achat en 2 temps avant d\u2019avoir ses cartes en main, d\u2019abord avec l\u2019argent puis un contrat en ressource et un nombre limit\u00e9 de cartes en attente de r\u00e9alisation de leurs contrats. Il faut bien les choisir ne pas faire feu de tout bois et faire comboter leurs actions avec la facilit\u00e9 que l\u2019on va avoir de les amener en main. Mais en plus il faut tenir compte de leur couleur, action sp\u00e9ciale imm\u00e9diate ou de fin de manche ou encore ressources mais il faut bien \u00e9quilibrer tout cela. Donc le choix des cartes est multifactoriel et impact tout notre jeu. De plus rapidement il faut beaucoup de ressources donc des cartes qui en fournissent plus et qui elles-m\u00eames en demandent plus pour venir dans notre main\u2026 Ajouter \u00e0 cela le fait que le jeu de placement sur le plateau d\u00e9pend aussi des cartes que l\u2019on prend\u2026 Donc toutes les m\u00e9caniques sont li\u00e9es avec au c\u0153ur la main de carte que l\u2019on se construit. Et pour finir les cartes se sont des points de victoire et pas qu\u2019un peu.<\/p>\n<p><a href=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2018\/12\/2127-Blackout-3.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-large wp-image-30424\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2018\/12\/2127-Blackout-3-1024x683.jpg\" alt=\"\" width=\"720\" height=\"480\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2018\/12\/2127-Blackout-3-1024x683.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2018\/12\/2127-Blackout-3-300x200.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2018\/12\/2127-Blackout-3-768x512.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2018\/12\/2127-Blackout-3-160x107.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2018\/12\/2127-Blackout-3-368x245.jpg 368w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2018\/12\/2127-Blackout-3-510x340.jpg 510w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2018\/12\/2127-Blackout-3.jpg 1200w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><\/a>Peut-on \u00e9purer\u00a0? Oui. On n\u2019est pas vraiment dans du deckbuilding mais les cartes de d\u00e9parts de couleur qui vont \u00e0 l\u2019h\u00f4pital on sera bien tent\u00e9 de les y laisser. Peu de points perdus et au moins on a en main des cartes de plus grande valeur qui tournent.<\/p>\n<p>Et ajouter \u00e0 cela le syst\u00e8me de colonne de carte dont les couleurs sont aussi des pr\u00e9requis d\u2019objectifs est excellent. D\u00e9riv\u00e9 de Mombasa on r\u00e9fl\u00e9chit bien avant de poser ses cartes mais attention \u00e0 chercher \u00e0 faire une colonne on repousse la reprise en main de ses cartes et on ne peut pas le faire ind\u00e9finiment, les cartes on en a besoin.<\/p>\n<h3>Et un plateau principal<\/h3>\n<p>Oui les cartes sont le c\u0153ur du jeu mais le plateau principal est tr\u00e8s important, prendre les tuiles explorations avec ces cadeaux et des points de victoire fin de partie \u00e0 la clef et surtout poser ses cubes aux bons emplacement. S\u00e9curiser les districts et profiter gr\u00e2ce \u00e0 un placement intelligent avec un cube de plusieurs s\u00e9curisation de districts. L\u00e0 aussi le jeu est tr\u00e8s bien pens\u00e9, ce syst\u00e8me de placement o\u00f9 se m\u00eale strat\u00e9gie et concurrence, course m\u00eame, est tr\u00e8s bon. Il y a g\u00e9n\u00e9ralement toujours la m\u00eame dynamique on explore d\u2019abord puis peu \u00e0 peu on s\u00e9curise. En s\u00e9curisant on fait partir les tuiles exploration, \u00e0 \u00e9viter au d\u00e9but de partie et s\u00e9curiser \u00e7a demande d\u2019avoir eu le temps de poser ses cubes, donc il y a une dynamique et qui a tendance \u00e0 mettre un peu de pression quand le voisin commence \u00e0 se placer et qu\u2019il va s\u00e9curiser rapidement de toute \u00e9vidence\u2026<\/p>\n<p>Donc Black out Honk Kong m\u2019a beaucoup plu, un usage multiple des cartes qui est tr\u00e8s bon, il faut tout prendre en compte dans nos choix. Une gestion de notre main et des colonnes o\u00f9 l\u2019on joue les cartes qui doit \u00eatre parfaitement anticip\u00e9e. Et le placement sur le plateau principal qui est fondamental et pour lequel se m\u00eale course et opportunisme.<\/p>\n<p>Mais j\u2019ai n\u00e9anmoins failli mettre 8,5 au lieu de 9. A cause de la longueur du jeu, en tout cas \u00e0 4, 3h c\u2019est un peu trop long, 2h30 aurait \u00e9t\u00e9 parfait. Cette dur\u00e9e peut engendrer un petit passage \u00e0 vide \u00ab\u00a0bon et maintenant\u2026\u00a0\u00bb et faire se coucher tard donc sortir le jeu moins souvent. D\u2019autre part si chaque m\u00e9canique est bien reli\u00e9e au th\u00e8me on ne le ressent pas. Personnellement je ne me suis pas senti en train de sauver Honk Kong. Donc un th\u00e8me pr\u00e9sent dans les m\u00e9caniques mais absent du ressenti. Ce sont les b\u00e9mols pour moi de Black out Honk Kong sinon c\u2019est du tout bon, donc ses qualit\u00e9s me font laisser 9 en note.<\/p>\n<hr \/>\n<p><a href=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/01\/Thierry-1-e1484155191437.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-thumbnail wp-image-16153\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/01\/Thierry-1-e1484155191437-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a><\/p>\n<h5><span style=\"color: #333399;\">Thierry<\/span>: <span style=\"color: #800000;\">9,5\/10<\/span><\/h5>\n<p>Quel jeu g\u00e9nial ! Blackout Hong Kong, c&rsquo;est du lourd, c&rsquo;est assez long mais c&rsquo;est surtout un \u00e9norme plaisir de jeu !\u00a0 A l&rsquo;instar de Mombasa, j&rsquo;ai ador\u00e9 ce jeu innovant et profond quant aux m\u00e9caniques en place et aux choix d&rsquo;actions. Le seul petit b\u00e9mol, c&rsquo;est que le jeu est tellement bon que l&rsquo;on en oublie le th\u00e8me\u2026. bref, pour ma part un coup de c\u0153ur de cette ann\u00e9e ;)))<\/p>\n<p>\u00a0<\/p>\n<hr \/>\n<p><a href=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2018\/11\/1931-Blackout-8-e1542986325949.jpg\"><br \/><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-26129\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2018\/11\/1931-Blackout-8-e1542986325949.jpg\" alt=\"1931 Blackout 8\" width=\"1200\" height=\"900\" \/><\/a><\/p>\n\n\n<hr class=\"wp-block-separator is-style-wide\"\/>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"color\" style=\"color:#f78da7\">Vin d&rsquo;jeu d&rsquo;vid\u00e9o<\/span><\/h2>\n\n\n\n<h4 class=\"wp-block-heading\">La bouteille de Chaps en 55 minutes<\/h4>\n\n\n\n<figure class=\"wp-block-embed-youtube wp-block-embed is-type-video is-provider-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"video-container\"><iframe loading=\"lazy\" title=\"Blackout Honk Kong : Explication et Analyse du jeu\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/Yi_n4n0jOXY?feature=oembed&#038;wmode=opaque\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<\/div><\/figure>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/07\/2127-Blackout-8.jpg\" alt=\"\" class=\"wp-image-30425\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/07\/2127-Blackout-8.jpg 1200w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/07\/2127-Blackout-8-300x200.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/07\/2127-Blackout-8-768x512.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/07\/2127-Blackout-8-1024x683.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/07\/2127-Blackout-8-160x107.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/07\/2127-Blackout-8-368x245.jpg 368w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/07\/2127-Blackout-8-510x340.jpg 510w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/07\/2127-Blackout-9-683x1024.jpg\" alt=\"\" class=\"wp-image-30426\" width=\"512\" height=\"768\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/07\/2127-Blackout-9-683x1024.jpg 683w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/07\/2127-Blackout-9-200x300.jpg 200w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/07\/2127-Blackout-9-107x160.jpg 107w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/07\/2127-Blackout-9-163x245.jpg 163w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/07\/2127-Blackout-9-227x340.jpg 227w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/07\/2127-Blackout-9.jpg 720w\" sizes=\"auto, (max-width: 512px) 100vw, 512px\" \/><figcaption>Le second vin de Beychevelle qui vieillit tr\u00e8s bien m\u00eame si, apr\u00e8s 20 ans, il est plut\u00f4t sur le d\u00e9clin.<\/figcaption><\/figure><\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"color\" style=\"color:#f78da7\">Vin d&rsquo;jeu d&rsquo;music<\/span><\/h2>\n\n\n\n<figure class=\"wp-block-embed-youtube wp-block-embed is-type-video is-provider-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"video-container\"><iframe loading=\"lazy\" title=\"Felix Cartal &amp; Lights - Love Me [Official Video]\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/z2i9TCymUG4?feature=oembed&#038;wmode=opaque\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p> Pfff, apr\u00e8s Coimbra, Gugong, A Pleasant Journey to Neko et Underwater Cities, on commence tout doucement \u00e0 en avoir marre de jouer \u00e0 d\u2019excellents jeux sortis lors du dernier salon d\u2019Essen\u00a0\ud83d\ude00\u00a0 Mais quel bon mill\u00e9sime ce 2018\u00a0\ud83d\ude42 Apr\u00e8s Mombasa (Vin d\u2019jeu d\u2019l\u2019ann\u00e9e 2016) et Great Wester Trail (Vin&#46;&#46;&#46;<\/p>\n","protected":false},"author":3,"featured_media":26130,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[4849],"tags":[7],"class_list":["post-26128","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-expert","tag-swatsh","annee-1616","auteurs-alexander-pfister","editeurs-eggertspiele","illustrateurs-chris-quilliams","distributeurs-asmodee","recompenses-vin-djeu-dcoups-dcoeur"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/26128","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/comments?post=26128"}],"version-history":[{"count":1,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/26128\/revisions"}],"predecessor-version":[{"id":59459,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/26128\/revisions\/59459"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media\/26130"}],"wp:attachment":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media?parent=26128"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/categories?post=26128"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/tags?post=26128"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}