{"id":27901,"date":"2019-03-06T16:09:01","date_gmt":"2019-03-06T15:09:01","guid":{"rendered":"https:\/\/www.vindjeu.eu\/?p=27901"},"modified":"2019-03-06T16:09:56","modified_gmt":"2019-03-06T15:09:56","slug":"fortune-city","status":"publish","type":"post","link":"https:\/\/www.vindjeu.eu\/prd\/2019\/03\/06\/fortune-city\/","title":{"rendered":"Fortune City"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"211\" class=\"alignleft size-medium wp-image-27902\" alt=\"\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/02\/FortuneCity00-300x211.jpg\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/02\/FortuneCity00-300x211.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/02\/FortuneCity00-768x541.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/02\/FortuneCity00-160x113.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/02\/FortuneCity00-348x245.jpg 348w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/02\/FortuneCity00-483x340.jpg 483w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/02\/FortuneCity00.jpg 852w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" class=\"alignleft size-thumbnail wp-image-18465\" alt=\"\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/08\/philrey201701-150x150.png\"><\/p>\n<h5><strong><span style=\"color: #333399;\">PhilRey<\/span>:<span style=\"color: #800000;\">&nbsp; 8\/10<\/span><\/strong><\/h5>\n<p>Fortune City est un jeu de pose de tuiles avec un semblant de placement d\u2019ouvriers avec un petit \u00ab pick-up \u00bb (sans le \u00ab delivery \u00bb).<\/p>\n<p>L\u2019id\u00e9e principale est de d\u00e9velopper sa ville au mieux et r\u00e9pondre \u00e0 la demande de travail.<\/p>\n<p><strong>Les tuiles et les ouvriers<\/strong><\/p>\n<p>En d\u00e9but de tour, plusieurs tuiles sont pr\u00e9sent\u00e9es auxquelles on assigne des habitants. Tout cela est fait au hasard. Ces paires tuile + habitant sont ainsi disponibles pour le tour qui d\u00e9bute. Les tuiles repr\u00e9sentent des produits d\u2019un c\u00f4t\u00e9 et un b\u00e2timent de l\u2019autre.<\/p>\n<p><strong>Les actions pas tr\u00e8s nombreuses<\/strong><\/p>\n<p>Les joueurs ex\u00e9cutent une action \u00e0 tour de r\u00f4le, jusqu\u2019\u00e0 ce que tout le monde ait pass\u00e9. Parmi les actions, on retrouve :<\/p>\n<ul>\n<li>Acheter un produit<img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"540\" class=\"alignright size-large wp-image-27903\" alt=\"\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/02\/FortuneCity01-1024x768.jpg\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/02\/FortuneCity01-1024x768.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/02\/FortuneCity01-300x225.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/02\/FortuneCity01-768x576.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/02\/FortuneCity01-160x120.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/02\/FortuneCity01-327x245.jpg 327w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/02\/FortuneCity01-453x340.jpg 453w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><br \/>\nPour ce faire, on paye le co\u00fbt indiqu\u00e9 sur la tuile et on la prend, ainsi que l\u2019habitant associ\u00e9. On place la tuile sur un emplacement libre de sa zona de construction et on place l\u2019habitant dans le parc.<\/li>\n<li>Construire un b\u00e2timent<br \/>\nIdem ici, on paye le co\u00fbt du produit pour le construire dans sa ville. On place la tuile dans sa ville, c\u00f4t\u00e9 B\u00e2timent cette fois, en suivant bien \u00e9videmment les r\u00e8gles de placement (comme \u00ab interdit de construire deux b\u00e2timents de m\u00eame type l\u2019un \u00e0 c\u00f4t\u00e9 de l\u2019autre \u00bb). Le b\u00e2timent produit soit des d\u00e9chets, soit de l\u2019argent soit un diamant. On place donc le jeton correspondant sur la tuile.<\/li>\n<li>Inviter des habitants VIP<br \/>\nIl s\u2019ag\u00eet ici de simplement attirer un habitant VIP (en quantit\u00e9 limit\u00e9e) qui sert un peu comme un \u00ab joker \u00bb en ville.<\/li>\n<\/ul>\n<p><strong>Les habitants<\/strong><\/p>\n<p>Les b\u00e2timents offre de l\u2019emploi aux habitant. Les joueurs peuvent donc assigner les habitants aux b\u00e2timents. Les habitants sont de 4 couleurs qui correspondent aux 4 types de b\u00e2timent. Vous l\u2019avez devin\u00e9, il faut que \u00ab les couleurs \u00bb correspondent. Et donc, les paires tuile + habitant disponibles en d\u00e9but de tour servent en g\u00e9n\u00e9ral \u00e0 \u00e9tendre sa ville mais \u00e9galement \u00e0 prendre des habitants qui pourront y \u00eatre plac\u00e9 .<\/p>\n<p>Les VIPs offrent une flexibilit\u00e9 mais \u00e0 un co\u00fbt.<\/p>\n<p><strong>Le plateau central<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" class=\"alignleft size-medium wp-image-27904\" alt=\"\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/02\/FortuneCity02-300x225.jpg\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/02\/FortuneCity02-300x225.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/02\/FortuneCity02-768x576.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/02\/FortuneCity02-1024x768.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/02\/FortuneCity02-160x120.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/02\/FortuneCity02-327x245.jpg 327w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/02\/FortuneCity02-453x340.jpg 453w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>Le plateau central reprend 4 roues qui repr\u00e9sentent en r\u00e9alit\u00e9 4 \u00e9chelles, une par couleur (\u00e0 savoir par type de b\u00e2timent). Chacune permet d\u2019augmenter une comp\u00e9tence:<\/p>\n<p>&#8211; Revenu (restaurants\/caf\u00e9s et magasins)<\/p>\n<p>&#8211; D\u00e9placement<\/p>\n<p>&#8211; PV en fin de partie<\/p>\n<p>Donner du travail \u00e0 ses habitants permet d\u2019augmenter ces comp\u00e9tences.<\/p>\n<p><strong>Le camion<\/strong><\/p>\n<p>Ha oui, je n\u2019en ai pas encore parl\u00e9 de celui-l\u00e0 ! C\u2019est la partie \u00ab pick-up \u00bb du jeu. En d\u00e9but de partie, votre camion de transport se trouve \u00e0 l\u2019h\u00f4tel de ville. A chaque tour, le joueur peut le d\u00e9placer pour circuler en ville et ramasser la \u00ab production \u00bb des b\u00e2timents par lesquelles il passe. C\u2019est un des petits plus du jeu: la production a lieu \u00e0 la construction du b\u00e2timent, affectant aussi les b\u00e2timents adjacents.<\/p>\n<p>Et si le joueur ne ramasse pas les d\u00e9chets de la ville, il perdra des PV en fin de partie.<\/p>\n<p>Fortune City n\u2019est donc pas vraiment un \u00ab pose d\u2019ouvriers \u00bb mais a des habitants. Ce n\u2019est qu\u2019un \u00ab pick-up \u00bb sans la partie \u00ab delivery \u00bb, c\u2019est un jeu de placement de tuiles, en deux temps. Bref, un peu de tout mais pas vraiment. Un joli m\u00e9lange de m\u00e9canismes qui donne un jeu qui m\u00e9rite l\u2019attention.<\/p>\n<hr>\n<h5><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"194\" class=\"alignnone size-full wp-image-27681 alignleft\" alt=\"\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/01\/tapi-e1521499595232.png\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/01\/tapi-e1521499595232.png 150w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/01\/tapi-e1521499595232-124x160.png 124w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><span style=\"color: #3366ff;\"><strong>Tapimoket : <span style=\"color: #ff0000;\">7\/10<\/span><\/strong><\/span><\/h5>\n<p>J&rsquo;ai stopp\u00e9 dans les all\u00e9es de Essen Spiel devant Fortune City.&nbsp; D&rsquo;abord, parce que je vais toujours fouiner du c\u00f4t\u00e9 des \u00e9diteurs asiatiques qui ont souvent des petits jeux tr\u00e8s sympathiques. Mais aussi parce que celui-ci&nbsp; m&rsquo;a tout de suite intrigu\u00e9 avec ses personnages \u00e0 grosses t\u00eates. Et qui dit intrigu\u00e9, dit claquer encore une 40aine d&rsquo;euros.<\/p>\n<p>Comme beaucoup de jeux asiatiques, Fortune City reste assez l\u00e9ger. Le but sera de b\u00e2tir une ville, d&rsquo;y mettre des employ\u00e9s, de prendre de l&rsquo;argent et des bonus, et enfin, retirer les d\u00e9chets gr\u00e2ce aux d\u00e9placements d&rsquo;un camion. Les tours s&rsquo;encha\u00eenent un poil r\u00e9p\u00e9titif, mais on ne s&rsquo;ennuie pas. On aura quand m\u00eame une sensation de course aux points en essayant de faire progresser 4 curseurs qui nous donneront plus d&rsquo;argent, plus de points et\/ou plus de d\u00e9placements pour le camion.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"225\" class=\"size-full wp-image-28083 alignleft\" alt=\"\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/02\/20190131_211126-e1550528256512.jpg\">La strat\u00e9gie de progression de d\u00e9placements du camion est quasi indispensable et le hasard des tuiles pourra parfois donner un avantage \u00e0 un joueur. En effet, plus le camion se d\u00e9place, plus on pourra ramasser de bonus et vider des poubelles (malus). Sachant que le camion est aussi une source de points non n\u00e9gligeable.<\/p>\n<p>Mais une autre strat\u00e9gie constitue le c\u0153ur du jeu, le point original.&nbsp; Il s&rsquo;agit de la construction et de l&rsquo;apparition des bonus, combin\u00e9es avec les d\u00e9placements. C&rsquo;est \u00e0 ce niveau qu&rsquo;il faudra le plus se synchroniser pour faire appara\u00eetre plusieurs fois un bonus, et, au contraire emp\u00eacher le moins de poubelles, tout en essayant d&rsquo;en ramasser le plus.<\/p>\n<p>J&rsquo;aime beaucoup aussi les cartes bancaires. Il n&rsquo;y a pas \u00e0 chipoter, m\u00eame si la tuile centrale est de qualit\u00e9 moyenne, Fortune City a un design plut\u00f4t chouette.<\/p>\n<p>En conclusion, je pense que les parties se ressembleront, mais c&rsquo;est un jeu tr\u00e8s fluide, simple et avec un rendu tr\u00e8s agr\u00e9able. Fortune City convient \u00e0 un public familial et n&rsquo;est pas d\u00e9nu\u00e9 d&rsquo;int\u00e9r\u00eat. Je n\u2019encha\u00eenerais pas les parties, mais je ne me suis jamais ennuy\u00e9 avec toutes celles que j&rsquo;ai faite pour tenter de b\u00e2tir ma petite ville \u00ab\u00a0id\u00e9ale\u00a0\u00bb. Un bon petit jeu qui m\u00e9rite une VF un jour.&nbsp; Enfin, il tourne assez bien, m\u00eame \u00e0 deux.<\/p>\n<hr>\n<p><img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"540\" class=\"aligncenter size-large wp-image-27905\" alt=\"\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/02\/FortuneCity03-1024x768.jpg\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/02\/FortuneCity03-1024x768.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/02\/FortuneCity03-300x225.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/02\/FortuneCity03-768x576.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/02\/FortuneCity03-160x120.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/02\/FortuneCity03-327x245.jpg 327w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/02\/FortuneCity03-453x340.jpg 453w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p> Fortune City est un jeu de pose de tuiles avec un semblant de placement d\u2019ouvriers avec un petit \u00ab pick-up \u00bb (sans le \u00ab delivery \u00bb). L\u2019id\u00e9e principale est de d\u00e9velopper sa ville au mieux et r\u00e9pondre \u00e0 la demande de travail. Les tuiles et les ouvriers En&#46;&#46;&#46;<\/p>\n","protected":false},"author":4,"featured_media":27902,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[4848],"tags":[6,877],"class_list":["post-27901","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-initie","tag-philrey212","tag-tapimoket","annee-1616","auteurs-chih-fan-chen","editeurs-big-fun-games","nombre_conseille-1185","nombre_conseille-1210","nombre_conseille-1355"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/27901","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/comments?post=27901"}],"version-history":[{"count":0,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/27901\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media\/27902"}],"wp:attachment":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media?parent=27901"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/categories?post=27901"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/tags?post=27901"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}