{"id":28110,"date":"2019-03-17T16:19:32","date_gmt":"2019-03-17T15:19:32","guid":{"rendered":"https:\/\/www.vindjeu.eu\/?p=28110"},"modified":"2019-03-17T20:35:10","modified_gmt":"2019-03-17T19:35:10","slug":"first-martians","status":"publish","type":"post","link":"https:\/\/www.vindjeu.eu\/prd\/2019\/03\/17\/first-martians\/","title":{"rendered":"First Martians"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/02\/2026-First-Martian-1.png\" alt=\"\" class=\"wp-image-28112\" width=\"880\" height=\"460\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/02\/2026-First-Martian-1.png 880w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/02\/2026-First-Martian-1-300x157.png 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/02\/2026-First-Martian-1-768x401.png 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/02\/2026-First-Martian-1-160x84.png 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/02\/2026-First-Martian-1-469x245.png 469w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/02\/2026-First-Martian-1-650x340.png 650w\" sizes=\"auto, (max-width: 880px) 100vw, 880px\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2016\/09\/Chaps-1-768x1024.jpg\" alt=\"\" class=\"wp-image-14812\" width=\"135\" height=\"180\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2016\/09\/Chaps-1-768x1024.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2016\/09\/Chaps-1-225x300.jpg 225w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2016\/09\/Chaps-1-120x160.jpg 120w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2016\/09\/Chaps-1-184x245.jpg 184w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2016\/09\/Chaps-1-255x340.jpg 255w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2016\/09\/Chaps-1.jpg 960w\" sizes=\"auto, (max-width: 135px) 100vw, 135px\" \/><\/figure><\/div>\n\n\n\n<h5 class=\"wp-block-heading\"><strong><span class=\"background-color\" style=\"background-color:#cf2e2e\"><span class=\"color\" style=\"color:#fcfdf5\">Chaps:  8\/10<\/span><\/span><\/strong><\/h5>\n\n\n\n<p>First Martians du bon coop\u2019 mais \u00e0 la prise en\nmain d\u00e9licate, heureusement maintenant en fran\u00e7ais. Je n\u2019ai qu\u2019une partie au\ncompteur et avec un sc\u00e9nario d\u00e9couverte donc peu d\u2019exp\u00e9rience mais l\u2019envie est\nforte de vite prendre un main un nouveau sc\u00e9nario qui cette fois nous plongera\nen plein dans la survie martienne et les m\u00e9caniques du jeu.<\/p>\n\n\n\n<p>Du th\u00e8me, il y en a bien s\u00fbr, augment\u00e9 par le fait que First Martians est un jeu \u00e0 sc\u00e9nario, 6 scenario ind\u00e9pendants et 2 campagnes de scenarios que je n\u2019ai pas regard\u00e9es. Les m\u00e9caniques du jeu sont toujours les m\u00eames mais son installation et son fonctionnement vont \u00eatre largement boulevers\u00e9s par le scenario jou\u00e9&nbsp;: Toutes les actions sont disponibles mais toutes n\u2019auront pas la m\u00eame importance d\u2019un scenario \u00e0 l\u2019autre, d\u2019ailleurs ils sont pr\u00e9sent\u00e9s par th\u00e8me (exploration, recherche, construction). Chaque scenario aura ses objectifs de mission, ses r\u00e8gles sp\u00e9ciales modifiant celles de base, voire souvent ses actions sp\u00e9ciales absentes des r\u00e8gles de base&nbsp;. Tout cela pour r\u00e9aliser la mission en 6 \u00e0 8 manches sans perdre d\u2019astronaute et en faisant face \u00e0 moultes dysfonctionnements dans notre base, notre Hub, tout du moins en essayant au mieux. Et une fois la mission r\u00e9ussie certains sc\u00e9nario n\u00e9cessiteront en plus d\u2019autres crit\u00e8res pour \u00e9viter l\u2019\u00e9chec, comme par exemple un maximum de modules d\u00e9faillants autoris\u00e9s en fin de partie, pas plus.<\/p>\n\n\n\n<p><strong>Le\nplateau, notre vie, nos actions sur Mars<\/strong><\/p>\n\n\n\n<p>Sur le plateau on retrouve une carte de Mars\navec notre Hub au milieu et les Blocs qui forment notre hub. Bloc syst\u00e8me, bloc\nhabitation et bloc atelier. Chaque bloc contient des modules (grandes tuiles\nsur le plateau, zones d\u2019action par pose de pions). Le bloc atelier contient des\nmodules de production d\u2019oxyg\u00e8ne, d\u2019\u00e9nergie et de nourriture, le bloc habitation\nde quoi diminuer le stress et monter le moral (vous verrez c\u2019est important)\nmais aussi de quoi anticiper d\u2019\u00e9ventuelles d\u00e9faillances. Enfin le bloc atelier\no\u00f9 nous construirons, r\u00e9parerons, partirons en exploration sur Mars et\nram\u00e8nerons des \u00e9chantillons martiens, enfin si cela est utile au sc\u00e9nario. N\u2019oubliez\npas, chaque scenario nous fera utiliser diff\u00e9remment le jeu, ses m\u00e9caniques,\nses zones d\u2019actions ce qui peut \u00eatre un peu d\u00e9routant au d\u00e9but.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignright is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/02\/2026-First-Martian-2.png\" alt=\"\" class=\"wp-image-28113\" width=\"660\" height=\"345\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/02\/2026-First-Martian-2.png 880w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/02\/2026-First-Martian-2-300x157.png 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/02\/2026-First-Martian-2-768x401.png 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/02\/2026-First-Martian-2-160x84.png 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/02\/2026-First-Martian-2-469x245.png 469w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/02\/2026-First-Martian-2-650x340.png 650w\" sizes=\"auto, (max-width: 660px) 100vw, 660px\" \/><\/figure><\/div>\n\n\n\n<p>Le jeu se d\u00e9roule donc en 6 \u00e0 8 manches, \u00e0\nchaque manche nous suivront une s\u00e9rie d\u2019\u00e9tapes dont celle o\u00f9 les joueurs programmeront\nleurs actions sous forme de pose de pions d\u2019action dans les diff\u00e9rent modules\ndu Hub. Une m\u00e9canique de type pose d\u2019ouvriers. Les actions seront r\u00e9solues toujours\ndans le m\u00eame ordre \u00e0 la fin de la programmation de tous les joueurs.<\/p>\n\n\n\n<p><strong>Une App\npour nous guider.<\/strong><\/p>\n\n\n\n<p>Oui le jeu n\u00e9cessite une application\n(tablette, smartphone), elle permet de bien suivre l\u2019\u00e9volution de la manche\nmais surtout le programme pr\u00e9sentera et r\u00e9soudra selon les actions des joueurs\ndiff\u00e9rentes situations. Il y a des algorithmes derri\u00e8re expliquant le besoin de\nl\u2019App et le jeu en est enti\u00e8rement d\u00e9pendant.<\/p>\n\n\n\n<p><strong>Premiers\npas, quelle combinaison vous va le mieux&nbsp;?<\/strong><\/p>\n\n\n\n<p>Pour commencer nous choisissons l\u2019astronaute\nque nous allons jouer&nbsp;: 4 diff\u00e9rents avec des comp\u00e9tences diff\u00e9rentes (4\nau total par astronaute) et une orientation th\u00e9matique. Attention nos\nastronautes pourront prendre des blessures, 3&nbsp;? L\u2019astronaute gagne une\ntuile maladie\u2026 vacherie.. 5&nbsp;? Une autre\u2026 6&nbsp;? il meure, partie perdue\u2026\n<\/p>\n\n\n\n<p>Nous choisissons aussi un scenario, d\u00e9couvrons\nl\u2019objectif de mission, les modifications de r\u00e8gles qui s\u2019appliquent et on peut\nd\u00e9marrer pour 6 \u00e0 8 manches.<\/p>\n\n\n\n<p>Chaque manche se divise en plusieurs\n\u00e9tape&nbsp;: Ev\u00e8nement, Moral, production, action, d\u00e9faillance, entretien. <\/p>\n\n\n\n<p><strong>Ev\u00e8nements,\nun p\u00e9pin&nbsp;? D\u00e9j\u00e0&nbsp;?<\/strong><\/p>\n\n\n\n<p>L\u2019App nous annonce un \u00e9v\u00e9nement, j\u2019avoue que\nj\u2019appr\u00e9cie toujours la mani\u00e8re tr\u00e8s th\u00e9matique et souvent humoristique de cette\npr\u00e9sentation qui am\u00e8ne souvent une bonne ambiance \u00e0 la table. Nous pourrons y\nfaire face si nous d\u00e9cidons de programmer l\u2019action \u00ab&nbsp;r\u00e9soudre l\u2019\u00e9v\u00e9nement\ndu tour&nbsp;\u00bb. Sinon il reste en m\u00e9moire pour 3 manches et peut entrainer de\nbien mauvaises surprises\u2026 Le r\u00e9soudre par contre si cela co\u00fbte toujours quelque\nchose sera b\u00e9n\u00e9fique. On peut aussi d\u00e9cider \u00e0 cette manche de r\u00e9soudre des\n\u00e9v\u00e8nements laiss\u00e9s en plan dans les 3 manches pr\u00e9c\u00e9dentes.<\/p>\n\n\n\n<p><strong>Moral,\ntous pour un&nbsp;!<\/strong><\/p>\n\n\n\n<p>Il y a une piste moral global de l\u2019\u00e9quipe et\nchaque joueur peut gagner des pions moral individuels. Des pions morals&nbsp;?\nOui on les d\u00e9pensera pour utiliser nos comp\u00e9tences. Le premier joueur gagne ou\nperd des pions moral selon le moral global de l\u2019\u00e9quipe indiqu\u00e9 sur la piste. Pas\nassez de pions \u00e0 perdre&nbsp;? Blessure pour chaque manque\u2026<\/p>\n\n\n\n<p><strong>Production,\nla vie consomme toujours des ressources\u2026<\/strong><\/p>\n\n\n\n<p>Oxyg\u00e8ne, \u00e9nergie et nourriture (si on ne mange\npas on est bless\u00e9\u2026). Tout cela d\u00e9pend du bloc syst\u00e8me et de ses modules. Dans\nune installation de base du jeu si tout fonctionne on produit exactement ce que\nl\u2019on consomme.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/02\/2026-First-Martian-3.png\" alt=\"\" class=\"wp-image-28114\" width=\"660\" height=\"345\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/02\/2026-First-Martian-3.png 880w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/02\/2026-First-Martian-3-300x157.png 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/02\/2026-First-Martian-3-768x401.png 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/02\/2026-First-Martian-3-160x84.png 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/02\/2026-First-Martian-3-469x245.png 469w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/02\/2026-First-Martian-3-650x340.png 650w\" sizes=\"auto, (max-width: 660px) 100vw, 660px\" \/><\/figure><\/div>\n\n\n\n<p>Sur chaque module du hub il est indiqu\u00e9 s\u2019il\nconsomme ou non \u00e9nergie et\/ou oxyg\u00e8ne. Production excessive&nbsp;? On rajoute\nla moiti\u00e9 de l\u2019exc\u00e8s \u00e0 notre r\u00e9serve. Oui on a une r\u00e9serve en cas de p\u00e9pin pour\nles 3 ressources. Production insuffisante&nbsp;? Il faut fermer un\nmodule&nbsp;! A\u00efe&nbsp;! Des tuiles sp\u00e9ciales sont l\u00e0 pour \u00e7a (\u00e0 poser sur les modules\nferm\u00e9s)\u2026 Le remettre en marche consommera une action, sera d\u00e9pendant d\u2019un jet\nde d\u00e9 (mis\u00e8re\u2026) et co\u00fbtera de la dite ressource de la r\u00e9serve\u2026 Mais par contre\nremontera la production de 1, ouf. &nbsp;Bon \u00e0\n\u00e9viter\u2026<\/p>\n\n\n\n<p>Mais on produit aussi\u2026 du stress\u2026<\/p>\n\n\n\n<p>Le stress&nbsp;: une piste de 18 cases, \u00e0\nchaque manche on augmente le stress du nombre de joueurs\u2026 Th\u00e9matique peu \u00e0 peu\non se marche sur les pieds et on s\u2019\u00e9nerve\u2026 18 ou plus en stress&nbsp;: on se\ntape dessus\u2026 Le moral global baisse de 1, tout le monde prend une blessure, le\nstress redescend \u00e0 0, une bonne bagarre rien de tel pour d\u00e9tendre l\u2019atmosph\u00e8re\u2026<\/p>\n\n\n\n<p><strong>Actions,\noui on n\u2019est pas l\u00e0 pour trainer au lit, quoique\u2026<\/strong><\/p>\n\n\n\n<p>Chaque joueur a 2 pions action. Ensemble on\nd\u00e9cide o\u00f9 les poser, on programme (on ne r\u00e9sout pas avant que tous les pions\nsoient pos\u00e9s). Il n\u2019y a pas de limite de pion par action et donc du nombre de\nfois o\u00f9 elle est r\u00e9alis\u00e9e par manche.<\/p>\n\n\n\n<p>&#8211; Au bloc d\u2019habitation les actions seront de\ngagner 1 pion moral pour soi (on traine au lit\u2026) ou bien +1 en moral pour\nl\u2019\u00e9quipe (piste) ou baisser de 6 le stress. On pourra se soigner (-1 blessure\nou retrait d\u2019un jeton maladie) et enfin anticiper les d\u00e9faillances. On pose un\nseul pion sur la salle concern\u00e9e (repos, d\u00e9tente, centre m\u00e9dical, centre de\ncontr\u00f4le) et l\u2019action sera r\u00e9ussie lors de la r\u00e9solution. A noter que pour se\nsoigner il faut que le joueur qui joue le m\u00e9decin pose un de ses pions sous le\nv\u00f4tre en soutien, obligatoirement.<\/p>\n\n\n\n<p>&#8211; Au bloc atelier&nbsp;: pour activer un\nmodule et donc avoir une action automatiquement r\u00e9ussie il faut poser ses 2\npions action l\u2019un sur l\u2019autre (on y passe du temps \u00e0 bien faire). Mais un pion\nd\u2019un autre joueur peut remplacer un des v\u00f4tres, il vous soutient. Si un seul\npion est plac\u00e9 il faut jeter 3 d\u00e9s&nbsp;: R\u00e9ussite\/Echec (mais 2 pions moral en\ncadeau de consolation en cas d\u2019\u00e9chec), Aventure\/Rien et Blessure\/Rien. Donc on\npeut \u00e9chouer et gagner 2 pions moral, devoir faire une aventure et \u00eatre bless\u00e9\nen un jet. En cas d\u2019aventure, on regarde ce que l\u2019on a rat\u00e9 et on clique sur le\nbouton ad\u00e9quat de l\u2019App qui nous fournira une jolie histoire avec un co\u00fbt et\ndes incidents \u00e0 g\u00e9rer\u2026<\/p>\n\n\n\n<p>Au bloc atelier on peut explorer Mars&nbsp;:\nCela co\u00fbtera des actions pour se d\u00e9placer sur Mars en plus du\/des pions pour\nl\u2019action \u00ab&nbsp;explorer&nbsp;\u00bb, on r\u00e9v\u00e8lera alors une tuile sur Mars l\u00e0 on\nl\u2019on explore (variable \u00e0 chaque partie), les tuiles peuvent contenir des\n\u00e9chantillons, des \u00ab&nbsp;spots&nbsp;\u00bb surprises (tuiles cadeaux \u00e0 piocher)\nli\u00e9es au sc\u00e9nario g\u00e9n\u00e9ralement, des ennuis\u2026 (r\u00e9gion qui co\u00fbte plus d\u2019action \u00e0\ntraverser, blessure\u2026) et encore d\u2019autres choses d\u00e9pendant du sc\u00e9nario. Il y a 2\nv\u00e9hicules (= pions actions bonus), indispensable pour se balader sur Mars,\nsinon on ne peut pas aller bien loin ou on est oblig\u00e9 de jeter des d\u00e9s ou d\u2019y\naller \u00e0 plusieurs (parfois 5 pions actions sont n\u00e9cessaire)&#8230; Bien s\u00fbr les\nv\u00e9hicules peuvent tomber en panne\u2026&nbsp;\ud83d\ude09<\/p>\n\n\n\n<p>Autre module\/action&nbsp;: aller chercher des\n\u00e9chantillons (d\u00e9couvert lors d\u2019une exploration pr\u00e9c\u00e9dente) et les analyser, \u00e0\nnouveau un v\u00e9hicule sera sans doute n\u00e9cessaire. L\u2019analyse en elle-m\u00eame ne sera\nfaite que dans un second temps car tout ce que l\u2019on ramasse dans une manche\nfini dans la soute \u00ab&nbsp;en instance&nbsp;\u00bb devenant disponible que pour le\ntour suivant.<\/p>\n\n\n\n<p>Module laboratoire&nbsp;: on peut donc faire\nde la recherche, cela n\u00e9cessite deux actions d\u2019analyser un \u00e9chantillon\npr\u00e9c\u00e9demment pr\u00e9lev\u00e9 et pr\u00e9c\u00e9demment explor\u00e9\u2026 Donc de l\u2019exploration \u00e0 la\nd\u00e9couverte se passe au moins 4 actions\u2026 D\u00e9couvrir quoi&nbsp;? Tout d\u00e9pend du\nsc\u00e9nario ou de la campagne. Enfin le laboratoire nous permets aussi de planter\nune graine \u00e0 la ferme (bloc syst\u00e8me) qui mettra 6 manches \u00e0 pousser pour donner\nune source de nourriture si une serre est disponible\u2026 Oui tout cela rajoute\nencore une couche d\u2019action que je ne d\u00e9taille pas, utile ou pas selon le\nsc\u00e9nario.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignright is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/02\/2026-First-Martian-5.png\" alt=\"\" class=\"wp-image-28115\" width=\"660\" height=\"345\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/02\/2026-First-Martian-5.png 880w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/02\/2026-First-Martian-5-300x157.png 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/02\/2026-First-Martian-5-768x401.png 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/02\/2026-First-Martian-5-160x84.png 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/02\/2026-First-Martian-5-469x245.png 469w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/02\/2026-First-Martian-5-650x340.png 650w\" sizes=\"auto, (max-width: 660px) 100vw, 660px\" \/><\/figure><\/div>\n\n\n\n<p>Enfin dernier modules&nbsp;: les r\u00e9parations\/constructions.\nPr\u00e9sent pour tout sc\u00e9nario. Chaque module de chaque bloc a un certain nombre de\nsous-unit\u00e9s de fonctionnement avec un cube vert, s\u2019il y a un p\u00e9pin on remplace\npar un cube rouge (belle id\u00e9e mimant des voyants d\u2019alerte). Dor\u00e9navant pour\nfaire fonctionner le bloc, malus\u2026 Oblig\u00e9 d\u2019utiliser un oxyg\u00e8ne ou \u00e9nergie de la\nr\u00e9serve, oblig\u00e9 de lancer le d\u00e9\u2026 Alors on r\u00e9pare, soit gr\u00e2ce \u00e0 une pi\u00e8ce\nd\u00e9tach\u00e9e qui doit \u00eatre en stock (4 diff\u00e9rentes) soit en utilisant une pi\u00e8ce\nd\u2019un autre module qui sera alors maintenant le module qui a un malus pour son\nutilisation, on d\u00e9monte pour remonter\u2026 Dans ce cas on \u00e9change alors un cube\nvert et rouge entre le modules. C\u2019est tr\u00e8s th\u00e9matique et bien trouv\u00e9. Mais on\nne s\u2019arr\u00eate pas l\u00e0, le module permet de construire, des am\u00e9liorations pour les\ndiff\u00e9rents modules du hub, les rendant plus efficace (ex&nbsp;: un autoscanner\net le centre de soin n\u2019a plus besoin du m\u00e9decin) et toutes ne sont pas\ndisponibles \u00e0 chaque sc\u00e9nario. Ou encore construire de nouveaux b\u00e2timents, tout\ncela d\u00e9pend du sc\u00e9nario\u2026 Encore et toujours\u2026<\/p>\n\n\n\n<p><strong>D\u00e9faillance,\ntout s\u2019use\u2026 un peu plus vite sur Mars.<\/strong><\/p>\n\n\n\n<p>Chaque bloc a une piste d\u00e9faillance. On peut\njeter un d\u00e9 (1-3) pour chaque bloc, les blocs concern\u00e9s d\u00e9pendent du sc\u00e9nario\net on monte sur la piste d\u00e9faillance du bloc de la valeur du d\u00e9. Pire certaines\nsous-unit\u00e9s de modules si elles sont au rouge ajoutent \u00e0 cette phase +1 en\nd\u00e9faillance pour le bloc concern\u00e9. Et&nbsp;? Arriv\u00e9 \u00e0 5 (ce n\u2019est pas beaucoup)\non retourne \u00e0 0 mais on tire une carte d\u00e9faillance, une vacherie pour le bloc\net pour le bloc syst\u00e8me la vie sur mars est vite compromise\u2026 Enfin en arrivant\nsur 5 en plus il se peut que dor\u00e9navant un bloc pour lequel on ne jetait pas encore\nde d\u00e9s doivent subir le jet pour les manches suivantes\u2026 L\u2019effet r\u00e9action en\nchaine module d\u00e9faillant, bloc d\u00e9faillant, nouveau bloc d\u00e9faillant est bien\nsympa.<\/p>\n\n\n\n<p>Enfin on finit la manche par un r\u00e9arrangement\ndu plateau, une phase d\u2019entretien.<\/p>\n\n\n\n<p>Et on tourne comme cela pendant le nombre de\nmanches n\u00e9cessaires, on suit le scenario, on cherche \u00e0 aller au bout de la\nmission en faisant face \u00e0 tout ce qui arrive et j\u2019avoue que ma partie\nd\u00e9couverte m\u2019a grandement donn\u00e9 envie de continuer. M\u00eame si le sc\u00e9nario\nd\u00e9couverte n\u2019est l\u00e0 que pour comprendre le jeu, en lui-m\u00eame il n\u2019a pas beaucoup\nd\u2019int\u00e9r\u00eat et on comprends vite ce qu\u2019il faut faire.<\/p>\n\n\n\n<p>Et je ne vous ai pas tout dit, il y a des\njetons p\u00e9nalit\u00e9 qui surviennent sur les modules et progressent \u00e0 chaque manche,\nil y a d\u2019autres cartes utiles ou non selon les sc\u00e9nario. Donc First Martians\nest un jeu modulaire o\u00f9 chaque sc\u00e9nario \/ campagne promet une exp\u00e9rience\ndiff\u00e9rente et j\u2019avoue que cela titille beaucoup ma curiosit\u00e9. Exploration,\ngestion construction, recherche\u2026 Il y a de quoi faire et chaque scenario nous\nplongera plus dans un type de m\u00e9canisme qu\u2019un autre assurant un bon\nrenouvellement.<\/p>\n\n\n\n<p>Je mets 8 en note, car j\u2019ai aim\u00e9 mais la prise en main est tout de m\u00eame d\u00e9licate et n\u00e9cessite un sc\u00e9nario pour cela, je vais donc devoir attendre ma deuxi\u00e8me partie pour rentrer en plein dans la difficult\u00e9 et donc le plaisir ludique. <\/p>\n\n\n\n<hr class=\"wp-block-separator is-style-wide\"\/>\n\n\n\n<figure class=\"wp-block-image alignfull\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/02\/2026-First-Martian-8-1024x576.jpg\" alt=\"\" class=\"wp-image-28111\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/02\/2026-First-Martian-8-1024x576.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/02\/2026-First-Martian-8-300x169.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/02\/2026-First-Martian-8-768x432.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/02\/2026-First-Martian-8-160x90.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/02\/2026-First-Martian-8-436x245.jpg 436w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/02\/2026-First-Martian-8-604x340.jpg 604w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/02\/2026-First-Martian-8.jpg 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<hr class=\"wp-block-separator is-style-wide\"\/>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"color\" style=\"color:#f78da7\">Vin d&rsquo;jeu d&rsquo;vid\u00e9o<\/span><\/h2>\n\n\n\n<h4 class=\"wp-block-heading\">La bouteille de Chaps en 80 minutes<\/h4>\n\n\n\n<figure class=\"wp-block-embed-youtube wp-block-embed is-type-video is-provider-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"video-container\"><iframe loading=\"lazy\" title=\"First Martians : explication du jeu\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/qS497LS_KkU?feature=oembed&#038;wmode=opaque\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<\/div><\/figure>\n\n\n\n<hr class=\"wp-block-separator is-style-wide\"\/>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"color\" style=\"color:#f78da7\">Vin d&rsquo;jeu d&rsquo;music<\/span><\/h2>\n\n\n\n<figure class=\"wp-block-embed-youtube wp-block-embed is-type-video is-provider-youtube wp-embed-aspect-4-3 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"video-container\"><iframe loading=\"lazy\" title=\"David Bowie \u2013 Space Oddity (Official Video)\" width=\"500\" height=\"375\" src=\"https:\/\/www.youtube.com\/embed\/iYYRH4apXDo?feature=oembed&#038;wmode=opaque\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p> First Martians du bon coop\u2019 mais \u00e0 la prise en main d\u00e9licate, heureusement maintenant en fran\u00e7ais. Je n\u2019ai qu\u2019une partie au compteur et avec un sc\u00e9nario d\u00e9couverte donc peu d\u2019exp\u00e9rience mais l\u2019envie est forte de vite prendre un main un nouveau sc\u00e9nario qui cette fois nous plongera en&#46;&#46;&#46;<\/p>\n","protected":false},"author":3,"featured_media":28112,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[4849],"tags":[1309],"class_list":["post-28110","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-expert","tag-chaps","annee-2083","auteurs-ignacy-trzewiczek","editeurs-edge-entertainment","editeurs-portal-games","distributeurs-asmodee"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/28110","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/comments?post=28110"}],"version-history":[{"count":0,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/28110\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media\/28112"}],"wp:attachment":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media?parent=28110"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/categories?post=28110"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/tags?post=28110"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}