{"id":28808,"date":"2019-04-23T21:52:20","date_gmt":"2019-04-23T19:52:20","guid":{"rendered":"https:\/\/www.vindjeu.eu\/?p=28808"},"modified":"2019-04-23T21:52:50","modified_gmt":"2019-04-23T19:52:50","slug":"great-western-trail-ruee-vers-le-nord","status":"publish","type":"post","link":"https:\/\/www.vindjeu.eu\/prd\/2019\/04\/23\/great-western-trail-ruee-vers-le-nord\/","title":{"rendered":"Great Western Trail: Ru\u00e9e vers le Nord"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/04\/2045-Great-Western-Trail-1.png\" alt=\"\" class=\"wp-image-28810\" width=\"441\" height=\"489\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/04\/2045-Great-Western-Trail-1.png 811w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/04\/2045-Great-Western-Trail-1-270x300.png 270w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/04\/2045-Great-Western-Trail-1-768x852.png 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/04\/2045-Great-Western-Trail-1-144x160.png 144w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/04\/2045-Great-Western-Trail-1-221x245.png 221w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/04\/2045-Great-Western-Trail-1-306x340.png 306w\" sizes=\"auto, (max-width: 441px) 100vw, 441px\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/02\/Swa-26.1.jpg\" alt=\"\" class=\"wp-image-28004\" width=\"193\" height=\"129\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/02\/Swa-26.1.jpg 1020w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/02\/Swa-26.1-300x200.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/02\/Swa-26.1-768x512.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/02\/Swa-26.1-160x107.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/02\/Swa-26.1-368x245.jpg 368w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/02\/Swa-26.1-510x340.jpg 510w\" sizes=\"auto, (max-width: 193px) 100vw, 193px\" \/><\/figure><\/div>\n\n\n\n<h5 class=\"wp-block-heading\"><strong><span class=\"background-color\" style=\"background-color:#cf2e2e\"><span class=\"color\" style=\"color:#eeeeee\">SwatSh: 10\/10<\/span><\/span><\/strong><\/h5>\n\n\n\n<p>Cette extension propose un gros module suppl\u00e9mentaire sous forme\nde nouveau plateau qui vient remplacer la ligne de train du plateau sup\u00e9rieur.\n&nbsp;Dor\u00e9navant, vous allez pouvoir livrer votre b\u00e9tail dans des villes plus\nau Nord que les villes du plateau original.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Le chemin de fer moins attractif<\/strong><\/h3>\n\n\n\n<p>Et vous aurez int\u00e9r\u00eat car les villes du plateau original\ndeviennent beaucoup moins attractives tout \u00e0 coup.&nbsp; Kansas City est encore\nmoins attractive (ses PVs n\u00e9gatifs passent de -6 \u00e0 -8) et les suivantes le sont\nencore moins&nbsp;: Columbia et St. Louis ne rapportent plus de point et si\nvous livrez aux 2 vous perdrez 5 PVs.&nbsp; Idem pour Chicago et D\u00e9troit.&nbsp;\nIl n\u2019y a que si vous arrivez \u00e0 livrer \u00e0 la 6<sup>\u00e8me<\/sup> et 7<sup>\u00e8me<\/sup>\nville (de valeur 12 et 15) que vous pourrez engendrer 4 maigres PVs.&nbsp; La\nderni\u00e8re ville, New York, ne vous rapportera que 3 PVs (6 en plus si vous\nlivrez \u00e0 la ville pr\u00e9c\u00e9dente aussi + un bonus de gare tr\u00e8s int\u00e9ressant tout de\nm\u00eame).&nbsp; <\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Les magasins<\/strong><\/h3>\n\n\n\n<p>Bref, la livraison de b\u00e9tail devient nettement moins\nint\u00e9ressante tout \u00e0 coup&nbsp;!&nbsp; Mais alors l\u00e0, vraiment moins et \u00e7a va\nchambouler vos automatismes. &nbsp;Il ne faut plus vous lancer t\u00eate baiss\u00e9e\ndans la livraison et dans l\u2019avancement de votre locomotive.&nbsp; Non, si vous\nvoulez mieux profiter de vos livraisons, vous allez devoir voyager dans le\nNord.&nbsp; Et pour cela, il vous faudra installer des magasins dans les\ndiff\u00e9rentes villes et villages nordiques.&nbsp; C\u2019est une nouvelle action que\nvous pouvez choisir en tant qu\u2019action secondaire (votre plateau personnel s\u2019est\nagrandi), sur un de vos nouveaux b\u00e2timents et sur certains bonus.\n&nbsp;Attention, placer un magasin n\u00e9cessite de d\u00e9fausser un b\u00e9tail de valeur\n2.&nbsp; Ce n\u2019est donc pas \u00e9vident de pouvoir le faire \u00e0 chaque fois que vous\nen avez l\u2019occasion.&nbsp; Placer un magasin se fait selon certaines r\u00e8gles qui\nvont n\u00e9cessiter d\u2019avoir une sorte de chaine de magasin pour atteindre certaines\nvilles.&nbsp; Une fois ces villes Nordiques atteintes avec vos magasins, vous\npourrez les livrer de b\u00e9tail et \u00e7a vous rapportera gros&nbsp;!&nbsp; Et en\nchemin, vous allez pouvoir r\u00e9colter des bonus int\u00e9ressants.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Qui dit livraisons plus difficiles dit &#8230; plus facile<\/strong><\/h3>\n\n\n\n<p>Et c\u2019est la strat\u00e9gie b\u00e2timents qui s\u2019en voit revaloris\u00e9e.&nbsp; Deux nouveaux b\u00e2timents s\u2019ajoutent \u00e0 votre panel dont un de 25 points.&nbsp; Les b\u00e2timents rapportent plus et les livraisons moins.&nbsp; Voil\u00e0 un nouvel \u00e9quilibrage int\u00e9ressant pour cette p\u00e9pite qu\u2019est <a href=\"https:\/\/www.vindjeu.eu\/2016\/12\/28\/great-western-trail-video\/\"><strong>Great Western Trail<\/strong><\/a>. <\/p>\n\n\n\n<hr class=\"wp-block-separator is-style-wide\"\/>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2016\/10\/Phil-2-e1477137058207-681x1024.jpg\" alt=\"\" class=\"wp-image-15196\" width=\"127\" height=\"191\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2016\/10\/Phil-2-e1477137058207-681x1024.jpg 681w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2016\/10\/Phil-2-e1477137058207-200x300.jpg 200w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2016\/10\/Phil-2-e1477137058207-768x1154.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2016\/10\/Phil-2-e1477137058207-106x160.jpg 106w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2016\/10\/Phil-2-e1477137058207-163x245.jpg 163w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2016\/10\/Phil-2-e1477137058207-226x340.jpg 226w\" sizes=\"auto, (max-width: 127px) 100vw, 127px\" \/><\/figure><\/div>\n\n\n\n<h5 class=\"wp-block-heading\"><strong><span class=\"background-color\" style=\"background-color:#cf2e2e\"><span class=\"color\" style=\"color:#eeeeee\">SwatSh: 9,5\/10<\/span><\/span><\/strong><\/h5>\n\n\n\n<p>La \u00ab\u00a0Ru\u00e9e vers le Nord\u00a0\u00bb ne modifie pas du tout les m\u00e9caniques du jeu de base. Et c&rsquo;est bien comme \u00e7a, je pense.<\/p>\n\n\n\n<p>L&rsquo;ajout principal consiste \u00e0 \u00e9tendre\/modifier la ligne de chemin de fer: des PVs diff\u00e9rents, de nouvelles lignes vers le nord, des PVs n\u00e9gatifs m\u00eame. Bref, cela modifie peut-\u00eatre la \u00ab\u00a0course\u00a0\u00bb \u00e0 la livraison. <\/p>\n\n\n\n<p>Les villes du nord offrent divers b\u00e9n\u00e9fices: des PVs (souvent les plus \u00e9loign\u00e9es), des sous (toujours bienvenus), des jetons bonus (pas toujours utiles)<\/p>\n\n\n\n<p>L&rsquo;extension n&rsquo;enl\u00e8ve pas la frustration qu&rsquo;on peut avoir avec la fin soudaine de la partie. En effet, si la fin a lieu quand vous \u00eates \u00e0 mi-chemin de Kansas City, vous n&rsquo;aurez pas l&rsquo;occasion d&rsquo;y arriver et de faire une livraison probablement pr\u00e9vue\/planifi\u00e9e. Ce qui aura un impact certain sur le d\u00e9compte final.<br>L&rsquo;extension n&rsquo;enl\u00e8ve pas non plus la part de hasard assez pr\u00e9sente lors de l&rsquo;apparition des tuiles \u00ab\u00a0ouvriers\u00a0\u00bb et autres.<\/p>\n\n\n\n<p>Par contre, \u00ab\u00a0La Ru\u00e9e vers le Nord\u00a0\u00bb offre une nouvelle dimension avec les magasins. S&rsquo;\u00e9tendre vers le Nord peut faire partie de votre strat\u00e9gie, elle le sera certainement. Reste \u00e0 bien d\u00e9terminer quand et comment, et quoi mettre en place pour y arriver. Bref, une belle surprise que cette extension, que je recommande vivement pour varier vos strat\u00e9gies!<\/p>\n\n\n\n<p><\/p>\n\n\n\n<hr class=\"wp-block-separator is-style-wide\"\/>\n\n\n\n<figure class=\"wp-block-image alignfull\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/04\/2045-Great-Western-Trail-8-1024x683.jpg\" alt=\"\" class=\"wp-image-28809\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/04\/2045-Great-Western-Trail-8-1024x683.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/04\/2045-Great-Western-Trail-8-300x200.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/04\/2045-Great-Western-Trail-8-768x512.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/04\/2045-Great-Western-Trail-8-160x107.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/04\/2045-Great-Western-Trail-8-368x245.jpg 368w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/04\/2045-Great-Western-Trail-8-510x340.jpg 510w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/04\/2045-Great-Western-Trail-8.jpg 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p> Cette extension propose un gros module suppl\u00e9mentaire sous forme de nouveau plateau qui vient remplacer la ligne de train du plateau sup\u00e9rieur. &nbsp;Dor\u00e9navant, vous allez pouvoir livrer votre b\u00e9tail dans des villes plus au Nord que les villes du plateau original. Le chemin de fer moins attractif Et&#46;&#46;&#46;<\/p>\n","protected":false},"author":3,"featured_media":28810,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[4849],"tags":[6,7],"class_list":["post-28808","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-expert","tag-philrey212","tag-swatsh","annee-1616","auteurs-alexander-pfister","editeurs-eggertspiele","illustrateurs-andreas-resch","distributeurs-asmodee"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/28808","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/comments?post=28808"}],"version-history":[{"count":0,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/28808\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media\/28810"}],"wp:attachment":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media?parent=28808"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/categories?post=28808"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/tags?post=28808"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}