{"id":28909,"date":"2019-04-24T09:13:58","date_gmt":"2019-04-24T07:13:58","guid":{"rendered":"https:\/\/www.vindjeu.eu\/?p=28909"},"modified":"2019-04-24T09:24:30","modified_gmt":"2019-04-24T07:24:30","slug":"a-la-gloire-dodin-les-norvegiens","status":"publish","type":"post","link":"https:\/\/www.vindjeu.eu\/prd\/2019\/04\/24\/a-la-gloire-dodin-les-norvegiens\/","title":{"rendered":"A la Gloire d&rsquo;Odin: Les Norv\u00e9giens"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft\"><img loading=\"lazy\" decoding=\"async\" width=\"331\" height=\"453\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/04\/2059-Odin-1.png\" alt=\"\" class=\"wp-image-28911\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/04\/2059-Odin-1.png 331w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/04\/2059-Odin-1-219x300.png 219w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/04\/2059-Odin-1-117x160.png 117w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/04\/2059-Odin-1-179x245.png 179w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/04\/2059-Odin-1-248x340.png 248w\" sizes=\"auto, (max-width: 331px) 100vw, 331px\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/04\/Swa-26.2-1024x683.jpg\" alt=\"\" class=\"wp-image-28823\" width=\"179\" height=\"120\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/04\/Swa-26.2-1024x683.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/04\/Swa-26.2-300x200.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/04\/Swa-26.2-768x512.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/04\/Swa-26.2-160x107.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/04\/Swa-26.2-368x245.jpg 368w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/04\/Swa-26.2-510x340.jpg 510w\" sizes=\"auto, (max-width: 179px) 100vw, 179px\" \/><\/figure><\/div>\n\n\n\n<h5 class=\"wp-block-heading\"><strong><span class=\"color\" style=\"color:#eeeeee\"><span class=\"background-color\" style=\"background-color:#cf2e2e\">SwatSh:&nbsp; 10\/10<\/span><\/span><\/strong><\/h5>\n\n\n\n<p>Ce qui est comique avec Les Norv\u00e9giens, cette premi\u00e8re extension d\u2019<a href=\"SwatSh:  10\/10 Ce qui est comique avec Les Norv\u00e9giens, cette premi\u00e8re extension d\u2019A la Gloire d\u2019Odin, c\u2019est que les Norv\u00e9giens, \u00e0 l\u2019exception du fait qu\u2019ils soient des vikings, n\u2019ont rien \u00e0 voir avec cette extension!!! Difficile d\u2019expliquer en long et en large ce que comprend cette extension mais je pr\u00e9f\u00e8re la r\u00e9sum\u00e9 en un mot : \u00e9quilibrage !  Apr\u00e8s le retour des joueurs et des milliers voire des millions de parties r\u00e9alis\u00e9es, Uwe et consorts se sont rendus compte de l\u00e9gers d\u00e9s\u00e9quilibres dans le jeu : -\tLe plateau des actions a \u00e9t\u00e9 revu et certaines actions ont \u00e9t\u00e9 l\u00e9g\u00e8rement modifi\u00e9es.  De plus, une cinqui\u00e8me colonne voit le jour : \u00ab la derni\u00e8re action \u00bb.  On peut y placer un ou 2 meeples.  G\u00e9n\u00e9ralement les actions de cette colonne sont assez puissantes.  Mais y placer un ouvrier doit \u00eatre notre derni\u00e8re action du tour.  Cette colonne donne un petit avantage aux joueuses qui terminent plus t\u00f4t leur tour au d\u00e9triment de la derni\u00e8re qui recevra l\u2019\u00e9lan premi\u00e8re joueuse en compensation. -\tLes plateaux \u00eele ont \u00e9t\u00e9 revus.  De plus, 4 nouvelles \u00eeles ont \u00e9t\u00e9 ajout\u00e9es. -\tQuelques nouvelles ressources voient le jour  -\tLa strat\u00e9gie \u00ab animale \u00bb se voit renforc\u00e9e gr\u00e2ce \u00e0 2 nouveaux types d\u2019animaux \u00e0 \u00e9lever : les cochons qui se reproduisent \u00e0 chaque tour et les chevaux qui valent 6 PVs chacun (ils sont tr\u00e8s int\u00e9ressants ces chevaux).  De plus, une case action permet d\u2019acqu\u00e9rir en une seule fois 2 animaux de la m\u00eame esp\u00e8ce afin de pouvoir se lancer directement dans la reproduction :-) -\tLes Norv\u00e9giens apportent \u00e9galement une petite asym\u00e9trie en permettant \u00e0 chaque joueur de construire une cabane unique apportant un revenu suppl\u00e9mentaire sp\u00e9cifique si on la construit. A la Gloire d\u2019Odin est d\u00e9j\u00e0 un jeu bien complexe.  J\u2019\u00e9tais donc assez r\u00e9ticent \u00e0 acheter cette nouvelle extension tant le jeu de base se suffit \u00e0 lui-m\u00eame.  Mais en fait non ;-)  Les Norv\u00e9giens sont indispensables au jeu de base tant ils le compl\u00e8tent bien en r\u00e9\u00e9quilibrant mieux les diff\u00e9rentes strat\u00e9gies possibles sans le complexifier plus pour autant.  Vivement les Su\u00e9dois :-)\"><strong>A la Gloire d\u2019Odin<\/strong><\/a>, c\u2019est que les Norv\u00e9giens, \u00e0 l\u2019exception du fait qu\u2019ils soient des vikings et que certaines \u00eeles vikings sont Norv\u00e9giennes donc \ud83d\ude09 ,\u00a0n\u2019ont rien \u00e0 voir avec cette extension!!!<\/p>\n\n\n\n<p>Difficile d\u2019expliquer en long et en large ce que comprend cette extension mais je pr\u00e9f\u00e8re la r\u00e9sumer en un mot\u00a0: <strong>\u00e9quilibrage<\/strong>\u00a0!\u00a0 Apr\u00e8s le retour des joueurs et des milliers voire des millions de parties r\u00e9alis\u00e9es par ceux-ci, <a href=\"https:\/\/www.vindjeu.eu\/auteurs\/uwe-rosenberg\/\"><strong>Uwe <\/strong><\/a>et consorts se sont rendus compte de l\u00e9gers d\u00e9s\u00e9quilibres dans le jeu\u00a0:<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Le plateau des actions a \u00e9t\u00e9 revu et certaines actions ont \u00e9t\u00e9 l\u00e9g\u00e8rement modifi\u00e9es.  De plus, une cinqui\u00e8me colonne voit le jour&nbsp;: \u00ab&nbsp;la derni\u00e8re action&nbsp;\u00bb.&nbsp; On peut y placer un ou 2 meeples.  G\u00e9n\u00e9ralement les actions de cette colonne sont assez puissantes.&nbsp; Mais y placer un ouvrier doit \u00eatre notre derni\u00e8re action du tour.&nbsp; Cette colonne donne un petit avantage aux joueuses qui terminent plus t\u00f4t leur tour au d\u00e9triment de la derni\u00e8re qui recevra l\u2019\u00e9lan premi\u00e8re joueuse en compensation.<\/li><li>Les plateaux \u00eele ont \u00e9t\u00e9 revus.&nbsp; De plus, 4 nouvelles \u00eeles ont \u00e9t\u00e9 ajout\u00e9es.<\/li><li>Quelques nouvelles ressources voient le jour <\/li><li>La strat\u00e9gie \u00ab&nbsp;animale&nbsp;\u00bb se voit renforc\u00e9e gr\u00e2ce \u00e0 2 nouveaux types d\u2019animaux \u00e0 \u00e9lever&nbsp;: les cochons qui se reproduisent \u00e0 chaque tour et les chevaux qui valent 6 PVs chacun (ils sont tr\u00e8s int\u00e9ressants ces chevaux).&nbsp; De plus, une case action permet d\u2019acqu\u00e9rir en une seule fois 2 animaux de la m\u00eame esp\u00e8ce afin de pouvoir se lancer directement dans la reproduction&nbsp;\ud83d\ude42<\/li><li>Les Norv\u00e9giens apportent \u00e9galement une petite asym\u00e9trie en permettant \u00e0 chaque joueur de construire une cabane unique apportant un revenu suppl\u00e9mentaire sp\u00e9cifique si on la construit.<\/li><\/ul>\n\n\n\n<p><strong><a href=\"SwatSh:  10\/10 Ce qui est comique avec Les Norv\u00e9giens, cette premi\u00e8re extension d\u2019A la Gloire d\u2019Odin, c\u2019est que les Norv\u00e9giens, \u00e0 l\u2019exception du fait qu\u2019ils soient des vikings, n\u2019ont rien \u00e0 voir avec cette extension!!! Difficile d\u2019expliquer en long et en large ce que comprend cette extension mais je pr\u00e9f\u00e8re la r\u00e9sum\u00e9 en un mot : \u00e9quilibrage !  Apr\u00e8s le retour des joueurs et des milliers voire des millions de parties r\u00e9alis\u00e9es, Uwe et consorts se sont rendus compte de l\u00e9gers d\u00e9s\u00e9quilibres dans le jeu : -&#9;Le plateau des actions a \u00e9t\u00e9 revu et certaines actions ont \u00e9t\u00e9 l\u00e9g\u00e8rement modifi\u00e9es.  De plus, une cinqui\u00e8me colonne voit le jour : \u00ab la derni\u00e8re action \u00bb.  On peut y placer un ou 2 meeples.  G\u00e9n\u00e9ralement les actions de cette colonne sont assez puissantes.  Mais y placer un ouvrier doit \u00eatre notre derni\u00e8re action du tour.  Cette colonne donne un petit avantage aux joueuses qui terminent plus t\u00f4t leur tour au d\u00e9triment de la derni\u00e8re qui recevra l\u2019\u00e9lan premi\u00e8re joueuse en compensation. -&#9;Les plateaux \u00eele ont \u00e9t\u00e9 revus.  De plus, 4 nouvelles \u00eeles ont \u00e9t\u00e9 ajout\u00e9es. -&#9;Quelques nouvelles ressources voient le jour  -&#9;La strat\u00e9gie \u00ab animale \u00bb se voit renforc\u00e9e gr\u00e2ce \u00e0 2 nouveaux types d\u2019animaux \u00e0 \u00e9lever : les cochons qui se reproduisent \u00e0 chaque tour et les chevaux qui valent 6 PVs chacun (ils sont tr\u00e8s int\u00e9ressants ces chevaux).  De plus, une case action permet d\u2019acqu\u00e9rir en une seule fois 2 animaux de la m\u00eame esp\u00e8ce afin de pouvoir se lancer directement dans la reproduction :-) -&#9;Les Norv\u00e9giens apportent \u00e9galement une petite asym\u00e9trie en permettant \u00e0 chaque joueur de construire une cabane unique apportant un revenu suppl\u00e9mentaire sp\u00e9cifique si on la construit. A la Gloire d\u2019Odin est d\u00e9j\u00e0 un jeu bien complexe.  J\u2019\u00e9tais donc assez r\u00e9ticent \u00e0 acheter cette nouvelle extension tant le jeu de base se suffit \u00e0 lui-m\u00eame.  Mais en fait non ;-)  Les Norv\u00e9giens sont indispensables au jeu de base tant ils le compl\u00e8tent bien en r\u00e9\u00e9quilibrant mieux les diff\u00e9rentes strat\u00e9gies possibles sans le complexifier plus pour autant.  Vivement les Su\u00e9dois :-)\">A la Gloire d\u2019Odin<\/a><\/strong> est d\u00e9j\u00e0 un jeu bien complexe. &nbsp;J\u2019\u00e9tais donc assez r\u00e9ticent \u00e0 acheter cette nouvelle extension tant le jeu de base se suffit \u00e0 lui-m\u00eame.&nbsp; Mais en fait non&nbsp;\ud83d\ude09&nbsp; Les Norv\u00e9giens sont indispensables au jeu de base tant ils le compl\u00e8tent bien en r\u00e9\u00e9quilibrant mieux les diff\u00e9rentes strat\u00e9gies possibles sans le complexifier plus pour autant.  Vivement les Su\u00e9dois&nbsp;\ud83d\ude42 <\/p>\n\n\n\n<hr class=\"wp-block-separator is-style-wide\"\/>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2015\/01\/Ren-11-1024x683.jpg\" alt=\"\" class=\"wp-image-22962\" width=\"214\" height=\"143\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2015\/01\/Ren-11-1024x683.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2015\/01\/Ren-11-300x200.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2015\/01\/Ren-11-768x512.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2015\/01\/Ren-11-160x107.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2015\/01\/Ren-11-368x245.jpg 368w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2015\/01\/Ren-11-510x340.jpg 510w\" sizes=\"auto, (max-width: 214px) 100vw, 214px\" \/><\/figure><\/div>\n\n\n\n<p><span class=\"background-color\" style=\"background-color:#cf2e2e\"><span class=\"color\" style=\"color:#eeeeee\"><strong>Ren:&nbsp; 9\/10<\/strong><\/span><\/span><\/p>\n\n\n\n<p>Premi\u00e8re extension pour le gargantuesque A la Gloire d\u2019Odin. Elle ajoute certes des nouvelles \u00eeles et une cabane personnelle qui sera propre \u00e0 chaque joueuse. Plus quelques nouvelles ressources et de nouveaux animaux.<br>Mais son m\u00e9rite principal est ailleurs&nbsp;: le plateau principal, avec les 63 actions, a \u00e9t\u00e9 l\u00e9g\u00e8rement modifi\u00e9 pour rendre certaines actions plus ou moins puissantes. Il est vrai que vu le nombre monumental d\u2019actions disponibles il \u00e9tait probablement difficile d\u2019avoir un \u00e9quilibre au cordeau apr\u00e8s \u00ab&nbsp;seulement&nbsp;\u00bb quelques dizaines (voire m\u00eame centaines) de parties de tests. Ensuite une colonne suppl\u00e9mentaire a \u00e9t\u00e9 ajout\u00e9e, ce qui ajoute de facto encore plus de choix (si si c\u2019\u00e9tait possible). Sachant qu\u2019une action de cette colonne doit toujours \u00eatre jou\u00e9e en dernier dans son tour. Mais sachant aussi que les actions de cette colonne sont plut\u00f4t tr\u00e8s int\u00e9ressantes. Donc dilemme&nbsp;: finir ou pas finir son tour rapidement pour b\u00e9n\u00e9ficier d\u2019une action maousse costo, that is the question\u2026<\/p>\n\n\n\n<p>Encore plus de choix, encore plus de\nbr\u00fblage de neurones, bienvenue aux Norv\u00e9giens&nbsp;!<\/p>\n\n\n\n<hr class=\"wp-block-separator is-style-wide\"\/>\n\n\n\n<figure class=\"wp-block-image alignfull\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/04\/2059-Odin-8.jpg\" alt=\"\" class=\"wp-image-28910\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/04\/2059-Odin-8.jpg 1200w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/04\/2059-Odin-8-300x200.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/04\/2059-Odin-8-768x512.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/04\/2059-Odin-8-1024x683.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/04\/2059-Odin-8-160x107.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/04\/2059-Odin-8-368x245.jpg 368w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/04\/2059-Odin-8-510x340.jpg 510w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p> Ce qui est comique avec Les Norv\u00e9giens, cette premi\u00e8re extension d\u2019A la Gloire d\u2019Odin, c\u2019est que les Norv\u00e9giens, \u00e0 l\u2019exception du fait qu\u2019ils soient des vikings et que certaines \u00eeles vikings sont Norv\u00e9giennes donc \ud83d\ude09 ,\u00a0n\u2019ont rien \u00e0 voir avec cette extension!!! Difficile d\u2019expliquer en long et en&#46;&#46;&#46;<\/p>\n","protected":false},"author":3,"featured_media":28911,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[4849],"tags":[323,7],"class_list":["post-28909","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-expert","tag-ren","tag-swatsh","annee-1616","auteurs-gernot-kopke","auteurs-uwe-rosenberg","editeurs-z-man-games","illustrateurs-dennis-lohausen","distributeurs-asmodee"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/28909","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/comments?post=28909"}],"version-history":[{"count":0,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/28909\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media\/28911"}],"wp:attachment":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media?parent=28909"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/categories?post=28909"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/tags?post=28909"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}