{"id":30457,"date":"2019-08-23T08:19:11","date_gmt":"2019-08-23T06:19:11","guid":{"rendered":"https:\/\/www.vindjeu.eu\/?p=30457"},"modified":"2019-08-23T12:24:04","modified_gmt":"2019-08-23T10:24:04","slug":"gangsta","status":"publish","type":"post","link":"https:\/\/www.vindjeu.eu\/prd\/2019\/08\/23\/gangsta\/","title":{"rendered":"Gangsta"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft\"><img loading=\"lazy\" decoding=\"async\" width=\"256\" height=\"480\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/07\/2130-Gangsta-1.2.jpg\" alt=\"\" class=\"wp-image-30460\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/07\/2130-Gangsta-1.2.jpg 256w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/07\/2130-Gangsta-1.2-160x300.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/07\/2130-Gangsta-1.2-85x160.jpg 85w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/07\/2130-Gangsta-1.2-131x245.jpg 131w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/07\/2130-Gangsta-1.2-181x340.jpg 181w\" sizes=\"auto, (max-width: 256px) 100vw, 256px\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft\"><img decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/07\/Serval-150x150.jpg\" alt=\"\" class=\"wp-image-30463\"\/><\/figure><\/div>\n\n\n\n<h5 class=\"wp-block-heading\"><span class=\"color\" style=\"color:#0693e3\">Serval: <\/span><span class=\"color\" style=\"color:#cf2e2e\">8\/10<\/span><\/h5>\n\n\n\n<p><strong><a href=\"https:\/\/www.kickstarter.com\/projects\/1316370263\/gangsta?ref=ksr_email_creator_launch\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\"La campagne de financement participatif de Gangsta (opens in a new tab)\">La campagne de financement participatif de Gangsta<\/a><\/strong> se lance aujourd&rsquo;hui (<strong><a aria-label=\"cliquez ici (opens in a new tab)\" rel=\"noreferrer noopener\" href=\"https:\/\/www.kickstarter.com\/projects\/1316370263\/gangsta?ref=ksr_email_creator_launch\" target=\"_blank\">cliquez ici<\/a><\/strong>).  Nous avons eu la chance de pouvoir y jouer et voici de quoi il en retourne. <\/p>\n\n\n\n<p>Voici le tout premier jeu de la maison Schmeta Games. Yves Rosenblaum et Fred Navez sont les principaux responsables de ce forfait.<br>Dans Gangsta! vous incarnez une belle borchette de truands pr\u00eats \u00e0 tout pour r\u00e9gner sur la p\u00e8gre locale et son mach\u00e9 noir \u00f4 combien juteux. <br>Gangsta! se joue de deux \u00e0 quatre joueurs et se d\u00e9roule en 3 Chapitres (3 grandes \u00e9tapes du jeu). <br>Au d\u00e9but du jeu, \u00e0 &nbsp;disposition de chaque joueur une unique carte Boss , un gangster typ\u00e9 leader. qu&rsquo;il pose face visible sur sa zone de jeu Sont dispos\u00e9es deux rang\u00e9es de 5 cartes et leur pioche respectives.<br>La premi\u00e8re est constitu\u00e9e de cartes Casse (Chapitre 1,2 et 3) cibles des attaques de gangster (on commencera donc par le paquet chapitre 1).<br>La deuxi\u00e8me repr\u00e9sente la manne de gangsters que chaque joueur pourra recruter.<br>Pendant la dur\u00e9e de chaque chapitre, chaque joueur \u00e0 tour de r\u00f4le va effectuer 2 phases de jeu, la mobilisation et un tour d&rsquo;actions.<\/p>\n\n\n\n<p> <strong>La mobilisation :<\/strong> c&rsquo;est \u00e0 ce moment l\u00e0 que notre gang se pr\u00e9pare pour planifier le futur casse.&nbsp; La m\u00e9canique est plut\u00f4t simple : <br> &#8211; Il convient de rendre disponible nos cartes gangsters , on retrouve ici la notion bien connue d&rsquo;engagement (rotation de la carte \u00e0 90\u00b0) et de d\u00e9gagement.<br> Pour ce faire , sur chaque carte gangster , figure une s\u00e9rie d\u2019ic\u00f4nes repr\u00e9sentant autant de capacit\u00e9. L&rsquo;une d&rsquo;entre elles, \u00ab\u00a0Leader\u00a0\u00bb (dont le boss est pourvu par d\u00e9faut) &nbsp;permet \u00e0 cette phase de jeu, de rendre disponible n&rsquo;importe quel autre gangster alors d\u00e9j\u00e0 engag\u00e9 (lors d&rsquo;un pr\u00e9c\u00e9dent casse) \u00e0 condition que ce \u00ab\u00a0leader\u00a0\u00bb soit lui m\u00eame disponible.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignright\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"401\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/07\/2130-Gangsta-2.jpg\" alt=\"\" class=\"wp-image-30464\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/07\/2130-Gangsta-2.jpg 500w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/07\/2130-Gangsta-2-300x241.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/07\/2130-Gangsta-2-160x128.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/07\/2130-Gangsta-2-305x245.jpg 305w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/07\/2130-Gangsta-2-424x340.jpg 424w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/figure><\/div>\n\n\n\n<p>Si aucun de nos gangster n&rsquo;a cette capacit\u00e9 , il est toujours possible, pour 1$ par gangster engag\u00e9 de les rendre disponible.<br> Il existe cependant une situation parfaite pour rendre disponible l&rsquo;int\u00e9gralit\u00e9 de notre gang gratuitement ; que ceux-ci soit tous engag\u00e9s au d\u00e9but de cette phase, la \u00ab\u00a0synchronisation\u00a0\u00bb est alors activ\u00e9e, tous nos truands se retrouvent fin pr\u00eat pour le prochain casse !<br><\/p>\n\n\n\n<p><strong>Le tour d&rsquo;action <\/strong>: apr\u00e8s la mobilisation, un joueur peut effectuer une action parmi trois :<br> &#8211; Recruter un gangster : son co\u00fbt se situe en haut \u00e0 gauche de la carte et vient rejoindre imm\u00e9diatement votre gang. &#8211; R\u00e9aliser un casse : si l\u2019int\u00e9gralit\u00e9 des ic\u00f4nes pr\u00e9sentes sur une carte casse est repr\u00e9sent\u00e9e sur une ou plusieurs cartes membres de votre gang, le joueur peut d\u00e9signer le carte casse correspondante et passer \u00e0 l&rsquo;offensive. Il convient alors de d\u00e9signer dans un ordre pr\u00e9cis <br> (certaines r\u00e8gles d&rsquo;engagement contraignent le joueur) quel(s) &nbsp;gangster(s) le joueur engage pour r\u00e9ussir ce casse.<br> Attention, pour optimiser le casse, le joueur \u00e0 tout int\u00e9r\u00eat \u00e0 engager l&rsquo;int\u00e9gralit\u00e9 de ses gangsters pour permettre \u00e0 la prochaine mobilisation de b\u00e9n\u00e9ficier de la fameuse \u00ab\u00a0synchronisation\u00a0\u00bb rendant gratuite \u00e0 la disponibilit\u00e9 de l&rsquo;int\u00e9gralit\u00e9 de votre gang.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"301\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/07\/2130-Gangsta-3.jpg\" alt=\"\" class=\"wp-image-30465\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/07\/2130-Gangsta-3.jpg 500w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/07\/2130-Gangsta-3-300x181.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/07\/2130-Gangsta-3-160x96.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/07\/2130-Gangsta-3-407x245.jpg 407w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/figure><\/div>\n\n\n\n<p>Chaque casse rapporte bien sur une fois r\u00e9solu, &nbsp;diff\u00e9rentes r\u00e9compenses : points d&rsquo;influence, &nbsp;argent, comp\u00e9tence suppl\u00e9mentaire, assassinat, etc&#8230;<br> A noter et c&rsquo;est plut\u00f4t bien trouv\u00e9, un casse peut se r\u00e9aliser en coop\u00e9ration (si cette carte casse le permet). Dans ce cas , le joueur actif engage au moins l&rsquo;un de ses gangster et peut engager les gangsters de ses adversaires pour r\u00e9aliser la combinaison d\u2019ic\u00f4nes n\u00e9cessaires pour la r\u00e9solution du casse.<br> Les r\u00e9compenses seront alors partag\u00e9es, toutefois \u00e0 l&rsquo;avantage du joueur actif. <br> Bien sur, plus le joueur engage de gangsters chez l&rsquo;adversaire, plus ces derniers auront des difficult\u00e9s \u00e0 r\u00e9aliser leur prochaine phase &nbsp;de \u00ab\u00a0Mobilisation\u00a0\u00bb.<br> &#8211; L\u2019ultime action possible est \u00ab\u00a0passer\u00a0\u00bb, un joueur r\u00e9cup\u00e9rant ainsi 1 $ par carte gangster leader pr\u00e9sent dans sa zone de jeu.<br><br><strong>Les chapitres :<\/strong><br> Le jeux se d\u00e9roule ainsi jusqu&rsquo;\u00e0 la fin du premier chapitre : le premier \u00e0 recruter un quatri\u00e8me gangster met fin \u00e0 cette premi\u00e8re manche. A lieu alors le revenu d&rsquo;opportunit\u00e9, permettant au joueur ayant le moins d&rsquo;icone sur ces cartes gangster de r\u00e9cup\u00e9rer un peu d&rsquo;argent.<br> Les cartes casse du chapitre 1 sont toutes d\u00e9fauss\u00e9es et remplac\u00e9es par les cartes du chapitre 2.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignright\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/07\/2130-Gangsta-4.jpg\" alt=\"\" class=\"wp-image-30466\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/07\/2130-Gangsta-4.jpg 500w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/07\/2130-Gangsta-4-150x150.jpg 150w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/07\/2130-Gangsta-4-300x300.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/07\/2130-Gangsta-4-160x160.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/07\/2130-Gangsta-4-245x245.jpg 245w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/07\/2130-Gangsta-4-340x340.jpg 340w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/figure><\/div>\n\n\n\n<p>La partie continue sous le m\u00eame mode jusqu&rsquo;\u00e0 la fin du chapitre 2 , la guerre des gangs, ou cette fois le 7 \u00e8me gangster recrut\u00e9 par un joueur met un terme \u00e0 ce chapitre, une confrontation \u00e0 lieu entre chaque adverse, le joueur ayant le plus d\u2019ic\u00f4nes \u00ab\u00a0mercenaires\u00a0\u00bb fait d\u00e9fausser une carte gangster aux autres.<br> Dernier chapitre (Domination) , le 9\u00e8me gangster recrut\u00e9 me fin \u00e0 la partie.Un d\u00e9compte final \u00e0 lieu \u00a0:point d&rsquo;influence des casses, point d&rsquo;influence des gangsters recrut\u00e9s, bonus pour le plus riche et le plus pourvu de gangster.<br> A noter, dans le chapitre 2 et 3, des cartes d\u00e9lateur apparaissent , mieux vaut \u00eatre pr\u00eat \u00e0 avoir quelques flics pourris dans notre gang !<br><br> En bonus ;\u00a0 deux variantes que nous avons inclues dans notre partie sont propos\u00e9es : Famille (ajout de notion de majorit\u00e9 sur les familles de gangster) et Carte ressource (Un avantage permanent \u00e0 d\u00e9bloquer).<br><br> Gangsta! est une vraie r\u00e9ussite, le jeu impose un rythme assez soutenu et nerveux , m\u00ealant combinaison et opportunit\u00e9, j&rsquo;aime tout particuli\u00e8rement la m\u00e9canique de casse coop\u00e9ratif pour le c\u00f4t\u00e9 salement opportuniste. Les variantes me semblent vraiment indispensables pour goutter pleinement \u00e0 Gangsta !<br> La notion de Chapitre apporte un vrai plus au rendu du th\u00e8me ma fois loin d&rsquo;\u00eatre plaqu\u00e9 ! Expliqu\u00e9 en 10 mn, dot\u00e9 d&rsquo;un graphisme abouti, \u00a0du plaisir \u00e0 2 ou 3 ou 4 \u00a0joueurs, pourquoi s&rsquo;en priver ?  <\/p>\n\n\n\n<hr class=\"wp-block-separator is-style-wide\"\/>\n\n\n\n<p><strong><a href=\"https:\/\/www.kickstarter.com\/projects\/1316370263\/gangsta?ref=ksr_email_creator_launch\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\"Lien vers la campagne de financement (opens in a new tab)\">Lien vers la campagne de financement<\/a><\/strong><\/p>\n\n\n\n<hr class=\"wp-block-separator is-style-wide\"\/>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/07\/2130-Gangsta-8.jpg\" alt=\"\" class=\"wp-image-30459\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/07\/2130-Gangsta-8.jpg 500w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/07\/2130-Gangsta-8-150x150.jpg 150w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/07\/2130-Gangsta-8-300x300.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/07\/2130-Gangsta-8-160x160.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/07\/2130-Gangsta-8-245x245.jpg 245w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/07\/2130-Gangsta-8-340x340.jpg 340w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/figure><\/div>\n\n\n\n<hr class=\"wp-block-separator is-style-wide\"\/>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/07\/2130-Gangsta-9-1024x815.jpg\" alt=\"\" class=\"wp-image-30458\" width=\"768\" height=\"611\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/07\/2130-Gangsta-9-1024x815.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/07\/2130-Gangsta-9-300x239.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/07\/2130-Gangsta-9-768x612.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/07\/2130-Gangsta-9-160x127.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/07\/2130-Gangsta-9-308x245.jpg 308w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/07\/2130-Gangsta-9-427x340.jpg 427w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/07\/2130-Gangsta-9.jpg 1100w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure><\/div>\n\n\n\n<p style=\"text-align:center\"><em> Maranges 2017 vieilles vignes , Domaine Charleux et fils.  Un vin comme je les aime, chaleureux et doucement tanique.  <\/em><\/p>\n\n\n\n<figure class=\"wp-block-embed-youtube wp-block-embed is-type-video is-provider-youtube wp-embed-aspect-4-3 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"video-container\"><iframe loading=\"lazy\" title=\"Coolio - Gangsta&#039;s Paradise (feat. L.V.) [Official Music Video]\" width=\"500\" height=\"375\" src=\"https:\/\/www.youtube.com\/embed\/fPO76Jlnz6c?feature=oembed&#038;wmode=opaque\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p> La campagne de financement participatif de Gangsta se lance aujourd&rsquo;hui (cliquez ici). Nous avons eu la chance de pouvoir y jouer et voici de quoi il en retourne. Voici le tout premier jeu de la maison Schmeta Games. Yves Rosenblaum et Fred Navez sont les principaux responsables de&#46;&#46;&#46;<\/p>\n","protected":false},"author":3,"featured_media":30460,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[4848],"tags":[2460],"class_list":["post-30457","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-initie","tag-serval","annee-2083","auteurs-yves-rosenbaum","editeurs-schemeta-games","illustrateurs-fred-navez","nombre_conseille-1210"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/30457","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/comments?post=30457"}],"version-history":[{"count":0,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/30457\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media\/30460"}],"wp:attachment":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media?parent=30457"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/categories?post=30457"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/tags?post=30457"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}