{"id":30691,"date":"2019-08-31T17:41:43","date_gmt":"2019-08-31T15:41:43","guid":{"rendered":"https:\/\/www.vindjeu.eu\/?p=30691"},"modified":"2019-08-31T18:18:51","modified_gmt":"2019-08-31T16:18:51","slug":"little-town","status":"publish","type":"post","link":"https:\/\/www.vindjeu.eu\/prd\/2019\/08\/31\/little-town\/","title":{"rendered":"Little Town"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/08\/pic4624124.jpg\" alt=\"\" class=\"wp-image-30692\" width=\"557\" height=\"560\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/08\/pic4624124.jpg 597w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/08\/pic4624124-150x150.jpg 150w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/08\/pic4624124-160x160.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/08\/pic4624124-244x245.jpg 244w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/08\/pic4624124-338x340.jpg 338w\" sizes=\"auto, (max-width: 557px) 100vw, 557px\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/07\/Swa-29-e1562181108347-150x150.jpg\" alt=\"\" class=\"wp-image-30311\"\/><\/figure><\/div>\n\n\n\n<h5 class=\"wp-block-heading\"><strong><span class=\"color\" style=\"color:#0693e3\">SwatSh<\/span><\/strong>: <span class=\"color\" style=\"color:#cf2e2e\">8\/10<\/span><\/h5>\n\n\n\n<p>Little Town veut d\u00e9mocratiser la m\u00e9canique du placement d&rsquo;ouvriers et celle de la gestion de ressources \u00ab\u00a0cubenbois\u00a0\u00bb en les rendant plus familiales tout en apportant un nouveau twist original.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><a href=\"https:\/\/www.vindjeu.eu\/2009\/12\/24\/caylus\/\">Caylus<\/a><\/h3>\n\n\n\n<p>Little Town se rapproche un peu de <a href=\"https:\/\/www.vindjeu.eu\/2009\/12\/24\/caylus\/\"><strong>Caylus<\/strong><\/a> gr\u00e2ce \u00e0 son syst\u00e8me de construction de b\u00e2timents qui, eux-m\u00eames, vont rapporter des choses tout en pouvant \u00eatre utilis\u00e9s tout autant par leur propri\u00e9taire que par leurs adversaires moyennant le paiement d&rsquo;un maigre pot de vin d&rsquo;un sous.<br>Classiquement, les joueuses vont r\u00e9colter les 5 ressources du jeu pour les d\u00e9penser afin de construire des b\u00e2timents ou de nourrir leurs ouvriers! Et oui, <a href=\"https:\/\/www.vindjeu.eu\/2011\/05\/08\/agricola\/\"><strong>Agricola<\/strong><\/a> fait encore des petits malgr\u00e9 son grand age \ud83d\ude42 A chaque fin des 4 tours de jeu, vous allez devoir nourrir tous vos ouvriers sous peine de perdre des PVs (\u00e7e qui peut \u00eatre quelques fois un sacrifice n\u00e9cessaire&#8230;)<br>Les b\u00e2timents vont apporter des possibilit\u00e9s d\u00e9j\u00e0 vues de nombreuses fois: r\u00e9colte de plus de ressources, transformation de ressources et \u00e9change de ressources contre des PVs. Certains b\u00e2timents vont rapporter des PVs en fonction de ce qui les entourent et un autre permet de r\u00e9aliser des actions des b\u00e2timents adjacents une fois par tour.<br><\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignright is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/08\/2137-Little-Town-3-1024x683.jpg\" alt=\"\" class=\"wp-image-30831\" width=\"638\" height=\"425\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/08\/2137-Little-Town-3-1024x683.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/08\/2137-Little-Town-3-300x200.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/08\/2137-Little-Town-3-768x512.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/08\/2137-Little-Town-3-160x107.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/08\/2137-Little-Town-3-368x245.jpg 368w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/08\/2137-Little-Town-3-510x340.jpg 510w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/08\/2137-Little-Town-3.jpg 1200w\" sizes=\"auto, (max-width: 638px) 100vw, 638px\" \/><\/figure><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">Tout sur le terrain<br><\/h3>\n\n\n\n<p>Un peu comme dans <a href=\"https:\/\/www.vindjeu.eu\/2018\/03\/15\/charterstone\/\"><strong>Charterstone<\/strong><\/a>, les b\u00e2timents seront construits sur le plateau. C&rsquo;est \u00e7a le twist int\u00e9ressant de Little Town, tout se fait sur le plateau. Sur celui-ci, sont predessinn\u00e9s des arbres produisant du bois, des \u00e9tangs produisant du poisson et des colines produisant de la pierre. Quand on place une de ses ouvri\u00e8res sur le plateau, on r\u00e9colte toutes les ressources situ\u00e9es sur les 8 cases adjacentes. De plus, on peut activer tous les b\u00e2timents situ\u00e9s sur ces m\u00eames 8 cases adjacentes. Si on d\u00e9sire activer un b\u00e2timent qui n&rsquo;est pas \u00e0 soi, on doit payer 1 sous \u00e0 son propri\u00e9taire.&nbsp;<br><\/p>\n\n\n\n<p>Et c&rsquo;est gr\u00e2ce \u00e0 ce syst\u00e8me qu&rsquo;on va pouvoir se cr\u00e9er des combos d\u00e9vastatrices qui vont permettre d&rsquo;utiliser directement les ressources r\u00e9colt\u00e9es pour les transformer en d&rsquo;autres ressources ou en PVs. Mais ce syst\u00e8me va permettre \u00e0 tout le monde d&rsquo;en profiter. Vous n&rsquo;allez pas vous construire une combo rien que pour vous mais si elle est trop puissante, vous pourriez ne pas en profiter et voir tristement vos adversaires se placer sur les meilleurs emplacements. \u00c9videmment, en compensation, vous recevrez quelques pi\u00e9cettes qui ne vont malheureusement jamais remplacer les b\u00e9n\u00e9fices d&rsquo;une bonne combo. Heureusement, votre salut vient du fait qu&rsquo;il n&rsquo;est pas ais\u00e9 de r\u00e9colter des pi\u00e9cettes et que vos adversaires pourraient \u00eatre en manque au moment o\u00f9 ils pourraient en profiter. N\u00e9anmoins, ce syst\u00e8me qui plaira \u00e0 tous les amateurs d&rsquo;interaction forte, pourra chagriner les amateurs de planification tant vous ne savez jamais si vous pourrez profiter de vos r\u00e9alisations.&nbsp;<br><\/p>\n\n\n\n<p>La grande force de Little Town est d&rsquo;\u00eatre arriv\u00e9 \u00e0 d\u00e9mocratiser le jeu de gestion de ressources et de placement d&rsquo;ouvriers en proposant un jeu plus familial. Les amateurs de ce syst\u00e8me n&rsquo;y verront qu&rsquo;une p\u00e2le copie des grands de ce style avec le trio d\u00e9sormais bien connu r\u00e9colte &#8211; transformation &#8211; \u00e9change de ressources contre des PVs. Il plaira n\u00e9anmoins gr\u00e2ce \u00e0 son syst\u00e8me unique de construction de b\u00e2timents au milieu du plateau de recolte de ressources, sa forte interaction et la fa\u00e7on dont il permet de faire d\u00e9couvrir votre passion aux plus jeunes. Comptez n\u00e9anmoins minimum 12 ans, Little Town n&rsquo;\u00e9tant pas pour les too little \ud83d\ude42<\/p>\n\n\n\n<hr class=\"wp-block-separator is-style-wide\"\/>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"194\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/01\/tapi-e1521499595232.png\" alt=\"\" class=\"wp-image-27681\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/01\/tapi-e1521499595232.png 150w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/01\/tapi-e1521499595232-124x160.png 124w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/figure><\/div>\n\n\n\n<h5 class=\"wp-block-heading\">Tapimoket : <span class=\"color\" style=\"color:#cf2e2e\">8\/10<\/span><\/h5>\n\n\n\n<p>Un jeu charmant et charmeur qui s&rsquo;inscrit dans la lign\u00e9e des jeux simples et th\u00e9matiques comme peut l&rsquo;\u00eatre <em>Kingdomino<\/em>. Si ce dernier initie \u00e0 la pose de tuiles, <strong>Little town<\/strong> initie agr\u00e9ablement \u00e0 la pose d&rsquo;ouvriers et la construction.<\/p>\n\n\n\n<p>Ses 4 courtes manches lui donnent le bon timing sans basculer dans le r\u00e9p\u00e9titif. <\/p>\n\n\n\n<p>De plus, les strat\u00e9gies vont varier entre des parties \u00e0 2  joueurs et celles \u00e0 4. Ainsi, \u00e0 deux, on aura tendance \u00e0 se cr\u00e9er un ensemble \u00e0 soi qu&rsquo;on cherchera \u00e0 optimiser par des combinaisons entre ses b\u00e2timents, alors qu&rsquo;\u00e0 4, le jeu sera plus opportuniste. En effet, il y a cette subtilit\u00e9 \u00e0 construire un b\u00e2timent et prendre le risque d&rsquo;en faire profiter son ou ses adversaires avant soi-m\u00eame.<\/p>\n\n\n\n<p>J&rsquo;aime beaucoup ce jeu casual, fluide et mignon comme tout.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<hr class=\"wp-block-separator is-style-wide\"\/>\n\n\n\n<figure class=\"wp-block-image alignfull\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/08\/2137-Little-Town-9.jpg\" alt=\"\" class=\"wp-image-30830\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/08\/2137-Little-Town-9.jpg 1200w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/08\/2137-Little-Town-9-300x200.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/08\/2137-Little-Town-9-768x512.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/08\/2137-Little-Town-9-1024x683.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/08\/2137-Little-Town-9-160x107.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/08\/2137-Little-Town-9-368x245.jpg 368w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/08\/2137-Little-Town-9-510x340.jpg 510w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/figure>\n\n\n\n<hr class=\"wp-block-separator is-style-wide\"\/>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"color\" style=\"color:#f78da7\">Vin d&rsquo;jeu d&rsquo;music<\/span><\/h2>\n\n\n\n<figure class=\"wp-block-embed-youtube wp-block-embed is-type-video is-provider-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"video-container\"><iframe loading=\"lazy\" title=\"Doolittle by Pixies -  full album\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/nwf2zYFF1Ho?feature=oembed&#038;wmode=opaque\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p> Little Town veut d\u00e9mocratiser la m\u00e9canique du placement d&rsquo;ouvriers et celle de la gestion de ressources \u00ab\u00a0cubenbois\u00a0\u00bb en les rendant plus familiales tout en apportant un nouveau twist original.&nbsp; Caylus Little Town se rapproche un peu de Caylus gr\u00e2ce \u00e0 son syst\u00e8me de construction de b\u00e2timents qui, eux-m\u00eames,&#46;&#46;&#46;<\/p>\n","protected":false},"author":3,"featured_media":30692,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[5],"tags":[7],"class_list":["post-30691","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-famille","tag-swatsh","annee-2083","auteurs-aya","auteurs-shun","editeurs-iello","illustrateurs-sabrina-miramon","distributeurs-iello"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/30691","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/comments?post=30691"}],"version-history":[{"count":0,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/30691\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media\/30692"}],"wp:attachment":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media?parent=30691"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/categories?post=30691"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/tags?post=30691"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}