{"id":30808,"date":"2019-09-07T12:27:52","date_gmt":"2019-09-07T10:27:52","guid":{"rendered":"https:\/\/www.vindjeu.eu\/?p=30808"},"modified":"2019-09-07T12:27:11","modified_gmt":"2019-09-07T10:27:11","slug":"old-west-empresario","status":"publish","type":"post","link":"https:\/\/www.vindjeu.eu\/prd\/2019\/09\/07\/old-west-empresario\/","title":{"rendered":"Old West Empresario"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft\"><img loading=\"lazy\" decoding=\"async\" width=\"441\" height=\"600\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/08\/2143-Old-Wild-Empresario-1.jpg\" alt=\"\" class=\"wp-image-30810\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/08\/2143-Old-Wild-Empresario-1.jpg 441w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/08\/2143-Old-Wild-Empresario-1-221x300.jpg 221w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/08\/2143-Old-Wild-Empresario-1-118x160.jpg 118w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/08\/2143-Old-Wild-Empresario-1-180x245.jpg 180w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/08\/2143-Old-Wild-Empresario-1-250x340.jpg 250w\" sizes=\"auto, (max-width: 441px) 100vw, 441px\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/08\/Swa-31-150x150.png\" alt=\"\" class=\"wp-image-30774\"\/><\/figure><\/div>\n\n\n\n<h5 class=\"wp-block-heading\"><span class=\"color\" style=\"color:#0693e3\">SwatSh<\/span>:&nbsp; <span class=\"color\" style=\"color:#cf2e2e\">7\/10<\/span><\/h5>\n\n\n\n<p>Old West Empresario est un jeu de dice drafting, de placement de\ntuiles et de construction de moteur assez classique.<\/p>\n\n\n\n<p>Le jeu se joue en un nombre ind\u00e9termin\u00e9 de tours jusqu\u2019\u00e0 ce\nqu\u2019une des conditions de fin ne survienne.&nbsp; A chaque tour, on jette 2 d\u00e9s\npar joueuses +1 et chacune, \u00e0 son tour, en choisit un pour ex\u00e9cuter une\naction.&nbsp; Quand tout le monde en a choisi 2, il reste un d\u00e9 et toutes les\njoueuses ex\u00e9cutent une derni\u00e8re action avec ce d\u00e9 commun.&nbsp; Ensuite,\nsurvient la fin du tour avec une phase de nettoyage, de remplissage de\nnouvelles tuiles et de nouveau jet de d\u00e9s.<\/p>\n\n\n\n<p>Avec un d\u00e9, on peut r\u00e9aliser 2 actions&nbsp;: soit on prend un\ndes b\u00e2timents correspondant \u00e0 sa valeur soit on r\u00e9alise l\u2019action de tous ses\nb\u00e2timents ayant la m\u00eame valeur.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Choisir un b\u00e2timent<\/strong><\/h3>\n\n\n\n<p>Au d\u00e9but d\u2019un tour, on place 2 b\u00e2timents en dessous de chaque\nvaleur de d\u00e9 possible. &nbsp;Deux b\u00e2timents par valeur, cela donne donc 12\nb\u00e2timents disponibles pr\u00e9sent\u00e9s en 6 colonnes relatives aux 6 valeurs de d\u00e9s\npossibles.&nbsp; Apr\u00e8s avoir jet\u00e9 les d\u00e9s, on les place sur les colonnes\nrepr\u00e9sentant leur valeur.&nbsp; Quand on choisit un d\u00e9, on peut prendre un des\nb\u00e2timents pr\u00e9sents dans la colonne repr\u00e9sentant cette valeur. &nbsp;Evidemment,\nOld West Empresario est un jeu bien actuel et une m\u00e9canique permet d\u2019influer\nsur la valeur du d\u00e9 en d\u00e9pensant des sous.&nbsp; Gr\u00e2ce \u00e0 cette m\u00e9canique, les\nchoix vont rester tr\u00e8s nombreux et il n\u2019est pas rare qu\u2019en d\u00e9but de tour, un\njoueur puisse acqu\u00e9rir n\u2019importe lequel des 12 b\u00e2timents ce qui lui laisse de\nquoi r\u00e9fl\u00e9chir un peu&nbsp;\ud83d\ude09&nbsp; A noter qu\u2019on peut aussi d\u00e9fausser le\nb\u00e2timent pour gagner des sous.<\/p>\n\n\n\n<p>Quand on choisit un b\u00e2timent, on le place face cach\u00e9e dans sa\nville ce qui va indiquer qu\u2019on ne pourra l\u2019activer qu\u2019une fois qu\u2019il sera\nconstruit.&nbsp; Pour ce faire, il faudra activer les pouvoirs de ses\nb\u00e2timents.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Activer ses b\u00e2timents<\/strong><\/h3>\n\n\n\n<p>Chaque b\u00e2timent va montrer la valeur d\u2019un d\u00e9 et l\u2019action du\nb\u00e2timent.&nbsp; Quand on choisit un d\u00e9 pour activer ses b\u00e2timents, on active\ntous ses b\u00e2timents dont la valeur du d\u00e9 correspond. &nbsp;Si je choisis un d\u00e9\nd\u2019une valeur 3 par exemple, je peux activer tous mes b\u00e2timents de valeur\n3.&nbsp; <\/p>\n\n\n\n<p>Les actions des b\u00e2timents sont diverses et assez\nclassiques&nbsp;: pouvoir construire un b\u00e2timent, gagner des ressources, faire\nperdre un sous \u00e0 ses adversaires ou gagner de nouveaux b\u00e2timents.&nbsp;\nCertains b\u00e2timents n\u2019apportent aucun pouvoir mais des PVs en fin de partie en\nfonction des types de b\u00e2timents construits, du nombre de ressources acquises ou\ndes b\u00e2timents adjacents.<\/p>\n\n\n\n<p>Ajoutez \u00e0 \u00e7a un syst\u00e8me de cartes objectifs toujours diff\u00e9rentes \u00e0 chaque partie et un syst\u00e8me de petits pouvoirs asym\u00e9triques et vous obtenez un jeu classique certes, mais complet et \u00e9quilibr\u00e9 qui fait le taf comme on dit.&nbsp; Old West Empresario, \u00e0 d\u00e9faut de titiller les amateurs de nouveaut\u00e9s, s\u00e9duira les adeptes de choix tactiques nombreux.&nbsp; Il permet de se construire progressivement un petit moteur dont les combinaisons et l\u2019orientation tactique variera \u00e0 chaque partie apportant un petit axe strat\u00e9gique int\u00e9ressant.&nbsp; Ravi de se balader une nouvelle fois dans ce bon vieux Old West&nbsp;\ud83d\ude00<\/p>\n\n\n\n<hr class=\"wp-block-separator is-style-wide\"\/>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"632\" height=\"833\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/08\/2143-Old-Wild-Empresario-2.jpg\" alt=\"\" class=\"wp-image-30809\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/08\/2143-Old-Wild-Empresario-2.jpg 632w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/08\/2143-Old-Wild-Empresario-2-228x300.jpg 228w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/08\/2143-Old-Wild-Empresario-2-121x160.jpg 121w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/08\/2143-Old-Wild-Empresario-2-186x245.jpg 186w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/08\/2143-Old-Wild-Empresario-2-258x340.jpg 258w\" sizes=\"auto, (max-width: 632px) 100vw, 632px\" \/><\/figure><\/div>\n","protected":false},"excerpt":{"rendered":"<p> Old West Empresario est un jeu de dice drafting, de placement de tuiles et de construction de moteur assez classique. Le jeu se joue en un nombre ind\u00e9termin\u00e9 de tours jusqu\u2019\u00e0 ce qu\u2019une des conditions de fin ne survienne.&nbsp; A chaque tour, on jette 2 d\u00e9s par joueuses&#46;&#46;&#46;<\/p>\n","protected":false},"author":3,"featured_media":30810,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[4848],"tags":[7],"class_list":["post-30808","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-initie","tag-swatsh","annee-2083","auteurs-stan-kordonskiy","editeurs-tasty-minstrel-games","illustrateurs-sergi-marcet","distributeurs-asmodee-uk"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/30808","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/comments?post=30808"}],"version-history":[{"count":0,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/30808\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media\/30810"}],"wp:attachment":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media?parent=30808"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/categories?post=30808"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/tags?post=30808"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}