{"id":32730,"date":"2019-12-06T15:43:17","date_gmt":"2019-12-06T14:43:17","guid":{"rendered":"https:\/\/www.vindjeu.eu\/?p=32730"},"modified":"2024-10-18T18:35:41","modified_gmt":"2024-10-18T16:35:41","slug":"expedition-to-newdale","status":"publish","type":"post","link":"https:\/\/www.vindjeu.eu\/prd\/2019\/12\/06\/expedition-to-newdale\/","title":{"rendered":"Expedition to Newdale"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/11\/2251-Newdale-1.jpg\" alt=\"\" class=\"wp-image-32711\" width=\"407\" height=\"569\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/11\/2251-Newdale-1.jpg 429w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/11\/2251-Newdale-1-215x300.jpg 215w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/11\/2251-Newdale-1-114x160.jpg 114w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/11\/2251-Newdale-1-175x245.jpg 175w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/11\/2251-Newdale-1-243x340.jpg 243w\" sizes=\"auto, (max-width: 407px) 100vw, 407px\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/10\/2019-10-23-12.08.08-150x150.jpg\" alt=\"\" class=\"wp-image-32064\"\/><figcaption><br><\/figcaption><\/figure><\/div>\n\n\n\n<h5 class=\"wp-block-heading\"><span class=\"color\" style=\"color:#0693e3\">SwatSh<\/span>: <span class=\"color\" style=\"color:#cf2e2e\"> 8,5\/10<\/span><\/h5>\n\n\n\n<p>Apr\u00e8s la nomination de <a href=\"https:\/\/www.vindjeu.eu\/2016\/04\/07\/mombasa\/\"><strong>Mombasa <\/strong><\/a>au <a href=\"https:\/\/www.vindjeu.eu\/2016\/09\/19\/vin-djeu-dlannee-2016\/\"><strong>Vin d&rsquo;jeu d&rsquo;l&rsquo;ann\u00e9e 2016<\/strong><\/a>, celle de <a href=\"https:\/\/www.vindjeu.eu\/2016\/12\/28\/great-western-trail-video\/\"><strong>Great Western Trail<\/strong><\/a> comme <a href=\"http:\/\/www.vindjeu.eu\/2017\/09\/19\/vin-djeu-dlannee-2017\/\"><strong>Vin d&rsquo;jeu d&rsquo;l&rsquo;ann\u00e9e 2017 cat\u00e9gorie Expert<\/strong><\/a> et celle de <a href=\"https:\/\/www.vindjeu.eu\/2018\/12\/18\/blackhout-hong-kong\/\"><strong>Blackout Hong Kong<\/strong><\/a> comme <a href=\"https:\/\/www.vindjeu.eu\/2019\/09\/23\/vin-djeu-dlannee-2019\/\"><strong>Vin d&rsquo;jeu d&rsquo;coup d&rsquo;c\u0153ur de cette ann\u00e9e<\/strong><\/a>, on peut facilement affirmer que nous adorons les jeux d&rsquo;<a href=\"https:\/\/www.vindjeu.eu\/auteurs\/alexander-pfister\/\"><strong>Alexander Pfister<\/strong><\/a> chez Vin d&rsquo;jeu! On \u00e9tait donc impatient de pouvoir jouer \u00e0 Expedition to Newdale, son dernier opus avec Maracaibo sur lequel on vous reviendra. Surtout qu&rsquo;Expedition to Newdale a \u00e9t\u00e9 \u00e9dit\u00e9 par <a href=\"https:\/\/www.vindjeu.eu\/editeurs\/lookout-games\/\"><strong>Lookout Games<\/strong><\/a> qui ont d\u00e9j\u00e0 d\u00e9montr\u00e9 leur savoir faire entre autre avec <a href=\"https:\/\/www.vindjeu.eu\/2011\/05\/08\/agricola\/\"><strong>Agricola<\/strong><\/a>.<\/p>\n\n\n\n<p>Et on peut dire qu&rsquo;Alexander a bien choisi son \u00e9diteur!  C&rsquo;est en effet son jeu le plus proche d&rsquo;<a href=\"https:\/\/www.vindjeu.eu\/2011\/05\/08\/agricola\/\"><strong>Agricola<\/strong><\/a> et de son syst\u00e8me de gestion de ressources.  Dans Expedition to Newdale, vous allez produire du charbon, du bl\u00e9 qui pourra \u00eatre transform\u00e9 en pain, \u00e9lever des vaches qui pourront vous rapporter de la viande,&#8230;  <\/p>\n\n\n\n<p>Pou produire vous allez devoir construire des b\u00e2timents. Ces b\u00e2timents correspondent \u00e0 des cartes que vous allez piocher en cours de jeu. La pioche se fait au hasard mais, un peu comme dans <a href=\"https:\/\/www.vindjeu.eu\/2016\/11\/26\/terraforming-mars-video-2\/\"><strong>Terraforming Mars<\/strong><\/a>, vous allez piocher tellement de cartes que le hasard est limit\u00e9 (mais toujours pr\u00e9sent bien entendu).  Ces b\u00e2timents seront \u00e9galement repr\u00e9sent\u00e9s par de petites maisons sur le plateau central o\u00f9 une lutte pour \u00eatre le premier sur chaque ville va avoir lieu entre joueurs.<\/p>\n\n\n\n<p>Le c\u0153ur du jeu est une m\u00e9canique de <a href=\"https:\/\/www.vindjeu.eu\/mecanismes\/placement-douvriers\/\"><strong>placement d&rsquo;ouvriers<\/strong><\/a> tr\u00e8s classique. Vous disposez de 2 ouvriers et pouvez les placer soit sur votre plateau personnel afin de faire produire vos b\u00e2timents soit sur une des 5 cases action du plateau central. Ces cases action ne sont pas limit\u00e9es et n&rsquo;importe qui peut s&rsquo;y mettre sans se g\u00eaner. Ca limite la tension et l&rsquo;interaction du jeu mais \u00e7a en favorise sa ma\u00eetrise. Vous pourrez classiquement y acheter un ou deux ouvriers suppl\u00e9mentaires, gagner un peu d&rsquo;argent en d\u00e9faussant des cartes, \u00e9changer et piocher de nouvelles cartes, am\u00e9liorer certaines habilit\u00e9s ou construire un b\u00e2timent. <\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignright is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/11\/2251-Newdale-8-1024x683.jpg\" alt=\"\" class=\"wp-image-32736\" width=\"595\" height=\"397\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/11\/2251-Newdale-8-1024x683.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/11\/2251-Newdale-8-300x200.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/11\/2251-Newdale-8-768x512.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/11\/2251-Newdale-8-160x107.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/11\/2251-Newdale-8-368x245.jpg 368w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/11\/2251-Newdale-8-510x340.jpg 510w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/11\/2251-Newdale-8.jpg 1140w\" sizes=\"auto, (max-width: 595px) 100vw, 595px\" \/><\/figure><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">La production des b\u00e2timents<\/h3>\n\n\n\n<p>La production de vos b\u00e2timents est quant \u00e0 elle assez particuli\u00e8re. Tout d&rsquo;abord, \u00e7a ne se fait pas \u00ab\u00a0tout seul\u00a0\u00bb. Vous aurez besoin d&rsquo;un ouvrier pour cela. Inutile donc de construire des b\u00e2timents \u00e0 tout va, encore vous faudra-t-il assez de main d&rsquo;\u0153uvre pour les faire fonctionner \ud83d\ude42 Mais chaque b\u00e2timent poss\u00e8de 3 cases o\u00f9 un ouvrier peut se placer pour le faire fonctionner! Chacune va le faire produire entre 1 et 4 fois en fonction des assistants pr\u00e9sents. Au d\u00e9but de tour, on tire une carte \u00e9v\u00e9nement qui va indiquer le nombre d&rsquo;assistants de chacune des 4 couleurs pr\u00e9sents ce tour-ci pour aider tous les joueurs (par exemple: 2 jaunes, 1 vert, 2 rouges et 0 bleu). Chaque carte b\u00e2timent va indiquer le nombre d&rsquo;assistants n\u00e9cessaire pour fonctionner (par exemple 3 jaunes et 2 rouges). Les 3 cases action disponibles pour chaque b\u00e2timent vont indiquer si vous devez avoir exactement le nombre et la couleur des assistants indiqu\u00e9s sur le b\u00e2timent, si vous pouvez en avoir un de moins, ou si vous devez en avoir 1 ou 2 de plus! Dans notre exemple, vous allez placer votre ouvrier sur la case \u00ab\u00a0-1&Prime;qui produit une fois car vous avez besoin de 3 jaunes alors qu&rsquo;il n&rsquo;y en a que 2 de disponibles.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/11\/2251-Newdale-2-1024x683.jpg\" alt=\"\" class=\"wp-image-32735\" width=\"768\" height=\"512\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/11\/2251-Newdale-2-1024x683.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/11\/2251-Newdale-2-300x200.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/11\/2251-Newdale-2-768x512.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/11\/2251-Newdale-2-160x107.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/11\/2251-Newdale-2-368x245.jpg 368w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/11\/2251-Newdale-2-510x340.jpg 510w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/11\/2251-Newdale-2.jpg 1140w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure><\/div>\n\n\n\n<p>Ce serait vrai s&rsquo;il n&rsquo;y avait une phase, juste apr\u00e8s la phase de placement des ouvriers, o\u00f9 l&rsquo;on pioche, au hasard, 4 assistants suppl\u00e9mentaires. Et gr\u00e2ce \u00e0 cette pioche, avec un brin de chance, arrivera 1 voir m\u00eame 2 assistants jaunes! Autant alors placer son ouvrier sur la case permettant de produire 2 fois \u00e0 condition d&rsquo;avoir exactement le nombre d&rsquo;ouvriers exig\u00e9, ou, en prenant un peu plus de risques, esp\u00e9rer pouvoir produire 3 fois en esp\u00e9rant piocher un assistant de la bonne couleur de plus qu&rsquo;exig\u00e9! Bien qu&rsquo;apportant une m\u00e9canique de prise de risque, il y a un hasard un peu d\u00e9rangeant dans ce syst\u00e8me mais qui peut \u00eatre compens\u00e9 par la d\u00e9fausse de cartes. Si vous n&rsquo;avez pas tous les assistants esp\u00e9r\u00e9s, vous pouvez vous d\u00e9fausser de 3 cartes pour combler 1 assistant manquant. Plus tard dans la partie vous pourrez m\u00eame am\u00e9liorer cette facult\u00e9 en ne devant d\u00e9fausser plus que 2 cartes par assistant manquant. Ca permet de mitiger le hasard sans l&rsquo;annihiler pour autant. De plus, vous pourrez toujours augmenter votre production en d\u00e9faussant certaines cartes ou en transformant des ressources sp\u00e9cifiques.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/11\/2251-Newdale-5-1024x683.jpg\" alt=\"\" class=\"wp-image-32737\" width=\"624\" height=\"416\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/11\/2251-Newdale-5-1024x683.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/11\/2251-Newdale-5-300x200.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/11\/2251-Newdale-5-768x512.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/11\/2251-Newdale-5-160x107.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/11\/2251-Newdale-5-368x245.jpg 368w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/11\/2251-Newdale-5-510x340.jpg 510w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/11\/2251-Newdale-5.jpg 1140w\" sizes=\"auto, (max-width: 624px) 100vw, 624px\" \/><\/figure><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">Money money money<\/h3>\n\n\n\n<p>Mais toutes les ressources d&rsquo;Expedition to Newdale peuvent se r\u00e9sumer en une seule: l&rsquo;argent!  Car toutes les cartes b\u00e2timents produisent diff\u00e9rentes denr\u00e9es qui ont, chacune, un taux de conversion avec l&rsquo;argent allant de 1 pour 1 \u00e0 1 pour 5.  Produire un pain valant 5 sous est donc 5 fois plus int\u00e9ressant que de produire un charbon ne valant qu&rsquo;1.  Car tout se paye en argent.  Si vous avez produit 2 pains et 6 charbons, vous disposez donc de 16 sous pour r\u00e9aliser votre action comme acheter un nouvel ouvrier pour 7 sous ou construire un b\u00e2timent pour 12.  Cette m\u00e9canique est bien trouv\u00e9e car elle simplifie bien le jeu et diminue la complexit\u00e9 des jeux de <a href=\"https:\/\/www.vindjeu.eu\/mecanismes\/gestion-de-ressources\/\"><strong>gestion de ressources<\/strong><\/a>.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">8 en 1<\/h3>\n\n\n\n<p>Mais la magie d&rsquo;Expedition to Newdale n&rsquo;est pas l\u00e0 et se situe dans la nouvelle tendance lanc\u00e9e par <a href=\"https:\/\/www.vindjeu.eu\/2019\/01\/30\/dicium\/\"><strong>Dicium <\/strong><\/a>et poursuivie par <a href=\"https:\/\/www.vindjeu.eu\/2019\/11\/25\/sierra-west\/\"><strong>Sierra West<\/strong><\/a>: plusieurs jeux en 1! Et ici ce n&rsquo;est pas 4 mais bien 8 jeux diff\u00e9rents que propose Expedition to Newdale. Bon, soyons honn\u00eate, c&rsquo;est une m\u00e9canique qu&rsquo;on a d\u00e9j\u00e0 rencontr\u00e9e autrement sous forme de mini extensions, variantes ou m\u00eame full extension comme pour <a href=\"https:\/\/www.vindjeu.eu\/2015\/10\/18\/tuscany-expand-the-world-of-viticulture\/\"><strong>Viticulture Tuscany<\/strong><\/a> ou <a href=\"https:\/\/www.vindjeu.eu\/2018\/11\/19\/scythe-le-reveil-de-fenris-the-rise-of-fenris\/\"><strong>Scythe Le R\u00e9veil de Fenris<\/strong><\/a>. Mais quand m\u00eame, on va pouvoir \u00e9voluer, de partie en partie en ajoutant de nouvelles m\u00e9caniques, de nouvelles cartes, de nouvelles cases action,&#8230; tout au long de 8 chapitres permettant d&rsquo;assimiler les r\u00e8gles plus facilement et de d\u00e9couvrir le jeu progressivement. Attention cependant, ces diff\u00e9rents chapitres proposent une mont\u00e9e en puissance du jeu mais chacun est ind\u00e9pendant des autres. Vous pourrez tr\u00e8s bien ne jouer qu&rsquo;\u00e0 un seul des chapitres. C&rsquo;est super tant \u00e7a varie bien vos parties toutes bas\u00e9es sur une m\u00eame m\u00e9canique centrale.<\/p>\n\n\n\n<p>Expedition to Newdale est un nouveau chapitre dans les cr\u00e9ations d&rsquo;<a href=\"https:\/\/www.vindjeu.eu\/auteurs\/alexander-pfister\/\"><strong>Alexander Pfister&nbsp;<\/strong><\/a>\ud83d\ude42   Avec un peu d&rsquo;audace, on pourrait m\u00eame affirmer qu&rsquo;Expedition to Newdale est la revisite d&rsquo;<a href=\"https:\/\/www.vindjeu.eu\/2011\/05\/08\/agricola\/\"><strong>Agricola<\/strong><\/a> \u00e0 la sauce <a href=\"https:\/\/www.vindjeu.eu\/auteurs\/alexander-pfister\/https:\/\/www.vindjeu.eu\/auteurs\/alexander-pfister\/\"><strong>Pfister <\/strong><\/a>\ud83d\ude09 Il est coh\u00e9rent avec ses derni\u00e8res cr\u00e9ations tant il est profond, strat\u00e9gique original et aux choix corn\u00e9liens. Le hasard de la pioche des cartes ou de l&rsquo;apport des ressources peut en rebuter plus d&rsquo;un mais si vous l&rsquo;acceptez vous serez agr\u00e9ablement surpris par ce jeu indispensable pour tout amateur des jeux d&rsquo;Alexander comme nous le sommes \ud83d\ude42<\/p>\n\n\n\n<hr class=\"wp-block-separator is-style-wide\"\/>\n\n\n\n<figure class=\"wp-block-image alignfull\"><img loading=\"lazy\" decoding=\"async\" width=\"1320\" height=\"880\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/11\/2251-Newdale-14.jpg\" alt=\"\" class=\"wp-image-32731\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/11\/2251-Newdale-14.jpg 1320w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/11\/2251-Newdale-14-300x200.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/11\/2251-Newdale-14-768x512.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/11\/2251-Newdale-14-1024x683.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/11\/2251-Newdale-14-160x107.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/11\/2251-Newdale-14-368x245.jpg 368w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/11\/2251-Newdale-14-510x340.jpg 510w\" sizes=\"auto, (max-width: 1320px) 100vw, 1320px\" \/><\/figure>\n\n\n\n<hr class=\"wp-block-separator is-style-wide\"\/>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"color\" style=\"color:#f78da7\">Vin d&rsquo;jeu d&rsquo;vid\u00e9o<\/span><\/h2>\n\n\n\n<h4 class=\"wp-block-heading\">L&rsquo;explication et la d\u00e9gustation en 24 minutes par SwatSh<\/h4>\n\n\n\n<figure class=\"wp-block-embed-youtube wp-block-embed is-type-video is-provider-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"video-container\"><iframe loading=\"lazy\" title=\"Expedition to Newdale (Vin d&#039;jeu d&#039;vid\u00e9o)\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/gYzmpWZ87vc?feature=oembed&#038;wmode=opaque\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p> Apr\u00e8s la nomination de Mombasa au Vin d&rsquo;jeu d&rsquo;l&rsquo;ann\u00e9e 2016, celle de Great Western Trail comme Vin d&rsquo;jeu d&rsquo;l&rsquo;ann\u00e9e 2017 cat\u00e9gorie Expert et celle de Blackout Hong Kong comme Vin d&rsquo;jeu d&rsquo;coup d&rsquo;c\u0153ur de cette ann\u00e9e, on peut facilement affirmer que nous adorons les jeux d&rsquo;Alexander Pfister chez&#46;&#46;&#46;<\/p>\n","protected":false},"author":3,"featured_media":32711,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[4849],"tags":[7],"class_list":["post-32730","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-expert","tag-swatsh","annee-2083","auteurs-alexander-pfister","editeurs-lookout-games","illustrateurs-klemens-franz","mecanismes-gestion-de-ressources","mecanismes-jeu-de-cartes","mecanismes-placement-douvriers"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/32730","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/comments?post=32730"}],"version-history":[{"count":1,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/32730\/revisions"}],"predecessor-version":[{"id":59428,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/32730\/revisions\/59428"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media\/32711"}],"wp:attachment":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media?parent=32730"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/categories?post=32730"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/tags?post=32730"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}