{"id":32749,"date":"2019-12-07T15:20:08","date_gmt":"2019-12-07T14:20:08","guid":{"rendered":"https:\/\/www.vindjeu.eu\/?p=32749"},"modified":"2024-10-18T18:35:23","modified_gmt":"2024-10-18T16:35:23","slug":"valley-of-the-kings-premium-edition","status":"publish","type":"post","link":"https:\/\/www.vindjeu.eu\/prd\/2019\/12\/07\/valley-of-the-kings-premium-edition\/","title":{"rendered":"Valley of the Kings Premium Edition"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/11\/2252-Valley-of-the-kings-2.png\" alt=\"\" class=\"wp-image-32750\" width=\"456\" height=\"458\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/11\/2252-Valley-of-the-kings-2.png 598w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/11\/2252-Valley-of-the-kings-2-150x150.png 150w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/11\/2252-Valley-of-the-kings-2-300x300.png 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/11\/2252-Valley-of-the-kings-2-160x160.png 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/11\/2252-Valley-of-the-kings-2-244x245.png 244w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/11\/2252-Valley-of-the-kings-2-339x340.png 339w\" sizes=\"auto, (max-width: 456px) 100vw, 456px\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/10\/2019-10-23-12.08.08-150x150.jpg\" alt=\"\" class=\"wp-image-32064\"\/><figcaption><br><\/figcaption><\/figure><\/div>\n\n\n\n<h5 class=\"wp-block-heading\"><strong><span class=\"color\" style=\"color:#0693e3\">SwatSh<\/span><\/strong>:&nbsp;<span class=\"color\" style=\"color:#cf2e2e\"> <\/span><strong><span class=\"color\" style=\"color:#cf2e2e\">8,5 \/10<\/span><\/strong><\/h5>\n\n\n\n<p>Valley of the Kings \u00e9tait une sortie tr\u00e8s discr\u00e8te de 2014&nbsp;de l&rsquo;\u00e9diteur Am\u00e9ricain <a href=\"http:\/\/www.vindjeu.eu\/editeurs\/alderac-entertainment-group\/\" target=\"_blank\" rel=\"noreferrer noopener\">AEG<\/a>.&nbsp; Mais depuis lors, l&rsquo;eau a coul\u00e9 sous les ponts et le jeu s&rsquo;est vu enrichir de 2 extensions.  Cette ann\u00e9e, AEG a d\u00e9cid\u00e9 de sortir une version premium du jeu comprenant non seulement le jeu de base mais \u00e9galement ses 2 extensions.  De plus, cette version permet d\u00e9sormais d&rsquo;y jouer \u00e0 5 ou 6 joueurs et m\u00eame tout seul si vous n&rsquo;avez pas d&rsquo;ami \ud83d\ude09  Les cartes sont maintenant plus grandes et la boite comprend des compartiments pour mieux les classer.  Enfin, le jeu comprend une nouvelle extension: les pharaons qui vont donner des pouvoirs asym\u00e9triques.<\/p>\n\n\n\n<p>Valley of the Kings est un jeu de deckbuilding l\u00e9ger mais profond et assez original.&nbsp; Concentrons-nous d&rsquo;ailleurs sur ces originalit\u00e9s :<\/p>\n\n\n\n<p><strong>1) La pyramide\n<\/strong>Un peu \u00e0 la mani\u00e8re de l&rsquo;excellent <a href=\"http:\/\/www.vindjeu.eu\/2013\/02\/06\/ascension-des-ames-dechainees\/\" target=\"_blank\" rel=\"noreferrer noopener\">Ascension<\/a>, Valley of the Kings pr\u00e9sente, chaque tour, un nombre limit\u00e9 de cartes \u00e0 l&rsquo;achat. 3 exactement, ou presque \ud83d\ude09<\/p>\n\n\n\n<p>On va construire une pyramide, enfin plut\u00f4t un triangle, de 3 cartes \u00e0 la base, puis 2 puis 1. Seules les 3 cartes du dessous sont disponibles \u00e0 l&rsquo;achat.<\/p>\n\n\n\n<p>Ce qui est int\u00e9ressant, c&rsquo;est que d\u00e8s qu&rsquo;une carte est achet\u00e9e, la carte du dessus de la pyramide descend et comble le vide afin que vous ayez toujours le choix entre 3 cartes. Comme on peut faire plusieurs achats lors de son tour (\u00e0 condition d&rsquo;avoir assez de pognon \ud83d\ude09 ), on va souvent tenir compte des cartes qui vont descendre, soit pour pouvoir l&rsquo;acqu\u00e9rir soi-m\u00eame, soit pour \u00e9viter qu&rsquo;une autre, plus fructueuse, devienne disponible pour un adversaire.<\/p>\n\n\n\n<p>Cerise sur le g\u00e2teau, les pouvoirs de certaines cartes jouent avec cette m\u00e9canique.&nbsp; Certaines cartes permettent d&rsquo;intervertir la position de 2 cartes dans la pyramide, d&rsquo;autres d&rsquo;acheter une carte situ\u00e9e plus haut et d&rsquo;autres de d\u00e9fausser des cartes de la pyramide.<\/p>\n\n\n\n<p>Ce syst\u00e8me est d&rsquo;autant plus excellent qu&rsquo;il permet d&rsquo;anticiper les cartes qui seront disponibles plus tard et de jouer avec cette information afin de pouvoir en profiter ou de laisser volontairement ses adversaires s&rsquo;en accaparer (sans mettre son sac \u00e0 part \ud83d\ude00 )<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignright\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/11\/2252-Valley-of-the-kings-3.png\" alt=\"\" class=\"wp-image-32752\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/11\/2252-Valley-of-the-kings-3.png 500w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/11\/2252-Valley-of-the-kings-3-150x150.png 150w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/11\/2252-Valley-of-the-kings-3-300x300.png 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/11\/2252-Valley-of-the-kings-3-160x160.png 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/11\/2252-Valley-of-the-kings-3-245x245.png 245w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/11\/2252-Valley-of-the-kings-3-340x340.png 340w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/figure><\/div>\n\n\n\n<p><strong>2) La tombe<\/strong><br>\nContrairement \u00e0 tous les jeux de deckbuilding, dans Valley of the Kings, \u00e0 la fin du jeu, on ne va pas regarder les cartes de votre main + de votre d\u00e9fausse + de votre deck pour gagner des PVs. Non, dans Valley of the Kings, toutes les cartes qu&rsquo;il vous reste en main, d\u00e9fausse et deck valent que dalle, nada !&nbsp; Seules les cartes dans votre tombe valent quelque chose.<\/p>\n\n\n\n<p>A votre tour, vous pouvez effectuer autant d&rsquo;achats que d\u00e9sir\u00e9s, autant d&rsquo;actions que d\u00e9sir\u00e9es et une seule mise en tombe. Une mise en tombe consiste \u00e0 placer une carte de sa main dans sa tombe. \u00c9videmment, certaines cartes action permettent de placer plusieurs cartes dans sa tombe \u00e0 son tour \u00e0 certaines conditions.<\/p>\n\n\n\n<p>Et les cartes dans votre tombe procurent des PVs en fonction du nombre de cartes de la m\u00eame famille (= la m\u00eame couleur) que vous avez dans votre tombe.&nbsp; Au plus vous en avez d&rsquo;une s\u00e9rie, au plus vous gagnerez des PVs. Oui, Valley of the Kings est un jeu qui parle aux joueurs qui ont la collectionnite aig\u00fce \ud83d\ude00<\/p>\n\n\n\n<p>Vous l&rsquo;aurez compris, mettre&nbsp;une carte dans sa tombe, non seulement vous permet de gagner des PVs mais vous permet \u00e9galement de nettoyer votre deck des petites cartes crasseuses du d\u00e9part \ud83d\ude42<\/p>\n\n\n\n<p>L\u00e0 aussi les choix sont int\u00e9ressants car on va souvent \u00eatre face \u00e0 des choix difficiles: mieux vaut-il nettoyer son deck maintenant en pla\u00e7ant une petite carte dans sa tombe ou placer cette superbe carte qui procure beaucoup de PVs mais qui ne pourra plus me donner son bonus en pi\u00e8ces ou en pouvoir?\u2026<\/p>\n\n\n\n<p><strong>3) Les pouvoirs des cartes<\/strong><br>\nGr\u00e2ce \u00e0 cette m\u00e9canique originale, les pouvoirs des cartes sont eux aussi originaux: d\u00e9placer\/d\u00e9truire\/acqu\u00e9rir\/\u00e9changer des cartes dans la pyramide, mais aussi pas mal de cartes permettent beaucoup d&rsquo;interaction avec les adversaires: les faire d\u00e9fausser une ou plusieurs cartes, d\u00e9fausser une de ses cartes dans la d\u00e9fausse d&rsquo;un adversaire (celle-l\u00e0 je l&rsquo;adore \ud83d\ude42 id\u00e9al pour nettoyer son deck tout en pourrissant celui d&rsquo;un adversaire \ud83d\ude42 ), des habilit\u00e9s qui s&rsquo;ex\u00e9cutent lorsqu&rsquo;un autre joueur effectue telle ou telle autre action (il met une carte dans sa tombe, il vous oblige \u00e0 d\u00e9fausser,\u2026), voler des cartes aux autres,\u2026<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"497\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/11\/2252-Valley-of-the-kings-5-1024x497.jpg\" alt=\"\" class=\"wp-image-32753\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/11\/2252-Valley-of-the-kings-5-1024x497.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/11\/2252-Valley-of-the-kings-5-300x146.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/11\/2252-Valley-of-the-kings-5-768x373.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/11\/2252-Valley-of-the-kings-5-160x78.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/11\/2252-Valley-of-the-kings-5-504x245.jpg 504w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/11\/2252-Valley-of-the-kings-5-700x340.jpg 700w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/11\/2252-Valley-of-the-kings-5.jpg 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div>\n\n\n\n<p><strong>4) La difficult\u00e9s des choix lors des achats mais aussi&nbsp;lors jeu de la carte<\/strong><br>\nVous aurez \u00e0 faire des choix \u00e0 2 niveaux:<br>\na. Quelle carte acheter dans la pyramide?<br>\nEt ce choix n&rsquo;est d\u00e9j\u00e0 pas facile car il va d\u00e9pendre de nombreux \u00e9l\u00e9ments.&nbsp; Parmi les cartes disponibles:<br>\n-laquelle propose le pouvoir le plus int\u00e9ressant?<br>\n-laquelle fournit le plus d&rsquo;or pour les prochains achats?<br>\n-laquelle est de la couleur d&rsquo;une collection que je vise pour l&rsquo;avoir dans ma tombe et gagner plus de PVs?<br>\n-laquelle co\u00fbte le moins pour pouvoir jouer certaines de mes cartes en main&nbsp;pour leur action ou pour pouvoir en mettre une dans ma tombe (sans b\u00e9n\u00e9ficier de son apport d&rsquo;or)<br>\n-laquelle va \u00eatre disponible \u00e0 l&rsquo;achat pour l&rsquo;adversaire suivant?<\/p>\n\n\n\n<p>b. Comment jouer les cartes de sa main?<br>\nOn peut en effet jouer ses cartes de 3 mani\u00e8res diff\u00e9rentes:<br>\n-Pour apporter de l&rsquo;or afin de pouvoir acheter une carte qui nous int\u00e9resse<br>\n-Pour le pouvoir qu&rsquo;elle propose<br>\n-Pour les mettre dans sa tombe (on ne peut mettre que maximum une carte dans sa tombe par tour)<\/p>\n\n\n\n<p>Et ces choix ne sont pas \u00e9vidents, surtout qu&rsquo;on ne sait pas tout faire: jouer tous les pouvoirs et avoir un max de pognon pour acheter les meilleures cartes est antagonique.&nbsp; D\u00e9cider quelle carte est \u00e0 mettre dans sa tombe n&rsquo;est pas un choix facile non plus: plut\u00f4t les cartes faibles qui pourrissent un peu votre deck afin de le rendre plus puissant ou les cartes fortes qui vont vous rapporter beaucoup de PVs mais qui vont affaiblir votre deck car ils n&rsquo;apporteront plus leur pouvoir et leurs pi\u00e8ces n\u00e9cessaires \u00e0 l&rsquo;achat de cartes encore plus puissantes.<\/p>\n\n\n\n<p>Comme dans tout bon jeu de deckbuilding, Valley of the King n\u00e9cessite une vision long terme car vous allez acqu\u00e9rir des cartes dont vous ne pourrez profiter que bien plus tard.&nbsp; Ce n&rsquo;est pas pour autant que Valley of the King propose de multiples strat\u00e9gies.&nbsp; Non, ce seront vos choix, toujours difficiles, qui feront la diff\u00e9rence.&nbsp; Acqu\u00e9rir les bonnes cartes, savoir jouer les bonnes cartes pour leur pouvoir et d&rsquo;autres pour l&rsquo;or qu&rsquo;elles g\u00e9n\u00e8rent, choisir les bonnes cartes \u00e0 mettre dans sa tombe au bon moment,\u2026&nbsp; Tous ces choix sont succulents et donnent, avec des m\u00e9canismes innovants, originaux et ing\u00e9nieux un jeu vraiment \u00e0 part, l\u00e9ger par ses r\u00e8gles mais profond dans ses choix et sa planification, interactif et au final tr\u00e8s addictif.<\/p>\n\n\n\n<hr class=\"wp-block-separator is-style-wide\"\/>\n\n\n\n<figure class=\"wp-block-image alignfull\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"734\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/11\/2252-Valley-of-the-kings-7.jpg\" alt=\"\" class=\"wp-image-32751\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/11\/2252-Valley-of-the-kings-7.jpg 1200w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/11\/2252-Valley-of-the-kings-7-300x184.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/11\/2252-Valley-of-the-kings-7-768x470.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/11\/2252-Valley-of-the-kings-7-1024x626.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/11\/2252-Valley-of-the-kings-7-160x98.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/11\/2252-Valley-of-the-kings-7-401x245.jpg 401w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/11\/2252-Valley-of-the-kings-7-556x340.jpg 556w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p> Valley of the Kings \u00e9tait une sortie tr\u00e8s discr\u00e8te de 2014&nbsp;de l&rsquo;\u00e9diteur Am\u00e9ricain AEG.&nbsp; Mais depuis lors, l&rsquo;eau a coul\u00e9 sous les ponts et le jeu s&rsquo;est vu enrichir de 2 extensions. Cette ann\u00e9e, AEG a d\u00e9cid\u00e9 de sortir une version premium du jeu comprenant non seulement&#46;&#46;&#46;<\/p>\n","protected":false},"author":3,"featured_media":32750,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[4848],"tags":[7],"class_list":["post-32749","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-initie","tag-swatsh","annee-2083","auteurs-tom-cleaver","editeurs-alderac-entertainment-group","illustrateurs-banu-andaru","illustrateurs-matt-paquette","mecanismes-deckbuilding"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/32749","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/comments?post=32749"}],"version-history":[{"count":1,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/32749\/revisions"}],"predecessor-version":[{"id":59427,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/32749\/revisions\/59427"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media\/32750"}],"wp:attachment":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media?parent=32749"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/categories?post=32749"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/tags?post=32749"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}