{"id":32945,"date":"2019-12-25T12:05:18","date_gmt":"2019-12-25T11:05:18","guid":{"rendered":"https:\/\/www.vindjeu.eu\/?p=32945"},"modified":"2024-11-13T23:17:23","modified_gmt":"2024-11-13T22:17:23","slug":"trismegistus-lultime-formule","status":"publish","type":"post","link":"https:\/\/www.vindjeu.eu\/prd\/2019\/12\/25\/trismegistus-lultime-formule\/","title":{"rendered":"Trismegistus: L&rsquo;Ultime Formule"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"alignleft is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/12\/2263-Trismegistus-1.png\" alt=\"\" class=\"wp-image-32947\" style=\"width:459px;height:459px\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/12\/2263-Trismegistus-1.png 600w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/12\/2263-Trismegistus-1-150x150.png 150w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/12\/2263-Trismegistus-1-300x300.png 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/12\/2263-Trismegistus-1-160x160.png 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/12\/2263-Trismegistus-1-245x245.png 245w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/12\/2263-Trismegistus-1-340x340.png 340w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure>\n<\/div>\n\n<div class=\"wp-block-image\">\n<figure class=\"alignleft\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/10\/2019-10-23-15.15.22-e1572208476982-150x150.jpg\" alt=\"\" class=\"wp-image-32085\"\/><\/figure>\n<\/div>\n\n\n<h5 class=\"wp-block-heading\"><span class=\"color\" style=\"color:#0693e3\">SwatSh<\/span>:  <span class=\"color\" style=\"color:#cf2e2e\">9,5\/10<\/span><\/h5>\n\n\n\n<p>Avec <a href=\"https:\/\/www.vindjeu.eu\/2019\/09\/26\/barrage\/\"><strong>Barrage<\/strong><\/a>, Trismegistus est certainement un des meilleurs si pas le meilleur jeu sorti \u00e0 Essen cette ann\u00e9e!  Bon, on n&rsquo;a pas encore su jouer \u00e0 tous les jeux int\u00e9ressants, il nous manque encore Maracaibo, Dreamscape, Cooper Island et The Magnificent mais l&rsquo;\u00e9tau se resserre \ud83d\ude09<\/p>\n\n\n\n<p>D\u00e9j\u00e0 sur papier, Trismegistus a tout pour plaire.  Tout comme pour l&rsquo;excellent <a href=\"https:\/\/www.vindjeu.eu\/2018\/12\/21\/teotihuacan-la-cite-des-dieux\/\"><strong>Teotihuacan<\/strong><\/a> (<a href=\"https:\/\/www.vindjeu.eu\/2019\/09\/23\/vin-djeu-dlannee-2019\/\"><strong>Vin d&rsquo;jeu d&rsquo;coup d&rsquo;c\u0153ur 2019<\/strong><\/a>),  Trismegistus L&rsquo;Ultime Formule est issu de la collaboration entre <a href=\"https:\/\/www.vindjeu.eu\/editeurs\/boarddice\/\"><strong>Board &amp; Dice<\/strong><\/a> et <a href=\"https:\/\/www.vindjeu.eu\/distributeurs\/pixie-games\/\"><strong>Pixie Games<\/strong><\/a>.  De plus, il a \u00e9t\u00e9 r\u00e9alis\u00e9 par <a href=\"https:\/\/www.vindjeu.eu\/auteurs\/daniele-tascini\/\"><strong>Daniele Tascini<\/strong><\/a>, l&rsquo;auteur de bombes ludiques telles que <a href=\"https:\/\/www.vindjeu.eu\/2018\/12\/21\/teotihuacan-la-cite-des-dieux\/\"><strong>Teotihuacan <\/strong><\/a>bien s\u00fbr mais aussi <a href=\"https:\/\/www.vindjeu.eu\/2013\/03\/11\/tzolkin-the-mayan-calendar\/\"><strong>Tzolkin <\/strong><\/a>(<a href=\"https:\/\/www.vindjeu.eu\/vin-djeu-dlannee\/2013-2\/\"><strong>Vin d&rsquo;jeu d&rsquo;l&rsquo;ann\u00e9e 2013<\/strong><\/a>) et <a href=\"https:\/\/www.vindjeu.eu\/2015\/07\/29\/les-voyages-de-marco-polo\/\"><strong>Les Voyages de Marco Polo<\/strong><\/a>.<\/p>\n\n\n\n<p>Dans Trismegistus, vous allez m\u00e9langer vos ingr\u00e9dients et les transformer pour r\u00e9aliser des formules qui vous feront gagner des bonus et des PVs en fin de partie. Un peu comme dans le <a href=\"https:\/\/www.vindjeu.eu\/2019\/09\/23\/vin-djeu-dlannee-2019\/\">Vin d&rsquo;jeu d&rsquo;l&rsquo;ann\u00e9e<\/a> de cette ann\u00e9e <a href=\"https:\/\/www.vindjeu.eu\/2018\/12\/07\/coimbra\/\"><strong>Coimbra<\/strong><\/a>, le c\u0153ur du jeu est une m\u00e9canique de choix de d\u00e9s mis en commun m\u00eal\u00e9e \u00e0 un syst\u00e8me de points d&rsquo;action.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Les d\u00e9s veulent tout dire<\/h3>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignright is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/12\/2263-Trismegistus-2-1024x683.jpg\" alt=\"\" class=\"wp-image-32950\" style=\"width:566px;height:377px\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/12\/2263-Trismegistus-2-1024x683.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/12\/2263-Trismegistus-2-300x200.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/12\/2263-Trismegistus-2-768x512.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/12\/2263-Trismegistus-2-160x107.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/12\/2263-Trismegistus-2-368x245.jpg 368w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/12\/2263-Trismegistus-2-510x340.jpg 510w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/12\/2263-Trismegistus-2.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<p>Le choix d&rsquo;un d\u00e9 a de multiples cons\u00e9quences. En fonction du nombre de d\u00e9s pr\u00e9sentant la m\u00eame face disponible, on aura plus ou moins de points d&rsquo;action. Si, lorsqu&rsquo;on choisit un d\u00e9, il en reste 4 de la m\u00eame face dans le pot commun, on aura 4 points d&rsquo;action, s&rsquo;il n&rsquo;en reste que 2, on n&rsquo;aura que 2 points d&rsquo;action. Les points d&rsquo;action sont primordiaux et on choisira, bien souvent, un d\u00e9 pr\u00e9sentant une face populaire \ud83d\ude09 Le choix est donc assez simple bien qu&rsquo;il ait de multiples cons\u00e9quences puisque les actions sont fonction de la face et de la couleur du d\u00e9 choisit.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Multifaces &amp; multi-effets<\/h3>\n\n\n\n<p>Avec les d\u00e9s, on va pouvoir r\u00e9aliser pas mal d&rsquo;actions diff\u00e9rentes chacune avec de multiples cons\u00e9quences.  Outre la simple r\u00e9colte de ressources, vous allez pouvoir transformer vos ressources ce qui va engendrer des effets puissants gr\u00e2ce \u00e0 vos art\u00e9facts.  En effet, vous allez \u00e9galement pouvoir acqu\u00e9rir des art\u00e9facts qui vont d\u00e9clencher leurs effets d\u00e8s l&rsquo;acquisition.  Chaque art\u00e9fact apporte des effets diff\u00e9rents qui vont en plus \u00eatre de plus en plus puissants au fil de la partie.  Une fois acquis, on va placer son art\u00e9fact sur un des 6 chemins de transformation de ressources.  A chaque fois qu&rsquo;on transforme une ressource en passant par l&rsquo;artefact, on active l&rsquo;artefact et on le retourne pour indiquer qu&rsquo;on ne pourra plus l&rsquo;utiliser \u00e0 ce tour.  Une action, qu&rsquo;on n\u00e9glige peut \u00eatre trop souvent, permet n\u00e9anmoins de retourner un artefact face visible et donc d&rsquo;actionner son effet plusieurs fois.  Et attention car ces artefacts vont \u00e9galement permettre de r\u00e9aliser d&rsquo;autres actions qui pourront \u00e9galement avoir d&rsquo;autres sous-effets!  Bonjour les combinaisons!<\/p>\n\n\n\n<p>Vous allez \u00e9galement pouvoir acqu\u00e9rir des cartes potion et les r\u00e9aliser contre les ressources exig\u00e9es. Ces potions, une fois construites, vont \u00e9galement apporter de multiples effets qui vont potentiellement pouvoir en d\u00e9clencher d&rsquo;autres. R\u00e9aliser une potion va vous lib\u00e9rer une formule qui va vous donner des habilit\u00e9s \u00ab\u00a0one shot\u00a0\u00bb qui vont se placer dans votre coffre qui, lui-m\u00eame, va vous apporter des actions suppl\u00e9mentaires lorsque chacune de ses lignes et colonnes seront compl\u00e9t\u00e9es.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignleft is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/12\/2263-Trismegistus-4-1024x683.jpg\" alt=\"\" class=\"wp-image-32952\" style=\"width:526px;height:351px\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/12\/2263-Trismegistus-4-1024x683.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/12\/2263-Trismegistus-4-300x200.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/12\/2263-Trismegistus-4-768x512.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/12\/2263-Trismegistus-4-160x107.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/12\/2263-Trismegistus-4-368x245.jpg 368w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/12\/2263-Trismegistus-4-510x340.jpg 510w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/12\/2263-Trismegistus-4.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<h3 class=\"wp-block-heading\">Actions r\u00e9actions<\/h3>\n\n\n\n<p>Outre les multiples actions et leurs multiples cons\u00e9quences, vous allez pouvoir r\u00e9agir aux actions adverses et en profiter.  Autrement dit, m\u00eame si vous choisissez un d\u00e9 au d\u00e9triment d&rsquo;un autre qui vous int\u00e9ressait \u00e9galement, vous allez pouvoir en profiter m\u00eame si un adversaire le choisit gr\u00e2ce \u00e0 votre capacit\u00e9, limit\u00e9e, de r\u00e9action.  Magnifique id\u00e9e.  <\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Ergonomie<\/h3>\n\n\n\n<p>Le d\u00e9faut tr\u00e8s frappant du jeu est son ergonomie. D\u00e9j\u00e0, il est impossible de s&rsquo;en sortir sans une bonne aide de jeu (je vous conseille celle de matg82, pas super jolie mais efficace, que vous pouvez retrouver <strong><a aria-label=\"ici (opens in a new tab)\" href=\"https:\/\/www.boardgamegeek.com\/file\/download_redirect\/6823d26de930697babc23e98ea836e3ee3211b3c1767e06b\/aide_jeu_Trismegistus.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">ici<\/a><\/strong>). Ca n&rsquo;aurait rien co\u00fbt\u00e9 d&rsquo;indiquer les diff\u00e9rentes actions qu&rsquo;on peut faire sur un bord du plateau personnel des joueurs ou m\u00eame sur une carte s\u00e9par\u00e9e. De plus, un rappel de certaines r\u00e8gles sur la mat\u00e9riel aurait \u00e9t\u00e9 judicieux. Quand on transforme une ressource, non seulement on ne doit pas oublier d&rsquo;activer l&rsquo;artefact li\u00e9, mais on doit \u00e9galement d\u00e9penser un \u00e9l\u00e9ment et monter sur une des \u00e9chelles. Ces divers co\u00fbts et effets ne sont indiqu\u00e9s nulle part. Lorsqu&rsquo;on d\u00e9cide de prendre des \u00e9l\u00e9ments ou de transformer des ressources, pour une action, on ne peut prendre que les m\u00eames \u00e9l\u00e9ments ou n&rsquo;utiliser que la m\u00eame fl\u00e8che de transformation. L\u00e0 aussi, aucun rappel de la r\u00e8gle n&rsquo;est disponible, il faut s&rsquo;en souvenir! Les jetons r\u00e9action n&rsquo;indiquent qu&rsquo;un \u00e9clair. Mais on ne peut pas copier toutes les actions, rien ne rappelle quelles actions on peut copier,&#8230; Bref, les r\u00e8gles de Trismegistus L&rsquo;Ultime Formule sont d\u00e9j\u00e0 complexes en soi (elles s&rsquo;expliquent en une heure), un rappel des \u00e9l\u00e9ments essentiels aurait \u00e9t\u00e9 clairement le bienvenu. C&rsquo;est le gros d\u00e9faut du jeu et c&rsquo;est ce qui m&#8217;emp\u00eache de lui donner un dix!<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignright is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/12\/2263-Trismegistus-5-1024x683.jpg\" alt=\"\" class=\"wp-image-32953\" style=\"width:618px;height:412px\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/12\/2263-Trismegistus-5-1024x683.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/12\/2263-Trismegistus-5-300x200.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/12\/2263-Trismegistus-5-768x512.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/12\/2263-Trismegistus-5-160x107.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/12\/2263-Trismegistus-5-368x245.jpg 368w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/12\/2263-Trismegistus-5-510x340.jpg 510w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/12\/2263-Trismegistus-5.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<p>De plus, les r\u00e8gles laissent de multiples incertitudes.  Il y a des contradictions et le plus fort ce sont les ic\u00f4nes qui ne sont pas toutes expliqu\u00e9es.  On va devoir interpr\u00e9ter, ensemble, les tuiles avec plus ou mois de r\u00e9ussite.  <\/p>\n\n\n\n<p>A noter \u00e9galement que tout ceci doit \u00eatre li\u00e9 \u00e0 une grande confiance entre joueuses car il est impossible de v\u00e9rifier ce que chacun fait et si chacun respecte bien toutes les r\u00e8gles (un oubli peut facilement arriver).<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Crescendo<\/h3>\n\n\n\n<p>Mais si on passe outre cette mauvaise ergonomie, Trismegistus est une petite merveille. Vous allez pouvoir augmenter votre capacit\u00e9 de r\u00e9action, augmenter le pouvoir de vos actions, augmenter le pouvoir de vos art\u00e9facts ou de vos potions,&#8230; Trismegistus offre la panoplie compl\u00e8te du parfait jeu expert: une mont\u00e9e en puissance savoureuse, des choix difficiles, des multiples effets pour chaque choix, des combinaisons \u00e0 optimiser, des objectifs priv\u00e9s qui vont dans tous les sens et des pouvoirs asym\u00e9triques qu&rsquo;on va acqu\u00e9rir en cours de partie, tout \u00e7a pour un plaisir ludique \u00e9poustouflant!<\/p>\n\n\n\n<hr class=\"wp-block-separator has-css-opacity is-style-wide\"\/>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignleft\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2016\/09\/Chaps-1-150x150.jpg\" alt=\"\" class=\"wp-image-14812\"\/><\/figure>\n<\/div>\n\n\n<h5 class=\"wp-block-heading\"><span class=\"color\" style=\"color:#0693e3\">Chaps<\/span>:  <span class=\"color\" style=\"color:#cf2e2e\">8\/10<\/span><\/h5>\n\n\n\n<p>Trismegistus a pour moi un tr\u00e8s bon point qui\nest une sensation originale de jeu et beaucoup de strat\u00e9gie. L\u2019utilisation des\nd\u00e9s et le fait que tout soit li\u00e9, le symbole, la couleur, le lieu o\u00f9 on le\nprend sur le plateau principal si on cible une carte exp\u00e9rience&#8230;Vraiment tr\u00e8s\nbien.<\/p>\n\n\n\n<p>En plus je trouve le mat\u00e9riel de tr\u00e8s bonne\nqualit\u00e9, agr\u00e9able \u00e0 manipuler.<\/p>\n\n\n\n<p>Ensuite le syst\u00e8me de transmutation aussi est\nbien trouv\u00e9, on est dans le th\u00e8me on a des m\u00e9caniques originales et toujours\nbeaucoup de strat\u00e9gie. Il faut bien pr\u00e9voir ce que l\u2019on va faire et surtout\noptimiser&nbsp;: d\u00e9clencher des actions en cascade, je valide une carte\nexp\u00e9rience, je prends un cube formule, j\u2019active son bonus, je le pose finis une\nligne et\/ou colonne et je d\u00e9clenche les bonus\u2026 Tr\u00e8s agr\u00e9able d\u2019aboutir \u00e0 cela\nen utilisant toute la richesse m\u00e9canistique du jeu.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignright is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/12\/2263-Trismegistus-7-1024x683.jpg\" alt=\"\" class=\"wp-image-33002\" style=\"width:648px;height:432px\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/12\/2263-Trismegistus-7-1024x683.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/12\/2263-Trismegistus-7-300x200.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/12\/2263-Trismegistus-7-768x512.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/12\/2263-Trismegistus-7-160x107.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/12\/2263-Trismegistus-7-368x245.jpg 368w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/12\/2263-Trismegistus-7-510x340.jpg 510w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/12\/2263-Trismegistus-7.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<p>Mais le jeu est tr\u00e8s tr\u00e8s tendu, nos mat\u00e9riaux\ndisparaissent attention \u00e0 ne pas se retrouver avec 2 pauvres cubes sur son\nplateau, la puissance des cubes file trop vite, beaucoup trop vite, si peu d\u2019actions,\ntellement \u00e0 faire\u2026 <\/p>\n\n\n\n<p>On a l\u2019impression que l\u2019on arrivera \u00e0 rien\nfaire et parfois si l\u2019on s\u2019y prends mal c\u2019est le cas\u2026&nbsp; Cette tension forte personnellement me g\u00e2che\nun peu le plaisir, je pr\u00e9f\u00e8re \u00e0 chaque manche un jeu strat\u00e9gique o\u00f9 je vais\noptimiser mes coups avec des objectifs en t\u00eate, avoir toujours des choses \u00e0\nfaire&nbsp; mais \u00e0 bien faire, sentir une\nconstruction, un moteur qui ronronne de plus en plus fort. Trismegistus fait partie\ndes jeux o\u00f9 je me sens parfois pieds et poings li\u00e9s avec beaucoup de mal \u00e0\narriver \u00e0 me d\u00e9coincer pour finir dans un \u00ab&nbsp;ouf\u2026&nbsp;\u00bb ok j\u2019ai r\u00e9ussi \u00e0\nfaire \u00e7a. Cette \u00ab&nbsp;souffrance&nbsp;\u00bb me plait moins qu\u2019avant je pr\u00e9f\u00e8re\nplonger dans l\u2019ambiance d\u2019un jeu riche o\u00f9 je me sens libre de d\u00e9velopper au\nmieux une strat\u00e9gie, o\u00f9 ce n\u2019est pas facile mais on a moultes chemins \u00e0\nemprunter et \u00e0 nous de bien le faire, avec Trismegistus j\u2019ai trop eu la\nsensation d\u2019\u00eatre coinc\u00e9 et de me dire que je ne vais jamais y arriver. \n\nAu final j\u2019y suis arriv\u00e9 pas trop mal mais la\nfrustration de ramer un tantinet avant de voir le ciel se d\u00e9gager me g\u00e2che un\npeu le plaisir. Long paragraphe car c\u2019est tr\u00e8s personnel et en plus sur une\npremi\u00e8re partie donc avec un jeu que je ne connaissais pas, donc apr\u00e8s d\u2019autres\nparties et une meilleure maitrise peut-\u00eatre que je mettrais de l\u2019eau dans mon\nvin, surtout avec un jeu aux m\u00e9caniques que j\u2019ai trouv\u00e9 originales et donc\nprenantes. Mais en attendant je reste sur un peu trop de\n\u00ab&nbsp;souffrance&nbsp;\u00bb m\u00eame si au final ma partie n\u2019a pas \u00e9t\u00e9 une catastrophe\nen points. Et bien s\u00fbr aujourd\u2019hui la concurrence ludique est si forte que l\u2019on\ndevient exigent\u2026\n\n\n\n<\/p>\n\n\n\n<hr class=\"wp-block-separator has-css-opacity is-style-wide\"\/>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignleft\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2018\/01\/AuteurClansOfCaledonia-150x150.jpg\" alt=\"\" class=\"wp-image-20864\"\/><\/figure>\n<\/div>\n\n\n<h5 class=\"wp-block-heading\"><span class=\"color\" style=\"color:#0693e3\">Philrey<\/span>:<span class=\"color\" style=\"color:#cf2e2e\">    8,5\/10<\/span><\/h5>\n\n\n\n<p>SwatSh et Ren sont revenus de Essen (2019) en annon\u00e7ant que Trismegistus sentait bon \u00ab\u00a0la bombe\u00a0\u00bb ludique. Avec une annonce comme \u00e7a, on ne peut qu&rsquo;\u00eatre impatient d&rsquo;y jouer. Chose faite \ud83d\ude09<\/p>\n\n\n\n<p>Alors, personnellement, je reste un peu mitiger apr\u00e8s notre partie. Je peux \u00e9noncer les \u00e9l\u00e9ments qui m&rsquo;ont s\u00e9duit.<br>Tout d&rsquo;abord, on retrouve les d\u00e9s \u00e0 valeurs multiples et \u00e0 3 couleurs. Ces deux \u00e9l\u00e9ments sont importants car le choix influencera l&rsquo;action que le joueur peut faire. On a d\u00e9j\u00e0 exp\u00e9riment\u00e9 cela dans Coimbra, par exemple.<\/p>\n\n\n\n<p>Ensuite, les actions \u00ab\u00a0r\u00e9action\u00a0\u00bb que l&rsquo;on peut effectuer lors du tour d&rsquo;un adversaire. Il faut \u00e9videmment d\u00e9penser un jeton pour pouvoir le faire mais c&rsquo;est une m\u00e9canique qui permet de \u00ab\u00a0briser\u00a0\u00bb l&rsquo;attente de son tour. Ce que j&rsquo;appr\u00e9cie beaucoup d&rsquo;ailleurs.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignleft is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/12\/2263-Trismegistus-3-1024x683.jpg\" alt=\"\" class=\"wp-image-32951\" style=\"width:599px;height:399px\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/12\/2263-Trismegistus-3-1024x683.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/12\/2263-Trismegistus-3-300x200.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/12\/2263-Trismegistus-3-768x512.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/12\/2263-Trismegistus-3-160x107.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/12\/2263-Trismegistus-3-368x245.jpg 368w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/12\/2263-Trismegistus-3-510x340.jpg 510w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/12\/2263-Trismegistus-3.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<p>Enfin, plusieurs strat\u00e9gies sont possibles. Dans notre partie, tous le monde me voyait bien \u00e0 la ramasse. Mais je gardais l&rsquo;accomplissement de mes objectifs bien secrets. Au d\u00e9compte, je comptabilisait ainsi plus de 50 PVs, \u00e0 la surprise g\u00e9n\u00e9rale. Cela ne m&rsquo;a pas permis de passer en t\u00eate mais bien de finir deuxi\u00e8me, pas loin du tout du vainqueur et distan\u00e7ant de pas mal de points les suivants.<\/p>\n\n\n\n<p>Il faut quand m\u00eame savoir que c&rsquo;est pas mal casse-t\u00eate. En effet, le choix des d\u00e9s avec deux \u00e9l\u00e9ments \u00e0 tenir en compte limiteront vos actions. Il faut donc bien choisir en connaissance de cause. Voir m\u00eame anticiper le choix suivant possible, important aussi pour \u00e9tablir son plan d&rsquo;actions.<\/p>\n\n\n\n<p>En cons\u00e9quence de ce dernier point, le jeu est lent et long. C&rsquo;est pour moi ce qui me d\u00e9range le plus. Pour moi, les quelques derniers tours furent longs car chacun analysait les choix qu&rsquo;il lui restait et calculait les PV \u00e0 gagner pour chacun des choix afin de glaner 1 ou 2 PV de plus. Au final, 4 heures de jeu! Pour ce type de jeu, je trouve cela trop long. On n&rsquo;est quand m\u00eame loin d&rsquo;un jeu de civilisation, r\u00e9put\u00e9s \u00eatre longs.<\/p>\n\n\n\n<p>En conclusion, Trismegistus offre beaucoup de plaisir ludique pour les gamers qui aiment se torturer un peu les m\u00e9ninges. Beaucoup de m\u00e9caniques, m\u00eame si pas toutes innovantes, s&rsquo;entre-m\u00eale pour offrir une belle coh\u00e9rence. Je referai volontiers une nouvelle partie, ce qui est un bon signe, pour essayer une autre strat\u00e9gie et pour voir si on peut r\u00e9duire la dur\u00e9e d&rsquo;une partie.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-css-opacity is-style-wide\"\/>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignleft\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/10\/2019-10-23-13.39.14-1-e1572207242544-150x150.jpg\" alt=\"\" class=\"wp-image-32076\"\/><\/figure>\n<\/div>\n\n\n<h5 class=\"wp-block-heading\"><span class=\"color\" style=\"color:#0693e3\">Ren<\/span>:<span class=\"color\" style=\"color:#cf2e2e\"> 9\/10<\/span><\/h5>\n\n\n\n<p>Trismegistus,\nrien que le nom annonce la couleur&nbsp;: on n\u2019est pas l\u00e0 pour rigoler. Avant\nde commencer \u00e0 jouer il va d\u2019abord falloir apprendre \u00e0 prononcer le nom du jeu.\nC\u2019est parfaitement \u00e0 l\u2019image du jeu&nbsp;: avant de jouer il va falloir\ncommencer par apprendre les r\u00e8gles, les comprendre et puis ne pas les oublier (on\nva revenir sur ce dernier point plus bas\u2026).<\/p>\n\n\n\n<p>Pas l\u00e0 pour rigoler&nbsp;? Ben oui, dans Trismegistus on va r\u00e9colter des ingr\u00e9dients, les transformer puis les assembler pour gagner des points de victoire de diff\u00e9rentes mani\u00e8res. Et autant vous pr\u00e9venir tout de suite, on n\u2019est pas dans du Party Game. On est dans du gamer de comp\u00e9tition, du lourd, du velu, du cors\u00e9. Avec une pointe de gingembre et un zeste de piment d\u2019espelette.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"color\" style=\"color:#0693e3\">3 tours, 3 choix par tour, simple! La bonne blague&#8230;<\/span><\/h3>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignright is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/12\/2263-Trismegistus-6-1024x683.jpg\" alt=\"\" class=\"wp-image-32955\" style=\"width:710px;height:473px\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/12\/2263-Trismegistus-6-1024x683.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/12\/2263-Trismegistus-6-300x200.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/12\/2263-Trismegistus-6-768x512.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/12\/2263-Trismegistus-6-160x107.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/12\/2263-Trismegistus-6-368x245.jpg 368w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/12\/2263-Trismegistus-6-510x340.jpg 510w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/12\/2263-Trismegistus-6.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<p>Le jeu se\njoue en 3 tours. Et \u00e0 chaque tour chaque joueuse va choisir 3 d\u00e9s, point \u00e0 la\nligne. C\u2019est tout&nbsp;? C\u2019est tout. \u00ab&nbsp;Ben le jeu est super court alors&nbsp;?&nbsp;\u00bb\nHa non pas vraiment\u2026 Ces 3 d\u00e9s vont vous ouvrir une multitude de possibilit\u00e9s. Les\nd\u00e9s ont en effet 3 couleurs diff\u00e9rentes, des symboles diff\u00e9rents, et sont en\nnombre diff\u00e9rent (selon le nombre de d\u00e9s, tir\u00e9s au hasard au d\u00e9but de chaque\ntour, qui ont le m\u00eame symbole). Et ces diff\u00e9rentes caract\u00e9ristiques vont\nd\u00e9terminer ce que vous allez pouvoir faire.<\/p>\n\n\n\n<p>Le nombre\nde d\u00e9s ayant le m\u00eame symbole (au moment o\u00f9 vous choisissez le d\u00e9) va d\u00e9terminer\nla force de votre d\u00e9. Si vous prenez un d\u00e9 d\u2019un pot o\u00f9 il y en avait 4, votre\nd\u00e9 aura une force de 4. Ce qui signifie que vous pourrez faire 4 fois une\naction de force 1 li\u00e9e au d\u00e9, ou une fois une action de force 4 li\u00e9e au d\u00e9. Ou\ntoute autre combinaison de votre choix.<\/p>\n\n\n\n<p>La couleur\ndu d\u00e9 va d\u00e9terminer quelles transformations de ressources vous pourrez\neffectuer.<\/p>\n\n\n\n<p>Le symbole\ndu d\u00e9 va d\u00e9terminer quelles ressources vous pouvez r\u00e9colter et quelle potion\nvous pouvez acqu\u00e9rir (potion que vous pourrez r\u00e9aliser en d\u00e9pensant les ressources\nad\u00e9quates).<\/p>\n\n\n\n<p>Ce m\u00e9canisme de choix de d\u00e9s est tout \u00e0 fait succulent, il y a une tension de ouf \u00e0 chaque tour vu les possibilit\u00e9s multiples qui sont offertes. Et l\u2019interaction, si elle n\u2019est pas dingue, est quand m\u00eame pr\u00e9sente car il faut jeter un \u0153il aux plateaux des autres joueuses pour essayer de deviner ce dont elles ont besoin. Et si on peut piquer un d\u00e9 crucial sous le nez de son adversaire, on ne va pas se priver.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"color\" style=\"color:#0693e3\">Ok pas si simple. Mais quand m\u00eame simple! La bonne blague&#8230;<\/span><\/h3>\n\n\n\n<p>Bon ok super\non choisit des d\u00e9s, avec des possibilit\u00e9s multiples, mais on ne choisit\ntoujours que 3 d\u00e9s par tour, donc le jeu sera court alors&nbsp;? Ha non pas\nvraiment, car il y a encore beaucoup, beaucoup d\u2019autres choses \u00e0 dire\u2026<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignleft is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/12\/2263-Trismegistus-8.1-1024x683.jpg\" alt=\"\" class=\"wp-image-33167\" style=\"width:647px;height:431px\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/12\/2263-Trismegistus-8.1-1024x683.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/12\/2263-Trismegistus-8.1-300x200.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/12\/2263-Trismegistus-8.1-768x512.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/12\/2263-Trismegistus-8.1-160x107.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/12\/2263-Trismegistus-8.1-368x245.jpg 368w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/12\/2263-Trismegistus-8.1-510x340.jpg 510w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/12\/2263-Trismegistus-8.1.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<p>Tout d\u2019abord\nles artefacts. On va pouvoir acqu\u00e9rir des artefacts, qu\u2019on va placer autour de\nson plateau personnel, le long des routes de transformation de ressources.\nChaque fois (une fois par tour en fait, car on retourne l\u2019artefact une fois\nutilis\u00e9, mais on peut utiliser une action pour le remettre sur sa face\nutilisable) qu\u2019on transformer les ressources en question, on b\u00e9n\u00e9ficiera de l\u2019effet\nde l\u2019artefact.<\/p>\n\n\n\n<p>Les potions\nensuite. On pourra acqu\u00e9rir des cartes potions pendant la partie (en fonction du\nsymbole du d\u00e9 choisi). Une fois r\u00e9alis\u00e9es (en fournissant les ingr\u00e9dients ad\nhoc) les potions ont un double effet&nbsp;: elles donnent un ou des bonus\nimm\u00e9diats. Et elles d\u00e9bloquent \u00e9ventuellement des formules. Formules qui donnent\nun bonus \u00e0 utiliser quand vous le souhaitez. Et formules que vous allez placer\ndans votre coffre, sur votre plateau personnel. Et une fois que vous remplissez\ndes lignes et colonnes dans votre coffre (un peu comme les livres dans Newton),\nvous obtiendrez d\u2019autres bonus&nbsp;! A noter que chaque joueuse a un coffre\ndiff\u00e9rent (i.e. avec des bonus diff\u00e9rents), ce qui augmente la rejouabilit\u00e9 (pas\nqu\u2019il y avait un stress \u00e0 ce sujet, rassurez-vous\u2026).<\/p>\n\n\n\n<p>Chaque\njoueuse a aussi des jetons r\u00e9action instantan\u00e9e, qui vont permettre de copier\nune action jou\u00e9e par une autre joueuse. Il y a \u00e9galement dans le jeu des jetons\nde modification de d\u00e9s, qui permettent d\u2019augmenter la force d\u2019un d\u00e9 choisi. On peut\nen recevoir plus via des bonus.<\/p>\n\n\n\n<p>Il faut\n\u00e9galement mentionner les pistes d\u2019\u00e9l\u00e9ments. Les symboles sont li\u00e9s \u00e0 des \u00e9l\u00e9ments.\nEn fonction de certaines actions vous allez \u00e9voluer sur ces diff\u00e9rentes pistes\nd\u2019\u00e9l\u00e9ments. Dans chaque piste il y a une course pour des bonus, la premi\u00e8re\njoueuse qui atteint le niveau requis re\u00e7oit le bonus. Et \u00e0 la fin de la partie\nces pistes permettent de marquer des points en fonction du niveau atteint.<\/p>\n\n\n\n<p>Et last but\nnot least (\u00e0 mentionner vu que nous sommes dans un jeu d\u2019alchimiste), on peut arriver\n\u00e0 produire de l\u2019or, or qui sera un joker pour n\u2019importe quelle mati\u00e8re, qui\nsera n\u00e9cessaire pour certaines potions, ou qui vaudra des points \u00e0 la fin de la\npartie.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignright is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/12\/2263-Trismegistus-8-1024x683.jpg\" alt=\"\" class=\"wp-image-33168\" style=\"width:660px;height:440px\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/12\/2263-Trismegistus-8-1024x683.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/12\/2263-Trismegistus-8-300x200.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/12\/2263-Trismegistus-8-768x512.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/12\/2263-Trismegistus-8-160x107.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/12\/2263-Trismegistus-8-368x245.jpg 368w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/12\/2263-Trismegistus-8-510x340.jpg 510w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/12\/2263-Trismegistus-8.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<p>A la fin de la partie on marque des points pour les potions r\u00e9alis\u00e9es, pour l\u2019avanc\u00e9e de compl\u00e9tude de son coffre, pour les cartes objectifs (personnelles), pour son avanc\u00e9e sur les pistes d\u2019\u00e9l\u00e9ments\u2026<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"color\" style=\"color:#0693e3\">Finie la bonne blague!<\/span><\/h3>\n\n\n\n<p>Et&nbsp;? Et\ntout \u00e7a nous donne un br\u00fble-neurones de premi\u00e8re cat\u00e9gorie. Les possibilit\u00e9s sont\nimmenses \u00e0 chaque tour, les choix corn\u00e9liens. Oui il n\u2019y a que 3 tours o\u00f9 on\nchoisit 3 d\u00e9s. Mais comme vous l\u2019avez maintenant compris ces 3 tours avec 3\nchoix de d\u00e9s ouvrent 13977676576358762972987029808928092809280982092802098209809280982092809220\ncombinaisons diff\u00e9rentes&nbsp;!!! Combo. Maxi combo. Gold combo. Platinum\ncombo. Combo interstellaire. You name it.<\/p>\n\n\n\n<p>Il y a 2 d\u00e9fauts\n\u00e9vidents au jeu. Ou plut\u00f4t un d\u00e9faut et un point faible. Le point faible est li\u00e9\nau paragraphe pr\u00e9c\u00e9dent&nbsp;: les possibilit\u00e9s sont gigantesques. Et le choix\ndes autres (\u00ab&nbsp;elle vient de piquer le d\u00e9 que je voulais&nbsp;\u00bb) a un\nimpact direct sur son jeu et ses choix. Du coup les tours de jeu peuvent \u00eatre\ntr\u00e8\u00e8\u00e8\u00e8\u00e8\u00e8\u00e8\u00e8\u00e8\u00e8\u00e8\u00e8s longs. C\u2019est un jeu o\u00f9 il est quasi impossible de jouer vite\n(sauf \u00e0 vouloir jouer n\u2019importe comment, mais dans ce cas cela n\u2019a aucun\nint\u00e9r\u00eat). Du coup les parties peuvent \u00eatre loooooooongues. Je n\u2019ai aucun souci\navec les jeux longs. Mais ici l\u2019attente entre les tours m\u2019a parfois l\u00e9g\u00e8rement pes\u00e9.<\/p>\n\n\n\n<p>Et le\nd\u00e9faut est bien \u00e9videmment l\u2019iconographie et les rappels des r\u00e8gles. Dans les deux\ncas c\u2019est poussif ou inexistant. Et totalement insuffisant pour un jeu qui sort\nen 2019.<\/p>\n\n\n\n<p>Mais si\nvous \u00eates une joueuse velue, ces d\u00e9faut et faiblesse ne doivent en aucun cas\nvous emp\u00eacher de jouer \u00e0 ce jeu qui pour le reste est clairement une bombe\nludique. Les choix sont immenses comme d\u00e9j\u00e0 dit. Les combos sont l\u00e9gion, et\nsurtout (ce qui est pour moi une grande qualit\u00e9) pas du tout \u00e9videntes d\u00e8s la\npremi\u00e8re partie. Vu la vari\u00e9t\u00e9 des possibilit\u00e9s et des mani\u00e8res de marquer des\npoints, il sera tr\u00e8s compliqu\u00e9 (sauf si vous \u00eates une g\u00e9nie) de comprendre\nimm\u00e9diatement comment combiner les diff\u00e9rents choix pour marquer le maximum de points.\nDonc il y a une grande courbe d\u2019apprentissage. Dans le jeu en lui-m\u00eame il y a\nune mont\u00e9e en puissance d\u00e9licieuse. Premi\u00e8re action, premier tour&nbsp;: vous\nr\u00e9coltez gentiment des ressources. Troisi\u00e8me tour&nbsp;: vous claquez une\npotion \u00e0 15 points.<\/p>\n\n\n\n<p>Trismegistus,\nun jeu long, mais booooooooon&nbsp;!!!<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignleft size-thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/05\/Clem-1-150x150.png\" alt=\"\" class=\"wp-image-57851\"\/><\/figure>\n<\/div>\n\n\n<h5 class=\"wp-block-heading\"><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-cyan-blue-color\">Clem<\/mark> :<mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-red-color\"> 8,5\/10<\/mark><\/h5>\n\n\n\n<p>Je profite de cet avis pour remettre en lumi\u00e8re ce superbe jeu qu&rsquo;est Trimegistus !! Et bonne nouvelle, visiblement une r\u00e9-\u00e9dition a \u00e9t\u00e9 annonc\u00e9e lors du dernier Spiel \u00e0 Essen pour 2025 avec un passage par le financement participatif (KS). On peut donc esp\u00e9rer que cette nouvelle mouture gomme les probl\u00e8mes d&rsquo;\u00e9dition de la version initiale et ajoute quelques modules compl\u00e9mentaires&#8230; Affaire \u00e0 suivre ;-).<\/p>\n\n\n\n<p>Bref, pour revenir \u00e0 mon avis, j&rsquo;\u00e9tais ravi de pouvoir rejouer r\u00e9cemment \u00e0 Trismegistus. M\u00eame si c&rsquo;est un titre qui ravi les eurogamers (dont je fais partie), il n&rsquo;est tout de m\u00eame pas exempt de quelques petits d\u00e9fauts, hormis les probl\u00e8mes d&rsquo;\u00e9dition dont j&rsquo;ai d\u00e9j\u00e0 fait mention.<\/p>\n\n\n\n<p>En effet, il y a certainement plusieurs mani\u00e8res d&rsquo;op\u00e9rer dans Trismegistus mais pour esp\u00e9rer jouer la victoire, il faut absolument tout d\u00e9bloquer, monter au maximum de toutes les pistes, jouer tous les types de potions et lib\u00e9rer 3 bonus avec de l&rsquo;or pour remplir compl\u00e8tement le plateau central. Pour cela, il faut optimiser chaque action. Avoir un maximum d&rsquo;actions bonus pendant le tour des autres joueurs. Forc\u00e9ment, c&rsquo;est un jeu tr\u00e8s exigeant qui semble r\u00e9server aux joueurs experts les plus inv\u00e9t\u00e9r\u00e9s. Sans cette exigence lors des parties, Trismegistus se r\u00e9v\u00e8le extr\u00eamement punitif et les \u00e9carts de points \u00e0 la fin de la partie peuvent \u00eatre \u00e9normes&#8230;  <br>D&rsquo;autre part, je ne me rappelai plus que le hasard jouait son petit r\u00f4le \u00e9galement et notamment lors du tirage en d\u00e9but de partie des objectifs communs qui peuvent \u00eatre largement favorables \u00e0 un joueur lorsqu&rsquo;ils matchent avec son artefact et sa carte de d\u00e9part. Le hasard joue \u00e9galement un petit r\u00f4le dans le tirage des cartes objectifs, mais c&rsquo;est moins marqu\u00e9 \u00e0 mon sens.<\/p>\n\n\n\n<p>Au final, m\u00eame si Trismegistus n&rsquo;est pas le jeu de Mister T que je pr\u00e9f\u00e8re, il reste un excellent eurogame auquel il est plaisant de se confronter de temps en temps.  <\/p>\n\n\n\n<hr class=\"wp-block-separator has-css-opacity is-style-wide\"\/>\n\n\n\n<figure class=\"wp-block-image alignfull\"><img loading=\"lazy\" decoding=\"async\" width=\"1320\" height=\"880\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/12\/2263-Trismegistus-9.jpg\" alt=\"\" class=\"wp-image-32946\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/12\/2263-Trismegistus-9.jpg 1320w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/12\/2263-Trismegistus-9-300x200.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/12\/2263-Trismegistus-9-768x512.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/12\/2263-Trismegistus-9-1024x683.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/12\/2263-Trismegistus-9-160x107.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/12\/2263-Trismegistus-9-368x245.jpg 368w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/12\/2263-Trismegistus-9-510x340.jpg 510w\" sizes=\"auto, (max-width: 1320px) 100vw, 1320px\" \/><\/figure>\n\n\n\n<hr class=\"wp-block-separator has-css-opacity is-style-wide\"\/>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"color\" style=\"color:#f78da7\">Vin d&rsquo;jeu d&rsquo;vid\u00e9o<\/span><\/h2>\n\n\n\n<h4 class=\"wp-block-heading\">La bouteille de Chaps en 51 minutes<\/h4>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"video-container\"><iframe loading=\"lazy\" title=\"Trismegistus : Explication et analyse du jeu\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/vZBXGWByaKM?feature=oembed&#038;wmode=opaque\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p> Avec Barrage, Trismegistus est certainement un des meilleurs si pas le meilleur jeu sorti \u00e0 Essen cette ann\u00e9e! Bon, on n&rsquo;a pas encore su jouer \u00e0 tous les jeux int\u00e9ressants, il nous manque encore Maracaibo, Dreamscape, Cooper Island et The Magnificent mais l&rsquo;\u00e9tau se resserre \ud83d\ude09 D\u00e9j\u00e0 sur&#46;&#46;&#46;<\/p>\n","protected":false},"author":3,"featured_media":32947,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[4849],"tags":[6,323,7],"class_list":["post-32945","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-expert","tag-philrey212","tag-ren","tag-swatsh","annee-2083","auteurs-daniele-tascini","auteurs-federico-pierlorenzi","editeurs-boarddice","editeurs-pixie-games","illustrateurs-paulina-wach","illustrateurs-pawel-niziolek","distributeurs-pixie-games","mecanismes-asymetrie-construite","mecanismes-asymetrie-de-depart","mecanismes-points-daction"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/32945","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/comments?post=32945"}],"version-history":[{"count":2,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/32945\/revisions"}],"predecessor-version":[{"id":60056,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/32945\/revisions\/60056"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media\/32947"}],"wp:attachment":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media?parent=32945"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/categories?post=32945"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/tags?post=32945"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}