{"id":33218,"date":"2020-01-05T21:33:20","date_gmt":"2020-01-05T20:33:20","guid":{"rendered":"https:\/\/www.vindjeu.eu\/?p=33218"},"modified":"2020-01-05T21:33:43","modified_gmt":"2020-01-05T20:33:43","slug":"coloma","status":"publish","type":"post","link":"https:\/\/www.vindjeu.eu\/prd\/2020\/01\/05\/coloma\/","title":{"rendered":"Coloma"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/09\/coloma.png\" alt=\"\" class=\"wp-image-31213\" width=\"484\" height=\"484\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/09\/coloma.png 900w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/09\/coloma-150x150.png 150w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/09\/coloma-300x300.png 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/09\/coloma-768x768.png 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/09\/coloma-160x160.png 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/09\/coloma-245x245.png 245w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/09\/coloma-340x340.png 340w\" sizes=\"auto, (max-width: 484px) 100vw, 484px\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/10\/2019-10-23-15.15.22-e1572208476982-150x150.jpg\" alt=\"\" class=\"wp-image-32085\"\/><\/figure><\/div>\n\n\n\n<h5 class=\"wp-block-heading\"><span class=\"color\" style=\"color:#0693e3\">SwatSh<\/span>: <span class=\"color\" style=\"color:#cf2e2e\"> 8\/10<\/span><\/h5>\n\n\n\n<p>Coloma est le dernier n\u00e9 de <a href=\"https:\/\/www.vindjeu.eu\/editeurs\/final-frontier-games\/\"><strong>Final Frontier Games<\/strong><\/a> qui pr\u00e9sente une ligne \u00e9ditoriale particuli\u00e8rement bien illustr\u00e9e par <a href=\"https:\/\/www.vindjeu.eu\/illustrateurs\/mihajlo-dimitrievski\/\"><strong>Mihajlo Dimitrievski<\/strong><\/a> avec <a href=\"https:\/\/www.vindjeu.eu\/2018\/04\/06\/rise-to-nobility\/\"><strong>Rise to Nobility<\/strong><\/a>, <a href=\"https:\/\/www.vindjeu.eu\/2019\/02\/22\/robin-hood-and-the-merry-men\/\"><strong>Robin Hood<\/strong><\/a> ou <a href=\"https:\/\/www.vindjeu.eu\/2018\/01\/03\/cavern-tavern\/\"><strong>Cavern Tavern<\/strong><\/a> par exemple.  Et Coloma ne t\u00e2che pas tant il est beau, tr\u00e8s bien iconographi\u00e9 et au mat\u00e9riel splendide.<\/p>\n\n\n\n<p>La m\u00e9canique centrale de Coloma est une m\u00e9canique de choix d&rsquo;action simultan\u00e9. Les joueurs vont s\u00e9lectionner secr\u00e8tement l&rsquo;action qu&rsquo;ils vont r\u00e9aliser puis d\u00e9voiler leur choix et placer leur Meeple sur l&rsquo;action d\u00e9sir\u00e9e. On va alors d\u00e9placer la croix sur l&rsquo;action o\u00f9 se trouvent le plus de meeples. En cas d&rsquo;\u00e9galit\u00e9, la croix ne bouge pas. Chaque action est double en fait. Elle correspond \u00e0 2 actions. Si la croix s&rsquo;est d\u00e9plac\u00e9e sur votre case d&rsquo;action, vous ne pourrez donc plus que r\u00e9aliser une des 2 actions pr\u00e9vues. C&rsquo;est assez punitif et \u00e7a d\u00e9pend beaucoup des choix de vos adversaires qu&rsquo;il va falloir pr\u00e9voir donc. Ce ne sera <br>pas une t\u00e2che \u00e9vidente vous vous en doutez surtout lorsque du double guessing (je pense que tu vas faire \u00e7a donc je vais faire \u00e7a mais si tu penses que je pense \u00e7a tu vas alors peut \u00eatre faire \u00e7a, alors il vaut mieux que je fasse \u00e7a sauf si tu te dis que je pense \u00e7a \ud83d\ude42 ) va intervenir. Bref, une p\u00e9nalit\u00e9 de la moiti\u00e9 d&rsquo;une action est assez s\u00e9v\u00e8re mais \u00e7a aurait pu \u00eatre pire (ne pas r\u00e9aliser d&rsquo;action du tout). Cela va d\u00e9pendre des choix de vos adversaires que vous aurez beaucoup de mal \u00e0 pr\u00e9voir et donc du hasard. C&rsquo;est le plus grand \u00e9cueil que l&rsquo;on puisse faire \u00e0 Coloma car le reste est tr\u00e8s bon.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/01\/2286-Coloma-2-1024x683.jpg\" alt=\"\" class=\"wp-image-33417\" width=\"768\" height=\"512\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/01\/2286-Coloma-2-1024x683.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/01\/2286-Coloma-2-300x200.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/01\/2286-Coloma-2-768x512.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/01\/2286-Coloma-2-160x107.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/01\/2286-Coloma-2-368x245.jpg 368w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/01\/2286-Coloma-2-510x340.jpg 510w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/01\/2286-Coloma-2.jpg 1080w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure><\/div>\n\n\n\n<p>Avec vos actions, vous allez pouvoir r\u00e9colter des ressources et les d\u00e9penser pour construire des b\u00e2timents qui apporteront des petits bonus \u00e0 vos actions.  Vous allez \u00e9galement pouvoir construire des ponts qui repr\u00e9sentent des fa\u00e7ons de scorer suppl\u00e9mentaires.  Vous devrez \u00e9galement \u0153uvrer pour le bien de la communaut\u00e9 en la d\u00e9fendant contre les hors la loi o\u00f9 un syst\u00e8me de majorit\u00e9 r\u00e9compensera les plus courageux et p\u00e9nalisera les mauviettes \ud83d\ude09<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignright is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/01\/2286-Coloma-3.jpg\" alt=\"\" class=\"wp-image-33418\" width=\"586\" height=\"391\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/01\/2286-Coloma-3.jpg 1080w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/01\/2286-Coloma-3-300x200.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/01\/2286-Coloma-3-768x512.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/01\/2286-Coloma-3-1024x683.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/01\/2286-Coloma-3-160x107.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/01\/2286-Coloma-3-368x245.jpg 368w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/01\/2286-Coloma-3-510x340.jpg 510w\" sizes=\"auto, (max-width: 586px) 100vw, 586px\" \/><\/figure><\/div>\n\n\n\n<p>La roue d&rsquo;action pr\u00e9sentant les 5 actions possibles a \u00e9galement un syst\u00e8me de cache qui va rendre une action impossible \u00e0 chaque tour.  Le syst\u00e8me est ing\u00e9nieux mais je l&rsquo;ai trouv\u00e9 trop restrictif car il r\u00e9duit le nombre d&rsquo;actions et donc les choix.  Si la roue permettait, \u00e0 la base, plus d&rsquo;actions, 6 ou 7 par exemple, je pense que ce syst\u00e8me de cache y aurait toute sa place.  Ici malheureusement, il a plut\u00f4t un r\u00f4le d&rsquo;orientation et les joueuses vont se voire forcer de r\u00e9aliser certaines actions \u00e0 des moments pr\u00e9cis.<\/p>\n\n\n\n<p>Malgr\u00e9 un syst\u00e8me de choix d&rsquo;action faisant place au hasard et une m\u00e9canique restrictive rendant les actions possibles trop limit\u00e9es et fort dirig\u00e9es, Coloma est tr\u00e8s plaisant gr\u00e2ce \u00e0 ses nombreux b\u00e2timents apportant des bonus en tout genre \u00e0 vos actions.  De plus, son syst\u00e8me de pont offrant des moyens de scorer suppl\u00e9mentaires apporte une belle profondeur et de nombreuses strat\u00e9gies au jeu.  Son th\u00e8me du far ouest et de sa ru\u00e9e vers lors est tr\u00e8s bien retranscrit et contribue pleinement, avec le superbe mat\u00e9riel et les magnifiques illustrations, au plaisir du jeu.  <\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/01\/2286-Coloma-4-1024x683.jpg\" alt=\"\" class=\"wp-image-33419\" width=\"768\" height=\"512\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/01\/2286-Coloma-4-1024x683.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/01\/2286-Coloma-4-300x200.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/01\/2286-Coloma-4-768x512.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/01\/2286-Coloma-4-160x107.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/01\/2286-Coloma-4-368x245.jpg 368w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/01\/2286-Coloma-4-510x340.jpg 510w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/01\/2286-Coloma-4.jpg 1080w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure><\/div>\n\n\n\n<hr class=\"wp-block-separator is-style-wide\"\/>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2016\/10\/Phil-2-e1477137058207-150x150.jpg\" alt=\"\" class=\"wp-image-15196\"\/><\/figure><\/div>\n\n\n\n<h5 class=\"wp-block-heading\"><span class=\"color\" style=\"color:#0693e3\">PhilRey<\/span>:<span class=\"color\" style=\"color:#cf2e2e\">     7,5\/10<\/span><\/h5>\n\n\n\n<p><br><\/p>\n\n\n\n<p>Coloma est vraiment magnifiquement illustr\u00e9, il donne vraiment envie d\u2019y jouer. Le mat\u00e9riel est \u00e9galement de premi\u00e8re qualit\u00e9 avec les jetons style \u00ab&nbsp;jeton poker&nbsp;\u00bb pour repr\u00e9senter l\u2019argent. Les p\u00e9pites d\u2019or bien \u00ab&nbsp;sculpt\u00e9es&nbsp;\u00bb donnent un bel effet sur le plateau. Comme l\u2019a mentionn\u00e9 SwatSh (et contrairement \u00e0 ce que j\u2019ai dit dans la vid\u00e9o de d\u00e9gustation, me semble-t-il), Coloma est un jeu de programmation simultan\u00e9e. Pour ce faire, on utilise une petite roue sur laquelle le joueur indique le num\u00e9ro de l\u2019action qu\u2019il veut effectuer. Les joueurs r\u00e9v\u00e8lent alors leurs choix respectifs et place leur pion sur l\u2019action choisie de la roue.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/01\/2286-Coloma-5-1024x683.jpg\" alt=\"\" class=\"wp-image-33420\" width=\"768\" height=\"512\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/01\/2286-Coloma-5-1024x683.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/01\/2286-Coloma-5-300x200.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/01\/2286-Coloma-5-768x512.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/01\/2286-Coloma-5-160x107.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/01\/2286-Coloma-5-368x245.jpg 368w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/01\/2286-Coloma-5-510x340.jpg 510w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/01\/2286-Coloma-5.jpg 1080w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure><\/div>\n\n\n\n<p>Et parlons en de cette roue du plateau central. Pour continuer dans la qualit\u00e9 du mat\u00e9riel, pas de montage. Un syst\u00e8me d\u2019aimant fait magnifiquement l\u2019affaire et permet la rotation de la partie centrale de la roue. Nickel!<\/p>\n\n\n\n<p>Ce syst\u00e8me de programmation et de roue combin\u00e9es est vraiment sympa. En effet, une action sera indisponible \u00e0 chaque tour. Les joueurs devront en tenir compte lors de leur choix et avoir une \u00ab&nbsp;vision&nbsp;\u00bb plus long terme pour \u00e9viter de \u00ab&nbsp;perdre&nbsp;\u00bb une action importante par la suite.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/01\/2286-Coloma-6-1024x683.jpg\" alt=\"\" class=\"wp-image-33421\" width=\"612\" height=\"408\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/01\/2286-Coloma-6-1024x683.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/01\/2286-Coloma-6-300x200.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/01\/2286-Coloma-6-768x512.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/01\/2286-Coloma-6-160x107.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/01\/2286-Coloma-6-368x245.jpg 368w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/01\/2286-Coloma-6-510x340.jpg 510w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/01\/2286-Coloma-6.jpg 1080w\" sizes=\"auto, (max-width: 612px) 100vw, 612px\" \/><\/figure><\/div>\n\n\n\n<p>Les illustrations rendent bien le th\u00e8me: d\u00e9couverte du premier (ou un des premiers) filon d\u2019or \u00e0 Coloma, dans l\u2019ouest des Etats-Unis, provoquant, on imagine, la ru\u00e9e vers l\u2019or. La pelle et la brouette sont deux symboles qui indiquent la r\u00e9colte de ressources et autres bonus, la scie et le marteau indiquent la possibilit\u00e9 de construire (des b\u00e2timents), l\u2019un exigeant un paiement en dollars et l\u2019autre en p\u00e9pites d\u2019or.<\/p>\n\n\n\n<p>Les actions respectent \u00e9galement le th\u00e8me: fouille de rivi\u00e8res, construire des b\u00e2timents, explorer les alentours de Coloma avec sa diligence, installer des campements et envoyer ses cowboys d\u00e9fendre Coloma contre des hors-la-loi, etc. <\/p>\n\n\n\n<p>Parlant des hors-la-loi, la derni\u00e8re phase de chaque ann\u00e9e repr\u00e9sente une fusillade entre ces derniers et les cowboys des joueurs. Les plus impliqu\u00e9s pourront gagner des PVs\/ressources, les moins impliqu\u00e9s risquent de perdre des cowboys et ceux pas impliqu\u00e9s du tout en perdront certainement.<\/p>\n\n\n\n<p>Par contre, on aurait aim\u00e9 peut-\u00eatre un peu moins de hasard lors de la s\u00e9lection de l\u2019action. En effet, si plusieurs joueurs choisissent le m\u00eame num\u00e9ro d\u2019action, une des deux actions disponible risque de devenir indisponible. Dans une partie \u00e0 2 joueurs, cela est g\u00e9r\u00e9 via des cartes et un troisi\u00e8me pion \u00ab&nbsp;neutre&nbsp;\u00bb. A plus de 4 joueurs, ce sera sans plus rare q\u2019un joueur se retrouve seul sur un case action. En soi, ce n\u2019est pas trop g\u00eanant puisque la r\u00e8gle est la m\u00eame pour tous le monde et que chaque joueur en tiendra sans doute compte dans ses choix, mais \u00e7a peut d\u00e9plaire \u00e0 certains de ne pas compl\u00e8tement ma\u00eetriser ses actions.<\/p>\n\n\n\n<hr class=\"wp-block-separator is-style-wide\"\/>\n\n\n\n<figure class=\"wp-block-image alignfull\"><img loading=\"lazy\" decoding=\"async\" width=\"1380\" height=\"920\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/12\/2286-Coloma-12.jpg\" alt=\"\" class=\"wp-image-33219\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/12\/2286-Coloma-12.jpg 1380w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/12\/2286-Coloma-12-300x200.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/12\/2286-Coloma-12-768x512.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/12\/2286-Coloma-12-1024x683.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/12\/2286-Coloma-12-160x107.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/12\/2286-Coloma-12-368x245.jpg 368w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/12\/2286-Coloma-12-510x340.jpg 510w\" sizes=\"auto, (max-width: 1380px) 100vw, 1380px\" \/><\/figure>\n\n\n\n<hr class=\"wp-block-separator is-style-wide\"\/>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"color\" style=\"color:#f78da7\">Vin d&rsquo;jeu d&rsquo;vid\u00e9o<\/span><\/h2>\n\n\n\n<h4 class=\"wp-block-heading\">L&rsquo;explication des r\u00e8gles d\u00e9gust\u00e9es par Philrey<\/h4>\n\n\n\n<figure class=\"wp-block-embed-youtube wp-block-embed is-type-video is-provider-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"video-container\"><iframe loading=\"lazy\" title=\"Coloma (Vin d&#039;jeu d&#039;vid\u00e9o)\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/S_TGqLqGfFo?feature=oembed&#038;wmode=opaque\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<\/div><\/figure>\n\n\n\n<hr class=\"wp-block-separator is-style-wide\"\/>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"color\" style=\"color:#f78da7\">Vin d&rsquo;jeu d&rsquo;music<\/span><\/h2>\n\n\n\n<figure class=\"wp-block-embed-youtube wp-block-embed is-type-video is-provider-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"video-container\"><iframe loading=\"lazy\" title=\"Zwangere Guy - NIEMAND (PROD. YUNG UMBRO) [Official Video]\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/bZ0DYsNLV7E?feature=oembed&#038;wmode=opaque\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p> Coloma est le dernier n\u00e9 de Final Frontier Games qui pr\u00e9sente une ligne \u00e9ditoriale particuli\u00e8rement bien illustr\u00e9e par Mihajlo Dimitrievski avec Rise to Nobility, Robin Hood ou Cavern Tavern par exemple. Et Coloma ne t\u00e2che pas tant il est beau, tr\u00e8s bien iconographi\u00e9 et au mat\u00e9riel splendide. La&#46;&#46;&#46;<\/p>\n","protected":false},"author":3,"featured_media":31213,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[4849],"tags":[6,7],"class_list":["post-33218","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-expert","tag-philrey212","tag-swatsh","annee-2083","auteurs-jonny-pac-cantin","editeurs-final-frontier-games","illustrateurs-mihajlo-dimitrievski","mecanismes-asymetrie-construite","mecanismes-majorite","mecanismes-objectifs-prives"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/33218","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/comments?post=33218"}],"version-history":[{"count":0,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/33218\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media\/31213"}],"wp:attachment":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media?parent=33218"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/categories?post=33218"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/tags?post=33218"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}