{"id":34664,"date":"2020-03-25T15:44:32","date_gmt":"2020-03-25T14:44:32","guid":{"rendered":"https:\/\/www.vindjeu.eu\/?p=34664"},"modified":"2020-03-25T15:48:18","modified_gmt":"2020-03-25T14:48:18","slug":"geode-proto","status":"publish","type":"post","link":"https:\/\/www.vindjeu.eu\/prd\/2020\/03\/25\/geode-proto\/","title":{"rendered":"Geode (proto)"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/IMG_1699-e1584101502895-1024x1024.jpg\" alt=\"\" class=\"wp-image-34669\" width=\"289\" height=\"289\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/IMG_1699-e1584101502895-1024x1024.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/IMG_1699-e1584101502895-150x150.jpg 150w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/IMG_1699-e1584101502895-300x300.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/IMG_1699-e1584101502895-768x768.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/IMG_1699-e1584101502895-160x160.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/IMG_1699-e1584101502895-245x245.jpg 245w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/IMG_1699-e1584101502895-340x340.jpg 340w\" sizes=\"auto, (max-width: 289px) 100vw, 289px\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2018\/07\/PhilRey201802-1024x768.jpg\" alt=\"\" class=\"wp-image-23586\" width=\"194\" height=\"145\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2018\/07\/PhilRey201802-1024x768.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2018\/07\/PhilRey201802-300x225.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2018\/07\/PhilRey201802-768x576.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2018\/07\/PhilRey201802-160x120.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2018\/07\/PhilRey201802-327x245.jpg 327w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2018\/07\/PhilRey201802-453x340.jpg 453w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2018\/07\/PhilRey201802.jpg 1280w\" sizes=\"auto, (max-width: 194px) 100vw, 194px\" \/><\/figure><\/div>\n\n\n\n<h4 class=\"wp-block-heading\"><span class=\"color\" style=\"color:#3157b7\">PhilRey<\/span><\/h4>\n\n\n\n<p>Geode est un jeu de pose de tuile, un peu \u00e0 la Carcassonne mais diff\u00e9rent. Ce jeu n&rsquo;est pas encore sorti \u00e0 l&rsquo;heure o\u00f9 cet article est publi\u00e9 mais sera lanc\u00e9 en financement participatif dans pas trop longtemps.<\/p>\n\n\n\n<p>Des tuiles donc, color\u00e9es en deux coins, formant ainsi, lorsque plac\u00e9es c\u00f4te \u00e0 c\u00f4te, des gemmes de couleur. Il faut donc bien 4 tuiles pour composer une gemme compl\u00e8te. Parmi les deux tuiles qu&rsquo;il a en main, le joueur en choisit une qu&rsquo;il place dans une grille \u00ab\u00a0virtuelle\u00a0\u00bb de 8&#215;8, commune aux joueurs. Il refait sa main ensuite pour avoir \u00e0 nouveau 2 tuiles.<\/p>\n\n\n\n<p>Si le joueur parvient \u00e0 compl\u00e9ter une gemme, il l&rsquo;identifie avec un jeton de sa couleur et il doit prendre une tuile Contrat d&rsquo;une des pioches encore disponibles. Il y a une petite prise de risque ici puisque la valeur de la carte Contrat pourrait \u00eatre sup\u00e9rieure \u00e0 la valeur de la gemme;<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignright is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/IMG_1697-1-e1584102329258-1024x236.jpg\" alt=\"\" class=\"wp-image-34671\" width=\"369\" height=\"85\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/IMG_1697-1-e1584102329258-1024x236.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/IMG_1697-1-e1584102329258-300x69.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/IMG_1697-1-e1584102329258-768x177.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/IMG_1697-1-e1584102329258-160x37.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/IMG_1697-1-e1584102329258-520x120.jpg 520w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/IMG_1697-1-e1584102329258-720x166.jpg 720w\" sizes=\"auto, (max-width: 369px) 100vw, 369px\" \/><\/figure><\/div>\n\n\n\n<p>J&rsquo;avoue que le risque est quand m\u00eame assez limit\u00e9 mais il est bien r\u00e9el. La valeur d&rsquo;une gemme est d\u00e9termin\u00e9e par les chiffres des 4 tuiles qui la compose. Si une gemme a une valeur de 10, le joueur peut risquer de prendre une tuile Contrat dans la pile 10-14, en sachant que si le contrat est finalement de 12, il ne pourra pas l&rsquo;honorer avec cette gemme. Le joueur peut aussi d\u00e9cider de prendre une tuile Contrat de la pile 7-9 pour s&rsquo;assurer sa bonne r\u00e9alisation.<\/p>\n\n\n\n<p>Geode est tr\u00e8s tactique. En effet, les joueurs vont agir en fonction de la situation du \u00ab\u00a0plateau\u00a0\u00bb central. Un part de hasard est \u00e9galement pr\u00e9sente dans la pioche des tuiles Exploration. Il arrive r\u00e9guli\u00e8rement de ne pas avoir la tuile qu&rsquo;il nous faut. Le jeu est tactique car les joueurs essaieront de ne pas former des \u00ab\u00a03\/4\u00a0\u00bb de gemme: avoir trois tuiles pour une gemme en \u00ab\u00a0construction\u00a0\u00bb offre une opportunit\u00e9 aux adversaires de la terminer et d&#8217;empocher un contrat.<\/p>\n\n\n\n<p>Par rapport \u00e0 Carcassonne, Geode est nettement plus accessible. Les joueurs qui entrent dans le monde des jeux de soci\u00e9t\u00e9 s&rsquo;en sortiront bien avec Geode avant de passer \u00e0 du plus complexe, \u00e9ventuellement.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/IMG_1697-1024x768.jpg\" alt=\"\" class=\"wp-image-34667\" width=\"1112\" height=\"834\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/IMG_1697-1024x768.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/IMG_1697-300x225.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/IMG_1697-768x576.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/IMG_1697-160x120.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/IMG_1697-327x245.jpg 327w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/IMG_1697-453x340.jpg 453w\" sizes=\"auto, (max-width: 1112px) 100vw, 1112px\" \/><figcaption>En cours de partie, \u00e0 deux joueurs. N&rsquo;oubliez pas, il s&rsquo;ag\u00eet d&rsquo;un prototype!<\/figcaption><\/figure><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/IMG_1698-1024x768.jpg\" alt=\"\" class=\"wp-image-34668\" width=\"1127\" height=\"845\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/IMG_1698-1024x768.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/IMG_1698-300x225.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/IMG_1698-768x576.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/IMG_1698-160x120.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/IMG_1698-327x245.jpg 327w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/IMG_1698-453x340.jpg 453w\" sizes=\"auto, (max-width: 1127px) 100vw, 1127px\" \/><figcaption>Situation en fin de partie. Les contrats que les joueurs parviennent \u00e0 associer \u00e0 une gemme (de valeur \u00e9gale ou inf\u00e9rieure) rapportent les point \u00ab\u00a0or\u00a0\u00bb. Les autres contrats rapportent les points \u00ab\u00a0argent\u00a0\u00bb<\/figcaption><\/figure><\/div>\n","protected":false},"excerpt":{"rendered":"<p>PhilRey Geode est un jeu de pose de tuile, un peu \u00e0 la Carcassonne mais diff\u00e9rent. Ce jeu n&rsquo;est pas encore sorti \u00e0 l&rsquo;heure o\u00f9 cet article est publi\u00e9 mais sera lanc\u00e9 en financement participatif dans pas trop longtemps. Des tuiles donc, color\u00e9es en deux coins, formant ainsi, lorsque plac\u00e9es&#46;&#46;&#46;<\/p>\n","protected":false},"author":4,"featured_media":34666,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[5],"tags":[6],"class_list":["post-34664","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-famille","tag-philrey212","annee-2346","auteurs-stuart-garside","auteurs-theo-clarke","editeurs-district-31","illustrateurs-bellafquih-mohammed","nombre_conseille-1185","nombre_conseille-1210","nombre_conseille-1355","mecanismes-pose-de-tuiles"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/34664","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/comments?post=34664"}],"version-history":[{"count":0,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/34664\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media\/34666"}],"wp:attachment":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media?parent=34664"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/categories?post=34664"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/tags?post=34664"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}