{"id":36318,"date":"2020-06-28T18:34:44","date_gmt":"2020-06-28T16:34:44","guid":{"rendered":"https:\/\/www.vindjeu.eu\/?p=36318"},"modified":"2020-06-28T18:35:49","modified_gmt":"2020-06-28T16:35:49","slug":"monumental-the-lost-kingdoms","status":"publish","type":"post","link":"https:\/\/www.vindjeu.eu\/prd\/2020\/06\/28\/monumental-the-lost-kingdoms\/","title":{"rendered":"Monumental: The Lost Kingdoms"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft\"><img loading=\"lazy\" decoding=\"async\" width=\"324\" height=\"389\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/06\/Monumental-1-e1593185402440.jpg\" alt=\"\" class=\"wp-image-36319\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/06\/Monumental-1-e1593185402440.jpg 324w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/06\/Monumental-1-e1593185402440-250x300.jpg 250w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/06\/Monumental-1-e1593185402440-133x160.jpg 133w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/06\/Monumental-1-e1593185402440-204x245.jpg 204w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/06\/Monumental-1-e1593185402440-283x340.jpg 283w\" sizes=\"auto, (max-width: 324px) 100vw, 324px\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/06\/Swa-36-150x150.jpg\" alt=\"\" class=\"wp-image-36051\"\/><\/figure><\/div>\n\n\n\n<h5 class=\"wp-block-heading\"><span style=\"color:#0693e3\" class=\"color\">SwatSh<\/span>:  <span style=\"color:#cf2e2e\" class=\"color\">7,5\/10<\/span><\/h5>\n\n\n\n<p>Lost Kingdoms est la premi\u00e8re extension du tr\u00e8s chouette <a href=\"https:\/\/www.vindjeu.eu\/2020\/03\/28\/monumental\/\"><strong>Monumental <\/strong><\/a>parue en m\u00eame temps que le jeu original.  Elle apporte plusieurs nouveaut\u00e9s.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">5\u00e8me \u00e9l\u00e9ment<\/h2>\n\n\n\n<p>Elle permet tout d&rsquo;abord de pouvoir y jouer \u00e0 5 joueuses.  C&rsquo;est une configuration que je ne conseille pas sp\u00e9cialement car le jeu \u00e0 4 dure d\u00e9j\u00e0 tr\u00e8s longtemps mais si \u00e7a correspond plus \u00e0 votre fa\u00e7on de jouer, pourquoi pas.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">4 terrains<\/h2>\n\n\n\n<p>L&rsquo;extension apporte \u00e9galement 4 nouveaux types de tuiles terrain.  Les ponts ne sont accessibles que par 2 c\u00f4t\u00e9s oppos\u00e9s, certaines tuiles ne sont accessibles qu&rsquo;en payant une ressource comme de l&rsquo;or ou une ressource rare pour la jungle et le d\u00e9sert fait mourir vos soldats.  Gr\u00e2ce \u00e0 ces nouvelles tuiles et au 5\u00e8me joueur, les r\u00e8gles vont proposer diff\u00e9rentes nouvelles cartes ce qui va aider \u00e0 faire varier vos parties.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">4 civilisations<\/h2>\n\n\n\n<p>C&rsquo;est \u00e9videmment l&rsquo;apport majeur de Lost Kindgoms, l&rsquo;ajout de 4 nouvelles civilisations de d\u00e9part permettant d&rsquo;attaquer le jeu sous de nouveaux angles.  Les azt\u00e8ques sont tr\u00e8s chouettes \u00e0 jouer et vont bien convenir aux novices.  Ils vont essentiellement tourner autour de la m\u00e9canique du sacrifice.  De nombreuses cartes vous permettront de sacrifier des soldats pour recevoir des ressources et autres avantages.<\/p>\n\n\n\n<p>Les autres civilisations n\u00e9cessitent plus d&rsquo;exp\u00e9rience pour pouvoir profiter pleinement de leurs capacit\u00e9s.  Les Amazones vont introduire une nouvelle ressource: les chevaux qui leur apporteront diff\u00e9rents avantages comme augmenter leur d\u00e9fense de 1 lorsqu&rsquo;elles les montent.  Les Moghols vont apporter de nouveaux types de cartes qui vont se placer autour de votre damier de 3&#215;3 cartes pour correspondre chacune \u00e0 une ligne ou une colonne et s&rsquo;activant lorsque vous r\u00e9aliserez la ligne ou colonne correspondante.  Leurs effets ne sont pas tr\u00e8s puissants mais vous pourrez en b\u00e9n\u00e9ficier tout au long de la partie.  Enfin, les Atlantides sont des cr\u00e9atures maritimes et vont proposer des nouvelles cartes qui pourront s&rsquo;activer selon certaines conditions.<\/p>\n\n\n\n<p>Tout comme la majorit\u00e9 des extensions, The Lost Kingdoms permet essentiellement de varier vos parties et d&rsquo;optimiser de nouvelles m\u00e9caniques propres \u00e0 chaque civilisation.  Elle n&rsquo;est \u00e9videmment pas indispensable mais ce n&rsquo;est pas un d\u00e9faut en soi.  De nombreux jeux issus du financement participatif sortent avec des extensions.  Quand celles-ci sont indispensables, cela refl\u00e8te plus par le fait que le jeu de base ait \u00e9t\u00e9 trop d\u00e9pouill\u00e9 et donc d\u00e9natur\u00e9.  Pour <a href=\"https:\/\/www.vindjeu.eu\/2020\/03\/28\/monumental\/\"><strong>Monumental <\/strong><\/a>et Lost Kingdoms ce n&rsquo;est clairement pas le cas et c&rsquo;est beaucoup mieux comme \u00e7a car Monumental se suffit \u00e0 lui m\u00eame et bien plus que \u00e7a \ud83d\ude09<\/p>\n\n\n\n<hr class=\"wp-block-separator is-style-wide\"\/>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"934\" height=\"900\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/06\/2441-Monumental-Lost-5.jpg\" alt=\"\" class=\"wp-image-36326\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/06\/2441-Monumental-Lost-5.jpg 934w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/06\/2441-Monumental-Lost-5-300x289.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/06\/2441-Monumental-Lost-5-768x740.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/06\/2441-Monumental-Lost-5-160x154.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/06\/2441-Monumental-Lost-5-254x245.jpg 254w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/06\/2441-Monumental-Lost-5-353x340.jpg 353w\" sizes=\"auto, (max-width: 934px) 100vw, 934px\" \/><\/figure><\/div>\n","protected":false},"excerpt":{"rendered":"<p> Lost Kingdoms est la premi\u00e8re extension du tr\u00e8s chouette Monumental parue en m\u00eame temps que le jeu original. Elle apporte plusieurs nouveaut\u00e9s. 5\u00e8me \u00e9l\u00e9ment Elle permet tout d&rsquo;abord de pouvoir y jouer \u00e0 5 joueuses. C&rsquo;est une configuration que je ne conseille pas sp\u00e9cialement car le jeu \u00e0&#46;&#46;&#46;<\/p>\n","protected":false},"author":3,"featured_media":36319,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[4849],"tags":[7],"class_list":["post-36318","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-expert","tag-swatsh","annee-2346","auteurs-matthew-dunstan","editeurs-funforge","nombre_conseille-1185","nombre_conseille-1210","nombre_conseille-1355","mecanismes-combat","mecanismes-deckbuilding","mecanismes-majorite","mecanismes-objectifs-communs"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/36318","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/comments?post=36318"}],"version-history":[{"count":0,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/36318\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media\/36319"}],"wp:attachment":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media?parent=36318"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/categories?post=36318"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/tags?post=36318"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}