{"id":36385,"date":"2020-07-19T12:54:48","date_gmt":"2020-07-19T10:54:48","guid":{"rendered":"https:\/\/www.vindjeu.eu\/?p=36385"},"modified":"2020-07-19T12:57:14","modified_gmt":"2020-07-19T10:57:14","slug":"wolle-hamstern-honey-moon-volle-weide","status":"publish","type":"post","link":"https:\/\/www.vindjeu.eu\/prd\/2020\/07\/19\/wolle-hamstern-honey-moon-volle-weide\/","title":{"rendered":"Wolle\/Hamstern\/Honey Moon\/Volle Weide"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"132\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/boxNSV-1024x132.png\" alt=\"\" class=\"wp-image-36384\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/boxNSV-1024x132.png 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/boxNSV-300x39.png 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/boxNSV-768x99.png 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/boxNSV-160x21.png 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/boxNSV-520x67.png 520w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/boxNSV-720x93.png 720w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/08\/philrey201701.png\" alt=\"\" class=\"wp-image-18465\" width=\"145\" height=\"167\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/08\/philrey201701.png 427w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/08\/philrey201701-260x300.png 260w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/08\/philrey201701-139x160.png 139w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/08\/philrey201701-212x245.png 212w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2017\/08\/philrey201701-294x340.png 294w\" sizes=\"auto, (max-width: 145px) 100vw, 145px\" \/><\/figure><\/div>\n\n\n\n<h4 class=\"wp-block-heading\"><span style=\"color:#4838bf\" class=\"color\">PhilRey: <\/span><span style=\"color:#cf2e2e\" class=\"color\">7,5\/10<\/span><\/h4>\n\n\n\n<p>Voil\u00e0 4 petits Roll &amp; Write que je qualifierais de minimalistes! En effet, chaque petit jeu tient dans un petit paquet de la taille d\u2019une demi-enveloppe et contient petit d\u00e9 blanc, un petit crayon standard et un petit bloc de feuillets.<\/p>\n\n\n\n<p>La petite touche pour varier un peu les parties: les feuillet sont recto-verso, offrant un \u201ctableau\u201d diff\u00e9rent de l\u2019autre c\u00f4t\u00e9!<\/p>\n\n\n\n<p>Voici donc un petit r\u00e9sum\u00e9 des diff\u00e9rents jeux.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/boxWolle-530x1024.png\" alt=\"\" class=\"wp-image-36381\" width=\"248\" height=\"480\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/boxWolle-530x1024.png 530w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/boxWolle-155x300.png 155w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/boxWolle-768x1484.png 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/boxWolle-83x160.png 83w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/boxWolle-127x245.png 127w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/boxWolle-176x340.png 176w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/boxWolle.png 1448w\" sizes=\"auto, (max-width: 248px) 100vw, 248px\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignright is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/IMG_2151-720x1024.png\" alt=\"\" class=\"wp-image-36377\" width=\"309\" height=\"440\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/IMG_2151-720x1024.png 720w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/IMG_2151-211x300.png 211w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/IMG_2151-768x1093.png 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/IMG_2151-112x160.png 112w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/IMG_2151-172x245.png 172w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/IMG_2151-239x340.png 239w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/IMG_2151.png 1996w\" sizes=\"auto, (max-width: 309px) 100vw, 309px\" \/><\/figure><\/div>\n\n\n\n<p>Dans Wolle, le but est de d\u00e9rouler une pelote de laine pour jouer avec le chat, l\u2019attirer vers les objets qui jonchent le sol tout en \u00e9vitant les tasses de porcelaine qui trainent de ci, de l\u00e0.<\/p>\n\n\n\n<p>Le r\u00e9sultat du d\u00e9 indique le nombre de traits que les joueurs doivent tracer sur leur feuillet, en sachant qu\u2019ils ne peuvent changer de direction qu\u2019une seule fois. Le but est de passer par un maximum d\u2019objet et, si possible, arriver en bas, la sortie, la patte du chat! Evidemment, certains obstacles bloquent le passage.<\/p>\n\n\n\n<p>D\u00e8s qu\u2019un joueur rassemble un objet de chaque, le compte \u00e0 rebours d\u00e9bute. Et c\u2019est pas mal trouv\u00e9: dor\u00e9navant, \u00e0 chaque tour, on v\u00e9rifie si le d\u00e9 \u00e0 une valeur \u00e9gale ou sup\u00e9rieurs \u00e0 5 (puis \u00e0 4, puis \u00e0 3 et enfin \u00e0 2) et si c\u2019est le cas, on barre le d\u00e9 en question sur le feuillet. La partie s\u2019acc\u00e9l\u00e8re \u00e9videmment, stressant les joueurs sur la fin.<\/p>\n\n\n\n<p>Cette petite astuce est bien trouv\u00e9e car elle oblige d\u2019\u00eatre attentif \u00e0 ce que font les autres joueurs. En plus d\u2019avoir une fin de partie variable dans le temps. Deux strat\u00e9gie peuvent \u00e9ventuellement s\u2019affronter: (1) rassembler un ensemble d\u2019objet rapidement et se rendre en bas du feuillet rapidement (ce qui donne 5PV \u00e0 ceux qui y arrivent) ou (2) passer par un max d\u2019objets, si possible vari\u00e9s car chaque ensemble rapporte des PVs suppl\u00e9mentaires.<\/p>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/boxVolleWeide-532x1024.png\" alt=\"\" class=\"wp-image-36380\" width=\"255\" height=\"491\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/boxVolleWeide-532x1024.png 532w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/boxVolleWeide-156x300.png 156w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/boxVolleWeide-768x1477.png 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/boxVolleWeide-83x160.png 83w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/boxVolleWeide-127x245.png 127w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/boxVolleWeide-177x340.png 177w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/boxVolleWeide.png 1467w\" sizes=\"auto, (max-width: 255px) 100vw, 255px\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignright is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/IMG_2148-713x1024.png\" alt=\"\" class=\"wp-image-36376\" width=\"306\" height=\"440\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/IMG_2148-713x1024.png 713w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/IMG_2148-209x300.png 209w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/IMG_2148-768x1103.png 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/IMG_2148-111x160.png 111w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/IMG_2148-171x245.png 171w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/IMG_2148-237x340.png 237w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/IMG_2148.png 1769w\" sizes=\"auto, (max-width: 306px) 100vw, 306px\" \/><\/figure><\/div>\n\n\n\n<p>On reprend ici un peu le m\u00eame principe de Wolle, \u00e0 savoir qu\u2019il faut cette fois-ci poser des cl\u00f4tures pour s\u00e9curiser le maximum de moutons. Il y a \u00e9videmment plusieurs diff\u00e9rences, suffisantes pour le diff\u00e9rencier de Wolle.<\/p>\n\n\n\n<p>La premi\u00e8re: la partie a un nombre de tours fixe: 10, avec 2 d\u00e9comptes. Le d\u00e9compte interm\u00e9diaire apr\u00e8s le 6<sup>\u00e8me<\/sup> tour et le final en fin de partie.<\/p>\n\n\n\n<p>En fait, ce n\u2019est pas tout \u00e0 fait exact (et on s&rsquo;est tromp\u00e9 dans nos premi\u00e8res parties). En effet, si la valeur du d\u00e9 est \u00e9gale \u00e0 valeur du d\u00e9 du tour pr\u00e9c\u00e9dent, on gagne un tour (puisqu\u2019on n\u2019indique pas le chiffre dans la case).<\/p>\n\n\n\n<p>Le d\u00e9 indique la disposition des traits \u00e0 tracer entre les poteaux: le 1, en U; le 3 en L ou le 6 en S.<\/p>\n\n\n\n<p>En d\u00e9but de partie, un mouton est colori\u00e9 et vaudra pour 2 moutons lors des d\u00e9comptes.<\/p>\n\n\n\n<p>Volle Weide est un peu plus lin\u00e9aire et rapide de Wolle mais rentre parfaitement dans la m\u00eame cat\u00e9gorie.<\/p>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/IMG_2157-553x1024.png\" alt=\"\" class=\"wp-image-36383\" width=\"249\" height=\"461\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/IMG_2157-553x1024.png 553w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/IMG_2157-162x300.png 162w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/IMG_2157-768x1422.png 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/IMG_2157-86x160.png 86w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/IMG_2157-132x245.png 132w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/IMG_2157-184x340.png 184w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/IMG_2157.png 1392w\" sizes=\"auto, (max-width: 249px) 100vw, 249px\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignright is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/IMG_2156-1024x712.png\" alt=\"\" class=\"wp-image-36382\" width=\"512\" height=\"356\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/IMG_2156-1024x712.png 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/IMG_2156-300x209.png 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/IMG_2156-768x534.png 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/IMG_2156-160x111.png 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/IMG_2156-352x245.png 352w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/IMG_2156-489x340.png 489w\" sizes=\"auto, (max-width: 512px) 100vw, 512px\" \/><\/figure><\/div>\n\n\n\n<p>Le th\u00e8me ici est assez, heu, irr\u00e9aliste. On creuse des tunnels dans la lune pour en trouver des bonbons et autres sucreries.Le d\u00e9 ici indique le nombre de croix \u00e0 placer sur le feuillet, croix qui repr\u00e9sentent les tunnels. La r\u00e8gle principale est de causer en ligne droite, soit de la surface (les bords) ou \u00e0 partir d\u2019un tunnel existant. En sachant aussi que deux tunnels ne peuvent pas \u00eatre creus\u00e9s c\u00f4te \u00e0 c\u00f4te (risque d\u2019effondrement).&nbsp;Une petite astuce: avec un r\u00e9sultat de d\u00e9 de 1, le joueur peut choisir de faire de 1 \u00e0 7 croix. Chaque croix est d\u00e8s lors retir\u00e9e de sa r\u00e9serve (de 7). Cela permet une petite flexibilit\u00e9 au joueur. N\u00e9anmoins, quand la r\u00e9serve est vide, le joueur devra passer son tour si le d\u00e9 indique 1.L\u2019objectif est, comme dans Wolle, de trouver un maximum de friandises. On retourne aussi des cornichons qui eux feront perdre des PVs.Comme dans Wolle, la dur\u00e9e d\u2019une partie est variable: le compte \u00e0 rebours d\u00e9marre d\u00e8s qu\u2019un joueur \u00e0 rassembler une friandise de chaque type.Ici aussi, le joueur pourra essayer d\u2019acc\u00e9l\u00e9rer la partie ou essayer de \u201cse sp\u00e9cialiser\u201d en un type de friandise, rapportant de plus en plus de points en fonction du nombre (1\/3\/6\/10\/15 pour 1\/2\/3\/4\/5 friandises de m\u00eame type).La diversification rapporte elle aussi des points: 5 par ensemble.<\/p>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/boxHamstern-550x1024.png\" alt=\"\" class=\"wp-image-36379\" width=\"248\" height=\"462\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/boxHamstern-550x1024.png 550w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/boxHamstern-161x300.png 161w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/boxHamstern-768x1429.png 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/boxHamstern-86x160.png 86w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/boxHamstern-132x245.png 132w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/boxHamstern-183x340.png 183w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/boxHamstern.png 1498w\" sizes=\"auto, (max-width: 248px) 100vw, 248px\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignright is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/IMG_2153-737x1024.png\" alt=\"\" class=\"wp-image-36378\" width=\"322\" height=\"447\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/IMG_2153-737x1024.png 737w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/IMG_2153-216x300.png 216w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/IMG_2153-768x1066.png 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/IMG_2153-115x160.png 115w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/IMG_2153-176x245.png 176w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/IMG_2153-245x340.png 245w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/IMG_2153.png 1907w\" sizes=\"auto, (max-width: 322px) 100vw, 322px\" \/><\/figure><\/div>\n\n\n\n<p>En tant qu\u2019hamster, les joueurs doivent remplir leur terrier de victuailles pour bien passer l\u2019hiver.<\/p>\n\n\n\n<p>Le feuillet repr\u00e9sente le terrier avec plusieurs pi\u00e8ces et des tunnels les reliant. Le principe est de remplir les \u201cchambres\u201d de croix (pour gagner des PV en fin de partie) en respectant une r\u00e8gle simple: chaque croix doit \u00eatre adjacente \u00e0 une autre.<\/p>\n\n\n\n<p>Les tunnels entre les chambres font en sorte que les cases sont bien adjacentes de part et d\u2019autre.<\/p>\n\n\n\n<p>On retrouve dans Hamstern les m\u00eames principes que dans les autres jeux: le d\u00e9 de valeur 1 permet de tracer de 1 \u00e0 7 croix (voir Honey Moon), la dur\u00e9e d\u2019une partie est variable grace au syst\u00e8me de compte \u00e0 rebours (voir Wolle).<\/p>\n\n\n\n<p>La diff\u00e9rence en points se fera ici principalement sur l\u2019acc\u00e8s aux champignons et noisettes r\u00e9partis dans les galeries.<\/p>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<p>Ils sont tous jouables de 2 \u00e0 6 joueurs et sont accessibles \u00e0 un large public, tr\u00e8s familial donc. Une partie ne dure pas plus de 10 minutes, donc rapide, facile, id\u00e9al aussi pour les plus jeunes qui appr\u00e9cient rarement les jeux trop longs. Et chose, j\u2019allais dire surprenante, amusante (c\u2019est un peu plus correct), quelques petites m\u00e9caniques sont sympas et valent la peine de se retrouver dans d\u2019autres jeux peut-\u00eatre plus complexes.<\/p>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n","protected":false},"excerpt":{"rendered":"<p> Voil\u00e0 4 petits Roll &amp; Write que je qualifierais de minimalistes! En effet, chaque petit jeu tient dans un petit paquet de la taille d\u2019une demi-enveloppe et contient petit d\u00e9 blanc, un petit crayon standard et un petit bloc de feuillets. La petite touche pour varier un peu&#46;&#46;&#46;<\/p>\n","protected":false},"author":4,"featured_media":36590,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[5],"tags":[6],"class_list":["post-36385","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-famille","tag-philrey212","annee-2346","auteurs-moritz-dressler","editeurs-nsv","illustrateurs-christian-opperer","mecanismes-roll-write"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/36385","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/comments?post=36385"}],"version-history":[{"count":0,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/36385\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media\/36590"}],"wp:attachment":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media?parent=36385"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/categories?post=36385"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/tags?post=36385"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}