{"id":37103,"date":"2020-09-16T07:20:01","date_gmt":"2020-09-16T05:20:01","guid":{"rendered":"https:\/\/www.vindjeu.eu\/?p=37103"},"modified":"2020-09-16T07:20:52","modified_gmt":"2020-09-16T05:20:52","slug":"les-aventuriers-du-rail-amsterdam","status":"publish","type":"post","link":"https:\/\/www.vindjeu.eu\/prd\/2020\/09\/16\/les-aventuriers-du-rail-amsterdam\/","title":{"rendered":"Les aventuriers du rail : Amsterdam"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/09\/Les-aventuriers-du-rail-Amsterdam-770x769.png\" alt=\"\" class=\"wp-image-37112\" width=\"385\" height=\"385\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/09\/Les-aventuriers-du-rail-Amsterdam-770x769.png 770w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/09\/Les-aventuriers-du-rail-Amsterdam-770x769-150x150.png 150w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/09\/Les-aventuriers-du-rail-Amsterdam-770x769-300x300.png 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/09\/Les-aventuriers-du-rail-Amsterdam-770x769-768x767.png 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/09\/Les-aventuriers-du-rail-Amsterdam-770x769-160x160.png 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/09\/Les-aventuriers-du-rail-Amsterdam-770x769-245x245.png 245w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/09\/Les-aventuriers-du-rail-Amsterdam-770x769-340x340.png 340w\" sizes=\"auto, (max-width: 385px) 100vw, 385px\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft\"><img loading=\"lazy\" decoding=\"async\" width=\"160\" height=\"160\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/09\/67098605_638740099964023_5792793147129987072_n-1.jpg\" alt=\"\" class=\"wp-image-31027\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/09\/67098605_638740099964023_5792793147129987072_n-1.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2019\/09\/67098605_638740099964023_5792793147129987072_n-1-150x150.jpg 150w\" sizes=\"auto, (max-width: 160px) 100vw, 160px\" \/><\/figure><\/div>\n\n\n\n<h5 class=\"wp-block-heading\"><span style=\"color:#0693e3\" class=\"color\">Tapimoket <\/span>: <span style=\"color:#cf2e2e\" class=\"color\">7\/10<\/span><\/h5>\n\n\n\n<h3 class=\"wp-block-heading\">Un Express sur la voie<\/h3>\n\n\n\n<p>Si vous ne connaissez pas encore la gamme des \u00ab\u00a0aventuriers du rail\u00a0\u00bb, il est grand temps de le d\u00e9couvrir car il constitue un des fleurons du jeu de soci\u00e9t\u00e9 grand public. Ce doit \u00eatre d&rsquo;ailleurs la meilleure vente de chez <em>Days of Wonder<\/em>, l&rsquo;\u00e9diteur.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Un rappel du principe<\/h3>\n\n\n\n<p>Bon d&rsquo;accord, vous ne connaissez pas&#8230; Si ?  Alors passez au paragraphe suivant !<\/p>\n\n\n\n<p>Dans les aventuriers du rail, les joueurs ont chacun un lot de wagons \u00e0 poser sur diverses voies parcourant le pays. Pour cela, ils devront collecter des cartes de couleurs correspondant \u00e0 la couleur des voies qu&rsquo;ils souhaitent remplir de leur wagons. Plus la route est longue, plus elle rapporte des points. A cela, s&rsquo;ajoute des cartes objectifs secr\u00e8tes o\u00f9 ils devront relier deux destinations afin de marquer les points inscrits, en g\u00e9n\u00e9ral c&rsquo;est tr\u00e8s rentable.  <\/p>\n\n\n\n<p>Durant la partie, ils pourront se servir de cartes jokers (toutes les couleurs) mais pioche moins, et pourront reprendre, \u00e0 souhait, des objectifs. Mais attention ! Tout objectif non r\u00e9alis\u00e9 engendre des points n\u00e9gatifs !<\/p>\n\n\n\n<p>Les aventuriers du rail n&rsquo;est pas un seul jeu, mais toutes une collection avec des variantes et des pays diff\u00e9rents (USA le plus connu, Europe, Asie, Scandinavie, Allemagne, etc.)<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignright is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/09\/20200902_193513-1024x768.jpg\" alt=\"\" class=\"wp-image-37114\" width=\"512\" height=\"384\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/09\/20200902_193513-1024x768.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/09\/20200902_193513-300x225.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/09\/20200902_193513-768x576.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/09\/20200902_193513-160x120.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/09\/20200902_193513-327x245.jpg 327w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/09\/20200902_193513-453x340.jpg 453w\" sizes=\"auto, (max-width: 512px) 100vw, 512px\" \/><\/figure><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">Amsterdam, qu&rsquo;est-ce que tu nous cache ?<\/h3>\n\n\n\n<p><strong>Les aventuriers du rail Amsterdam<\/strong> n&rsquo;utilisera pas de wagons cette fois. On aurait presque pu l&rsquo;appeler les aventuriers du chemin, puisque celui-ci utilisera de vieilles charrettes au lieu des wagons, et des chemins au lieu des rails ! Forcement, \u00e0 cette vitesse, les routes sont moins longues et on sera surpris par un format plus petit de la boite et bien s\u00fbr du plateau.<\/p>\n\n\n\n<p>Alors que les routes les plus longues de la version standard culminent jusqu&rsquo;\u00e0 8 emplacements pour une route, celui-ci ne d\u00e9passera pas 4 cases et les routes seront bien moins nombreuses ! On a presque envie de dire que la carte a \u00e9t\u00e9 r\u00e9duite au quart.<\/p>\n\n\n\n<p>Bien entendu, cette diminution se fera ressentir sur la dur\u00e9e puisqu&rsquo;une partie est pr\u00e9vue aux alentours de 15 minutes seulement, au lieu des 45-60 minutes de sa premi\u00e8re version (USA)<\/p>\n\n\n\n<p>On aurait pu dire que c&rsquo;est une version express, mais cela aurait fait croire qu&rsquo;il y avaient des trains \u00e0 grande vitesse ou l&rsquo;orient express, ce qui n&rsquo;est pas le cas.<\/p>\n\n\n\n<p>Au niveau des r\u00e8gles pas de gros changement, on a toujours les cartes de couleurs, les jokers, le m\u00eame syst\u00e8me de pioche. On pose des charrettes avec ses cartes de couleurs, ses jokers et on marque des points selon la longueur des routes. Les places sont bien s\u00fbr tr\u00e8s vite occup\u00e9es&#8230;<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/09\/20200902_194328-1024x768.jpg\" alt=\"\" class=\"wp-image-37116\" width=\"512\" height=\"384\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/09\/20200902_194328-1024x768.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/09\/20200902_194328-300x225.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/09\/20200902_194328-768x576.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/09\/20200902_194328-160x120.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/09\/20200902_194328-327x245.jpg 327w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/09\/20200902_194328-453x340.jpg 453w\" sizes=\"auto, (max-width: 512px) 100vw, 512px\" \/><\/figure><\/div>\n\n\n\n<p>La diff\u00e9rence viendra sur le gain de cartes \u00ab\u00a0marchandises\u00a0\u00bb obtenues en posant sur des chemins o\u00f9 sont dessin\u00e9s des charrettes. En fin de partie, celui qui en a le plus de cartes marchandises aura un bonus de 8 points qui sera d\u00e9croisant pour les autres joueurs selon le nombre de cartes marchandises en possession.<\/p>\n\n\n\n<p>Ces chemins \u00e0 charrettes sont bien s\u00fbr plac\u00e9s sur les routes p\u00e9riph\u00e9riques pour compenser les points et inciter \u00e0 ne pas se ruer au centre du plateau qui est une position strat\u00e9gique&#8230;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Les aventuriers du Rail sans la magie<\/h3>\n\n\n\n<p>J&rsquo;avoue que cette version m&rsquo;\u00e9tonne un peu. Si, certes, elle permet de jouer plus rapidement, je trouve que l&rsquo;on a perdu toute la magie de la version originale (et celle de l&rsquo;Europe, l&rsquo;une de mes pr\u00e9f\u00e9r\u00e9es). <\/p>\n\n\n\n<p>En effet, la partie se r\u00e9v\u00e8le trop courte pour moi et j&rsquo;ai perdu ce bonheur de construire mes routes une \u00e0 une, de devoir faire parfois un d\u00e9tour lorsqu&rsquo;on me pique un chemin n\u00e9cessaire, mais tout en gardant la possibilit\u00e9 de r\u00e9ussir. Les longues routes apportaient de cette sensation de satisfaction. Quel bonheur de r\u00e9ussir \u00e0 traverser toute la carte alors qu&rsquo;\u00e0 tout moment on peut vous piquer un chemin, quel bonheur de cumuler peu \u00e0 peu ses 8 cartes pour marquer un gros paquet de points avec cette tension que quelqu&rsquo;un y arrive avant vous car il prend toujours la m\u00eame couleur aussi&#8230; <\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignright is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/09\/20200902_194321-1024x768.jpg\" alt=\"\" class=\"wp-image-37118\" width=\"512\" height=\"384\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/09\/20200902_194321-1024x768.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/09\/20200902_194321-300x225.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/09\/20200902_194321-768x576.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/09\/20200902_194321-160x120.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/09\/20200902_194321-327x245.jpg 327w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/09\/20200902_194321-453x340.jpg 453w\" sizes=\"auto, (max-width: 512px) 100vw, 512px\" \/><\/figure><\/div>\n\n\n\n<p>Oui, je vais faire mon ronchon, mais je trouve que l&rsquo;on a perdu de cette magie avec cette version. <\/p>\n\n\n\n<p>Les aventuriers du rail, pour moi, je le vois plut\u00f4t comme un jeu pos\u00e9 que l&rsquo;on installe pour jouer le dimanche en famille, avec des joueurs novices ou pas, un beau jeu, un grand jeu qui a de \u00ab\u00a0la gueule\u00a0\u00bb comme on dit, avec tous ces petits wagons partout. D&rsquo;ailleurs je me suis jet\u00e9 sur la version 10\u00e8me anniversaire, vraiment magnifique alors que j&rsquo;ai plus souvent l&rsquo;habitude de jouer plut\u00f4t \u00e0 des jeux plus velu. Je l&rsquo;ai fait car il est immense avec un mat\u00e9riel sublime et fr\u00f4le l&rsquo;objet de collection.<\/p>\n\n\n\n<p>Cette version courte a, pour moi, juste l&rsquo;int\u00e9r\u00eat de jouer plus rapidement (\u00e0 regret) ou pour initier des joueurs qui doutent de jouer longtemps. Il peut aussi compl\u00e9ter une gamme que l&rsquo;on collectionne. Ceci dit, le design reste tr\u00e8s joli comme d&rsquo;habitude, avec de belles illustrations et de jolies charrettes.<\/p>\n\n\n\n<p>.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/09\/20200902_194857-1024x768.jpg\" alt=\"\" class=\"wp-image-37119\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/09\/20200902_194857-1024x768.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/09\/20200902_194857-300x225.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/09\/20200902_194857-768x576.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/09\/20200902_194857-160x120.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/09\/20200902_194857-327x245.jpg 327w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/09\/20200902_194857-453x340.jpg 453w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div>\n","protected":false},"excerpt":{"rendered":"<p> Un Express sur la voie Si vous ne connaissez pas encore la gamme des \u00ab\u00a0aventuriers du rail\u00a0\u00bb, il est grand temps de le d\u00e9couvrir car il constitue un des fleurons du jeu de soci\u00e9t\u00e9 grand public. Ce doit \u00eatre d&rsquo;ailleurs la meilleure vente de chez Days of&#46;&#46;&#46;<\/p>\n","protected":false},"author":6,"featured_media":37112,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[5],"tags":[877],"class_list":["post-37103","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-famille","tag-tapimoket","annee-2346","auteurs-alan-r-moon","editeurs-days-of-wonder","illustrateurs-cyrille-daujean","illustrateurs-julien-delval","nombre_conseille-1185","mecanismes-gestion-de-main-de-cartes"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/37103","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/comments?post=37103"}],"version-history":[{"count":0,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/37103\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media\/37112"}],"wp:attachment":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media?parent=37103"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/categories?post=37103"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/tags?post=37103"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}