{"id":37341,"date":"2020-10-02T10:25:14","date_gmt":"2020-10-02T08:25:14","guid":{"rendered":"https:\/\/www.vindjeu.eu\/?p=37341"},"modified":"2020-10-02T10:46:06","modified_gmt":"2020-10-02T08:46:06","slug":"butterfly","status":"publish","type":"post","link":"https:\/\/www.vindjeu.eu\/prd\/2020\/10\/02\/butterfly\/","title":{"rendered":"Butterfly"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/boxButterfly.jpg\" alt=\"\" class=\"wp-image-37340\" width=\"346\" height=\"501\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/boxButterfly.jpg 622w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/boxButterfly-207x300.jpg 207w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/boxButterfly-111x160.jpg 111w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/boxButterfly-169x245.jpg 169w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/boxButterfly-235x340.jpg 235w\" sizes=\"auto, (max-width: 346px) 100vw, 346px\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2018\/07\/PhilRey201803-768x1024.jpg\" alt=\"\" class=\"wp-image-23587\" width=\"187\" height=\"249\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2018\/07\/PhilRey201803-768x1024.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2018\/07\/PhilRey201803-225x300.jpg 225w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2018\/07\/PhilRey201803-120x160.jpg 120w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2018\/07\/PhilRey201803-184x245.jpg 184w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2018\/07\/PhilRey201803-255x340.jpg 255w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2018\/07\/PhilRey201803.jpg 960w\" sizes=\"auto, (max-width: 187px) 100vw, 187px\" \/><\/figure><\/div>\n\n\n\n<h4 class=\"wp-block-heading\"><span style=\"color:#465bb7\" class=\"color\">PhilRey:<\/span> <span style=\"color:#cf2e2e\" class=\"color\">7,5\/10<\/span><\/h4>\n\n\n\n<p>Butterfly est un jeu \u00e9dit\u00e9 en 2019 chez Rio Grande Games, \u00e9diteur dont je n\u2019entendais plus trop parler mais qui semble refaire un peu surface avec plusieurs jeux de gabarits vari\u00e9s: Butterfly sorti discr\u00e8tement l&rsquo;ann\u00e9e pass\u00e9e; Nevada City, nettement plus costaud (voyez <a href=\"https:\/\/www.vindjeu.eu\/2020\/09\/14\/nevada-city\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\"ici (opens in a new tab)\">ici<\/a>) ou encore Praga Caput Regni annonc\u00e9 cette ann\u00e9e (2020)<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">D\u00e9j\u00e0 vu<\/h4>\n\n\n\n<p>Revenons donc \u00e0 Butterfly. Le jeu est vraiment simple et il faut le prendre tel quel. Il n\u2019y a pas vraiment de m\u00e9canique innovante dans Butterfly. On retrouve un plateau central quadrill\u00e9, sur lequel on va placer des tuiles de mani\u00e8re al\u00e9atoire. Le nombre de tuile, et donc la taille du plateau,&nbsp; d\u00e9pendra du nombre de joueurs. Enfin, un joueur place le pion H\u00e9risson sur une des cases de son choix et dans une direction choisie \u00e9galement.<\/p>\n\n\n\n<p>La partie d\u00e9marre par le premier joueur (bien vu Phil) qui peut pivoter le pion H\u00e9risson d\u2019un quart de tour vers la droite ou vers la gauche. Ensuite, il d\u00e9place le pion en ligne droite pour s\u2019arr\u00eater sur la tuile de son choix et la prend. Seule obligation&nbsp;: le joueur doit prendre une tuile. S\u2019il ne sait pas, la partie s\u2019arr\u00eate.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignright is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/IMG_E2297-952x1024.jpg\" alt=\"\" class=\"wp-image-37337\" width=\"339\" height=\"365\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/IMG_E2297-952x1024.jpg 952w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/IMG_E2297-279x300.jpg 279w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/IMG_E2297-768x826.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/IMG_E2297-149x160.jpg 149w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/IMG_E2297-228x245.jpg 228w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/IMG_E2297-316x340.jpg 316w\" sizes=\"auto, (max-width: 339px) 100vw, 339px\" \/><\/figure><\/div>\n\n\n\n<p>Le joueur suivant joue de la m\u00eame mani\u00e8re, et ainsi de suite jusqu\u2019\u00e0 ce qu\u2019un joueur ne sache plus prendre de tuile.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Collection<\/h4>\n\n\n\n<p>Le but des joueurs est bien \u00e9videmment de ramasser les tuiles qui rapportent le plus de PVs. Pour ce faire, il y plusieurs type de tuiles qui offrent diff\u00e9rentes mani\u00e8res de marquer des PVs, ou d\u2019en faire perdre. Et c\u2019est un peu l\u00e0 qu\u2019on trouve le plaisir de jouer \u00e0 Butterfly. Les joueurs regardent les possibilit\u00e9s des adversaires afin de soit privil\u00e9gier un max de PVs r\u00e9colt\u00e9s, soit faire en sorte que les autres n\u2019aient d\u2019autres choix que de prendre de faibles tuiles, voir celles qui font perdre des points. Et cela s\u2019accentue au fil de la partie avec la diminution des tuiles, donc des possibilit\u00e9s.<\/p>\n\n\n\n<p>Quant aux tuiles, il y en a plusieurs types (je me r\u00e9p\u00e8te)&nbsp;:<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignright is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/IMG_E2299-1024x576.jpg\" alt=\"\" class=\"wp-image-37339\" width=\"511\" height=\"287\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/IMG_E2299-1024x576.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/IMG_E2299-300x169.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/IMG_E2299-768x432.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/IMG_E2299-160x90.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/IMG_E2299-436x245.jpg 436w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/IMG_E2299-605x340.jpg 605w\" sizes=\"auto, (max-width: 511px) 100vw, 511px\" \/><\/figure><\/div>\n\n\n\n<ul class=\"wp-block-list\"><li>Les papillons rapportent simplement les points indiqu\u00e9s&nbsp;;<\/li><li>Les abeilles se combinent avec une autre tuile (ruche) pour rapporter beaucoup&nbsp;;<\/li><li>Pour les libellules, on ne compte que la plus \u00e9lev\u00e9e<\/li><li>Pour les sauterelles, ce n\u2019est que la derni\u00e8re ramass\u00e9e par le joueur qui compte&nbsp;;<\/li><li>Les feux-follet, uniquement la tuile la plus faible<\/li><li>Les gu\u00eapes font perdre les points indiqu\u00e9s<\/li><\/ul>\n\n\n\n<p>La force principale de Butterfly est sa simplicit\u00e9\u00a0: les r\u00e8gles sont simples, \u00e0 expliquer et \u00e0 assimiler, et les tours sont rapides (sauf peut-\u00eatre pour ceux qui veulent planifier au maximum les probabilit\u00e9s de mouvement des adversaires).<\/p>\n\n\n\n<p>Nous avons fait 2 parties d\u2019affil\u00e9es, \u00e0 trois, et l\u2019ambiance \u00e9tait bien au rendez-vous, surtout gr\u00e2ce aux discussions pour influencer dans un sens ou dans l\u2019autre. Au final, on passe 30 minutes anim\u00e9es de \u00ab\u00a0mais tu vas faire gagner Papa\u00a0!\u00a0\u00bb, de \u00ab\u00a0Du moment que toi tu ne gagnes pas\u00a0!\u00a0\u00bb et de \u00ab\u00a0Tu ne peux pas prendre cette tuile l\u00e0 sinon il va se faire 15 points\u00a0\u00bb. Bref, de l\u2019influence comme on aime\u00a0\ud83d\ude09<\/p>\n\n\n\n<p>Si vous avez d\u00e9j\u00e0 un jeu \u00e0 d\u00e9placement d\u2019un pion unique et collection, celui-ci risque peut-\u00eatre de faire double emploi. Quoi que, vu ses r\u00e8gles simples, la dur\u00e9e courte d\u2019une partie, Butterfly est super facile \u00e0 sortir.<\/p>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/IMG_E2298-834x1024.jpg\" alt=\"\" class=\"wp-image-37338\" width=\"1011\" height=\"1241\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/IMG_E2298-834x1024.jpg 834w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/IMG_E2298-244x300.jpg 244w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/IMG_E2298-768x943.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/IMG_E2298-130x160.jpg 130w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/IMG_E2298-200x245.jpg 200w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/IMG_E2298-277x340.jpg 277w\" sizes=\"auto, (max-width: 1011px) 100vw, 1011px\" \/><\/figure><\/div>\n","protected":false},"excerpt":{"rendered":"<p> Butterfly est un jeu \u00e9dit\u00e9 en 2019 chez Rio Grande Games, \u00e9diteur dont je n\u2019entendais plus trop parler mais qui semble refaire un peu surface avec plusieurs jeux de gabarits vari\u00e9s: Butterfly sorti discr\u00e8tement l&rsquo;ann\u00e9e pass\u00e9e; Nevada City, nettement plus costaud (voyez ici) ou encore Praga Caput Regni&#46;&#46;&#46;<\/p>\n","protected":false},"author":4,"featured_media":37340,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[5],"tags":[6],"class_list":["post-37341","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-famille","tag-philrey212","annee-2083","auteurs-stephen-glenn","editeurs-rio-grande-games","illustrateurs-martin-hoffmann","nombre_conseille-1210","nombre_conseille-1355","nombre_conseille-1217"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/37341","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/comments?post=37341"}],"version-history":[{"count":0,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/37341\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media\/37340"}],"wp:attachment":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media?parent=37341"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/categories?post=37341"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/tags?post=37341"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}