{"id":37809,"date":"2020-10-18T20:14:11","date_gmt":"2020-10-18T18:14:11","guid":{"rendered":"https:\/\/www.vindjeu.eu\/?p=37809"},"modified":"2021-04-08T22:26:36","modified_gmt":"2021-04-08T20:26:36","slug":"alma-mater","status":"publish","type":"post","link":"https:\/\/www.vindjeu.eu\/prd\/2020\/10\/18\/alma-mater\/","title":{"rendered":"Alma Mater"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/10\/2608-Alma-Mater-1.jpg\" alt=\"\" class=\"wp-image-37811\" width=\"496\" height=\"499\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/10\/2608-Alma-Mater-1.jpg 895w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/10\/2608-Alma-Mater-1-150x150.jpg 150w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/10\/2608-Alma-Mater-1-298x300.jpg 298w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/10\/2608-Alma-Mater-1-768x772.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/10\/2608-Alma-Mater-1-160x160.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/10\/2608-Alma-Mater-1-244x245.jpg 244w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/10\/2608-Alma-Mater-1-338x340.jpg 338w\" sizes=\"auto, (max-width: 496px) 100vw, 496px\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/09\/Swa-39-150x150.jpg\" alt=\"\" class=\"wp-image-37263\"\/><\/figure><\/div>\n\n\n\n<h5 class=\"wp-block-heading\"><span style=\"color:#0693e3\" class=\"color\">SwatSh<\/span>:  <span style=\"color:#cf2e2e\" class=\"color\">9,5\/10<\/span><\/h5>\n\n\n\n<p>Flaminia Brasini, Virginio Gigli, Stefano Luperto, Antonio Tinto, la quadrupl\u00e9e d&rsquo;auteurs d&rsquo;Alma Mater n&rsquo;en sont pas \u00e0 leur premi\u00e8re collaboration puisqu&rsquo;ils ont r\u00e9alis\u00e9, ensemble, les excellents <a href=\"https:\/\/www.vindjeu.eu\/2019\/09\/29\/terramara\/\"><strong>Terramara<\/strong><\/a>, un de <a href=\"https:\/\/www.vindjeu.eu\/2020\/10\/05\/vin-djeu-dlannee-2020\/\"><strong>nos coups de coeur de cette ann\u00e9e<\/strong><\/a> et <a href=\"https:\/\/www.vindjeu.eu\/2010\/01\/27\/egizia\/\"><strong>Egizia<\/strong><\/a>! Autant vous dire qu&rsquo;on \u00e9tait impatient de d\u00e9couvrir la suite \ud83d\ude42 Surtout qu&rsquo;ils n&rsquo;ont pas r\u00e9alis\u00e9 que \u00e7a. S\u00e9par\u00e9ment, ils ont cr\u00e9\u00e9 des jeux qui ont marqu\u00e9 l&rsquo;histoire du jeu ces derni\u00e8res ann\u00e9es comme <a href=\"https:\/\/www.vindjeu.eu\/2017\/06\/26\/lorenzo-il-magnifico-video\/\"><strong>Lorenzo le Magnifique<\/strong><\/a>, <a href=\"http:\/\/www.vindjeu.eu\/2017\/09\/19\/vin-djeu-dlannee-2017\/\"><strong>Vin d&rsquo;jeu d&rsquo;coup d&rsquo;coeur 2017<\/strong><\/a> ou <a href=\"https:\/\/www.vindjeu.eu\/2018\/12\/07\/coimbra\/\"><strong>Coimbra<\/strong><\/a>, notre <a href=\"https:\/\/www.vindjeu.eu\/2019\/09\/23\/vin-djeu-dlannee-2019\/\"><strong>Vin d&rsquo;jeu d&rsquo;l&rsquo;ann\u00e9e 2019<\/strong><\/a>.<\/p>\n\n\n\n<p>Alma Mater reprend le th\u00e8me de <a href=\"https:\/\/www.vindjeu.eu\/2018\/12\/29\/newton\/\"><strong>Newton <\/strong><\/a>puisqu&rsquo;on va engager des \u00e9tudiants et professeurs afin de servir au mieux nos int\u00e9r\u00eats. Il s&rsquo;agit d&rsquo;un jeu de placement d&rsquo;ouvriers assez classique o\u00f9 l&rsquo;on peut se placer sur les cases d&rsquo;action libres ou sur celles d\u00e9j\u00e0 occup\u00e9es par un adversaire \u00e0 condition d&rsquo;y placer un ouvrier de plus que le joueur pr\u00e9c\u00e9dent. Certaines cases action peuvent cependant \u00eatre occup\u00e9es par plus d&rsquo;un ouvrier, et ce, sans p\u00e9nalit\u00e9.<\/p>\n\n\n\n<p><span style=\"color:#eeeeee\" class=\"color\">.<\/span><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span style=\"color:#00d084\" class=\"color\">Les livres<\/span><\/h2>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignright is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/10\/2608-Alma-Mater-5-1024x683.jpg\" alt=\"\" class=\"wp-image-37815\" width=\"601\" height=\"401\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/10\/2608-Alma-Mater-5-1024x683.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/10\/2608-Alma-Mater-5-300x200.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/10\/2608-Alma-Mater-5-768x512.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/10\/2608-Alma-Mater-5-160x107.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/10\/2608-Alma-Mater-5-368x245.jpg 368w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/10\/2608-Alma-Mater-5-510x340.jpg 510w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/10\/2608-Alma-Mater-5.jpg 1080w\" sizes=\"auto, (max-width: 601px) 100vw, 601px\" \/><\/figure><\/div>\n\n\n\n<p>Dans le milieu estudiantin, la ressource la plus pris\u00e9e est \u00e9videmment les livres (qui a dit la bi\u00e8re? \ud83d\ude09 ). La gestion des livres est d&rsquo;ailleurs tr\u00e8s int\u00e9ressante dans Alma Mater. Chaque joueuse poss\u00e8de sa propre couleur de livre et ce sont ces livres qui serviront de monnaie d&rsquo;\u00e9change pour obtenir les diff\u00e9rentes tuiles et cartes du jeu apportant capacit\u00e9s et points de victoire. Vous devrez bien souvent payer une certaine combinaison de couleurs de livre. Et pour obtenir la couleur des livres adverses, vous allez devoir les leur acheter. Cela donne une belle dynamique au jeu o\u00f9 les joueuses vont s&rsquo;acheter les unes les autres des livres. Si une joueuse prend le dessus et gagne plus d&rsquo;argent que les autres, ce sera pour leur acheter des livres, l&rsquo;argent reviendra d\u00e8s lors aux plus pauvres. M\u00eame si le syst\u00e8me n&rsquo;engendre pas de choix corn\u00e9liens, il tourne bien et est assez original. Il va m\u00eame y avoir une certaine comp\u00e9tition sur les livres les plus pris\u00e9s.<\/p>\n\n\n\n<p>En effet, parall\u00e8lement \u00e0 ce syst\u00e8me \u00e9conomique, a lieu une comp\u00e9tition.   Les joueurs vont tenter de grimper sur l&rsquo;\u00e9chelle des d\u00e9fis en subissant des p\u00e9nalit\u00e9s (perte de ressources, d&rsquo;ouvriers, de possibilit\u00e9s,&#8230;) \u00e0 chaque \u00e9chelon. En contre partie, cette \u00e9chelle leur fera gagner certains bonus, des PVs et surtout, surtout, permettra \u00e0 leurs livres d&rsquo;\u00eatre plus recherch\u00e9s. En effet, les livres des joueurs en t\u00eate seront plus souvent n\u00e9cessaires que les autres pour \u00eatre utilis\u00e9s comme ressource. Cet enchev\u00eatrement de m\u00e9caniques est superbe.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/10\/2608-Alma-Mater-2-1024x683.jpg\" alt=\"\" class=\"wp-image-37816\" width=\"851\" height=\"568\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/10\/2608-Alma-Mater-2-1024x683.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/10\/2608-Alma-Mater-2-300x200.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/10\/2608-Alma-Mater-2-768x512.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/10\/2608-Alma-Mater-2-160x107.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/10\/2608-Alma-Mater-2-368x245.jpg 368w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/10\/2608-Alma-Mater-2-510x340.jpg 510w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/10\/2608-Alma-Mater-2.jpg 1080w\" sizes=\"auto, (max-width: 851px) 100vw, 851px\" \/><\/figure><\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><span style=\"color:#00d084\" class=\"color\">Profs &amp; \u00e9tudiants<\/span><\/h2>\n\n\n\n<p>Et ces livres serviront \u00e0 acqu\u00e9rir des tuiles \u00e9tudiants et des cartes profs. Les 2 vont fonctionner plus ou moins de la m\u00eame fa\u00e7ons. Elles vont apporter des bonus en revenu, en r\u00e9duction de co\u00fbt, en gain de ressources,&#8230; tout en proposant des fa\u00e7ons de scorer suppl\u00e9mentaires. M\u00eame si les profs pr\u00e9sentent une certaine vari\u00e9t\u00e9 (on jouera avec 8 des 16 profs possibles \u00e0 chaque partie), il n&rsquo;en va pas de m\u00eame avec les \u00e9tudiants. On jouera toujours avec les m\u00eames 16 \u00e9tudiants. Et \u00e7a, j&rsquo;ai vraiment trouv\u00e9 dommage car \u00e7a peut induire certains automatismes qui nuiront au plaisir des futures parties. De plus, il y a un certain d\u00e9s\u00e9quilibre, sans doute voulu, entre les \u00e9tudiants et les profs. De telle sorte qu&rsquo;il est quasi obligatoire d&rsquo;engager des \u00e9tudiants, le gain de profs \u00e9tant plus superflu.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/10\/2608-Alma-Mater-11-1024x683.jpg\" alt=\"\" class=\"wp-image-37818\" width=\"592\" height=\"395\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/10\/2608-Alma-Mater-11-1024x683.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/10\/2608-Alma-Mater-11-300x200.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/10\/2608-Alma-Mater-11-768x512.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/10\/2608-Alma-Mater-11-160x107.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/10\/2608-Alma-Mater-11-368x245.jpg 368w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/10\/2608-Alma-Mater-11-510x340.jpg 510w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/10\/2608-Alma-Mater-11.jpg 1080w\" sizes=\"auto, (max-width: 592px) 100vw, 592px\" \/><\/figure><\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><span style=\"color:#f4f6f7\" class=\"color\">.<\/span><\/h2>\n\n\n\n<h2 class=\"wp-block-heading\"><span style=\"color:#00d084\" class=\"color\">Les 3 ma\u00eetres<\/span><\/h2>\n\n\n\n<p>Attention n\u00e9anmoins, ce d\u00e9s\u00e9quilibre est contrebalanc\u00e9 par les 3 ma\u00eetres qui vont apporter certains bonus aux joueurs qui auront atteint l&rsquo;objectif pour les obtenir.  Il y a pas mal d&rsquo;objectifs diff\u00e9rents apportant ici, une belle rejouabilit\u00e9.  Certains objectifs vont vous encourager \u00e0 aller dans l&rsquo;une ou l&rsquo;autre strat\u00e9gie. Un peu comme dans <a href=\"https:\/\/www.vindjeu.eu\/2020\/01\/01\/paladins-du-royaume-de-louest\/\"><strong>Paladins<\/strong><\/a>, ces objectifs vont vous donner une direction \u00e0 suivre.<\/p>\n\n\n\n<p><span style=\"color:#f0f4f6\" class=\"color\">.<\/span><\/p>\n\n\n\n<p><span style=\"color:#f3f5f6\" class=\"color\">.<\/span><\/p>\n\n\n\n<p><span style=\"color:#f7fafb\" class=\"color\">.<\/span><\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignright is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/10\/2608-Alma-Mater-3-1024x683.jpg\" alt=\"\" class=\"wp-image-37817\" width=\"623\" height=\"416\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/10\/2608-Alma-Mater-3-1024x683.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/10\/2608-Alma-Mater-3-300x200.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/10\/2608-Alma-Mater-3-768x512.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/10\/2608-Alma-Mater-3-160x107.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/10\/2608-Alma-Mater-3-368x245.jpg 368w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/10\/2608-Alma-Mater-3-510x340.jpg 510w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/10\/2608-Alma-Mater-3.jpg 1080w\" sizes=\"auto, (max-width: 623px) 100vw, 623px\" \/><\/figure><\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><span style=\"color:#00d084\" class=\"color\">M\u00e8re nourrici\u00e8re<\/span><\/h2>\n\n\n\n<p>Alma Mater, m\u00e8re nourrici\u00e8re en latin \ud83d\ude09 , qui d\u00e9signe l&rsquo;universit\u00e9 o\u00f9 on a \u00e9tudi\u00e9, est un jeu assez froid et math\u00e9matique. Le th\u00e8me ne transpire pas dans le jeu et les \u00e9tudiants auraient tr\u00e8s bien pu \u00eatre des voitures ou des b\u00e2timents. Il reste donc un jeu tr\u00e8s math\u00e9matique o\u00f9 on va acqu\u00e9rir et transformer des ressources pour obtenir des bonus de r\u00e9duction de co\u00fbt, de gain de ressources et de PVs par de multiples moyens. On se doit de suivre les objectifs de partie et le jeu laisse trop peu de place \u00e0 la libert\u00e9 et \u00e0 la vari\u00e9t\u00e9. Ceci dit, il est superbement fait et donne clairement l&rsquo;envie d&rsquo;y revenir pour tenter d&rsquo;autres combinaisons et d&rsquo;autres strat\u00e9gies. Il poss\u00e8de une belle courbe d&rsquo;apprentissage et il vous faudra de nombreuses partie pour en ma\u00eetriser tous les aspects. M\u00eame si on peut se chagriner de certains de ses d\u00e9fauts, Alma Mater est clairement un tr\u00e8s bon jeu qui a sa place dans toute ludoth\u00e8que experte qui se respecte.<\/p>\n\n\n\n<hr class=\"wp-block-separator is-style-wide\"\/>\n\n\n\n<figure class=\"wp-block-image alignfull\"><img loading=\"lazy\" decoding=\"async\" width=\"1380\" height=\"920\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/10\/2608-Alma-Mater-15.jpg\" alt=\"\" class=\"wp-image-37812\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/10\/2608-Alma-Mater-15.jpg 1380w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/10\/2608-Alma-Mater-15-300x200.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/10\/2608-Alma-Mater-15-768x512.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/10\/2608-Alma-Mater-15-1024x683.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/10\/2608-Alma-Mater-15-160x107.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/10\/2608-Alma-Mater-15-368x245.jpg 368w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/10\/2608-Alma-Mater-15-510x340.jpg 510w\" sizes=\"auto, (max-width: 1380px) 100vw, 1380px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p> Flaminia Brasini, Virginio Gigli, Stefano Luperto, Antonio Tinto, la quadrupl\u00e9e d&rsquo;auteurs d&rsquo;Alma Mater n&rsquo;en sont pas \u00e0 leur premi\u00e8re collaboration puisqu&rsquo;ils ont r\u00e9alis\u00e9, ensemble, les excellents Terramara, un de nos coups de coeur de cette ann\u00e9e et Egizia! Autant vous dire qu&rsquo;on \u00e9tait impatient de d\u00e9couvrir la suite&#46;&#46;&#46;<\/p>\n","protected":false},"author":3,"featured_media":37811,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[4849],"tags":[7],"class_list":["post-37809","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-expert","tag-swatsh","annee-2346","auteurs-antonio-tinto","auteurs-flaminia-brasini","auteurs-stefano-luperto","auteurs-virginio-gigli","editeurs-eggertspiele","illustrateurs-chris-quilliams","nombre_conseille-1185","nombre_conseille-1210","nombre_conseille-1355","mecanismes-asymetrie","mecanismes-draft","mecanismes-placement-douvriers"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/37809","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/comments?post=37809"}],"version-history":[{"count":0,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/37809\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media\/37811"}],"wp:attachment":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media?parent=37809"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/categories?post=37809"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/tags?post=37809"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}