{"id":37885,"date":"2020-10-24T14:22:26","date_gmt":"2020-10-24T12:22:26","guid":{"rendered":"https:\/\/www.vindjeu.eu\/?p=37885"},"modified":"2020-10-24T14:22:46","modified_gmt":"2020-10-24T12:22:46","slug":"deep-state-new-world-order-global-conspiracy","status":"publish","type":"post","link":"https:\/\/www.vindjeu.eu\/prd\/2020\/10\/24\/deep-state-new-world-order-global-conspiracy\/","title":{"rendered":"Deep State New World Order + Global Conspiracy"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/10\/2619-Deep-State-1.jpg\" alt=\"\" class=\"wp-image-37886\" width=\"554\" height=\"554\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/10\/2619-Deep-State-1.jpg 900w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/10\/2619-Deep-State-1-150x150.jpg 150w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/10\/2619-Deep-State-1-300x300.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/10\/2619-Deep-State-1-768x768.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/10\/2619-Deep-State-1-160x160.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/10\/2619-Deep-State-1-245x245.jpg 245w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/10\/2619-Deep-State-1-340x340.jpg 340w\" sizes=\"auto, (max-width: 554px) 100vw, 554px\" \/><\/figure><\/div>\n\n\n\n<figure class=\"wp-block-image is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/10\/2619-Deep-State-1.2.jpg\" alt=\"\" class=\"wp-image-37887\" width=\"514\" height=\"514\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/10\/2619-Deep-State-1.2.jpg 900w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/10\/2619-Deep-State-1.2-150x150.jpg 150w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/10\/2619-Deep-State-1.2-300x300.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/10\/2619-Deep-State-1.2-768x768.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/10\/2619-Deep-State-1.2-160x160.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/10\/2619-Deep-State-1.2-245x245.jpg 245w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/10\/2619-Deep-State-1.2-340x340.jpg 340w\" sizes=\"auto, (max-width: 514px) 100vw, 514px\" \/><\/figure>\n\n\n\n<p><span style=\"color:#f1f3f4\" class=\"color\">.<\/span><\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/10\/Swa-40-150x150.jpg\" alt=\"\" class=\"wp-image-37847\"\/><\/figure><\/div>\n\n\n\n<h5 class=\"wp-block-heading\"><span style=\"color:#0693e3\" class=\"color\">SwatSh<\/span>: <span style=\"color:#cf2e2e\" class=\"color\"> 7\/10<\/span><\/h5>\n\n\n\n<p>Alors que Deep State est sorti en 2019, son extension vient de sortir et tous deux seront disponibles lors du prochain salon virtuel d&rsquo;Essen, voil\u00e0 pourquoi je vous les pr\u00e9sente maintenant.  <\/p>\n\n\n\n<p>Il s&rsquo;agit d&rsquo;un jeu de placement d&rsquo;ouvriers assez classique o\u00f9 vous allez devoir d\u00e9penser des ressources pour monter le long de diff\u00e9rentes \u00e9chelles afin de gagner des points de victoire ainsi que diff\u00e9rents bonus.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span style=\"color:#abb8c3\" class=\"color\">Majorit\u00e9s<\/span><\/h2>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignright is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/10\/2619-Deep-State-3.jpg\" alt=\"\" class=\"wp-image-37890\" width=\"593\" height=\"395\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/10\/2619-Deep-State-3.jpg 900w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/10\/2619-Deep-State-3-300x200.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/10\/2619-Deep-State-3-768x512.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/10\/2619-Deep-State-3-160x107.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/10\/2619-Deep-State-3-368x245.jpg 368w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/10\/2619-Deep-State-3-510x340.jpg 510w\" sizes=\"auto, (max-width: 593px) 100vw, 593px\" \/><\/figure><\/div>\n\n\n\n<p>Chaque joueur joue \u00e0 son tour dans Deep State et ex\u00e9cute une action.  Il va pouvoir aller chercher des ouvriers dans sa r\u00e9serve, les placer sur des cartes objectif et progresser sur les cartes projet.  Quand on place des ouvriers sur l carte objectif on ne peut le faire qu&rsquo;en y pla\u00e7ant plus d&rsquo;ouvriers qu&rsquo;un adversaire et donc, en prenant la majorit\u00e9.  Et quand on prend la majorit\u00e9, les agents adverses retournent dans leur r\u00e9serve.<\/p>\n\n\n\n<p>Ces agents vont alors \u00eatre d\u00e9fauss\u00e9s pour payer les avanc\u00e9es sur les cartes projet.  Et lorsqu&rsquo;on avance sur une carte projet, on va gagner des bonus.  Il va falloir bien planifier vos actions pour optimiser les b\u00e9n\u00e9fices de vos diff\u00e9rentes avanc\u00e9es.  <\/p>\n\n\n\n<p>Le jeu se complexifie ensuite gr\u00e2ce aux cartes \u00ab\u00a0Treaty\u00a0\u00bb qui vont elles aussi apporter certains bonus et effets que vous allez devoir optimiser au mieux.<\/p>\n\n\n\n<p>Tout \u00e7a est du d\u00e9j\u00e0 vu bien que le syst\u00e8me de majorit\u00e9 bouleverse un peu tout et vous allez voir vos majorit\u00e9s disput\u00e9es par vos adversaires.  Il va falloir vous battre pour les garder ou les reprendre.  Ce syst\u00e8me de majorit\u00e9 est clairement l&rsquo;aspect le plus fun de Deep State qui propose, gr\u00e2ce \u00e0 lui, une belle interactivit\u00e9.<\/p>\n\n\n\n<hr class=\"wp-block-separator is-style-wide\"\/>\n\n\n\n<figure class=\"wp-block-image alignfull\"><img loading=\"lazy\" decoding=\"async\" width=\"1875\" height=\"985\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/10\/2619-Deep-State-8.jpg\" alt=\"\" class=\"wp-image-37888\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/10\/2619-Deep-State-8.jpg 1875w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/10\/2619-Deep-State-8-300x158.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/10\/2619-Deep-State-8-768x403.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/10\/2619-Deep-State-8-1024x538.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/10\/2619-Deep-State-8-160x84.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/10\/2619-Deep-State-8-466x245.jpg 466w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/10\/2619-Deep-State-8-647x340.jpg 647w\" sizes=\"auto, (max-width: 1875px) 100vw, 1875px\" \/><\/figure>\n\n\n\n<hr class=\"wp-block-separator is-style-wide\"\/>\n\n\n\n<h2 class=\"wp-block-heading\"><span style=\"color:#abb8c3\" class=\"color\">Vin d&rsquo;jeu d&rsquo;music<\/span><\/h2>\n\n\n\n<figure class=\"wp-block-embed-youtube wp-block-embed is-type-video is-provider-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"video-container\"><iframe loading=\"lazy\" title=\"Vertige - Conduire (Clip officiel)\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/raQxxdmnO0Y?feature=oembed&#038;wmode=opaque\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p> Alors que Deep State est sorti en 2019, son extension vient de sortir et tous deux seront disponibles lors du prochain salon virtuel d&rsquo;Essen, voil\u00e0 pourquoi je vous les pr\u00e9sente maintenant. Il s&rsquo;agit d&rsquo;un jeu de placement d&rsquo;ouvriers assez classique o\u00f9 vous allez devoir d\u00e9penser des ressources&#46;&#46;&#46;<\/p>\n","protected":false},"author":3,"featured_media":37886,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[4849],"tags":[7],"class_list":["post-37885","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-expert","tag-swatsh","annee-2083","auteurs-konstantin-seleznev","editeurs-crowd-games","illustrateurs-alexander-khromov","nombre_conseille-1185","nombre_conseille-1210","nombre_conseille-1355","nombre_conseille-1217","mecanismes-marche","mecanismes-placement-douvriers"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/37885","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/comments?post=37885"}],"version-history":[{"count":0,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/37885\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media\/37886"}],"wp:attachment":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media?parent=37885"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/categories?post=37885"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/tags?post=37885"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}