{"id":38389,"date":"2020-11-18T09:40:09","date_gmt":"2020-11-18T08:40:09","guid":{"rendered":"https:\/\/www.vindjeu.eu\/?p=38389"},"modified":"2020-11-18T09:40:35","modified_gmt":"2020-11-18T08:40:35","slug":"conversion","status":"publish","type":"post","link":"https:\/\/www.vindjeu.eu\/prd\/2020\/11\/18\/conversion\/","title":{"rendered":"CONVERSION"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/11\/conversion_cover-1-660x330.jpg\" alt=\"\" class=\"wp-image-38453\" width=\"596\" height=\"298\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/11\/conversion_cover-1-660x330.jpg 660w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/11\/conversion_cover-1-660x330-300x150.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/11\/conversion_cover-1-660x330-160x80.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/11\/conversion_cover-1-660x330-490x245.jpg 490w\" sizes=\"auto, (max-width: 596px) 100vw, 596px\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/10\/Serval.jpg\" alt=\"\" class=\"wp-image-37790\" width=\"113\" height=\"140\"\/><\/figure><\/div>\n\n\n\n<p class=\"has-medium-font-size\"><span style=\"color:#0693e3\" class=\"color\"><strong>Serval<\/strong><\/span><strong> <\/strong><span style=\"color:#cf2e2e\" class=\"color\"><strong>7\/10<\/strong><\/span><\/p>\n\n\n\n<p><span style=\"color:#eeeeee\" class=\"color\">..<\/span><\/p>\n\n\n\n<p> <br> <br>  <br><span style=\"color:#eeeeee\" class=\"color\">.. <\/span><\/p>\n\n\n\n<p><br>  <br><span style=\"color:#eeeeee\" class=\"color\">..<\/span><\/p>\n\n\n\n<p><span style=\"color: #eeeeee;\" class=\"color\"> .. <\/span><\/p>\n\n\n\n<p><span style=\"color:#eeeeee\" class=\"color\"> .. <\/span><\/p>\n\n\n\n<p>Conversion est un jeu pour le moins atypique, tout droit sorti du Canada et d\u00e9j\u00e0 distribu\u00e9 outre Atlantique.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span style=\"color:#cf2e2e\" class=\"color\">Un matos d\u00e9moniaque<\/span><\/h2>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/11\/123436755_408656870136493_1134769472120815009_n-1-764x1024.jpg\" alt=\"\" class=\"wp-image-38523\" width=\"251\" height=\"337\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/11\/123436755_408656870136493_1134769472120815009_n-1-764x1024.jpg 764w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/11\/123436755_408656870136493_1134769472120815009_n-1-224x300.jpg 224w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/11\/123436755_408656870136493_1134769472120815009_n-1-768x1029.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/11\/123436755_408656870136493_1134769472120815009_n-1-119x160.jpg 119w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/11\/123436755_408656870136493_1134769472120815009_n-1-183x245.jpg 183w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/11\/123436755_408656870136493_1134769472120815009_n-1-254x340.jpg 254w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/11\/123436755_408656870136493_1134769472120815009_n-1.jpg 1504w\" sizes=\"auto, (max-width: 251px) 100vw, 251px\" \/><\/figure><\/div>\n\n\n\n<p>Trois kilos&nbsp;! C\u2019est le poids que fait la boite, premi\u00e8re surprise&nbsp;! (il y en aura d\u2019autres.) Un mat\u00e9riel de qualit\u00e9 pour un jeu cr\u00e9\u00e9 et fabriqu\u00e9 de toute pi\u00e8ce par&nbsp;&nbsp;Nicolas Desaulniers-Soucy . Une sorte de prototype abouti, carton plume noir \u00e0 l\u2019int\u00e9rieur, sac en toile sur mesure, magnifique pierres grav\u00e9es comme marqueur de joueur ( en jade, opale, am\u00e9thyste, lapis-lazuli, aventurine, h\u00e9matite, agate , rien que \u00e7a !) , feutres effa\u00e7ables, tuiles \u00e9paisses, et carnets de joueur plastifi\u00e9s. Un joli et gros travail maison pr\u00eat pour l\u2019auto\u00e9dition ! Sorti de l&rsquo;imagination de son auteur en 1996, il est finalement n\u00e9 en avril 2020 sur Ulule. <\/p>\n\n\n\n<p><span style=\"color:#eeeeee\" class=\"color\">..<\/span><\/p>\n\n\n\n<p>Deuxi\u00e8me surprise le jeu se d\u00e9guste en mode connexion, soit\nvia un simple navigateur web, soit et c\u2019est plut\u00f4t la meilleur fa\u00e7on de\nd\u00e9couvrir ce jeu via l\u2019application d\u00e9di\u00e9e. La seule condition pour profiter de\nl\u2019app, avoir la puce&nbsp;NFC install\u00e9e sur son Smartphone. Ce n\u2019\u00e9tait pas le\ncas pour le test (dommage), j\u2019ai donc test\u00e9 le jeu via un navigateur web sur ma\ntablette.<\/p>\n\n\n\n<p>Conversion est un jeu \u00e0 r\u00f4les cach\u00e9s, o\u00f9 deux clans vont\ns\u2019affronter&nbsp;: les forces du bien et du mal.<\/p>\n\n\n\n<p>Le but du jeu pour les forces du bien&nbsp;: D\u00e9truire le\ngrand d\u00e9mon qui sommeille dans sa tombe. Le mal lui devra convertir les\nengeances du bien ou prot\u00e9ger cette tombe jusqu\u2019\u00e0 la fin du temps imparti.\n(1h15 pour une premi\u00e8re partie et 1 h pour le mode normal).&nbsp; Oui mais&nbsp;! Un certain nombre de points\nseront perdus ou gagn\u00e9s par les joueurs en fonction des actions qu\u2019ils vont mener\ntout au long de la partie, un clan l\u2019emportera donc mais un seul joueur gagnera\nla partie&nbsp;!<\/p>\n\n\n\n<p>Un joueur est cens\u00e9 cr\u00e9er la partie sur le site http:\/\/jeuconversion.net\/ et d\u2019y inscrire les participants ou plus simplement de scanner le QR Code sur la boite du jeu (toujours avec la puce NFC), cr\u00e9ant ainsi automatiquement une partie, les joueurs participants scannant cette m\u00eame balise pour rejoindre la partie. <\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/11\/Sans-titre-4-1.jpg\" alt=\"\" class=\"wp-image-38528\" width=\"357\" height=\"409\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/11\/Sans-titre-4-1.jpg 713w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/11\/Sans-titre-4-1-262x300.jpg 262w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/11\/Sans-titre-4-1-140x160.jpg 140w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/11\/Sans-titre-4-1-214x245.jpg 214w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/11\/Sans-titre-4-1-297x340.jpg 297w\" sizes=\"auto, (max-width: 357px) 100vw, 357px\" \/><\/figure><\/div>\n\n\n\n<p>Selon le nombre de joueurs s\u00e9lectionn\u00e9s (nous f\u00fbmes 5 pour\ncette partie), les r\u00f4les sont distribu\u00e9s automatiquement par l\u2019application (ou\nsite), assez pratique&nbsp;! Pour ma part, j\u2019ai demand\u00e9 \u00e0 chaque joueur de\nrentrer son nom dans la partie que j\u2019avais cr\u00e9\u00e9e sur la tablette et de bien\nnoter le nom de son personnage. Bien entendu, tous les joueurs ont pris soin de\nfaire cela tr\u00e8s discr\u00e8tement.<\/p>\n\n\n\n<p>Une fois les personnages identifi\u00e9s, les joueurs les inscrivent sur leur carnet personnel. Le jeu peut commencer et les joueurs placent leur jetons pierre dans la pi\u00e8ce o\u00f9 ils d\u00e9sirent d\u00e9buter leur aventure. Le meneur de jeu (celui qui a cr\u00e9\u00e9 la partie), indique le num\u00e9ro du tour en cours et demande \u00e0 chaque joueur de noter secr\u00e8tement sur son carnet plastifi\u00e9, l\u2019action programm\u00e9e parmi des actions de d\u00e9couvertes, de qu\u00eate ou dites de conversion.  Apr\u00e8s la programmation, toutes les actions se d\u00e9rouleront selon un certain ordre, voici le d\u00e9tail des actions :<\/p>\n\n\n\n<p><strong><span style=\"color:#eeeeee\" class=\"color\">&nbsp;         ..<\/span><\/strong><\/p>\n\n\n\n<p><span style=\"background-color:#eeeeee\" class=\"background-color\">..<\/span><\/p>\n\n\n\n<p><strong>   1.D\u00e9couvertes\/fouilles :<\/strong><\/p>\n\n\n\n<p>En fait, c\u2019est l\u2019action principale en d\u00e9but de jeu puisqu\u2019il s agit de fouiller les zones des pi\u00e8ces dans laquelle on se trouve. Le jeu poss\u00e8de X pi\u00e8ces, dans chaque pi\u00e8ces se trouvent du mobilier (lits, piano, meubles, tables, etc\u2026) qui indiquent autant de zones que l\u2019on peut fouiller.<\/p>\n\n\n\n<p>Quand un joueur d\u00e9sire fouiller, il pioche\nune tuile dans le sac en toile, la regarde secr\u00e8tement et selon l\u2019objet trouv\u00e9,\nr\u00e9v\u00e8le ou non la tuile en la repla\u00e7ant sur la zone fouill\u00e9e.<\/p>\n\n\n\n<p>On trouve, p\u00eale m\u00eame&nbsp;:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Rien&nbsp;\ud83d\ude42<\/li><li>Un pieu (qui sert uniquement aux forces du bien pour d\u00e9truire le grand d\u00e9mon) mais est de fait assez pris\u00e9 puisqu\u2019en nombre restreint,<\/li><li>Des runes, sorte de sortil\u00e8ges dont il faut bien noter l\u2019emplacement sur son carnet, on verra pourquoi apr\u00e8s, cette tuile est repos\u00e9e face cach\u00e9e sur la zone fouill\u00e9e et donc disponible pour une prochaine fouille a cet endroit par un autre joueur.<\/li><li>Des boules de cristal, objet assez puissant et qui vous permet imm\u00e9diatement de&nbsp;connaitre une des &nbsp;informations cruciales via l\u2019application ou le site web ( <br>L\u2019appli web se charge alors de r\u00e9pondre au joueur.) :<ul><li>Quels joueurs ont de la m\u00eame all\u00e9geance que moi,<\/li><li>Quels joueurs sont de l\u2019all\u00e9geance oppos\u00e9e,<\/li><li>Quels joueurs son personnage peut convertir,<\/li><li>Quels joueurs peuvent convertir son personnage,<\/li><li>Ou\u2026qui ai- je besoin de convertir avec surprise.<\/li><\/ul><\/li><li>Un passage secret, vous permettant bien sur de vous rendre dans une autre pi\u00e8ce secr\u00e8tement.<\/li><li>L\u2019entr\u00e9e la crypte (o\u00f9 se trouvent six cercueils dont un abrite le grand d\u00e9mon&nbsp;!)&nbsp; ; \u00f4 combien importante car c\u2019est une tuile unique&nbsp;!<strong> <\/strong><\/li><li><\/li><\/ul>\n\n\n\n<p><strong>&nbsp;         2. Se d\u00e9placer<\/strong>&nbsp;: chaque joueur peut se d\u00e9placer d\u2019une pi\u00e8ce voisine (attention en cas de d\u00e9placement concomitant de plusieurs joueurs dans une m\u00eame pi\u00e8ce, seul le joueur ayant une porte s\u2019ouvrant sur la pi\u00e8ce (d\u2019autres portent s\u2019ouvrent \u00e0 l\u2019int\u00e9rieur) pourra s\u2019y rendre, les autres perdront leur action ce tour. C\u2019est principalement gr\u00e2ce \u00e0 cette action que l\u2019on pourra effectuer la suivante&nbsp;:<\/p>\n\n\n\n<p><strong>&nbsp;           3.Convertir<\/strong><\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignright\"><img loading=\"lazy\" decoding=\"async\" width=\"345\" height=\"250\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/11\/Sans-titre-3.jpg\" alt=\"\" class=\"wp-image-38532\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/11\/Sans-titre-3.jpg 345w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/11\/Sans-titre-3-300x217.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/11\/Sans-titre-3-160x116.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/11\/Sans-titre-3-338x245.jpg 338w\" sizes=\"auto, (max-width: 345px) 100vw, 345px\" \/><\/figure><\/div>\n\n\n\n<p>Cette action est le c\u0153ur du jeu, toute la saveur r\u00e9side \u00e0 pouvoir convertir un joueur dans sa propre all\u00e9geance sans se tromper de cible&nbsp;! Oui car la conversion manqu\u00e9e sans \u00eatre forc\u00e9ment risqu\u00e9e peut faire perdre des points aux fautifs&nbsp;! Souvenez vous, les joueurs acqui\u00e8rent ou perdent des points&nbsp;!<\/p>\n\n\n\n<p>Quand une tentative de conversion \u00e0 lieu, le o\u00f9 les joueurs concern\u00e9s se\nrendent sur l\u2019appli ou le site web afin de v\u00e9rifier le r\u00e9sultat de leur\ntentative. L\u2019application d\u00e9termine le r\u00e9sultat selon une grille d\u2019\u00e9valuation\npr\u00e9\u00e9tablie. Chaque personnage du bien et du mal obtient une r\u00e9ussite\ninconditionnelle sur un personnage en particulier. Par exemple, le Moine\nconvertira automatiquement un Loup Garou et une sorci\u00e8re, manquera sa tentative\nsur un vampire et un fant\u00f4me mais r\u00e9ussira sa conversion sur un mort vivant et\nune poss\u00e9d\u00e9e sauf ci ces derniers r\u00e9ussissent une conversion avec surprise (en\nsortant d\u2019un passage secret) dans la m\u00eame action. <\/p>\n\n\n\n<p>Quelques malus : un personnage du bien convertissant un autre personnage du bien : -1 pt ! , le mal contre le mal : &#8211; 2 pts cependant dans ce cas, les personnages ainsi convertis se transforment en un autre personnage du mal augmentant math\u00e9matiquement leur capacit\u00e9 de conversion. Une conversion r\u00e9ussie : 6 points !<\/p>\n\n\n\n<p>Ce n\u2019est pas si complexe \u00e0 g\u00e9rer mais l\u2019application fait le boulot \u00e0 notre place et nous d\u00e9voile le r\u00e9sultat de nos tentatives et encore une fois, si on suit pas \u00e0 pas la proc\u00e9dure , \u00e7a fonctionne sans probl\u00e8me. Dans la partie , ma femme a \u00e9t\u00e9 convertie 4 fois , changeant ainsi 4 fois de personnages, tout \u00e7a \u00e0 l\u00e9 m\u00e9rite d&rsquo;\u00e9viter une certaine routine en tout cas..<\/p>\n\n\n\n<p>        <strong>   4.Entrer dans un passage<\/strong><\/p>\n\n\n\n<p>Cette action permet donc d&rsquo;utiliser un passage secret pour sortir secr\u00e8tement dans une autre pi\u00e8ce et tenter (pour les forces du mal uniquement) une conversion avec surprise, rendant les probabilit\u00e9 de r\u00e9ussite plus forte. Le passage secret permettant \u00e9galement un d\u00e9placement furtif vers un autre lieu du plateau.<\/p>\n\n\n\n<p><span style=\"background-color: #e8eaeb;\" class=\"color\"><\/span><\/p>\n\n\n\n<p><strong>&nbsp;         5.Entrer dans la crypte<\/strong><\/p>\n\n\n\n<p>Vous l&rsquo;aurez probablement compris, la crypte est le seul endroit ou les forces du mal peuvent d\u00e9truire le grand d\u00e9mon. D\u00e9j\u00e0 le premier joueur \u00e0 avoir trouver la tuile gagne 5 points, ensuite ce dernier peut tenter d&rsquo;ouvrir une tombe (parmi les six pr\u00e9sentes) afin de v\u00e9rifier si le grand d\u00e9mon s&rsquo;y trouve (gr\u00e2ce \u00e0 l&rsquo;application ou au site) et lui planter gentiment un pieu qu&rsquo;il aurait pr\u00e9c\u00e9demment obtenu et ainsi permettre aux forces du bien de remporter imm\u00e9diatement la partie !<\/p>\n\n\n\n<p><strong>&nbsp; <\/strong> <strong>&nbsp;      6.Activer une rune<\/strong> <\/p>\n\n\n\n<p>Il convient de d\u00e9clarer quelle rune est utilis\u00e9e en indiquant \u00e0 tous le lieu o\u00f9 se trouve cette rune (sur une pr\u00e9c\u00e9dente recherche) , le pouvoir s&rsquo;applique alors. Elle permettent diff\u00e9rents actions interactives ; se d\u00e9placer plus loin, voler un pieu, fouiller toutes les zones d&rsquo;une pi\u00e8ce, ouvrir toutes les tombes de la crypte, etc&#8230;. Si par malheur , un joueur se trompe (parce qu&rsquo;il \u00e0 mal rep\u00e9r\u00e9 le lieu de la rune ou s&rsquo;est tromp\u00e9 de rune), ce dernier perd 1 point.<\/p>\n\n\n\n<p>Evidemment, l&rsquo;ordre des actions programm\u00e9es \u00e0 son importance.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/11\/Sans-titre-4-2-1024x729.jpg\" alt=\"\" class=\"wp-image-38541\" width=\"388\" height=\"276\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/11\/Sans-titre-4-2-1024x729.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/11\/Sans-titre-4-2-300x214.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/11\/Sans-titre-4-2-768x547.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/11\/Sans-titre-4-2-160x114.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/11\/Sans-titre-4-2-344x245.jpg 344w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/11\/Sans-titre-4-2-477x340.jpg 477w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/11\/Sans-titre-4-2.jpg 1483w\" sizes=\"auto, (max-width: 388px) 100vw, 388px\" \/><figcaption>Magnifiques pierres !<\/figcaption><\/figure><\/div>\n\n\n\n<p>Conversion envoi du lourd pour le mat\u00e9riel, le plateau est clair , rappel un peu le c\u00e9l\u00e9brissime cluedo mais en plus abouti et est bien sur d&rsquo;aun autre calibre quand \u00e0 sa complexit\u00e9 et sa profondeur !<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span style=\"color:#cf2e2e\" class=\"color\">Convertissez vous !<\/span><\/h2>\n\n\n\n<p> Les r\u00e8gles ne sont pas si facile \u00e0 prendre en main, il m&rsquo;a fallu quelques lectures avant de lancer une partie, la r\u00e9vision des r\u00e8gles sur le site<a href=\"https:\/\/www.jeuconversion.net\/\"> https:\/\/www.jeuconversion.net\/<\/a>&nbsp;sont un peu plus abouties et r\u00e9pond finalement \u00e0 quelques interrogations, reste que le site pour une premi\u00e8re partie aiguille intelligemment les joueurs n\u00e9ophytes.<\/p>\n\n\n\n<p>Conversion est donc un jeu typiquement riche, tendu et devant n\u00e9cessiter quelques parties un peu chaotiques avant de prendre toute sa saveur. L&rsquo;acc\u00e8s \u00e0 l\u2019application via une puce NFC me semble quasi indispensable pour profiter pleinement du travail de l&rsquo;auteur. (A noter qu&rsquo;il est possible de jouer sans aucune connexion internet, rendant le jeu un peu plus laborieux toutefois).<\/p>\n\n\n\n<p>Un \u00e9norme travail qui m\u00e9rite le d\u00e9tour ! Un travail artistique qui fonctionne parfaitement avec le th\u00e8me nous aide \u00e0 s&rsquo;immerger. Pour changer un peu des jeux de r\u00f4les cach\u00e9s \u00ab\u00a0format\u00e9s\u00a0\u00bb , laissez vous tenter par Conversion, il est unique dans sa conception, il faut simplement savoir le prendre en main pour en tirer le meilleur parti. Rendez vous sur le site de l&rsquo;auteur !<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span style=\"color:#abb8c3\" class=\"color\">VIND&rsquo;JEU MUSIC<\/span><\/h2>\n\n\n\n<figure class=\"wp-block-embed-youtube wp-block-embed is-type-video is-provider-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"video-container\"><iframe loading=\"lazy\" title=\"Annie Lennox - Love Song for a Vampire (Audio)\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/N63RB2gQu-0?feature=oembed&#038;wmode=opaque\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p> .. .. .. .. .. Conversion est un jeu pour le moins atypique, tout droit sorti du Canada et d\u00e9j\u00e0 distribu\u00e9 outre Atlantique. Un matos d\u00e9moniaque Trois kilos&nbsp;! C\u2019est le poids que fait la boite, premi\u00e8re surprise&nbsp;! (il y en aura d\u2019autres.) Un mat\u00e9riel de qualit\u00e9 pour un&#46;&#46;&#46;<\/p>\n","protected":false},"author":9,"featured_media":38455,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[4848],"tags":[],"class_list":["post-38389","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-initie","annee-2346","auteurs-nicolas-desaulniers-soucy","illustrateurs-yannick-bouchard","nombre_conseille-1321","nombre_conseille-1919","nombre_conseille-2135","mecanismes-roles-caches"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/38389","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/comments?post=38389"}],"version-history":[{"count":0,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/38389\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media\/38455"}],"wp:attachment":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media?parent=38389"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/categories?post=38389"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/tags?post=38389"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}