{"id":38837,"date":"2020-11-22T20:20:21","date_gmt":"2020-11-22T19:20:21","guid":{"rendered":"https:\/\/www.vindjeu.eu\/?p=38837"},"modified":"2020-11-22T20:22:07","modified_gmt":"2020-11-22T19:22:07","slug":"magic-the-gathering-la-renaissance-de-zendikar","status":"publish","type":"post","link":"https:\/\/www.vindjeu.eu\/prd\/2020\/11\/22\/magic-the-gathering-la-renaissance-de-zendikar\/","title":{"rendered":"Magic The Gathering: La renaissance de Zendikar"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/11\/2672-Magic-Zendikar-1.jpg\" alt=\"\" class=\"wp-image-38839\" width=\"523\" height=\"492\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/11\/2672-Magic-Zendikar-1.jpg 850w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/11\/2672-Magic-Zendikar-1-300x282.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/11\/2672-Magic-Zendikar-1-768x723.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/11\/2672-Magic-Zendikar-1-160x151.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/11\/2672-Magic-Zendikar-1-260x245.jpg 260w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/11\/2672-Magic-Zendikar-1-361x340.jpg 361w\" sizes=\"auto, (max-width: 523px) 100vw, 523px\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/11\/Swa-43-150x150.jpg\" alt=\"\" class=\"wp-image-38808\"\/><\/figure><\/div>\n\n\n\n<h5 class=\"wp-block-heading\"><span style=\"color:#0693e3\" class=\"color\">SwatSh<\/span>:  <span style=\"color:#cf2e2e\" class=\"color\">9,5\/10<\/span><\/h5>\n\n\n\n<p>La renaissance de Zendikar est la derni\u00e8re extension de Magic The Gathering qui peut se jouer en standalone, comme toutes les autres extensions actuelles de Magic. Elle est vendue en boosters et en collector boosters qui contiennent quelques rares en plus et toutes les cartes en foil.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"> <span style=\"color:#00d084\" class=\"color\">Commander<\/span><\/h2>\n\n\n\n<p>La renaissance de Zendikar propose \u00e9galement 2 nouveaux decks commander dont la col\u00e8re de Zendikar que j&rsquo;ai eu la chance de jouer. Le deck tourne autour de la cr\u00e9ature l\u00e9gendaire Obuun qui exploite une des m\u00e9caniques de Zendikar: la pose de terrain. En effet, aussi simple que \u00e7a puisse para\u00eetre, une des m\u00e9caniques centrales de Zendikar est la pose de terrain. De nombreuses cartes vont activer leurs effets lorsqu&rsquo;un nouveau terrain vient en jeu sous votre contr\u00f4le. Obuun fait de m\u00eame. Il place un jeton +1\/+1 sur une cr\u00e9ature (en g\u00e9n\u00e9ral lui-m\u00eame) \u00e0 chaque fois qu&rsquo;un terrain arrive en jeu. Et \u00e0 chaque tour, il peut transformer, jusqu&rsquo;\u00e0 la fin du tour, un terrain en une cr\u00e9ature avec pi\u00e9tinement dont la force et l&rsquo;endurance \u00e9quivalent \u00e0 la force d&rsquo;Obuun. Et en soutien au commander, d&rsquo;autres cartes vont permettre de placer plus d&rsquo;un terrain par tour ou d&rsquo;augmenter les marqueurs +1\/+1. La col\u00e8re de Zendikar est un deck coh\u00e9rent et tr\u00e8s puissant qui concurrencera certainement vos meilleurs decks commander.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/11\/2672-Magic-Zendikar-2-1024x683.jpg\" alt=\"\" class=\"wp-image-38852\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/11\/2672-Magic-Zendikar-2-1024x683.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/11\/2672-Magic-Zendikar-2-300x200.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/11\/2672-Magic-Zendikar-2-768x512.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/11\/2672-Magic-Zendikar-2-160x107.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/11\/2672-Magic-Zendikar-2-368x245.jpg 368w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/11\/2672-Magic-Zendikar-2-510x340.jpg 510w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><span style=\"color:#00d084\" class=\"color\">Les autres effets de Zendikar<\/span><\/h2>\n\n\n\n<p>Outre les diff\u00e9rents effets provenant de la pose de terrain (la cr\u00e9ature a +2\/+2 chaque fois qu&rsquo;un terrain vient en jeu, taper la cr\u00e9ature cibl\u00e9e, infliger un point de d\u00e9g\u00e2t,&#8230;), Zendikar va \u00e9galement tourner autour d&rsquo;autres m\u00e9caniques comme le \u00ab\u00a0kick\u00a0\u00bb. De nombreuses cartes auront des effets suppl\u00e9mentaires si on paie le co\u00fbt kick et certaines vont avoir des effets quand on active le co\u00fbt kick d&rsquo;une autre carte comme cet enchantement qui va cr\u00e9er des 2\/2 volantes \u00e0 chaque fois qu&rsquo;un co\u00fbt kick aura \u00e9t\u00e9 pay\u00e9.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignright is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/11\/2672-Magic-Zendikar-10-1024x683.jpg\" alt=\"\" class=\"wp-image-38854\" width=\"546\" height=\"364\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/11\/2672-Magic-Zendikar-10-1024x683.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/11\/2672-Magic-Zendikar-10-300x200.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/11\/2672-Magic-Zendikar-10-768x512.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/11\/2672-Magic-Zendikar-10-160x107.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/11\/2672-Magic-Zendikar-10-368x245.jpg 368w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/11\/2672-Magic-Zendikar-10-510x340.jpg 510w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/11\/2672-Magic-Zendikar-10.jpg 1800w\" sizes=\"auto, (max-width: 546px) 100vw, 546px\" \/><\/figure><\/div>\n\n\n\n<p>De nombreuses cartes vont \u00e9galement jouer sur le gain de points de vie et sur des effets qui en d\u00e9coulent comme ce clerc qui fait perdre un point de vie \u00e0 l&rsquo;adversaire \u00e0 chaque fois que vous en gagnez ou la 3\/3 volante qui gagner un marqueur +1\/+1 \u00e0 chaque fois que vous gagnez des points de vie.<\/p>\n\n\n\n<p>Enfin, de nombreux effets seront d&rsquo;autant plus puissants que vous avez de membres dans votre groupe d&rsquo;aventuriers. Un groupe d&rsquo;aventuriers se compose d&rsquo;un sorcier, d&rsquo;un clerc, d&rsquo;un gredin et d&rsquo;un guerrier (\u00e9videmment \ud83d\ude09 ). J&rsquo;ai trouv\u00e9 cette derni\u00e8re m\u00e9canique un peu trop faible car il est tr\u00e8s difficile d&rsquo;avoir une \u00e9quipe compl\u00e8te sur son plan de jeu.<\/p>\n\n\n\n<p>Zendikar est une tr\u00e8s bonne extension et m\u00eame si sa m\u00e9canique de groupe d&rsquo;aventuriers est difficile \u00e0 optimiser, le reste des nouvelles m\u00e9caniques et combos est non seulement tr\u00e8s puissante et facile \u00e0 mettre en place mais \u00e9galement tr\u00e8s agr\u00e9able \u00e0 jouer. Jamais vous inclurez autant de cartes permettant de mettre plus de terrains en jeu ou de cartes au co\u00fbt kick \u00e9lev\u00e9 et jamais vous ne jouerez autant avec le gain de points de vie.<\/p>\n\n\n\n<hr class=\"wp-block-separator is-style-wide\"\/>\n\n\n\n<figure class=\"wp-block-image alignfull\"><img loading=\"lazy\" decoding=\"async\" width=\"1380\" height=\"920\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/11\/2672-Magic-Zendikar-5.jpg\" alt=\"\" class=\"wp-image-38838\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/11\/2672-Magic-Zendikar-5.jpg 1380w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/11\/2672-Magic-Zendikar-5-300x200.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/11\/2672-Magic-Zendikar-5-768x512.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/11\/2672-Magic-Zendikar-5-1024x683.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/11\/2672-Magic-Zendikar-5-160x107.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/11\/2672-Magic-Zendikar-5-368x245.jpg 368w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/11\/2672-Magic-Zendikar-5-510x340.jpg 510w\" sizes=\"auto, (max-width: 1380px) 100vw, 1380px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p> La renaissance de Zendikar est la derni\u00e8re extension de Magic The Gathering qui peut se jouer en standalone, comme toutes les autres extensions actuelles de Magic. Elle est vendue en boosters et en collector boosters qui contiennent quelques rares en plus et toutes les cartes en foil. Commander&#46;&#46;&#46;<\/p>\n","protected":false},"author":3,"featured_media":38839,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[4849],"tags":[7],"class_list":["post-38837","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-expert","tag-swatsh","annee-2346","auteurs-richard-garfield","editeurs-wizards-of-the-coast","nombre_conseille-1185","mecanismes-combat","mecanismes-jeu-de-cartes"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/38837","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/comments?post=38837"}],"version-history":[{"count":0,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/38837\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media\/38839"}],"wp:attachment":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media?parent=38837"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/categories?post=38837"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/tags?post=38837"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}