{"id":39224,"date":"2020-12-18T13:08:44","date_gmt":"2020-12-18T12:08:44","guid":{"rendered":"https:\/\/www.vindjeu.eu\/?p=39224"},"modified":"2020-12-18T13:08:53","modified_gmt":"2020-12-18T12:08:53","slug":"jy-crois-pas","status":"publish","type":"post","link":"https:\/\/www.vindjeu.eu\/prd\/2020\/12\/18\/jy-crois-pas\/","title":{"rendered":"J&rsquo;y Crois Pas"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/12\/2702-J-y-crois-pas-1.jpg\" alt=\"\" class=\"wp-image-39225\" width=\"502\" height=\"474\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/12\/2702-J-y-crois-pas-1.jpg 636w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/12\/2702-J-y-crois-pas-1-300x283.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/12\/2702-J-y-crois-pas-1-160x151.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/12\/2702-J-y-crois-pas-1-260x245.jpg 260w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/12\/2702-J-y-crois-pas-1-360x340.jpg 360w\" sizes=\"auto, (max-width: 502px) 100vw, 502px\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/11\/DSC07094-150x150.jpg\" alt=\"\" class=\"wp-image-38858\"\/><\/figure><\/div>\n\n\n\n<h5 class=\"wp-block-heading\"><span style=\"color:#0693e3\" class=\"color\">SwatSh<\/span>:  <span style=\"color:#cf2e2e\" class=\"color\">9\/10<\/span><\/h5>\n\n\n\n<p>Apr\u00e8s <a href=\"https:\/\/www.vindjeu.eu\/2019\/11\/17\/oriflamme\/\"><strong>Oriflamme<\/strong><\/a>, <a href=\"https:\/\/www.vindjeu.eu\/2019\/12\/16\/hagakure\/\"><strong>Hagakure <\/strong><\/a>et <a href=\"https:\/\/www.vindjeu.eu\/2019\/12\/31\/alubari-a-nice-cup-of-tea\/\"><strong>Alubari<\/strong><\/a>, J&rsquo;y crois pas est le dernier jeu du jeune \u00e9diteur <a href=\"https:\/\/www.vindjeu.eu\/editeurs\/studio-h\/\"><strong>Studio H<\/strong><\/a>. Cette fois-ci, ils ont d\u00e9cid\u00e9 de travailler avec un auteur qui a de la bouteille \ud83d\ude09 : <a href=\"https:\/\/www.vindjeu.eu\/auteurs\/herve-marly\/\"><strong>Herv\u00e9 Marly<\/strong><\/a>, auteur, entre autre, du g\u00e9nial <a href=\"https:\/\/www.vindjeu.eu\/2015\/12\/16\/twinz\/\"><strong>Twinz<\/strong><\/a>, de l&rsquo;intemporel <a href=\"https:\/\/www.vindjeu.eu\/2011\/08\/19\/les-loups-garous-de-thiercelieux\/\"><strong>Loups Garou<\/strong><\/a>, du g\u00e9n\u00e9rateur de fous rires <a href=\"https:\/\/www.vindjeu.eu\/2009\/07\/12\/petits-meurtres-et-faits-divers\/\"><strong>Petits Meurtres et Faits Divers<\/strong><\/a> et surtout du <a href=\"https:\/\/www.vindjeu.eu\/2010\/10\/25\/les-jeux-du-fictionnaire-classic-encyclopedia\/\"><strong>jeu du Fictionnaire<\/strong><\/a>.  Je dis \u00ab\u00a0surtout\u00a0\u00bb car J&rsquo;y crois pas s&rsquo;en est clairement inspir\u00e9 tout comme <a href=\"https:\/\/www.vindjeu.eu\/2010\/10\/25\/les-jeux-du-fictionnaire-classic-encyclopedia\/\"><strong>le jeu du Fictionnaire <\/strong><\/a>s&rsquo;est probablement inspir\u00e9 du jeu du dictionnaire, excellente \u00e9mission radio.  <\/p>\n\n\n\n<p>Pour rappel, le jeu du dictionnaire et du fictionnaire consistent \u00e0 dire diff\u00e9rentes d\u00e9finitions pour un mot et une joueuse doit tenter de d\u00e9couvrir la bonne d\u00e9finition.  <\/p>\n\n\n\n<p>J&rsquo;y crois pas c&rsquo;est un peu la m\u00eame chose mais sous forme de question dont la r\u00e9ponse est vraie.  Le joueur \u00ab\u00a0ignorant\u00a0\u00bb pioche une carte et lit la question: \u00ab\u00a0Quelle marque a vendu le plus de pneus en 2019?\u00a0\u00bb.  Les autres joueurs prennent la carte question, la retournent et lisent la r\u00e9ponse: \u00ab\u00a0Lego\u00a0\u00bb (qui est une vraie r\u00e9ponse, vous pouvez v\u00e9rifier).  Ils prennent un peu de temps pour r\u00e9fl\u00e9chir et donnent leur r\u00e9ponse, chacun \u00e0 son tour: Goodyear, Pirelli, Lego, Playmobil, Dinky Toys.  L&rsquo;ignorant va alors \u00e9liminer celles qu&rsquo;il consid\u00e8re comme \u00e9tant les mauvaises r\u00e9ponses et s&rsquo;arr\u00eatera quand il veut.  Il ramassera une pi\u00e8ce par mauvaise r\u00e9ponse \u00e9limin\u00e9e mais ne recevra rien s&rsquo;il \u00e9limine la bonne r\u00e9ponse.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/12\/2702-J-y-crois-pas-2.jpg\" alt=\"\" class=\"wp-image-39229\" width=\"765\" height=\"510\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/12\/2702-J-y-crois-pas-2.jpg 1020w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/12\/2702-J-y-crois-pas-2-300x200.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/12\/2702-J-y-crois-pas-2-768x512.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/12\/2702-J-y-crois-pas-2-160x107.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/12\/2702-J-y-crois-pas-2-368x245.jpg 368w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/12\/2702-J-y-crois-pas-2-510x340.jpg 510w\" sizes=\"auto, (max-width: 765px) 100vw, 765px\" \/><\/figure><\/div>\n\n\n\n<p>Et bien, voil\u00e0 une bonne surprise!  Le jeu du fictionnaire ne m&rsquo;avait pas laiss\u00e9 un immense souvenir par le s\u00e9rieux qu&rsquo;il imposait puisqu&rsquo;il s&rsquo;agissait \u00e0 chaque fois, d&rsquo;une vraie d\u00e9finition.  Ici, les r\u00e9ponses aux questions, bien que vraies et issues d&rsquo;un r\u00e9el travail de recherche, sont beaucoup plus comiques et susceptibles d&rsquo;engendrer des r\u00e9ponses saugrenues.  Dans j&rsquo;y crois pas, c&rsquo;est beaucoup plus amusant d&rsquo;imaginer des r\u00e9ponses et \u00e9liminer les mauvaises est \u00e0 chaque fois un d\u00e9fi.  Une partie se jouant avec 2 cartes question par joueuse, soit 10 \u00e0  5 joueuses, le jeu en comportant 350, cela vous assure au moins 35 parties sans jamais retomber sur une question lue pr\u00e9c\u00e9demment.  C&rsquo;est clairement une belle rejouabilit\u00e9.  Herv\u00e9 Marly a clairement r\u00e9ussit \u00e0 sortir un jeu inspir\u00e9 du jeu du dictionnaire tr\u00e8s amusant, autant pour la joueuse devant trouver la bonne r\u00e9ponse que pour les autres qui trouveront un malin plaisir \u00e0 inventer une r\u00e9ponse tout aussi saugrenue que la bonne \ud83d\ude42  De plus, ce n&rsquo;est pas si compliqu\u00e9 d&rsquo;imaginer une mauvaise r\u00e9ponse ce qui rend le jeu tout \u00e0 fait amusant en milieu familial ou amical \ud83d\ude00<\/p>\n\n\n\n<hr class=\"wp-block-separator is-style-wide\"\/>\n\n\n\n<figure class=\"wp-block-image alignfull\"><img loading=\"lazy\" decoding=\"async\" width=\"1380\" height=\"920\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/12\/2702-J-y-crois-pas-5.jpg\" alt=\"\" class=\"wp-image-39226\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/12\/2702-J-y-crois-pas-5.jpg 1380w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/12\/2702-J-y-crois-pas-5-300x200.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/12\/2702-J-y-crois-pas-5-768x512.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/12\/2702-J-y-crois-pas-5-1024x683.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/12\/2702-J-y-crois-pas-5-160x107.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/12\/2702-J-y-crois-pas-5-368x245.jpg 368w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2020\/12\/2702-J-y-crois-pas-5-510x340.jpg 510w\" sizes=\"auto, (max-width: 1380px) 100vw, 1380px\" \/><\/figure>\n\n\n\n<hr class=\"wp-block-separator is-style-wide\"\/>\n\n\n\n<h2 class=\"wp-block-heading\"><span style=\"color:#abb8c3\" class=\"color\">Vid\u00e9o de Ludovox (Ludochrono)<\/span><\/h2>\n\n\n\n<figure class=\"wp-block-embed-youtube wp-block-embed is-type-video is-provider-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"video-container\"><iframe loading=\"lazy\" title=\"Ludochrono - J\u2019y crois pas\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/kz-tZofa18c?feature=oembed&#038;wmode=opaque\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<\/div><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<hr class=\"wp-block-separator is-style-wide\"\/>\n\n\n\n<h2 class=\"wp-block-heading\"><span style=\"color:#abb8c3\" class=\"color\">Vin d&rsquo;jeu d&rsquo;music<\/span><\/h2>\n\n\n\n<figure class=\"wp-block-embed-youtube wp-block-embed is-type-video is-provider-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"video-container\"><iframe loading=\"lazy\" title=\"Dominique A - Les \u00e9veill\u00e9s\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/61c3DLu4b2E?feature=oembed&#038;wmode=opaque\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p> Apr\u00e8s Oriflamme, Hagakure et Alubari, J&rsquo;y crois pas est le dernier jeu du jeune \u00e9diteur Studio H. Cette fois-ci, ils ont d\u00e9cid\u00e9 de travailler avec un auteur qui a de la bouteille \ud83d\ude09 : Herv\u00e9 Marly, auteur, entre autre, du g\u00e9nial Twinz, de l&rsquo;intemporel Loups Garou, du g\u00e9n\u00e9rateur&#46;&#46;&#46;<\/p>\n","protected":false},"author":3,"featured_media":39225,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[5],"tags":[7],"class_list":["post-39224","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-famille","tag-swatsh","annee-2346","auteurs-herve-marly","editeurs-studio-h","illustrateurs-augustin-rogeret","nombre_conseille-1355","nombre_conseille-1217","nombre_conseille-1321","nombre_conseille-1919","nombre_conseille-2135","mecanismes-bluff","mecanismes-deduction"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/39224","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/comments?post=39224"}],"version-history":[{"count":0,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/39224\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media\/39225"}],"wp:attachment":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media?parent=39224"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/categories?post=39224"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/tags?post=39224"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}